{"id":3929,"date":"2012-08-16T09:39:40","date_gmt":"2012-08-16T08:39:40","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=3929"},"modified":"2012-08-16T09:39:40","modified_gmt":"2012-08-16T08:39:40","slug":"quebec","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2012\/08\/16\/quebec\/","title":{"rendered":"Qu\u00e9bec"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3932\" title=\"457 Quebec 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-1.jpg\" alt=\"\" width=\"350\" height=\"233\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-1-300x199.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-1-150x99.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-1-400x266.jpg 400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p><span style=\"color: #333399;\"><strong>SwatSh<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 7,5 \u00a0 \/10<\/strong><\/span><\/p>\n<p>La premi\u00e8re chose qu\u2019on doit oublier dans Qu\u00e9bec, c\u2019est son th\u00e8me.\u00a0 Qu\u00e9bec est un jeu de majorit\u00e9 abstrait et tr\u00e8s bien ficel\u00e9.<\/p>\n<p>A votre tour, vous avez le choix entre 4 actions mais g\u00e9n\u00e9ralement, vous allez devoir choisir entre les 2 principales\u00a0: d\u00e9placer son architecte ou contribuer \u00e0 la construction d\u2019un b\u00e2timent.<\/p>\n<p>Les joueurs disposent de petits cubes, appel\u00e9s ouvriers.\u00a0 Ces ouvriers ont 2 \u00e9tats\u00a0: actif (= pr\u00eats \u00e0 \u00eatre jou\u00e9s) ou passif (il faut les activer avant de pouvoir les jouer.\u00a0 Chaque construction en cours est repr\u00e9sent\u00e9e par une rondelle sur laquelle est pos\u00e9e un architecte d\u2019un joueur et 3 emplacements.\u00a0 Quand vous d\u00e9placez votre architecte, vous cr\u00e9ez un nouveau chantier et vous terminer la construction en cours et gagnez des points de victoire en fonction du nombre d\u2019emplacements occup\u00e9s.<\/p>\n<p>Quand vous d\u00e9cidez de contribuer \u00e0 une construction, vous placez dans un des emplacements libres le nombre de cubes actifs requis par la construction.\u00a0 Le truc c\u2019est qu\u2019\u00e0 chaque fois que vous contribuez \u00e0 une construction, si celle-ci n\u2019est pas celle de votre propre architecte, vous b\u00e9n\u00e9ficiez du bonus du b\u00e2timent.<\/p>\n<p>Les constructions ont 4 couleurs diff\u00e9rentes et lorsqu\u2019une construction est termin\u00e9e, tous les cubes pr\u00e9sents sur la construction se retrouvent dans la case de la couleur du b\u00e2timent.\u00a0 A chaque fin de phase, on effectue le d\u00e9compte de ces 4 cases color\u00e9es dans un ordre \u00e0 chaque fois diff\u00e9rent.\u00a0 C\u2019est l\u00e0 que les joueurs gagneront le plus de points de victoire.\u00a0 Quand on d\u00e9compte une case, chaque joueur gagne un nombre de PVs \u00e9quivalent aux nombre de cubes qu\u2019il poss\u00e8de dans cette case.\u00a0 Le joueur majoritaire, d\u00e9place la moiti\u00e9 de ses cubes dans la case suivante.\u00a0 Des r\u00e9actions en cha\u00eene\u00a0ont alors souvent lieu et un joueur majoritaire dans une case peut devenir majoritaire aussi dans les cases suivantes.\u00a0 Certains de ses cubes compteront alors en double voire plus.\u00a0 Ceci est une m\u00e9canique tr\u00e8s tactique et originale qui fait une bonne partie du sel du jeu.<\/p>\n<p>Qu\u00e9bec est donc un jeu tr\u00e8s tactique, qui ne fait pas trop r\u00eaver avec son syst\u00e8me tr\u00e8s abstrait mais qui fait r\u00e9fl\u00e9chir et qui soumet aux joueurs des choix pas toujours faciles\u00a0: en pla\u00e7ant son architecte sur tel b\u00e2timent, on permettra aux autres joueurs de faire certaines actions sp\u00e9ciales mais on gagnera \u00e9galement des points de victoire si de nombreux joueurs participent \u00e0 la construction de votre b\u00e2timent.\u00a0 De plus, les ouvriers des joueurs vont aller dans une case de la couleur du b\u00e2timent ce qui leur permettra de gagner des points de victoire.\u00a0 Il vaut mieux donc participer aux b\u00e2timents des autres tout en ayant un b\u00e2timent attrayant permettant de gagner des points de victoire et en changeant de b\u00e2timent assez souvent pour avoir toujours des ouvriers actifs.\u00a0 C\u2019est pas toujours \u00e9vident\u2026<\/p>\n<p><span style=\"color: #333399;\"><strong>Philrey212<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 7,8\/10<\/strong><\/span><\/p>\n<p>Malgr\u00e9 qu&rsquo;on n&rsquo;a pas vraiment l&rsquo;impression de participer au d\u00e9veloppement de la ville de Qu\u00e9bec, le jeu est assez plaisant. Les ingr\u00e9dients pour une bonne r\u00e9flexion y sont r\u00e9unis.<br \/>\nLes m\u00e9canismes que je retiens dans Qu\u00e9bec sont:<br \/>\n&#8211; Le fait de participer \u00e0 la construction des b\u00e2timents mis en chantier par vos adversaires vous octroie une action bonus que vous n&rsquo;auriez pas en vous occupant seulement de vos propres b\u00e2timents.<br \/>\n&#8211; La cascade d&rsquo;influences entre les diff\u00e9rentes zones (militaire, religion, \u00e9conomique, culture et la citadelle). Cet aspect rajoute une mani\u00e8re\u00a0d&rsquo;engranger\u00a0 des points de victoire. Ici, on pourrait reprocher, vu l&rsquo;importance de la cascade, de se concentrer sur la premi\u00e8re zone de d\u00e9compte (ce fut un peu la tendance dans notre partie)<\/p>\n<p>En r\u00e9sum\u00e9, Qu\u00e9bec offre une bonne r\u00e9flexion autour d&rsquo;un plateau de jeu tr\u00e8s color\u00e9, avec une m\u00e9canique originale (la cascade d&rsquo;influence) et du mat\u00e9riel de bonne augure. Autre aspect int\u00e9ressant, le dur\u00e9e aussi bien des r\u00e8gles que d&rsquo;une partie est raisonnable.<\/p>\n<p><span style=\"color: #333399;\"><strong><br \/>\n<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3931\" title=\"457 Quebec 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-2-1024x768.jpg\" alt=\"\" width=\"819\" height=\"614\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3930\" title=\"457 Quebec 3\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-3-1024x768.jpg\" alt=\"\" width=\"717\" height=\"538\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-3-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/08\/457-Quebec-3-400x300.jpg 400w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/a>Je vous conseille particuli\u00e8rement ce vin blanc Chilien tout \u00e0 fait surprenant. \u00a0Alors que l&rsquo;\u00e9tiquette n&rsquo;attire pas sp\u00e9cialement, le nez et le go\u00fbt sont particuliers et envo\u00fbtants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> La premi\u00e8re chose qu\u2019on doit oublier dans Qu\u00e9bec, c\u2019est son th\u00e8me.\u00a0 Qu\u00e9bec est un jeu de majorit\u00e9 abstrait et tr\u00e8s bien ficel\u00e9. A votre tour, vous avez le choix entre 4 actions mais g\u00e9n\u00e9ralement, vous allez devoir choisir entre les 2 principales\u00a0: d\u00e9placer son architecte ou&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":3932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-3929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-344","auteurs-philippe-beaudoin","auteurs-pierre-poissant-marquis","editeurs-le-scorpion-masque","editeurs-ystari-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/3929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=3929"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/3929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/3932"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=3929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=3929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=3929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}