{"id":39615,"date":"2021-01-06T10:22:08","date_gmt":"2021-01-06T09:22:08","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=39615"},"modified":"2021-01-06T10:23:09","modified_gmt":"2021-01-06T09:23:09","slug":"amalfi","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/01\/06\/amalfi\/","title":{"rendered":"Amalfi"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-1.jpg\" alt=\"\" class=\"wp-image-39616\" width=\"450\" height=\"621\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-1.jpg 652w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-1-217x300.jpg 217w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-1-116x160.jpg 116w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-1-177x245.jpg 177w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-1-246x340.jpg 246w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/Swa-51-150x150.jpg\" alt=\"\" class=\"wp-image-39617\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\"> 9\/10<\/span><\/h5>\n\n\n\n<p>Amalfi est un jeu tr\u00e8s discret.  Tellement discret qu&rsquo;il est introuvable!  Je ne sais m\u00eame pas s&rsquo;il est sorti en magasin.  Mais une chose est s\u00fbre: <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/sylex\/\"><strong>Sylex <\/strong><\/a>a annonc\u00e9 l&rsquo;\u00e9diter en Fran\u00e7ais en 2021!  <\/p>\n\n\n\n<p>Heureusement pour moi, j&rsquo;ai \u00e9t\u00e9 invit\u00e9 par Pardieu d&rsquo;<strong><a rel=\"noreferrer noopener\" aria-label=\"Expert Game Award (opens in a new tab)\" href=\"http:\/\/www.expertgameaward.com\/\" target=\"_blank\">Expert Game Award<\/a><\/strong> afin de me faire d\u00e9couvrir ce petit bijou.  Et il a bien fait Pardieu car maintenant, je suis tout \u00e9moustill\u00e9 et impatient de voir la VF de <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/sylex\/\"><strong>Sylex <\/strong><\/a>\u00eatre publi\u00e9e pour pouvoir enfin y rejouer!<\/p>\n\n\n\n<p>Amalfi est un jeu de placement <del>d&rsquo;ouvriers <\/del>de bateaux avec des c\u00f4t\u00e9s classiques m\u00eal\u00e9s \u00e0 des twists assez sympas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Actions priv\u00e9es<\/span><\/h2>\n\n\n\n<p>Vous allez placer vos bateaux sur des cases actions afin de r\u00e9colter diff\u00e9rentes ressources.  Avec ces ressources, vous allez pouvoir acheter des cartes actions qui vous donneront des actions sp\u00e9cifiques que seuls vous pourrez utiliser en y pla\u00e7ant vos bateaux.  Ces cases actions priv\u00e9es seront g\u00e9n\u00e9ralement plus puissantes ou vous donneront plus de possibilit\u00e9s que les cases communes.  De plus, contrairement aux cases actions communes fort disput\u00e9es, seuls vous aurez acc\u00e8s \u00e0 ces actions priv\u00e9es.  Enfin, au fur et \u00e0 mesure de l&rsquo;avancement du jeu, utiliser vos actions priv\u00e9es sera le seul moyen d&rsquo;obtenir un grand nombre d&rsquo;une m\u00eame ressource car les cases communes ne vous permettent d&rsquo;en avoir qu&rsquo;un nombre tr\u00e8s limit\u00e9.<\/p>\n\n\n\n<p>Cette m\u00e9canique de gain d&rsquo;actions priv\u00e9es n&rsquo;est certes pas tout \u00e0 fait nouvelle (on la retrouve dans <a href=\"https:\/\/www.vindjeu.eu\/2015\/02\/19\/orleans\/\"><strong>Orl\u00e9ans <\/strong><\/a>par exemple) mais elle donne une profondeur au jeu assez int\u00e9ressante tout en accentuant son c\u00f4t\u00e9 crescendo. Evidemment, elle va aller de paire avec une possibilit\u00e9 d&rsquo;augmenter votre nombre de bateaux (= nombre d&rsquo;ouvriers) qui, un peu comme dans <a href=\"https:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\"><strong>Agricola<\/strong><\/a>, devront \u00eatre pay\u00e9s par un co\u00fbt d&rsquo;entretien \u00e0 chaque tour (co\u00fbt \u00e0 payer en pains, bon &#8230; passons \ud83d\ude09 ).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-3.jpg\" alt=\"\" class=\"wp-image-39623\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-3.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Contrats<\/span><\/h2>\n\n\n\n<p>Et ces ressources vont principalement servir \u00e0 acqu\u00e9rir des contrats qui, outre un petit b\u00e9n\u00e9fice, vont principalement vous apporter des PVs.  Heureusement, Amalfi ne s&rsquo;arr\u00eate pas l\u00e0 et enrichit le jeu gr\u00e2ce \u00e0 2 autres \u00e9l\u00e9ments.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-7.jpg\" alt=\"\" class=\"wp-image-39621\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-7.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-7-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-7-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-7-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-7-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-7-510x340.jpg 510w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Objectifs<\/span><\/h2>\n\n\n\n<p>Une partie d&rsquo;Amalfi est guid\u00e9e par 7 objectifs: 3 pour la partie et 4 pour chacun des 4 tours de jeu \u00e0 raison d&rsquo;un objectif par tour. Un peu comme dans <a href=\"https:\/\/www.vindjeu.eu\/2019\/07\/18\/wingspan\/\"><strong>Wingspan<\/strong><\/a>, \u00e0 chaque tour, vous aurez l&rsquo;occasion de grapiller quelques points en fonction de votre progression dans la condition fix\u00e9e par l&rsquo;objectif du tour. M\u00eame chose pour les objectifs de partie, bien que l\u00e0, une petite course entre joueuse va avoir lieu puisque la premi\u00e8re \u00e0 atteindre un objectif gagnera plus de points que la seconde qui en gagnera plus que la troisi\u00e8me, la derni\u00e8re ne recevant plus rien!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Cartes vari\u00e9es<\/span><\/h2>\n\n\n\n<p>Le second \u00e9l\u00e9ment qui enrichit consid\u00e9rablement Amalfi est son paquet de cartes aux effets divers.  En d\u00e9but de partie, les joueurs vont drafter leur main de cartes.  En cours de partie, ils auront l&rsquo;occasion d&rsquo;en gagner des suppl\u00e9mentaires.  Ces cartes vont apporter des effets divers.  Elles apporteront des objectifs priv\u00e9s qui permettront aux joueurs de gagner des points suppl\u00e9mentaires.  Elles permettront \u00e9galement de gagner des capacit\u00e9s permanentes, des r\u00e9ductions de co\u00fbt, des gains d&rsquo;ouvriers, des ressources,&#8230;  Elles sont g\u00e9n\u00e9ralement assez puissantes et il serait dommage de ne pas en profiter.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-5.jpg\" alt=\"\" class=\"wp-image-39624\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-5.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">La c\u00f4te Amalfitaine<\/span><\/h2>\n\n\n\n<p>Vous allez donc devoir faire vos choix sur base d&rsquo;une multitudes d&rsquo;\u00e9l\u00e9ments: sur base des objectifs de fin de partie, sur base des cartes que vous aurez en main et que vous voudrez jouer, sur base de l&rsquo;objectif du tour, sur base des cartes actions \u00e0 acqu\u00e9rir, sur base des contrats que vous voudrez r\u00e9aliser et sur base des actions disponibles sur le plateau de jeu et non encore prises par vos adversaires. Les choix sont nombreux, corn\u00e9liens et la tension est bien pr\u00e9sente car on veut absolument pouvoir prendre certaines cartes \/ cases action \/ objectifs avant ses adversaires.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-8.jpg\" alt=\"\" class=\"wp-image-39625\" width=\"454\" height=\"303\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-8.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 454px) 100vw, 454px\" \/><\/figure><\/div>\n\n\n\n<p>Tout cela n&rsquo;est pas tr\u00e8s nouveau mais tourne \u00e0 merveille.  Un peu trop m\u00eame car le dernier tour de jeu est assez poussif et r\u00e9p\u00e9titif.  Le jeu aurait gagn\u00e9 \u00e0 \u00eatre plus court.<\/p>\n\n\n\n<p>De plus, Amalfi est r\u00e9gi par une m\u00e9canique de mouvement de bateaux le long de la c\u00f4te amalfitaine absolument fabuleuse. Vos bateaux, qui vous servent d&rsquo;ouvrier pour r\u00e9aliser vos actions vont \u00e9galement servir de marqueur de ressources. Quand vous gagnez des ressources, vous allez l&rsquo;indiquer avec vos bateaux qui seront alors indisponibles pour r\u00e9aliser une action tant que vous poss\u00e9derez les ressources correspondantes. De plus, vous pourrez m\u00eame condamner des bateaux pour avoir un gain rapide de ressources gr\u00e2ce auquel vous allez pouvoir prendre vos adversaires de vitesse. Tout cela est superbement imagin\u00e9 et rend Amalfi assez unique et tr\u00e8s int\u00e9ressant.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15.jpg\" alt=\"\" class=\"wp-image-39618\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2716-Amalfi-15-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Amalfi est un jeu tr\u00e8s discret. Tellement discret qu&rsquo;il est introuvable! Je ne sais m\u00eame pas s&rsquo;il est sorti en magasin. Mais une chose est s\u00fbre: Sylex a annonc\u00e9 l&rsquo;\u00e9diter en Fran\u00e7ais en 2021! Heureusement pour moi, j&rsquo;ai \u00e9t\u00e9 invit\u00e9 par Pardieu d&rsquo;Expert Game Award afin de me&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":39616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-39615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2346","auteurs-yamada-takeo","editeurs-uchibacoya","illustrateurs-urabe-rocinante","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-asymetrie","mecanismes-deplacement-douvriers","mecanismes-draft","mecanismes-gestion-de-ressources","mecanismes-objectifs-communs","mecanismes-objectifs-prives"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/39615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=39615"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/39615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/39616"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=39615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=39615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=39615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}