{"id":39913,"date":"2021-01-16T20:42:05","date_gmt":"2021-01-16T19:42:05","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=39913"},"modified":"2021-01-16T20:47:08","modified_gmt":"2021-01-16T19:47:08","slug":"midnight-exchange","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/01\/16\/midnight-exchange\/","title":{"rendered":"Midnight exchange"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/midnight-exchange-1.jpg\" alt=\"\" class=\"wp-image-39946\" width=\"419\" height=\"419\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/midnight-exchange-1.jpg 372w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/midnight-exchange-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/midnight-exchange-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/midnight-exchange-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/midnight-exchange-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/midnight-exchange-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 419px) 100vw, 419px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Serval<\/span> <span style=\"color:#cf2e2e\" class=\"color\">7,5\/10<\/span><\/h5>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p>Dernier n\u00e9 du couple Wilfried et Marie Fort (Dragomino), Midnight exchange nous propose d\u2019endosser le masque d\u2019un cambrioleur opportuniste.<\/p>\n\n\n\n<p>Comme souvent ces auteurs proposent un jeu plut\u00f4t familial, ici on ne d\u00e9roge pas \u00e0 la r\u00e8gle, 8 ans suffisent (voir un peu moins pour les plus d\u00e9gourdis) pour d\u00e9fier papa et maman dans la cambriole.<\/p>\n\n\n\n<p><span style=\"color: #eeeeee;\" class=\"color\">&#8230;.<\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p><span style=\"color: #eeeeee;\" class=\"color\">&#8230;.<\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">&#8230;<\/span><\/p>\n\n\n\n<p>Chaque joueur recevra un plateau \u00ab&nbsp;identit\u00e9&nbsp;\u00bb symbolisant le genre du cambrioleur jou\u00e9 (homme ou femme) , chaque plateau (cambrioleur) &nbsp;pouvant accueillir jusqu\u2019\u00e0 6 jetons objets d\u2019art.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/3-2-768x1024.jpg\" alt=\"\" class=\"wp-image-39977\" width=\"224\" height=\"298\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/3-2-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/3-2-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/3-2-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/3-2-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/3-2-255x340.jpg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/3-2.jpg 1536w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/figure><\/div>\n\n\n\n<p>54 tuiles lieux sont dispers\u00e9es p\u00eale-m\u00e8le au centre de la zone de jeu \u00e0 disposition de tous. Il existe trois lieux, le garage (bleu), la bureau (violet) et le coffre-fort (orange) repr\u00e9sentant le verso de ces tuiles, au recto&nbsp;: argent, bijou, or, boites vides, sacoches, etc.. &nbsp;plus ou moins rares selon le lieu (on imagine ais\u00e9ment que trouver de l\u2019or dans un garage est moins \u00e9vident que dans un coffre-fort).<span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Une main dans le dos !<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/6-768x1024.jpg\" alt=\"\" class=\"wp-image-39953\" width=\"247\" height=\"329\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/6-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/6-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/6-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/6-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/6-255x340.jpg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/6.jpg 1536w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/figure><\/div>\n\n\n\n<p>Le concept est plut\u00f4t simple, avec une seule main, tous les\njoueurs vont gaiement s\u2019adonner \u00e0 un pillage en r\u00e8gle des tuiles garage, coffre-fort\net bureau. Oui mais pas n\u2019importe comment, l\u2019ordre est important&nbsp;! En\neffet pas de probl\u00e8me pour rentrer dans le garage (et retourner une tuile\nidoine) par contre, une cl\u00e9 en fer est obligatoire pour retourner une tuile\nbureau et une cl\u00e9 en laiton est indispensable pour forcer le coffre-fort. Et o\u00f9\ntrouve ton ces cl\u00e9s&nbsp;? Sous une tuile garage (pour la cl\u00e9 en fer) et sous\nune tuile bureau (pour le s\u00e9same en laiton).<\/p>\n\n\n\n<p>Il faudra donc farfouiller suffisamment intelligemment pour ne pas perdre son pr\u00e9cieux temps car la fouille se termine lorsque tous les joueurs ont r\u00e9cup\u00e9r\u00e9 une des tuiles \u00ab&nbsp;fuites&nbsp;\u00bb , il y en a autant que de joueurs num\u00e9rot\u00e9s de 1 \u00e0 X joueurs , le premier \u00e0 avoir fini sa cambriole prend la tuile \u00ab&nbsp;fuite&nbsp;\u00bb 1,&nbsp; puis le deuxi\u00e8me prend la \u00ab&nbsp;2&nbsp;\u00bb, etc.., jusqu\u2019\u00e0 ce que l\u2019avant dernier joueur ayant pris une tuile fuite d\u00e9clenche la fin du tour de jeu, le dernier joueur n\u2019aura donc comme butin que ce qu\u2019il a eu le temps de prendre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #0693e3;\" class=\"color\">Qui veut de ma came ?<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5-1024x831.jpg\" alt=\"\" class=\"wp-image-39941\" width=\"424\" height=\"344\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5-1024x831.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5-300x243.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5-768x623.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5-160x130.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5-302x245.jpg 302w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5-419x340.jpg 419w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/5.jpg 1536w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><figcaption>Ce revendeur propose divers objets d&rsquo;art ou une carte \u00ab\u00a0prestige\u00a0\u00bb contre une tuile \u00ab\u00a0bijoux\u00a0\u00bb<br><br><\/figcaption><\/figure><\/div>\n\n\n\n<p>Une fois les larcins en poche, les cambrioleurs doivent dans l&rsquo;ordre de leur tuile \u00ab\u00a0fuite\u00a0\u00bb \u00e9changer un (par tour) de leur butin contre un objet d&rsquo;art ou une carte prestige aupr\u00e8s des receleurs aux march\u00e9s noir. <\/p>\n\n\n\n<p>Ces receleurs ont tous besoin d&rsquo;un certain type de butin en \u00e9change des objets d&rsquo;art, indiqu\u00e9 en haut de la tuile idoine.<\/p>\n\n\n\n<p>Les objets d&rsquo;art valent de 2 \u00e0 3 points en fin de partie et\/ou peuvent servir \u00e0 compl\u00e9ter les cartes \u00ab\u00a0prestige\u00a0\u00bb qui sont en fait des exigences de collection de certains clients fortun\u00e9s !<\/p>\n\n\n\n<p>La partie se termine quand les receleurs n&rsquo;ont plus d&rsquo;objets d&rsquo;arts ou de cartes \u00ab\u00a0prestiges\u00a0\u00bb. On fait le total des collections compl\u00e8tes ou incompl\u00e8tes des cartes prestiges et des objets d&rsquo;arts dans les poches des cambrioleurs, le plus dou\u00e9 l&#8217;emporte !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><span style=\"color: #eeeeee;\" class=\"color\">..<\/span><\/p>\n\n\n\n<p><span style=\"color: #eeeeee;\" class=\"color\">..<\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Les rois de la rapine !<\/span><\/h2>\n\n\n\n<p>Midnight exchange se joue avec tout public, les plus jeunes sont ravis de transgresser les interdits et de jouer les voleurs en retournant fr\u00e9n\u00e9tiquement les tuiles butins. Tout le monde se prend vite au jeu et comprend assez vite qu&rsquo;il ne faut vraiment pas faire n&rsquo;importe quoi et n&rsquo;importe comment, la fr\u00e9n\u00e9sie ne fonctionnant pas forc\u00e9ment !<\/p>\n\n\n\n<p>Un poil de logique et de r\u00e9flexion rend le jeu tr\u00e8s vivant et suffisamment calculatoire lors des \u00e9changes des butins pour apprendre aux novices la logique du bon choix au bon moment ! <\/p>\n\n\n\n<p>M\u00eame le plus jeune \u00e0 notre table (10 ans) pourtant allergique aux nouveaut\u00e9s en a vite redemand\u00e9, gage de r\u00e9ussite !<\/p>\n\n\n\n<p>Bon vol \ud83d\ude09<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><span style=\"color: #eeeeee;\" class=\"color\">&#8230;.<\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/4-768x1024.jpg\" alt=\"\" class=\"wp-image-39931\" width=\"534\" height=\"712\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/4-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/4-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/4-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/4-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/4-255x340.jpg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/01\/4.jpg 1536w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Jacques Dutronc - Gentleman Cambrioleur.\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/lPGFjD_xkGY?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> .. .. Dernier n\u00e9 du couple Wilfried et Marie Fort (Dragomino), Midnight exchange nous propose d\u2019endosser le masque d\u2019un cambrioleur opportuniste. Comme souvent ces auteurs proposent un jeu plut\u00f4t familial, ici on ne d\u00e9roge pas \u00e0 la r\u00e8gle, 8 ans suffisent (voir un peu moins pour les plus&#46;&#46;&#46;<\/p>\n","protected":false},"author":9,"featured_media":39946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[3283],"class_list":["post-39913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-cambriolage","annee-2346","auteurs-marie-et-wilfried-fort","editeurs-blue-orange","illustrateurs-sylvain-aublin","distributeurs-blue-orange","nombre_conseille-1355","mecanismes-rapidite"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/39913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=39913"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/39913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/39946"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=39913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=39913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=39913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}