{"id":40,"date":"2009-05-21T19:33:00","date_gmt":"2009-05-21T18:33:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/2009\/05\/21\/origo-2007-2-a-5j\/"},"modified":"2010-06-06T16:11:09","modified_gmt":"2010-06-06T15:11:09","slug":"origo-2007-2-a-5j","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2009\/05\/21\/origo-2007-2-a-5j\/","title":{"rendered":"Origo"},"content":{"rendered":"<div><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5338347389995554386\" style=\"margin: 0px 10px 10px 0px; float: left; width: 250px; height: 250px;\" src=\"http:\/\/3.bp.blogspot.com\/_ea2yja0GmY8\/ShWeqtxRllI\/AAAAAAAAAKw\/pQ3cVwFMJ_g\/s400\/31+Origo.jpg\" border=\"0\" alt=\"\" \/><\/div>\n<div><strong><span style=\"color: #9999ff;\">Benoit<\/span><\/strong>: 7\/10<\/div>\n<p>J&rsquo;ai aim\u00e9 Origo mais sans plus. Je trouve que les coups \u00e0 jouer manquaient un peu de saveurs ou\/et d&rsquo;\u00e9pices. On prend ses d\u00e9cisions rapidement (ce qui est aussi un avantage) en suivant ses cartes&#8230; Tr\u00e8s peu de combat car ils peuvent couter tr\u00e8s cher.<br \/>\nJ&rsquo;ai par contre beaucoup appr\u00e9ci\u00e9 le plateau de jeu qui pr\u00e9sente l&rsquo;Europe du Vi\u00e8me si\u00e8cle apr\u00e8s la perte d&rsquo;h\u00e9g\u00e9monie de Rome&#8230; et la Belgique est hyper bien repr\u00e9sent\u00e9e!!!<\/p>\n<div><span style=\"color: #9999ff;\"><strong>Philrey212<\/strong><\/span>: 7,9\/10<\/div>\n<p>Origo est un pur jeu de majorit\u00e9 dans lequel s&rsquo;ajoute un brin de chance via la pioche de cartes.<br \/>\nCette chance n&rsquo;influence que tr\u00e8s peu le r\u00e9sultat final!<br \/>\n+ Pas de longs moment d&rsquo;attente (il faut r\u00e9fl\u00e9chir, c&rsquo;est s\u00fbr, mais c&rsquo;est tout \u00e0 fait acceptable);<br \/>\n+ Du coup, la dur\u00e9e n&rsquo;est pas du tout exag\u00e9r\u00e9e;<br \/>\n+ Facile d&rsquo;acc\u00e8s<br \/>\n+ Belle pr\u00e9sentation<br \/>\n+ Abstrait (pour ceux qui aiment)<br \/>\n&#8211; Peu d&rsquo;originalit\u00e9<br \/>\n&#8211; Abstrait (pour ceux qui n&rsquo;aiment pas)<br \/>\n&#8211; Chance peut-\u00eatre trop importante dans les combats<\/p>\n<div><strong><span style=\"color: #9999ff;\">SwatSh<\/span><\/strong>:   7,5\/10<\/div>\n<div>Origo est un jeu plaisant de Kramer qui a fait Tikal, Java,&#8230;<\/div>\n<div>Bref, un auteur de g\u00e9nie qui a voulu faire du plus l\u00e9ger et qui y a r\u00e9ussi.<\/div>\n<div>Le hasard est tr\u00e8s limit\u00e9 puisqu&rsquo;\u00e0 son tour, on pioche des cartes pour en avoir 10 en main et on en joue entre 2 et 4. On a donc beaucoup de chance d&rsquo;avoir exactement ce que l&rsquo;on cherche.<\/div>\n<div>Ces cartes nous permettent de placer nos jetons sur la carte qui nous permettent de gagner des majorit\u00e9s par territoire.<\/div>\n<div>C&rsquo;est tr\u00e8s bien fait, \u00e7a tourne bien mais ce n&rsquo;est pas un jeu tr\u00e8s original. Tous les m\u00e9canismes sont connus. Le seul m\u00e9canisme un peu limite \u00e0 mon go\u00fbt et qui n&rsquo;apporte rien au jeu est le fait que si notre pion \u00ab\u00a0point de victoire\u00a0\u00bb arrive sur la m\u00eame case que celui d&rsquo;un adversaire, il le \u00ab\u00a0saute\u00a0\u00bb. Quelques joueurs ont donc eu quelques fois la chance de gagner quelques points de victoire qui auraient pu faire la diff\u00e9rence (entre le premier et le deuxi\u00e8me, il y avait un \u00e9cart de 2 points).<\/div>\n<div>Sympa, \u00e0 ressortir de temps en temps chez Vin d&rsquo;jeux!<\/div>\n<div><\/div>\n<div><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5338348433509137762\" style=\"margin: 0px auto 10px; display: block; width: 400px; height: 400px; text-align: center;\" src=\"http:\/\/4.bp.blogspot.com\/_ea2yja0GmY8\/ShWfndKTPWI\/AAAAAAAAAK4\/JVhSBOj1mLM\/s400\/31+Origo+2.jpg\" border=\"0\" alt=\"\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p> J&rsquo;ai aim\u00e9 Origo mais sans plus. Je trouve que les coups \u00e0 jouer manquaient un peu de saveurs ou\/et d&rsquo;\u00e9pices. On prend ses d\u00e9cisions rapidement (ce qui est aussi un avantage) en suivant ses cartes&#8230; Tr\u00e8s peu de combat car ils peuvent couter tr\u00e8s cher. J&rsquo;ai par contre&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":8940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[8,6,7],"class_list":["post-40","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-benoit","tag-philrey212","tag-swatsh","annee-47","auteurs-wolfgang-kramer","editeurs-hasbro","editeurs-parker"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/40\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/8940"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=40"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}