{"id":40370,"date":"2021-02-01T08:10:08","date_gmt":"2021-02-01T07:10:08","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=40370"},"modified":"2021-02-01T08:14:00","modified_gmt":"2021-02-01T07:14:00","slug":"mariposas","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/02\/01\/mariposas\/","title":{"rendered":"Mariposas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxMariposas.png\" alt=\"\" class=\"wp-image-40369\" width=\"453\" height=\"464\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxMariposas.png 878w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxMariposas-293x300.png 293w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxMariposas-768x787.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxMariposas-156x160.png 156w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxMariposas-239x245.png 239w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxMariposas-332x340.png 332w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-768x1024.jpg\" alt=\"\" class=\"wp-image-23587\" width=\"164\" height=\"218\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-255x340.jpg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803.jpg 960w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color:#3731ab\" class=\"color\">PhilRey:<\/span> <span style=\"color:#cf2e2e\" class=\"color\">7\/10<\/span><\/h4>\n\n\n\n<p style=\"color:#416f83\" class=\"has-text-color\">Au printemps, chaque ann\u00e9e, des millions de papillons, les monarques, quittent le Mexique pour migrer vers l\u2019Am\u00e9rique du Nord. A l\u2019automne, des millions de nouveaux monarques reviennent au Mexique. Mais aucun d\u2019entre eux ne fait l\u2019aller-retour.<\/p>\n\n\n\n<p>Voil\u00e0 l\u2019introduction reprise dans le livret de r\u00e8gles de\u00a0Mariposas, invitant les joueurs \u00e0 participer \u00e0 cet \u00ab\u00a0incroyable voyage\u00a0\u00bb. Et ce th\u00e8me colle tr\u00e8s bien \u00e0 la m\u00e9canique du jeu.<\/p>\n\n\n\n<p>Mariposas&nbsp;est un jeu de d\u00e9placement (de papillons) et de collection avec objectifs de fin de manche.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">On \u00e9vite l\u2019hiver<\/h4>\n\n\n\n<p>Une partie de&nbsp;Mariposas&nbsp;se divise en trois manches, \u00e9quivalentes \u00e0 trois saisons&nbsp;: printemps, \u00e9t\u00e9 et automne. En d\u00e9but de chaque manche (parfois plus t\u00f4t) une carte Objectif est r\u00e9v\u00e9l\u00e9e et \u00e9valu\u00e9e en fin de manche. Au printemps, chaque joueur joue 4 tours, 5 tours en \u00e9t\u00e9 et 6 tours en automne.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Les d\u00e9placements<\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2515-768x1024.png\" alt=\"\" class=\"wp-image-40367\" width=\"300\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2515-768x1024.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2515-225x300.png 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2515-120x160.png 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2515-184x245.png 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2515-255x340.png 255w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Tous les joueurs d\u00e9marrent avec leurs pions Papillon de Michoac\u00e1n (Mexique) dans le bas du plateau. C\u2019est de l\u00e0 que d\u00e9marre le p\u00e9riple.<\/p>\n\n\n\n<p>A la fin du mouvement, le papillon se pose. EN fonction de la case d\u2019arriv\u00e9e, le joueur gagne un jeton Fleur, donne naissance \u00e0 un papillon de la g\u00e9n\u00e9ration suivante (en payant le co\u00fbt en jetons Fleur), re\u00e7oit un effet sp\u00e9cifique (carte Cycles de Vie ou carte Mouvement Bonus).<\/p>\n\n\n\n<p>Le joueur, \u00e0 son tour, joue une carte de sa main sur laquelle est indiqu\u00e9 les d\u00e9placements possibles&nbsp;: un papillon 4 ou 5 cases, deux papillons de 2 ou 3 cases, 3 points de mouvement \u00e0 distribuer, etc.<\/p>\n\n\n\n<p>La carte jou\u00e9 reste visible devant le joueur et sert, entre autre, \u00e0 compter le nombre de tour pour la manche en cours. Ces cartes ne seront d\u00e9fauss\u00e9es qu\u2019en fin de manche.<\/p>\n\n\n\n<p>Toutes ces actions suivent des r\u00e8gles bien pr\u00e9cises qui sont bien d\u00e9taill\u00e9es dans les r\u00e8gles avec exemples \u00e0 l\u2019appui.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Partie \u00ab&nbsp;structur\u00e9e&nbsp;\u00bb<\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514-626x1024.png\" alt=\"\" class=\"wp-image-40366\" width=\"191\" height=\"312\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514-626x1024.png 626w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514-183x300.png 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514-768x1256.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514-98x160.png 98w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514-150x245.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514-208x340.png 208w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2514.png 1258w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/figure><\/div>\n\n\n\n<p>Les saisons structurent en quelque sorte la partie et l\u2019\u00e9volution des papillons. En fin de chacune d\u2019elle, les joueurs marquent les points de la carte Objectif de la saison. Ensuite, on adapte l\u2019ordre du tour et les papillons de premi\u00e8re g\u00e9n\u00e9ration (\u00e0 la fin du printemps) sont retir\u00e9s&nbsp; du jeu. Cette astuce force les joueurs \u00e0 faire \u00e9voluer leurs papillons afin de ne pas les perdre.<\/p>\n\n\n\n<p>En fin de partie, on ajoute les points pour les cartes Cycles de Vie accumul\u00e9e et pour les papillons de 4<sup>\u00e8me<\/sup>&nbsp;g\u00e9n\u00e9ration qui sont de retour au Mexique.<\/p>\n\n\n\n<p>Avec&nbsp;Mariposas, Elizabeth Hargrave parvient \u00e0 \u00ab&nbsp;simuler&nbsp;\u00bb cette \u00e9pop\u00e9e en appliquant des contraintes en fin de manche, for\u00e7ant les joueurs \u00e0 faire \u00e9voluer leurs papillons et, si possible, \u00e0 les faire revenir au point de d\u00e9part. Et je pense qu\u2019il faudra plusieurs parties avant de bien identifier le moment crucial o\u00f9 les actions seront ax\u00e9es principalement sur le retour plut\u00f4t qu\u2019\u00e0 la r\u00e9colte de fleurs, plantes ou bonus.<\/p>\n\n\n\n<p>L\u2019interaction entre les joueurs est \u00e9galement bien pr\u00e9sente (le plateau central aide beaucoup \u00e9videmment) du fait qu\u2019il y aura une petite course au bon placement (avoir les bonnes fleurs, l\u2019acc\u00e8s aux plantes, etc.) tout en limitant les choix adverses. Le hasard est pr\u00e9sent par la pioche de cartes Mouvement et l\u2019apparition des bonus. En plus, avec son beau mat\u00e9riel,\u00a0Mariposas\u00a0a tout pour s\u00e9duir plus d\u2019un joueur\u00a0!<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512-790x1024.png\" alt=\"\" class=\"wp-image-40364\" width=\"974\" height=\"1263\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512-790x1024.png 790w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512-232x300.png 232w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512-768x995.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512-123x160.png 123w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512-189x245.png 189w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512-262x340.png 262w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2512.png 2042w\" sizes=\"auto, (max-width: 974px) 100vw, 974px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2513-1024x768.png\" alt=\"\" class=\"wp-image-40365\" width=\"985\" height=\"737\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2513-300x225.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2513-768x576.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2513-160x120.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2513-327x245.png 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2513-453x340.png 453w\" sizes=\"auto, (max-width: 985px) 100vw, 985px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2511-768x1024.png\" alt=\"\" class=\"wp-image-40363\" width=\"877\" height=\"1169\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2511-768x1024.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2511-225x300.png 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2511-120x160.png 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2511-184x245.png 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2511-255x340.png 255w\" sizes=\"auto, (max-width: 877px) 100vw, 877px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Au printemps, chaque ann\u00e9e, des millions de papillons, les monarques, quittent le Mexique pour migrer vers l\u2019Am\u00e9rique du Nord. A l\u2019automne, des millions de nouveaux monarques reviennent au Mexique. Mais aucun d\u2019entre eux ne fait l\u2019aller-retour. Voil\u00e0 l\u2019introduction reprise dans le livret de r\u00e8gles de\u00a0Mariposas, invitant les joueurs&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":40369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-40370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","annee-2346","auteurs-elizabeth-hargrave","editeurs-gigamic","illustrateurs-indi-maverick","illustrateurs-matt-paquette","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-collection","mecanismes-points-de-mouvement"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/40370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=40370"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/40370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/40369"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=40370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=40370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=40370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}