{"id":42051,"date":"2021-05-07T10:31:10","date_gmt":"2021-05-07T08:31:10","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=42051"},"modified":"2021-05-07T10:35:23","modified_gmt":"2021-05-07T08:35:23","slug":"nouvelle-france","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/05\/07\/nouvelle-france\/","title":{"rendered":"Nouvelle France"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR.jpg\" alt=\"\" class=\"wp-image-42050\" width=\"307\" height=\"307\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR.jpg 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNllFR-340x340.jpg 340w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/04\/PhilRey201703.png\" alt=\"\" class=\"wp-image-35040\" width=\"151\" height=\"133\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/04\/PhilRey201703.png 416w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/04\/PhilRey201703-300x265.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/04\/PhilRey201703-160x141.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/04\/PhilRey201703-278x245.png 278w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/04\/PhilRey201703-385x340.png 385w\" sizes=\"auto, (max-width: 151px) 100vw, 151px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#483eba\" class=\"color\">PhilRey:<\/span> <span style=\"color:#cf2e2e\" class=\"color\">7\/10<\/span><\/h5>\n\n\n\n<p>Nouvelle France est un\njeu qui nous vient du Qu\u00e9bec. Je ne suis d\u2019ailleurs pas certain qu\u2019on pourra le\ntrouver facilement de ce c\u00f4t\u00e9 de l\u2019Atlantique.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Le matos<\/h4>\n\n\n\n<p>Nouvelle France vient dans une grosse bo\u00eete, m\u00eame s\u2019il n\u2019y a pas une tonne de matos. Mais il faut bien \u00e7a afin de bien ranger la mousse blanche qui viendra simuler l\u2019accumulation de la neige autour des b\u00e2timents. De plus, des pi\u00e8ces en bois en style Tetris mais 3D viennent remplir le reste de la grande boite. Le matos est vraiment de bonne qualit\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/8E796CC1-021C-4E66-9FE2-EAA88D17C7DB-1024x768.jpeg\" alt=\"\" class=\"wp-image-42053\" width=\"399\" height=\"532\"\/><\/figure><\/div>\n\n\n\n<p>Il y a 9 formes de\npi\u00e8ce diff\u00e9rentes. Chaque pi\u00e8ce reprend au moins 1 cube de chaque couleur des\njoueurs. Et 2 cubes d\u2019un seul joueur, d\u2019o\u00f9 4 pi\u00e8ces par polyomino.&nbsp;<\/p>\n\n\n\n<p>Une pile de cartes\nreprend toutes les formes, plusieurs fois d\u2019ailleurs, et sert \u00e0 d\u00e9terminer les\npi\u00e8ces disponibles au joueur dont c\u2019est le tour. Normalement, ces cartes donne\nun choix de 3 formes mais il arrive d\u2019en avoir que deux, voire (si pas de bol)\nune seule.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Je joue<\/h4>\n\n\n\n<p>Au d\u00e9but de son tour,\non a 2 cartes visible, indiquant les pi\u00e8ces disponibles, et on en pioche une\nqu\u2019on ajoute aux 2 autres. Ce qui peut \u00e9largir \u00e0 trois les pi\u00e8ces disponibles.\nOn choisit donc une des pi\u00e8ces repr\u00e9sent\u00e9es par les cartes et on la place sur\nun des 3 b\u00e2timents en respectant bien \u00e9videmment les r\u00e8gles de placement: il ne\nfaut pas \u00ab d\u00e9passer \u00bb des cases grises (le pourtour), interdit de glisser sous\nune autre pi\u00e8ce d\u00e9j\u00e0 plac\u00e9e et pas plus de 3 \u00e9tages.<\/p>\n\n\n\n<p>On compte ensuite ses\npoints qui sont le nombre de cube \u00e0 votre couleur sur la pi\u00e8ce que l\u2019on place\net des cubes adjacents, toujours \u00e0 votre couleur. C\u2019est une mani\u00e8re de marquer\ndes points mais pas la principale car il n\u2019est pas toujours facile de coller\nses cubes \u00e0 d\u2019autres \u00e0 cause du bloquage de vos adversaires.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Un peu d\u2019aide<\/h4>\n\n\n\n<p>Une partie de Nouvelle\nFrance se d\u00e9compose en 3 manches, avec un d\u00e9compte en fin de chacune d\u2019elle.\nChaque joueur d\u00e9marre la partie avec trois pi\u00e8ces de sa couleur (une de 3 cubes\nalign\u00e9s, une de 2 cubes et une petite d\u2019un seul cube). Au lieu de piocher une\ncarte afin de placer une pi\u00e8ce expos\u00e9e, vous pouvez placer une de ces trois\npi\u00e8ces. La plus grande avant le premier d\u00e9compte, la seconde avant le deuxi\u00e8me\nd\u00e9compte et la derni\u00e8re avant le dernier d\u00e9compte. Si une pi\u00e8ce n\u2019est pas\nutilis\u00e9e \u00e0 temps, elle est perdue. Ce n\u2019est pas trop grave pour la derni\u00e8re, le\nplus petite, mais l\u2019impact est nettement plus important pour la grande qu\u2019il\nfaudra bien planifier \u00e0 placer avant l\u2019arriv\u00e9e de la premi\u00e8re temp\u00eate de neige.<\/p>\n\n\n\n<p>En plus de ces trois pi\u00e8ces, chaque joueur re\u00e7oit \u00e9galement 3 jetons: la Fille du Roy, le coureur des bois et la Premi\u00e8re Nation. Chacun peut \u00eatre utilis\u00e9 \u00e0 son tour, une fois par manche, et permet de doubler un score, de prendre la 1\/2 du score d\u2019un adversaire ou de prendre les 3 premi\u00e8res cartes de la pioche et les \u00ab trier \u00bb comme bon vous semble.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/8D9CFB3F-C22A-4C97-9A5F-5FD3A35AF142-1024x768.jpeg\" alt=\"\" class=\"wp-image-42055\" width=\"738\" height=\"984\"\/><\/figure><\/div>\n\n\n\n<p>Ces trois tuiles nous\naide donc mais s\u2019annulent en quelque sorte puisque chacun a les m\u00eames. Ce que\nje veux dire c\u2019est que le premier qui utilise le x2 prendra une avance\ntemporaire et se fera sans doute rejoindre lorsque le suivant l\u2019utilisera \u00e0 son\ntour.<\/p>\n\n\n\n<p>L\u2019arriv\u00e9e de la neige\nest repr\u00e9sent\u00e9 par des forme en mousse blanche qui viennent entourer les\nstructures des 3 b\u00e2timents. J\u2019admet que \u00e7a en jette! Chaque couche de neige\nrend les cubes de m\u00eame niveau \u00ab obsol\u00e8tes \u00bb. Plus question d\u00e8s lors d\u2019en tenir\ncompte lors des d\u00e9comptes futurs ou le du scoring en cours de manche.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Et \u00e7a donne quoi?<\/h4>\n\n\n\n<p>Et bien, Nouvelle France est agr\u00e9able \u00e0 jouer avec un th\u00e8me bien respect\u00e9. La mousse qui repr\u00e9sente la neige est du plus bel effet! On pourra regretter un peu le manque de \u00ab crescendo \u00bb et peut-\u00eatre un peu d\u2019asym\u00e9trie \u00e0 d\u00e9velopper en cours de partie? Les manches peuvent parfois \u00eatre assez \u00ab st\u00e9r\u00e9otyp\u00e9es\u00bb: on vise souvent le b\u00e2timent qui rapportera le plus \u00e0 la fin de la manche. C\u2019est le sel principal du jeu: d\u2019abord on vise \u00e0 optimaliser son coup pour le prochain d\u00e9compte, puis on vise \u00e0 emp\u00eacher les adversaires d\u2019en faire autant.<\/p>\n\n\n\n<p>Reste \u00e0 voir avec\nl\u2019\u00e9diteur, Jackbro, si cette belle bo\u00eete est disponible par chez nous \ud83d\ude09<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/BBD6EC72-3C16-413B-99EF-506C33F19BFA-1024x768.jpeg\" alt=\"\" class=\"wp-image-42054\" width=\"932\" height=\"1243\"\/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par Philrey<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Nouvelle France (Explication des r\u00e8gles et d\u00e9gustation du jeu)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gQW8GzlExBc?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Nouvelle France est un jeu qui nous vient du Qu\u00e9bec. Je ne suis d\u2019ailleurs pas certain qu\u2019on pourra le trouver facilement de ce c\u00f4t\u00e9 de l\u2019Atlantique. Le matos Nouvelle France vient dans une grosse bo\u00eete, m\u00eame s\u2019il n\u2019y a pas une tonne de matos. Mais il faut bien&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":42050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[6],"class_list":["post-42051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-philrey212","annee-2884","auteurs-jacques-dominique-landry","editeurs-jackbro","illustrateurs-jacques-dominique-landry","nombre_conseille-1210","nombre_conseille-1355"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/42051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=42051"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/42051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/42050"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=42051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=42051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=42051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}