{"id":43750,"date":"2021-08-28T13:01:23","date_gmt":"2021-08-28T11:01:23","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=43750"},"modified":"2021-08-28T13:01:58","modified_gmt":"2021-08-28T11:01:58","slug":"so-clover","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/08\/28\/so-clover\/","title":{"rendered":"So Clover"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover-.jpg\" alt=\"\" class=\"wp-image-43751\" width=\"501\" height=\"501\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover-.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover--150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover--300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover--768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover--160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover--245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/so-clover--340x340.jpg 340w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/07\/Swa-47-150x150.jpg\" alt=\"\" class=\"wp-image-43324\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">9\/10<\/span><\/h5>\n\n\n\n<p>Je vais pas vous dire que So Clover est <strong>le jeu de l\u2019\u00e9t\u00e9<\/strong> puisque l\u2019\u00e9t\u00e9 est d\u00e9j\u00e0 pass\u00e9 mais il l\u2019\u00e9tait pour nous.&nbsp; Autant <strong><a href=\"https:\/\/www.vindjeu.eu\/2020\/07\/22\/top-ten\/\">Top Ten&nbsp;<\/a><\/strong> l\u2019\u00e9tait l\u2019ann\u00e9e pass\u00e9e, autant So Clover le fut cette ann\u00e9e&nbsp;!&nbsp; Autant <strong><a href=\"https:\/\/www.youtube.com\/watch?v=3r9vJI5OiV8\">La Kiffance<\/a><\/strong> \u00e9tait la chanson de l\u2019\u00e9t\u00e9, autant So Clover \u00e9tait le jeu de l\u2019\u00e9t\u00e9&nbsp;&#x1f609;<\/p>\n\n\n\n<p>Il faut dire aussi que <strong>l\u2019\u00e9quipe<\/strong> qui est derri\u00e8re le jeu a pas mal d\u2019exp\u00e9rience en la mati\u00e8re de jeux d\u2019ambiance puisque <strong><a href=\"https:\/\/www.vindjeu.eu\/editeurs\/repos-production\/\">Repos Production<\/a><\/strong> a d\u00e9j\u00e0 r\u00e9alis\u00e9 des petites p\u00e9pites comme <strong>Just One<\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/2014\/01\/23\/concept\/\">Concept<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/2017\/11\/17\/when-i-dream-vf\/\">When I dream<\/a><\/strong> et bien s\u00fbr, l\u2019\u00e9ternel <strong><a href=\"https:\/\/www.vindjeu.eu\/2011\/08\/22\/times-up\/\">Time\u2019s Up<\/a><\/strong>&nbsp;!<\/p>\n\n\n\n<p>Pourtant, So Clover se base sur la m\u00e9canique <strong>d\u2019association de mots<\/strong> qui ne vont pas n\u00e9cessairement ensemble comme on le rencontre encore assez souvent dans les jeux actuels comme <strong><a href=\"https:\/\/www.vindjeu.eu\/2021\/03\/18\/mot-malin\/\">Mot Malin<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/2020\/03\/27\/association-10-des\/\">Association 10 d\u00e9s<\/a><\/strong> ou le pl\u00e9biscit\u00e9 <strong><a href=\"https:\/\/www.vindjeu.eu\/2016\/07\/13\/codenames-vf\/\">Codenames<\/a><\/strong>.&nbsp; Mais ici, le twist est un peu diff\u00e9rent et marche du tonnerre.&nbsp; Les joueurs vont recevoir 4 cartes et vont les placer al\u00e9atoirement sur leur tr\u00e8fle.&nbsp; Ce placement va g\u00e9n\u00e9rer <strong>4 associations de 2 mots<\/strong>.&nbsp; Les joueurs vont alors devoir <strong>trouver un mot g\u00e9n\u00e9rique<\/strong> correspondant \u00e0 chacune des 4 associations.&nbsp; Et comme l\u2019objectif est de faire deviner les mots qui ont g\u00e9n\u00e9r\u00e9 les 4 mots g\u00e9n\u00e9riques (et donc le bon placement des 4 cartes), les joueurs vont devoir bien <strong>faire attention \u00e0 tous les mots<\/strong> inscrits sur chaque carte pour que rien ne pr\u00eate \u00e0 confusion, ou le moins possible.&nbsp; Car en effet, vous avez d\u00e9j\u00e0 devin\u00e9 que \u00e7a n\u2019allait pas \u00eatre toujours facile.&nbsp; Certaines associations sont <strong>simples<\/strong> et d\u2019autres vraiment <strong>difficiles<\/strong>.&nbsp; Je vous laisse imaginer ce que vous indiqueriez pour l\u2019association suivante&nbsp;: \u00ab&nbsp;chirurgien \u2013 toupie&nbsp;\u00bb&nbsp;&#x1f609;&nbsp; &nbsp;De plus, les joueurs vont faire face au choix de trouver un mot qui convient \u00e0 <strong>chacun des 2 mots<\/strong> ou un mot qui convient <strong>\u00e0 l\u2019association des 2 mots<\/strong>.&nbsp; Par exemple, pour Voiture et Maison vous pourriez dire \u00ab&nbsp;garage&nbsp;\u00bb qui correspond \u00e0 l\u2019association des 2 mots alors que vous auriez pu dire \u00ab&nbsp;porte&nbsp;\u00bb qui correspond \u00e0 chacun d\u2019entre eux pris s\u00e9par\u00e9ment.&nbsp; L\u2019approche est proche&nbsp;&#x1f609; mais diff\u00e9rente.&nbsp; Tout d\u00e9pendra des autres mots inscrits sur vos cartes et de votre imagination\u2026<\/p>\n\n\n\n<p><strong>L\u2019objectif<\/strong> est de trouver, ensemble, la disposition de toutes les cartes de chaque joueuse.&nbsp; Et \u00e7a donne une <strong>chouette collaboration<\/strong> o\u00f9 on va discuter sur l\u2019interpr\u00e9tation de chaque mot ensemble avant de se d\u00e9cider sur une proposition.&nbsp; Et m\u00eame si <strong>l\u2019ambiance<\/strong> est plut\u00f4t <strong>soft<\/strong> autour du jeu (on n\u2019est pas dans du fr\u00e9n\u00e9tique \u00e0 la <strong><a href=\"https:\/\/www.vindjeu.eu\/2011\/08\/22\/times-up\/\">Time\u2019s Up<\/a><\/strong>&nbsp;&#x1f609; ), quand on a fini une partie, on va vouloir remettre \u00e7a tant le jeu est <strong>addictif<\/strong>, il encourage <strong>l\u2019imagination<\/strong> sans \u00eatre trop exigeant, est <strong>facile<\/strong> et <strong>super fun<\/strong>&nbsp;!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1613\" height=\"1210\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8.jpg\" alt=\"\" class=\"wp-image-43827\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8.jpg 1613w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/2925-So-Clover-8-453x340.jpg 453w\" sizes=\"auto, (max-width: 1613px) 100vw, 1613px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Vin d&rsquo;jeu d&rsquo;music<\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Naps - La kiffance (Clip Officiel)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/3r9vJI5OiV8?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Je vais pas vous dire que So Clover est le jeu de l\u2019\u00e9t\u00e9 puisque l\u2019\u00e9t\u00e9 est d\u00e9j\u00e0 pass\u00e9 mais il l\u2019\u00e9tait pour nous.&nbsp; Autant Top Ten&nbsp; l\u2019\u00e9tait l\u2019ann\u00e9e pass\u00e9e, autant So Clover le fut cette ann\u00e9e&nbsp;!&nbsp; Autant La Kiffance \u00e9tait la chanson de l\u2019\u00e9t\u00e9, autant So Clover \u00e9tait&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":43751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-43750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-2884","auteurs-francois-romain","editeurs-repos-production","distributeurs-asmodee","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","nombre_conseille-1321","mecanismes-cooperatif","mecanismes-devinettes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/43750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=43750"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/43750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/43751"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=43750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=43750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=43750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}