{"id":43800,"date":"2021-09-01T09:40:53","date_gmt":"2021-09-01T07:40:53","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=43800"},"modified":"2021-09-01T09:40:15","modified_gmt":"2021-09-01T07:40:15","slug":"glory-un-jeu-de-chevaliers","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/09\/01\/glory-un-jeu-de-chevaliers\/","title":{"rendered":"Glory &#8211; Un Jeu de Chevaliers"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers.jpg\" alt=\"\" class=\"wp-image-43801\" width=\"534\" height=\"534\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-340x340.jpg 340w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/Ren-15-150x150.jpg\" alt=\"\" class=\"wp-image-43787\"\/><\/figure><\/div>\n\n\n\n<p><strong><span style=\"color:#0693e3\" class=\"color\">Ren<\/span><\/strong>: <strong><span style=\"color:#cf2e2e\" class=\"color\">9\/10<\/span><\/strong><\/p>\n\n\n\n<p>\u00ab\u00a0Pur\u00e9e tu as vu ce truc?\u00a0\u00bb<\/p>\n\n\n\n<p>\u00a0\u00bb Ouais j&rsquo;ai vu, il y a au moins je ne sais pas combien de cartes et de jetons\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Et puis tu as vu les blasons et les chevaliers?!\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Et il y a des d\u00e9s aussi, des noirs, des blancs et des rouges!\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Et puis on va se battre pour l&rsquo;honneur, pour les gentes dames, pour la gloire!\u00a0\u00bb<\/p>\n\n\n\n<p>C&rsquo;\u00e9tait en ces termes qu&rsquo;on avait d\u00e9couvert le jeu lors de notre escapade (bi-) annuelle d&rsquo;Essen 2019.  On avait \u00e9t\u00e9 tout moubourr\u00e9 par le jeu \u00e0 l&rsquo;\u00e9poque et c&rsquo;est avec une grande joie qu&rsquo;on apprend que <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/super-meeple\/\"><strong>Super Meeple<\/strong><\/a> (<a href=\"https:\/\/www.vindjeu.eu\/2021\/04\/22\/la-baie-des-marchands\/\"><strong>La Baie des Marchands<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2021\/02\/12\/trickerion-legende-de-lillusion\/\"><strong>Trickerion<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2020\/06\/26\/endeavor-lage-de-la-voile\/\"><strong>Endeavor<\/strong><\/a>,&#8230;) vient de publier le jeu enti\u00e8rement en Fran\u00e7ais.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3784-e1629457426456-1024x768.jpg\" alt=\"\" class=\"wp-image-32454\" width=\"351\" height=\"262\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3784-e1629457426456-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3784-e1629457426456-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3784-e1629457426456-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3784-e1629457426456-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3784-e1629457426456-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3784-e1629457426456-453x340.jpg 453w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/figure><\/div>\n\n\n\n<p>Glory Un Jeu de Chevaliers est un jeu de joutes m\u00e9di\u00e9vales. Vous avez lu mon introduction, c&rsquo;est \u00e0 peu pr\u00e8s exactement ce qui m&rsquo;est arriv\u00e9: tu d\u00e9ambules d&rsquo;abord n\u00e9gligemment devant le stand, puis tu te dis \u00ab\u00a0tiens pas mal, c&rsquo;est toujours sympa de jouer au chevalier\u00a0\u00bb, ensuite on passe \u00e0 \u00ab\u00a0pur\u00e9e il y a un sacr\u00e9 matos\u00a0\u00bb puis \u00e0 \u00ab\u00a0waouw les illustrations ont l&rsquo;air canon dans leur genre!\u00a0\u00bb (moyen-\u00e2ge un peu sombre et chevaliers ombrageux). <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Montjoie Saint-Denis!<\/h3>\n\n\n\n<p>Joutes m\u00e9di\u00e9vales donc, mais encore? <strong>Dans Glory vous allez incarner un chevalier qui aura pour objectif de se couvrir de gloire en participant aux tournois<\/strong> (et en y r\u00e9coltant des victoires si possible \u00e9videmment). Le jeu propose deux modes: soit vous ne jouez que des tournois \u00ab\u00a0amicaux\u00a0\u00bb, dans 3 villes europ\u00e9ennes. Dans ce cas les joueuses et joueurs ne vont pas s&rsquo;affronter. Soit vous jouez en mode \u00a0\u00bb frontal\u00a0\u00bb, dans ce cas toutes les joueuses et joueurs vont s&rsquo;inscrire dans les m\u00eames tournois, et potentiellement s&rsquo;affronter. Tout le charme r\u00e9side \u00e9videmment dans cette 2\u00e8me option :-). Que nous allons voir plus en d\u00e9tail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3 tournois<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3782-150x150.jpg\" alt=\"\" class=\"wp-image-32449\" width=\"252\" height=\"252\"\/><figcaption>Le tableau d&rsquo;honneur&#8230;<\/figcaption><\/figure><\/div>\n\n\n\n<p>Le jeu se d\u00e9roule en 3 tours. A chaque tour l&rsquo;objectif sera de se pr\u00e9parer au mieux pour participer au tournoi (il y a donc 3 tournois), ou alternativement pour r\u00e9aliser des qu\u00eates (si vous perdez un duel pendant le tournoi, et \u00eates \u00e9limin\u00e9s). A chaque tour il y aura 5 phases, plus 2 phases apr\u00e8s le tournoi final.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Phase 1: Actions<\/h3>\n\n\n\n<p>Dans la premi\u00e8re phase les joueuses vont placer leurs pions (de jolis petits chevaliers) sur les diff\u00e9rentes cases d&rsquo;actions du plateau central. Certaines actions ne peuvent \u00eatre faites qu&rsquo;une fois par phase, d&rsquo;autres autant qu&rsquo;on le souhaite. Celles qu&rsquo;on ne peut faire qu&rsquo;une seule fois \u00e9tant \u00e9videmment plus int\u00e9ressantes, il y aura donc de la comp\u00e9tition dans l&rsquo;air&#8230; Les actions possibles sont:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S&rsquo;entra\u00eener avec un chevalier: donne 3 marqueurs de force (cfr plus bas pour l&rsquo;utilit\u00e9 de tous les avantages) &#8211; action unique<\/li><li>S&rsquo;entra\u00eener seul (entra\u00eenement \u00ab\u00a0ennuyeux\u00a0\u00bb dixit les r\u00e8gles, il y a plein de petites touches d&rsquo;humour comme \u00e7a): donne 2 marqueurs de force<\/li><li>S&rsquo;inscrire dans l\u00a0\u00bbarm\u00e9e: donne 3 pi\u00e8ces &#8211; action unique<\/li><li>Travailler pour le roi ou des nobles: rapporte 2 pi\u00e8ces<\/li><li>Prier: rapporte 3 marqueurs de foi &#8211; action unique<\/li><li>Prendre 2 cartes de qu\u00eates (il y a des qu\u00eates romantiques, des qu\u00eates financi\u00e8res, et des qu\u00eates guerri\u00e8res)<\/li><li>Acheter une meilleure armure ou une monture plus puissante<\/li><li>Recruter un supporter<\/li><li>Prendre l&rsquo;initiative (=prendre la 1\u00e8re place pour l&rsquo;ordre du tour suivant, o\u00f9 la 2\u00e8me si la 1\u00e8re est d\u00e9j\u00e0 prise&#8230;). L&rsquo;initiative \u00e9tant le facteur d\u00e9cisif en cas d\u00a0\u00bb\u00e9galit\u00e9 entre 2 chevaliers au combat&#8230;<\/li><li>S&rsquo;inscrire au tournoi (on peut aussi le faire \u00e0 la 4\u00e8me phase, l&rsquo;avantage ici \u00e9tant de pouvoir choisir en 1er qui on va affronter)<\/li><li>Prendre une carte de titre (on en tire 3 et on en garde 1)<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3785-e1629457898231-1024x768.jpg\" alt=\"\" class=\"wp-image-32457\" width=\"842\" height=\"631\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3785-e1629457898231-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3785-e1629457898231-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3785-e1629457898231-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3785-e1629457898231-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3785-e1629457898231-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3785-e1629457898231-453x340.jpg 453w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/figure><\/div>\n\n\n\n<p>Les joueuses vont donc jouer leurs 6 actions via un placement d&rsquo;ouvriers tout ce qu&rsquo;il y a de plus classique (mais tr\u00e8s bien foutu).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3788-e1573427667443-225x300.jpg\" alt=\"\" class=\"wp-image-32452\" width=\"304\" height=\"405\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3788-e1573427667443-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3788-e1573427667443-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3788-e1573427667443-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3788-e1573427667443-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3788-e1573427667443-255x340.jpg 255w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/><figcaption>Cette gente dame vous donnera 2 points de gloire<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Phase 2 Qu\u00eates<\/h3>\n\n\n\n<p>Les joueuses qui ont choisi des cartes qu\u00eates (dans la premi\u00e8re phase ou lors de tours pr\u00e9c\u00e9dents) vont pouvoir <strong>r\u00e9aliser jusqu&rsquo;\u00e0 3 qu\u00eates<\/strong>. Les qu\u00eates romantiques vous donnent des ressources imm\u00e9diatement (argent, marqueurs de foi, reliques&#8230;). Les qu\u00eates financi\u00e8res vous permettent d&rsquo;acheter des ressources. Enfin les qu\u00eates guerri\u00e8res vous permettent de faire un duel contre un chevalier selon les r\u00e8gles classiques d&rsquo;un tournoi (cfr point 4 ci-dessous) et de gagner le cas \u00e9ch\u00e9ant des points de gloire (=points de victoire) ou des reliques, ou des supporters, ou de l&rsquo;argent&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Phase 3 Refresh<\/h3>\n\n\n\n<p>Lors de cette phase on change l&rsquo;ordre des joueuses si certaines avaient choisi de prendre l&rsquo;initiative. On r\u00e9cup\u00e8re tous ses supporters ou reliques utilis\u00e9es lors des phases ou tours pr\u00e9c\u00e9dents (y compris juste avant lors des qu\u00eates). On change les cartes qu\u00eates, on met de nouveaux supporters. Et chaque joueuse re\u00e7oit son revenu (argent, marqueurs de force et marqueurs de foi)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Phase 4 S&rsquo;inscrire \u00e0 un tournoi<\/h3>\n\n\n\n<p>Si pas fait lors de la phase 1, les joueuses vont s&rsquo;inscrire au tournoi. Le tournoi est un tableau de 8, avec des chevaliers pr\u00e9-tir\u00e9s (c&rsquo;est-\u00e0-dire plac\u00e9s a d\u00e9but de chaque tour). Quand une joueuse choisit ou se placer, elle peut donc choisir de se mettre contre un chevalier neutre, contre une autre joueuse (si il y en a une qui s&rsquo;est d\u00e9j\u00e0 plac\u00e9e) ou contre un adversaire \u00e0 venir. Une fois que toutes les joueuses se sont plac\u00e9es on compl\u00e8te le tableau avec des chevaliers neutres.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Phase 5 Duels<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3783-e1573427788629-225x300.jpg\" alt=\"\" class=\"wp-image-32451\" width=\"321\" height=\"428\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3783-e1573427788629-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3783-e1573427788629-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3783-e1573427788629-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3783-e1573427788629-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3783-e1573427788629-255x340.jpg 255w\" sizes=\"auto, (max-width: 321px) 100vw, 321px\" \/><figcaption>Cette monture de niveau 4 vous sera bien utile pour bastonner<\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>Enfin on y est!La baston! Wou\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9!<\/strong> Tout le monde s&rsquo;est longuement pr\u00e9par\u00e9 pour une seule chose: le tournoi. Va falloir assurer&#8230; On va donc jouer tous les duels du tournoi. Le principe d&rsquo;un duel est simple sur papier: <strong>le chevalier qui a la plus grande valeur d&rsquo;attaque gagne<\/strong>. Si il y a \u00e9galit\u00e9 c&rsquo;est le chevalier qui a le plus de prestige. Et si il y a toujours \u00e9galit\u00e9 (possible uniquement entre 2 joueuses, pas contre un chevalier neutre), c&rsquo;est la position sur la piste d&rsquo;initiative qui d\u00e9termine la gagnante.<\/p>\n\n\n\n<p>Pour conna\u00eetre sa force d&rsquo;attaque on va lancer des d\u00e9s. Oui, une bonne vieille palanqu\u00e9e de d\u00e9s. Mais on va pouvoir solidement influencer, limiter, contr\u00f4ler le hasard li\u00e9 \u00e0 ces satan\u00e9s d\u00e9s. Le nombre de d\u00e9s \u00e0 disposition d\u00e9pendra de 3 choses: son armure, sa monture, et le nombre de marqueurs de force qu&rsquo;on d\u00e9cidera de jouer au d\u00e9but d&rsquo;un duel. Les armures donneront les d\u00e9s blancs, les montures les noirs, et les marqueurs les rouges. On jettera \u00e0 chaque round tous ses d\u00e9s, puis on gardera le meilleur dans chaque couleur. On a donc d&rsquo;office des d\u00e9s blanc et noirs (car on d\u00e9marre la partie avec une armure et une monture) mais pas automatiquement des d\u00e9s rouges. Plus son armure et\/ou sa monture seront puissantes, plus on recevra des d\u00e9s. Maximum 3, sachant que si on a l&rsquo;armure ou la monture la plus puissante une face de du d\u00e9 qui vaut normalement 0 donnera d&rsquo;office le r\u00e9sultat maximum du d\u00e9 de cette couleur (les d\u00e9s noirs sont plus puissants que les blancs, logique: sur un cheval vous \u00eates plus puissant que la pi\u00e9taille en b\u00eate armure). M\u00eame syst\u00e8me pour les d\u00e9s rouges, plus vous avez d\u00e9pens\u00e9 de marqueurs de force, plus vous aurez de d\u00e9s (3 max aussi, avec le r\u00e9sultat maximum donn\u00e9 par une des faces qui vaut normalement 0 si vous avez pay\u00e9 le nombre maximum de marqueurs de force) Sachant que les d\u00e9s rouges sont les plus puissants de tous (l&rsquo;entra\u00eenement, i n&rsquo;y a que \u00e7a de vrai!).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3787-e1573427893953-225x300.jpg\" alt=\"\" class=\"wp-image-32450\" width=\"332\" height=\"442\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3787-e1573427893953-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3787-e1573427893953-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3787-e1573427893953-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3787-e1573427893953-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3787-e1573427893953-255x340.jpg 255w\" sizes=\"auto, (max-width: 332px) 100vw, 332px\" \/><figcaption>Si vous perdez pendant le tournoi vous pourrez toujours d\u00e9fier ce chevalier lors d&rsquo;une qu\u00eate, pour quand m\u00eame gagner 3 points de gloire et 1 de prestige<\/figcaption><\/figure><\/div>\n\n\n\n<p>Mais ce n&rsquo;est pas tout. Avant de comparer les valeurs respectives, chaque joueuse (ou la joueuse toute seule si elle combat un chevalier neutre) aura l&rsquo;occasion d&rsquo;utiliser tout ce qu&rsquo;elle a durement acquis lors des 2 premi\u00e8res phases. Dans un ordre bien pr\u00e9cis elle aura l&rsquo;occasion de jouer un marqueur de foi pour relancer 2 d\u00e9s. Elle aura l&rsquo;occasion de faire appel \u00e0 des supporters recrut\u00e9s, qui vont l&rsquo;aider \u00e0 essayer de gagner (transformer un d\u00e9 en sa valeur maximale, relancer, donner +1 en force&#8230;). Elle pourra utiliser des reliques gagn\u00e9es pr\u00e9c\u00e9demment (ayant des effets similaires \u00e0 ceux des supporters). Sachant que l&rsquo;a joueuse ayant la valeur la plus basse en initiative doit toujours actionner les diff\u00e9rentes possibilit\u00e9s (qu&rsquo;on actionne une par une, dans l&rsquo;ordre) avant l&rsquo;autre. C&rsquo;est le 2\u00e8me avantage donn\u00e9 par une initative plus haute. Une fois tout cela fait on compare les valeurs d&rsquo;attaque et la joueuse ayant la plus haute gagne le round. La premi\u00e8re ayant gagn\u00e9 deux rounds gagne le combat. La gagnante se qualifie pour le combat suivant (3 combats maximum donc, puisque c&rsquo;est un tableau de 8) et gagner des points de gloire. La perdante gagne quand m\u00eame des points de gloire si elle a gagn\u00e9 1 round. Et elle peut r\u00e9aliser autant de qu\u00eates (si elle en a en main bien s\u00fbr) que de tours restants dans le tournoi (donc 2 si elle est \u00e9limin\u00e9e au premier combat, et 1 si elle est \u00e9limin\u00e9e au 2\u00e8me combat).<\/p>\n\n\n\n<p>Ensuite on r\u00e9sout tous les combats jusqu&rsquo;\u00e0 d\u00e9terminer le vainquer final du tournoi (qui gagne un point de gloire suppl\u00e9mentaire et une pi\u00e8ce).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tout droit!<\/h3>\n\n\n\n<p>On r\u00e9alise 3 tournois, et apr\u00e8s le 3\u00e8me on r\u00e9alise 2 dernbi\u00e8res phases: une phase additionnelle de qu\u00eates (cfr la phase 2 plus haut), et une phase de r\u00e9solution de titres. Les titres sont obtenus en r\u00e9alisant certaines conditions (avoir les 4 reliques, avoir r\u00e9alis\u00e9 x qu\u00eates de tel type&#8230;) et permettent d&rsquo;obtenir des points de gloire. Et la joueuse avec le plus de points de gloire l&#8217;emporte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sans peur et sans reproche!<\/h3>\n\n\n\n<p><strong>Tout \u00e7a nous donne un jeu dont je serais tr\u00e8s \u00e9tonn\u00e9 qu&rsquo;il ne cartonne pas! <\/strong>La partie placement d&rsquo;ouvrier, pour classique qu&rsquo;elle soit, est tr\u00e8s bien \u00e9x\u00e9cut\u00e9e comme d\u00e9j\u00e0 dit plus haut. Le syst\u00e8me de combat tourne parfaitement. Et si il y a bien un soup\u00e7on de chance (puisqu&rsquo;il y a des d\u00e9s), les multiples mani\u00e8res de l&rsquo;att\u00e9nuer ou de la contr\u00f4ler rendent cela parfaitement supportable. Voire carr\u00e9ment souhaitable, puisque ce sera la petite partie d&rsquo;incontr\u00f4lable qui rendra certains combats m\u00e9morables, et permettra \u00e0 certaines de chouiner pendant de longues minutes apr\u00e8s une partie perdue \u00e0 cause de ces maudits d\u00e9s! Le mat\u00e9riel est top avec des tas d&rsquo;objets (reliques, points de prestige, marqueurs de force et de foi), de cartes (qu\u00eates, titres, armures, montures), de d\u00e9s, avec des blasons magnifiques (qui sont les vrais blasons de vrais chevaliers).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3786-e1573428017478-225x300.jpg\" alt=\"\" class=\"wp-image-32459\" width=\"343\" height=\"457\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3786-e1573428017478-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3786-e1573428017478-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3786-e1573428017478-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3786-e1573428017478-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/IMG_3786-e1573428017478-255x340.jpg 255w\" sizes=\"auto, (max-width: 343px) 100vw, 343px\" \/><figcaption>Un magnifique blason de chevalier neutre<\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>Il y a une vraie mont\u00e9e d&rsquo;adr\u00e9naline chaque fois qu&rsquo;on pr\u00e9pare un tournoi, puis lors des combats<\/strong> (qui se gagnent pour rappel en 2 rounds) o\u00f9 on ne peut pas se contenter de taper comme un bourrin, puisqu&rsquo;il faut utiliser \u00e0 bon escient les diff\u00e9rentes aides dont on dispose, pour essayer d&rsquo;aller au bout du tournoi. Donc il y a un peu de strat\u00e9gie, ou \u00e0 tout le moins de planification. Et clairement plusieurs mani\u00e8res d&rsquo;arriver \u00e0 gagner des tournois: je peux tout faire pour avoir une grosse monture et une grosse armure (et donc avoir plus de d\u00e9s) mais je peux aussi recruter plein de supporters, faire des qu\u00eates, obtenir des reliques&#8230; bref il y a plein de choses diff\u00e9rentes \u00e0 faire dans le jeu. Et toutes ces choses sont parfaitement coh\u00e9rentes par rapport au th\u00e8me: vous allez vous entra\u00eener avec un chevalier exp\u00e9riment\u00e9, et bien c&rsquo;est plus efficace que tout seul&#8230; Vous allez prier, et bien Dieu sera avec vous (et vous pourrez donc relancer des d\u00e9s). Vous achetez une monture plus puissante, et bien vous serez plus fort le long de la lice&#8230; tout \u00e7a aide \u00e0 \u00eatre plong\u00e9 dans le th\u00e8me et \u00e0 s&rsquo;y croire. Dernier point \u00e0 relever: la joueuse qui perd un combat n&rsquo;est pas du tout \u00e9limin\u00e9e du jeu, et ne perd pas toutes ses chances de gagner le jeu. Je trouve \u00e7a extr\u00eamement bien pens\u00e9: on s&rsquo;\u00e9clate \u00e0 battre une adversaire dans un combat (c&rsquo;est toujours jouissif de \u00ab\u00a0battre\u00a0\u00bb l&rsquo;autre), mais on ne fout pas la partie de l&rsquo;autre en l&rsquo;air. Donc l&rsquo;interaction directe (et indirecte dans la partie placement d&rsquo;ouvriers) est \u00e9norme, mais sans le d\u00e9faut \u00ab\u00a0d&rsquo;\u00e9limination\u00a0\u00bb. Tr\u00e8s tr\u00e8s bien vu!<\/p>\n\n\n\n<p>Il faut clairement aimer le th\u00e8me, mais une chose est s\u00fbre: c&rsquo;est du bon! J&rsquo;ai mis 9 car je n&rsquo;ai jou\u00e9 qu&rsquo;une partie. Mais sur la partie que j&rsquo;ai jou\u00e9e, je me suis \u00e9clat\u00e9! Et je compte bien rejouer!<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1.jpg\" alt=\"\" class=\"wp-image-43803\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/glory-un-jeu-de-chevaliers-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Vin d&rsquo;jeu d&rsquo;vid\u00e9os<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">La d\u00e9gustation en 20 minutes par Ren<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Glory: A Game of Knights (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/jcOnj51nGJE?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">La bouteille de Chaps en 1 heure<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"[Proto-KS] Glory a game of knights : Explication et analyse du jeu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/z_0eIVpOVO8?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> \u00ab\u00a0Pur\u00e9e tu as vu ce truc?\u00a0\u00bb \u00a0\u00bb Ouais j&rsquo;ai vu, il y a au moins je ne sais pas combien de cartes et de jetons\u00a0\u00bb \u00ab\u00a0Et puis tu as vu les blasons et les chevaliers?!\u00a0\u00bb \u00ab\u00a0Et il y a des d\u00e9s aussi, des noirs, des blancs et des&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":43801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[],"class_list":["post-43800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","annee-2884","auteurs-dominik-mucha","auteurs-marcin-wisthal","editeurs-super-meeple","illustrateurs-jarek-nocon","illustrateurs-tymoteusz-chliszcz","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-collection","mecanismes-combat","mecanismes-jets-de-des","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/43800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=43800"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/43800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/43801"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=43800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=43800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=43800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}