{"id":44129,"date":"2021-10-03T12:02:45","date_gmt":"2021-10-03T10:02:45","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=44129"},"modified":"2021-10-03T12:02:50","modified_gmt":"2021-10-03T10:02:50","slug":"eriantys","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/10\/03\/eriantys\/","title":{"rendered":"Eriantys"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-1.jpg\" alt=\"\" class=\"wp-image-44130\" width=\"524\" height=\"525\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-1.jpg 599w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-1-339x340.jpg 339w\" sizes=\"auto, (max-width: 524px) 100vw, 524px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/08\/Swa-49.1-150x150.jpg\" alt=\"\" class=\"wp-image-43782\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:<span style=\"color:#cf2e2e\" class=\"color\"> 8\/10<\/span><\/h5>\n\n\n\n<p>Aux c\u00f4t\u00e9s de l&rsquo;excellent <a href=\"https:\/\/www.vindjeu.eu\/2021\/08\/18\/golem\/\"><strong>Golem<\/strong><\/a>, Eriantys sera la seconde sortie, pour Essen, de <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/cranio-creation\/\"><strong>Cranio Creations<\/strong><\/a>.<\/p>\n\n\n\n<p>Eryantis, qui a \u00e9t\u00e9 r\u00e9alis\u00e9 par l&rsquo;auteur l\u00e9gendaire <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/leo-colovini\/\"><strong>Leo Colovini<\/strong><\/a>, n&rsquo;est rien d&rsquo;autre qu&rsquo;une nouvelle version de son non moins l\u00e9gendaire <a href=\"https:\/\/www.vindjeu.eu\/2010\/05\/16\/carolus-magnus\/\"><strong>Carolus Magnus<\/strong><\/a>.<\/p>\n\n\n\n<p>M\u00eame si les similitudes entre les 2 jeux sont nombreuses, Eriantys apporte pas mal de changements \u00e0 son pr\u00e9d\u00e9cesseur pour en faire un jeu <strong>plus moderne<\/strong> et plus nerveux.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Majorit\u00e9s<\/span><\/h2>\n\n\n\n<p>Il s&rsquo;agit d&rsquo;un jeu de majorit\u00e9s extr\u00eamement bien foutu o\u00f9 <strong>chaque action sera un choix difficile<\/strong>.  A chaque tour, vous gagnerez des \u00e9tudiants repr\u00e9sent\u00e9s par des jetons de diff\u00e9rentes couleurs.  A chaque tour vous allez devoir placer 4 de ces jetons, soit sur votre <strong>plateau personnel<\/strong>, soit sur <strong>une des \u00eeles<\/strong> du plateau.  L&rsquo;id\u00e9al sera de les placer sur votre plateau personnel car plus vous en aurez dans chacune des 5 couleurs, plus vous pourrez gagner les majorit\u00e9s de chacune d&rsquo;entre elles.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-2-1024x660.jpg\" alt=\"\" class=\"wp-image-44139\" width=\"613\" height=\"395\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-2-1024x660.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-2-300x193.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-2-768x495.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-2-160x103.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-2-380x245.jpg 380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-2-527x340.jpg 527w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><\/figure><\/div>\n\n\n\n<p>Mais malheureusement ce n&rsquo;est pas si simple car vous devez \u00e9galement prendre <strong>les majorit\u00e9s sur les \u00eeles<\/strong> en y pla\u00e7ant des \u00e9tudiants des couleurs o\u00f9 vous d\u00e9tenez les majorit\u00e9s.  Evidemment, plus vous placerez des \u00e9tudiants sur les \u00eeles, plus vous pourrez en prendre le contr\u00f4le mais plus<strong> vous vous d\u00e9forcerez<\/strong> pour pouvoir garder ces majorit\u00e9s&#8230;  Vous allez \u00eatre constamment balanc\u00e9 entre la volont\u00e9 de renforcer vos majorit\u00e9s, de prendre des majorit\u00e9s \u00e0 vos adversaires et de prendre le contr\u00f4le des \u00eeles.  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"414\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7-1024x414.jpg\" alt=\"\" class=\"wp-image-44141\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7-1024x414.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7-300x121.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7-768x311.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7-160x65.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7-520x210.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7-720x291.jpg 720w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-7.jpg 1845w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Interaction<\/span><\/h2>\n\n\n\n<p>Evidemment, qui dit majorit\u00e9, dit interaction et celle-ci est <strong>forte <\/strong>dans Eriantys.  Il y aura constamment des <strong>combats <\/strong>entre joueuses pour <strong>gagner ou reprendre des majorit\u00e9s<\/strong>.  Et m\u00eame si le jeu est tr\u00e8s simple et familial, il peut \u00eatre <strong>m\u00e9chant <\/strong>car c&rsquo;est pas chouette de se voir prendre une majorit\u00e9 \ud83d\ude09<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4-1024x809.jpg\" alt=\"\" class=\"wp-image-44140\" width=\"530\" height=\"419\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4-1024x809.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4-300x237.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4-768x607.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4-160x126.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4-310x245.jpg 310w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4-430x340.jpg 430w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-4.jpg 1527w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Carolus melius<\/span><\/h2>\n\n\n\n<p>Eriantys apporte pas mal de changements \u00e0 Carolus Magnus. Tout d&rsquo;abord, il y a <strong>moins de tout<\/strong>: moins d&rsquo;\u00eeles, mois d&rsquo;\u00e9tudiants, moins de tours,&#8230; Tout \u00e7a va rendre le jeu <strong>plus nerveux<\/strong> et moins longuet. Il garde n\u00e9anmoins son effet <strong>win to win<\/strong> mais comme le jeu est plus ramass\u00e9, c&rsquo;est moins un calvaire puisque le jeu se termine rapidement apr\u00e8s qu&rsquo;un joueur ait pris le dessus.<\/p>\n\n\n\n<p>Les 5 jetons d&rsquo;initiative ont \u00e9t\u00e9 remplac\u00e9s par <strong>10 cartes<\/strong> qui vont \u00e9galement rythmer la parties puisque quand on n&rsquo;a plus de carte en main, c&rsquo;est que les 10 tours du jeu sont pass\u00e9s et que c&rsquo;est la fin du jeu. La mani\u00e8re de <strong>r\u00e9cup\u00e9rer des \u00e9tudiants<\/strong> a elle aussi \u00e9t\u00e9 bien am\u00e9lior\u00e9e. Au lieu que ce soit des d\u00e9s qui les d\u00e9terminent, vous choisirez vos \u00e9tudiants parmi des <strong>pr\u00e9sentoirs <\/strong>comme dans <a href=\"https:\/\/www.vindjeu.eu\/2018\/01\/08\/azul\/\"><strong>Azul<\/strong><\/a>. Et ce nouveau syst\u00e8me, m\u00eal\u00e9 aux nouvelles cartes va rendre <strong>l&rsquo;ordre du tour<\/strong> encore plus important accentuant d&rsquo;autant plus la difficult\u00e9 de vos choix.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5-1024x499.jpg\" alt=\"\" class=\"wp-image-44142\" width=\"768\" height=\"374\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5-1024x499.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5-300x146.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5-768x374.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5-160x78.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5-503x245.jpg 503w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5-698x340.jpg 698w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-5.jpg 2000w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>Enfin, Eriantys propose une variante qui me fait un peu penser \u00e0 <a href=\"https:\/\/www.vindjeu.eu\/2018\/07\/16\/santorini\/\"><strong>Santorini <\/strong><\/a>avec <strong>3 cartes pouvoir<\/strong> tir\u00e9es au hasard parmi 12 \u00e0 chaque partie et que les joueuses pourront actionner en payant quelques pi\u00e8ces qu&rsquo;elles auront gagn\u00e9es en accumulant les \u00e9tudiantes sur leur plateau. Ces cartes pouvoir vont permettre <strong>des<\/strong> <strong>actions sp\u00e9ciales<\/strong> qui vont casser le rythme un peu trop conventionnel du jeu sans elles. C&rsquo;est clairement un tr\u00e8s chouette ajout qui va augmenter consid\u00e9rablement le fun et la variabilit\u00e9 de vos parties.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"327\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6-1024x327.jpg\" alt=\"\" class=\"wp-image-44143\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6-1024x327.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6-300x96.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6-768x245.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6-160x51.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6-520x166.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6-720x230.jpg 720w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-6.jpg 1947w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Carolus bonus<\/span><\/h2>\n\n\n\n<p>Eriantys est un Carolus Magnus <strong>am\u00e9lior\u00e9<\/strong>. Il reste un jeu <strong>simple<\/strong> de majorit\u00e9, tr\u00e8s abstrait malgr\u00e9 son nouveau th\u00e8me, tr\u00e8s froid m\u00eame si son interaction est tr\u00e8s forte. Mais le jeu a \u00e9t\u00e9 consid\u00e9rablement am\u00e9lior\u00e9 gr\u00e2ce \u00e0 des menus changements le rendant plus nerveux, am\u00e9liorant la <strong>difficult\u00e9 de ses choix<\/strong> et, surtout, apportant cette <strong>petite touche fofolle<\/strong> avec les cartes pouvoir qui donnent au jeu une toute autre dimension.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"3277\" height=\"1907\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9.jpg\" alt=\"\" class=\"wp-image-44131\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9.jpg 3277w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9-300x175.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9-768x447.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9-1024x596.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9-160x93.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9-421x245.jpg 421w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/2942-Eriantys-9-584x340.jpg 584w\" sizes=\"auto, (max-width: 3277px) 100vw, 3277px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles et la partie en Fran\u00e7ais avec l&rsquo;\u00e9diteur du jeu<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"We play Eriantys with Vin d&#039;Jeu!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/1k3knXJw68k?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Aux c\u00f4t\u00e9s de l&rsquo;excellent Golem, Eriantys sera la seconde sortie, pour Essen, de Cranio Creations. Eryantis, qui a \u00e9t\u00e9 r\u00e9alis\u00e9 par l&rsquo;auteur l\u00e9gendaire Leo Colovini, n&rsquo;est rien d&rsquo;autre qu&rsquo;une nouvelle version de son non moins l\u00e9gendaire Carolus Magnus. M\u00eame si les similitudes entre les 2 jeux sont nombreuses,&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":44130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-44129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-2884","auteurs-leo-colovini","editeurs-cranio-creation","illustrateurs-alessandro-costa","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-asymetrie","mecanismes-majorite"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/44129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=44129"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/44129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/44130"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=44129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=44129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=44129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}