{"id":44288,"date":"2021-10-04T13:44:42","date_gmt":"2021-10-04T11:44:42","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=44288"},"modified":"2021-10-30T18:25:45","modified_gmt":"2021-10-30T16:25:45","slug":"kung-fur-fight","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/10\/04\/kung-fur-fight\/","title":{"rendered":"Kung Fur Fight"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783.jpeg\" alt=\"\" class=\"wp-image-44289\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783.jpeg 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783-150x150.jpeg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783-300x300.jpeg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783-768x768.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783-160x160.jpeg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783-245x245.jpeg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/f37900644353ec6c79a5a7781227d57571ff364284aefc0af963bfdd9783-340x340.jpeg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/05\/FM-printemps.jpg\" alt=\"\" class=\"wp-image-42468\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple : <\/span><span style=\"color:#cf2e2e\" class=\"color\">8\/10<\/span><\/h5>\n\n\n\n<p>Ha la sempiternelle division entre les adorateurs de chiens\net ceux qui pr\u00e9f\u00e8rent les chats&nbsp;! <strong>King\nFur Fight<\/strong> va aider \u00e0 trancher ce d\u00e9bat en proposant une solution&nbsp;: le\ncombat&nbsp;! Il faut choisir son camp&nbsp;: les Chiens Shaolins ou les Chats\nNinjas. L\u00e0, premier probl\u00e8me de taille car dans la famille Meeple nous faisons\ntous partie du camp des adorateurs des chats. Il a fallu que j\u2019incarne les\nChiens Shaolins car aucun enfant Meeple n\u2019a voulu c\u00e9der.<\/p>\n\n\n\n<p>Revenons-en \u00e0 notre affrontement. <strong>Kung Fur Fight<\/strong> se joue \u00e0 2 uniquement jusqu\u2019\u00e0 ce que mort s\u2019en\nsuive. Bon d\u2019accord, pas jusqu\u2019\u00e0 la mort de l\u2019adversaire mais la partie\ns\u2019arr\u00eate si l\u2019un des clans est KO ou s\u2019il y a une diff\u00e9rence de plus de 4\npoints de victoire.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"289\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011-300x289.jpg\" alt=\"\" class=\"wp-image-44296\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011-300x289.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011-768x740.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011-1024x987.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011-160x154.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011-254x245.jpg 254w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011-353x340.jpg 353w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7011.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>La pr\u00e9paration de l\u2019\u00e9quipe<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009-300x200.jpg\" alt=\"\" class=\"wp-image-44290\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7009.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010-300x200.jpg\" alt=\"\" class=\"wp-image-44291\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7010.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Chaque joueur prend les cartes associ\u00e9es \u00e0 son clan. Le jeu\nest hautement asym\u00e9trique, il va falloir exploiter au mieux les capacit\u00e9s de ces\nquadrup\u00e8des. Les chats sont aid\u00e9s par des jetons Raihuu et Kuna\u00efs et les chiens\npar les jetons Hua. Ces renforts permettent d\u2019augmenter la force d\u2019attaque de 1\nou 2. <br>\nIl y a trois combats qui se d\u00e9roulent dans une piste Ar\u00e8ne. \u00c0\nd\u00e9but de chaque manche, on dispose au hasard une carte sur chacun espace de\nlutte. Chaque duel gagn\u00e9 offre un point de victoire et la ou les cartes pos\u00e9es\nsur le ring. &nbsp;&nbsp;Les cartes ainsi r\u00e9cup\u00e9r\u00e9es offrent de\npr\u00e9cieux atouts en fonction de leur type&nbsp;: les Rangers sont des animaux\nqui se rallient \u00e0 votre cause et vous apportent leurs comp\u00e9tences lors des\ncombats, les cartes Nourriture permettent de r\u00e9cup\u00e9rer des forces, et les\ncartes Technique permettent d\u2019am\u00e9liorer vos assauts. Au fur et \u00e0 mesure le <em>deck<\/em> de d\u00e9part s\u2019am\u00e9liore et se\nrenforce. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>L\u2019attaque<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008-300x200.jpg\" alt=\"\" class=\"wp-image-44292\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/IMG_7008.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nIl\nfaut planifier ses attaques sur les trois rings en restant bien cach\u00e9 derri\u00e8re\nson paravent. Une carte peut \u00eatre jou\u00e9e pour sa valeur inscrite en haut \u00e0\ngauche, ou pour son h\u00e9ros et dans ce cas il faut aussi appliquer l\u2019effet\ninscrit. Au d\u00e9but de la partie on ne peut jouer que trois cartes. Plus on se\nrapproche du KO plus on peut jouer de cartes, cette augmentation est un peu\ncomme une faveur \u00e0 un mourant&nbsp;! <br>\nSi on d\u00e9cide de mettre le paquet sur une ar\u00e8ne en jouant deux cartes, il faudra\ns\u2019abstenir sur une autre\u2026 \u00c0\nl\u2019issue de chaque combat, les cartes jou\u00e9es sont d\u00e9fauss\u00e9es alors une strat\u00e9gie\ns\u2019impose&nbsp;: mettre les cartes les plus fortes d\u00e8s le d\u00e9but ou tenir dans la\ndur\u00e9e&nbsp;? Pas simple comme choix, surtout lorsque l\u2019on ne conna\u00eet pas la\ntactique de l\u2019adversaire, une petite dose de bluff peut \u00eatre utile. Les cartes\nd\u00e9fauss\u00e9es peuvent \u00eatre r\u00e9cup\u00e9r\u00e9es \u00e0 l\u2019aide de carte Ar\u00e8ne ou en utilisant l\u2019un\ndes trois jetons Nourriture pr\u00e9sent sur le plateau joueur.<br>\nUn point de r\u00e8gle tr\u00e8s important dans <strong>Kung\nFur Fight<\/strong>&nbsp;: les \u00e9galit\u00e9s ne sont pas d\u00e9partag\u00e9es&nbsp;! La carte reste\nsur l\u2019ar\u00e8ne, il y en aura donc deux au prochain tour. \n\n\n\n<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Chien ou chat&nbsp;?<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"159\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/53122d59cbe95c45b0e25915bad902595f242c4bbb29724b71fae5d5e1fe-300x159.jpeg\" alt=\"\" class=\"wp-image-44293\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/53122d59cbe95c45b0e25915bad902595f242c4bbb29724b71fae5d5e1fe-300x159.jpeg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/53122d59cbe95c45b0e25915bad902595f242c4bbb29724b71fae5d5e1fe-768x408.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/53122d59cbe95c45b0e25915bad902595f242c4bbb29724b71fae5d5e1fe-160x85.jpeg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/53122d59cbe95c45b0e25915bad902595f242c4bbb29724b71fae5d5e1fe-461x245.jpeg 461w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/53122d59cbe95c45b0e25915bad902595f242c4bbb29724b71fae5d5e1fe-640x340.jpeg 640w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/53122d59cbe95c45b0e25915bad902595f242c4bbb29724b71fae5d5e1fe.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"159\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/d2c1ae6ad144352b6104648357e57e22da397fbdfba6b0e5ef1e489f162d-300x159.jpeg\" alt=\"\" class=\"wp-image-44294\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/d2c1ae6ad144352b6104648357e57e22da397fbdfba6b0e5ef1e489f162d-300x159.jpeg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/d2c1ae6ad144352b6104648357e57e22da397fbdfba6b0e5ef1e489f162d-768x408.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/d2c1ae6ad144352b6104648357e57e22da397fbdfba6b0e5ef1e489f162d-160x85.jpeg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/d2c1ae6ad144352b6104648357e57e22da397fbdfba6b0e5ef1e489f162d-461x245.jpeg 461w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/d2c1ae6ad144352b6104648357e57e22da397fbdfba6b0e5ef1e489f162d-640x340.jpeg 640w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/d2c1ae6ad144352b6104648357e57e22da397fbdfba6b0e5ef1e489f162d.jpeg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Je ne vous donnerais pas d\u2019indice sur le clan vainqueur de nos nombreux duels mais la famille Meeple a bien ri lors des parties. La prise en main n\u2019est pas simple au d\u00e9but. Comme beaucoup de jeux asym\u00e9triques, il faut bien conna\u00eetre les cartes et leurs possibilit\u00e9s pour r\u00e9ussir \u00e0 \u00e9laborer une vraie strat\u00e9gie. Il est important de conna\u00eetre les cartes de l\u2019adversaire afin de savoir celles qu\u2019il lui reste en main, les compter est utile. Certaines cartes Ar\u00e8ne n\u00e9cessitent vraiment que l\u2019on se batte pour elles alors que d\u2019autres sont plus secondaires. <br> <strong>Kung Fur Fight<\/strong> rentre dans la cat\u00e9gorie des jeux qui poss\u00e8dent une m\u00e9canique connue et qui reposent sur une valeur s\u00fbre. Il remplit son r\u00f4le de faire passer un agr\u00e9able moment ludique o\u00f9 les cris de \u00ab\u00a0Non tu ne peux pas me faire \u00e7a\u00a0!\u00a0\u00bb r\u00e9sonnent \u2026<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"599\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/6a4759b0ed84e959dc285f219a678e1a6cac6d4597614400987a07e55591.png\" alt=\"\" class=\"wp-image-44295\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/6a4759b0ed84e959dc285f219a678e1a6cac6d4597614400987a07e55591.png 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/6a4759b0ed84e959dc285f219a678e1a6cac6d4597614400987a07e55591-300x200.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/6a4759b0ed84e959dc285f219a678e1a6cac6d4597614400987a07e55591-768x511.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/6a4759b0ed84e959dc285f219a678e1a6cac6d4597614400987a07e55591-160x106.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/6a4759b0ed84e959dc285f219a678e1a6cac6d4597614400987a07e55591-368x245.png 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/09\/6a4759b0ed84e959dc285f219a678e1a6cac6d4597614400987a07e55591-511x340.png 511w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Claire Ha la sempiternelle division entre les adorateurs de chiens et ceux qui pr\u00e9f\u00e8rent les chats&nbsp;! King Fur Fight va aider \u00e0 trancher ce d\u00e9bat en proposant une solution&nbsp;: le combat&nbsp;! Il faut choisir son camp&nbsp;: les Chiens Shaolins ou les Chats Ninjas. L\u00e0,&#46;&#46;&#46;<\/p>\n","protected":false},"author":10,"featured_media":44289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-44288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-2884","auteurs-po-jen-hsieh","auteurs-yunus-hsieh","editeurs-enjoy-thinking-studio","illustrateurs-hurricane","distributeurs-ludistri","nombre_conseille-1185"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/44288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=44288"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/44288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/44289"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=44288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=44288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=44288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}