{"id":45764,"date":"2021-11-22T11:28:29","date_gmt":"2021-11-22T10:28:29","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=45764"},"modified":"2021-11-22T11:32:40","modified_gmt":"2021-11-22T10:32:40","slug":"lost-ruins-of-arnak-expedition-leaders","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/11\/22\/lost-ruins-of-arnak-expedition-leaders\/","title":{"rendered":"Lost Ruins of Arnak: Expedition Leaders"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-1.png\" alt=\"\" class=\"wp-image-45766\" width=\"440\" height=\"604\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-1.png 656w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-1-219x300.png 219w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-1-117x160.png 117w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-1-179x245.png 179w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-1-248x340.png 248w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/2985-Spiel-Essen-21-1-150x150.jpg\" alt=\"Swa\" class=\"wp-image-45249\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:<span style=\"color:#cf2e2e\" class=\"color\"> 9\/10<\/span><\/h5>\n\n\n\n<p>Outre quelques cartes suppl\u00e9mentaires, Expedition Leaders apporte essentiellement 2 modules aux <a href=\"https:\/\/www.vindjeu.eu\/2021\/04\/18\/les-ruines-perdues-de-narak\/\"><strong>Ruines Perdues de Narak<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2021\/09\/22\/vin-djeu-dlannee-2021\/\"><strong>votre Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2021<\/strong><\/a>.<\/p>\n\n\n\n<p>Le premier est un <strong>plateau temple recto verso<\/strong> apportant donc 2 nouveaux temples aux m\u00e9canismes, co\u00fbts, bonus et conditions diff\u00e9rents et plus difficiles que ceux du jeu de base. C&rsquo;est sympa, \u00e7a offre de la vari\u00e9t\u00e9 mais surtout \u00e7a permet de <strong>contrebalancer <\/strong>la puissance du second et principal module de cette extension&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#175518\" class=\"color\">Les leaders<\/span><\/h2>\n\n\n\n<p><strong>6 nouveaux leaders<\/strong> vont venir agr\u00e9menter vos parties. Une leader consiste en un set de cartes action et un plateau personnel sp\u00e9cifique qui va apporter des <strong>capacit\u00e9s sp\u00e9ciales<\/strong> \u00e0 la joueuse la contr\u00f4lant. Le capitaine a un arch\u00e9ologue suppl\u00e9mentaire, la fauconni\u00e8re a un faucon qui va apporter des bonus \u00e0 chaque tour, la baronne n&rsquo;a aucun probl\u00e8me d&rsquo;argent \ud83d\ude09 , le professeur a un attrait particulier pour les art\u00e9facts, l&rsquo;exploratrice n&rsquo;a qu&rsquo;un seul arch\u00e9ologue mais va pouvoir le d\u00e9placer, et le mystique n&rsquo;a jamais peur de la peur \ud83d\ude09<\/p>\n\n\n\n<p>Ces diff\u00e9rents leaders vont changer fondamentalement votre fa\u00e7on de jouer \u00e0 ce petit bijou qu&rsquo;est les <a href=\"https:\/\/www.vindjeu.eu\/2021\/04\/18\/les-ruines-perdues-de-narak\/\"><strong>Ruines Perdues de Narak<\/strong><\/a>. Evidemment, on ne peut s&#8217;emp\u00eacher de penser que l&rsquo;un ou l&rsquo;autre leader est plus puissant qu&rsquo;un autre mais l&rsquo;\u00e9diteur est fort de nombreuses parties par de multiples testeurs sur une plateforme en ligne pour nous assurer d&rsquo;<strong>un \u00e9quilibre parfait<\/strong>. Tout \u00e7a donne \u00e9videmment une <strong>furieuse envie de les jouer tous<\/strong> et de prouver aux autres qu&rsquo;il y a moyen de gagner avec le \u00ab\u00a0soi-disant\u00a0\u00bb plus faible d&rsquo;entre eux \ud83d\ude00<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-3.jpg\" alt=\"\" class=\"wp-image-46054\" width=\"527\" height=\"351\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-3.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 527px) 100vw, 527px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/Ren-16-150x150.jpg\" alt=\"\" class=\"wp-image-45295\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color: #0693e3;\" class=\"color\">Ren<\/span>:<span style=\"color: #cf2e2e;\" class=\"color\"> 9\/10<\/span><\/h5>\n\n\n\n<p>Bon tout est dit ici plus haut, pas besoin d&rsquo;\u00e9piloguer 10 ans. Vous prenez une des merveilles ludiques de ces derni\u00e8res ann\u00e9es. Vous ajoutez <strong>2 nouveaux temples<\/strong> qui permettent d&rsquo;augmenter la vari\u00e9t\u00e9, de renouveler vos parties en vous sortant de vos automatismes, et de corser la difficult\u00e9. Vous pimentez de <strong>nouveaux leaders<\/strong> (ben oui l&rsquo;extension s&rsquo;appelle exp\u00e9dition leaders&#8230;) qui vont <strong>orienter votre strat\u00e9gie<\/strong> mais<strong> sans la forcer<\/strong> absolument. Chaque leader a en effet un pouvoir et un deck de cartes propre qui vont vous pousser \u00e0 maximiser ses forces, mais sans vous obliger absolument \u00e0 ne jouer que dans une seule direction.<\/p>\n\n\n\n<p>Vous m\u00e9langez le tout et vous obtenez une <strong>extension comme je les aime<\/strong>, qui respecte la philosophie du jeu original sans la d\u00e9voyer. Qui am\u00e8ne de la vari\u00e9t\u00e9 et de la nouveaut\u00e9 mais sans bouleverser ou chambouler tout le bastringue. L&rsquo;esprit de Narak est pr\u00e9serv\u00e9, vous allez devoir faire un peu de tout, en optimisant au mieux les encha\u00eenements de bonus pour avancer le plus vite possible dans les entrailles de la for\u00eat ou dans les profondeurs du temple. Gr\u00e2ce \u00e0 cette extension vous allez renouveler vos parties et continuer encore longtemps \u00e0 avoir du bonheur dans les ruines de Narak&#8230; C&rsquo;est ce qu&rsquo;on appelle de la belle ouvrage ludique, impeccable!<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8.jpg\" alt=\"\" class=\"wp-image-45765\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/3001-Ruines-Perdues-Narak-ext-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Outre quelques cartes suppl\u00e9mentaires, Expedition Leaders apporte essentiellement 2 modules aux Ruines Perdues de Narak, votre Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2021. Le premier est un plateau temple recto verso apportant donc 2 nouveaux temples aux m\u00e9canismes, co\u00fbts, bonus et conditions diff\u00e9rents et plus difficiles que ceux du jeu de&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":45766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[323,7],"class_list":["post-45764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-ren","tag-swatsh","annee-2884","auteurs-elwen","auteurs-min","editeurs-czech-games-edition","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-asymetrie-de-depart"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/45764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=45764"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/45764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/45766"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=45764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=45764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=45764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}