{"id":45800,"date":"2021-11-20T13:34:50","date_gmt":"2021-11-20T12:34:50","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=45800"},"modified":"2021-11-20T13:34:52","modified_gmt":"2021-11-20T12:34:52","slug":"rimtik-2","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/11\/20\/rimtik-2\/","title":{"rendered":"Rimtik"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"317\" height=\"320\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/id-bkEZEkCLSyAAAAAAAAMfFQw480h320.jpeg\" alt=\"\" class=\"wp-image-45801\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/id-bkEZEkCLSyAAAAAAAAMfFQw480h320.jpeg 317w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/id-bkEZEkCLSyAAAAAAAAMfFQw480h320-150x150.jpeg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/id-bkEZEkCLSyAAAAAAAAMfFQw480h320-297x300.jpeg 297w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/id-bkEZEkCLSyAAAAAAAAMfFQw480h320-243x245.jpeg 243w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/Claire-Mer-1.jpg\" alt=\"\" class=\"wp-image-45425\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple : <\/span><span style=\"color:#cf2e2e\" class=\"color\">8\/10<\/span><\/h5>\n\n\n\n<p>Une petite cure de jouvence pour <strong>Rimtik<\/strong> qui revient en version lift\u00e9e m\u00eame si les r\u00e8gles n\u2019ont pas pris une ride. Il est \u00e0 noter que<strong> Rimtik<\/strong> est fabriqu\u00e9 en France.<\/p>\n\n\n\n<p> Il s\u2019agit toujours de se d\u00e9barrasser en premier de ses cinq cartes. Dans ce jeu de rapidit\u00e9, il faut rester concentr\u00e9 sur la carte du dessus de la d\u00e9fausse. En effet, c\u2019est cette derni\u00e8re qui va indiquer comment jouer. Si le perroquet est tranquille, il faut poser une carte avec un oiseau de la m\u00eame couleur en \u00e9non\u00e7ant un mot qui rime avec celui prononc\u00e9 en dernier. Par contre si la carte symbolise un ara faisant une grosse f\u00eate, alors il faut dire n\u2019importe quoi comme mot&nbsp;et \u00e9videment poser un perroquet de la m\u00eame couleur !<\/p>\n\n\n\n<p>Cela vous para\u00eet simple&nbsp;? Sachez qu\u2019il n\u2019est pas\ntoujours facile de se concentrer sur la carte et sur les mots prononc\u00e9s. Bien\nentendu, il est interdit de prononcer des mots identiques\u2026 \u00c0\nla moindre faute, la sanction est imm\u00e9diate&nbsp;: on reprend sa carte et on en\npioche une&nbsp;! <\/p>\n\n\n\n<p><strong>Rimtik<\/strong> propose\nune version encore plus fun, en int\u00e9grant les arbres \u00e0 palabres. Ces derniers\nimposent pour la manche une contrainte suppl\u00e9mentaire, comme par exemple les\nmots doivent \u00eatre des objets ou des personnages historiques&nbsp;! Le jeu se\ncomplique d\u2019un coup avec ces arbres.\n\nEn r\u00e9sum\u00e9 <strong>Rimtik<\/strong>\nest un chouette jeu d\u2019ambiance avec des parties rapides o\u00f9 la concentration et\nla rapidit\u00e9 sont les clefs de la victoire. Plus on est nombreux plus il est\namusant. \n\n\n\n<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"354\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/thumbd.php_.jpg\" alt=\"\" class=\"wp-image-45802\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/thumbd.php_.jpg 945w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/thumbd.php_-300x112.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/thumbd.php_-768x288.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/thumbd.php_-160x60.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/thumbd.php_-520x195.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/11\/thumbd.php_-720x270.jpg 720w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Claire Une petite cure de jouvence pour Rimtik qui revient en version lift\u00e9e m\u00eame si les r\u00e8gles n\u2019ont pas pris une ride. Il est \u00e0 noter que Rimtik est fabriqu\u00e9 en France. Il s\u2019agit toujours de se d\u00e9barrasser en premier de ses cinq cartes.&#46;&#46;&#46;<\/p>\n","protected":false},"author":10,"featured_media":45801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-45800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-2884","auteurs-jean-baptiste-fremaux","auteurs-paul-adrien-tournier","auteurs-thomas-luzurier","editeurs-oldchap","illustrateurs-michel-verdu","distributeurs-blackrock-games","nombre_conseille-1355","nombre_conseille-1217","nombre_conseille-1321","mecanismes-jeu-dambiance"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/45800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=45800"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/45800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/45801"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=45800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=45800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=45800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}