{"id":46387,"date":"2021-12-20T09:50:19","date_gmt":"2021-12-20T08:50:19","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=46387"},"modified":"2021-12-20T09:52:08","modified_gmt":"2021-12-20T08:52:08","slug":"maka-bana-15eme-anniversaire","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2021\/12\/20\/maka-bana-15eme-anniversaire\/","title":{"rendered":"Maka Bana (15\u00e8me anniversaire)"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/maka-bana-15eme-anniversaire-p-image-74742-grande-1024x877.jpg\" alt=\"\" class=\"wp-image-46388\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/02\/IMG_33391-150x150.jpg\" alt=\"\" class=\"wp-image-40930\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple : <\/span><span style=\"color:#cf2e2e\" class=\"color\">8.5\/10<\/span><\/h5>\n\n\n\n<p>Avec ce froid signifiant l\u2019arriv\u00e9e de l\u2019hiver, rien de tel\npour se r\u00e9chauffer qu\u2019une partie de <strong>Maka\nBana<\/strong>. Histoire de 60 mn, on est projet\u00e9 sur une \u00eele paradisiaque o\u00f9 la\nseule pr\u00e9occupation est de savoir dans quel endroit implanter sa paillote. <\/p>\n\n\n\n<p>Si ce nom vous dit quelque chose, c\u2019est normal puisqu\u2019il\ns\u2019agit d\u2019une r\u00e9\u00e9dition du titre sorti en 2003. Apr\u00e8s un petit relooking p\u00e9tillant,\nnous voici, des agents immobiliers avides des meilleurs emplacements. Autant le\ndire tout de suite, on ne gagne qu\u2019en \u00e9crasant les autres. Pour l\u2019emporter \u00e0 <strong>Maka Bana<\/strong>, il faut \u00eatre filou, retord\net sans piti\u00e9. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sur la plage abandonn\u00e9e<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0489-300x160.jpg\" alt=\"\" class=\"wp-image-46389\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0489-300x160.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0489-768x410.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0489-1024x547.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0489-160x86.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0489-458x245.jpg 458w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0489-636x340.jpg 636w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"298\" height=\"300\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-298x300.jpg\" alt=\"\" class=\"wp-image-46390\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-298x300.jpg 298w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-768x774.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-1016x1024.jpg 1016w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-243x245.jpg 243w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0492-337x340.jpg 337w\" sizes=\"auto, (max-width: 298px) 100vw, 298px\" \/><figcaption>Exemple de combinaison pour placer cette paillote rose<\/figcaption><\/figure><\/div>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nElle\nne va pas \u00eatre longtemps abandonn\u00e9e cette plage puisqu\u2019\u00e0 chaque tour, les\njoueurs vont essayer de construire une de leur 10 paillotes. En th\u00e9orie c\u2019est\nassez simple mais en pratique, vous pouvez compter sur vos adversaires pour\nvous compliquer la t\u00e2che&nbsp;! <br>\nSur l\u2019\u00eele, les emplacements constructibles sont mat\u00e9rialis\u00e9s par une\ncombinaison unique de 3 \u00e9l\u00e9ments&nbsp;: le nom de la plage, le secteur et le\npaysage. Au d\u00e9but de chaque tour, les joueurs choisissent parmi leurs 15\ncartes, une association de 3 cartes permettant d\u2019identifier l\u2019emplacement sur\nlequel ils veulent construire. Cette programmation est simultan\u00e9e mais secr\u00e8te.\nD\u00e8s que tout le monde a fait son choix, il faut r\u00e9v\u00e9ler une seule carte. L\u00e0, il\nfaut \u00eatre strat\u00e9gique&nbsp;car il faut emp\u00eacher les autres de deviner\nl\u2019emplacement convoit\u00e9. Pourquoi&nbsp;? Car la derni\u00e8re \u00e9tape du jeu consiste \u00e0\nplacer son tiki sur une case du plateau avec pour objectif d\u2019emp\u00eacher toute\naction \u00e0 cet endroit&nbsp;! <br>\nUne fois ces 3 \u00e9tapes r\u00e9alis\u00e9es, on passe \u00e0 la r\u00e9v\u00e9lation des cartes. Si un\nadversaire a plac\u00e9 son tiki sur votre endroit, dommage mais vous ne pouvez pas\nconstruire \u00e0 ce tour. Par contre si personne n\u2019a d\u00e9couvert vos plans, vous\npouvez fi\u00e8rement placer votre paillote. \n\n\n\n<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0491-150x150.jpg\" alt=\"\" class=\"wp-image-46391\"\/><\/figure><\/div>\n\n\n\n<p>Mais ne vous croyez pas tranquille pour autant car il est\npossible pour vos adversaires de venir repeindre votre havre de paix&nbsp;!!!\nCette action, comme celle de construire un club de plong\u00e9e est facilement\nrep\u00e9rable car elle n\u00e9cessite 4 cartes de programmation. Vos adversaires, ayant\nune bonne indication sur vos plans, il va falloir \u00eatre tr\u00e8s tactique lors de la\nr\u00e9v\u00e9lation de la carte qui devra brouiller les pistes. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Coquillages et crustac\u00e9s<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0487-300x225.jpg\" alt=\"\" class=\"wp-image-46392\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0487-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0487-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0487-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0487-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0487-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0487-453x340.jpg 453w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>La fin de partie intervient d\u00e8s qu\u2019une plage est enti\u00e8rement\nconstruite ou lorsqu\u2019un joueur n\u2019a plus qu\u2019une seule paillote en r\u00e9serve. Un\ndernier tour est r\u00e9alis\u00e9 avant de passer au d\u00e9compte des points apport\u00e9s par\nles paillotes en fonction de leur agencement.<\/p>\n\n\n\n<p><strong>Maka Bana<\/strong> est un\njeu que nous avons appr\u00e9ci\u00e9 pour la simplicit\u00e9 de ses r\u00e8gles mais aussi pour la\ntactique qu\u2019il n\u00e9cessite. Un jeu familial accessible \u00e0 tous mais dans lequel il\nfaudra \u00eatre malin pour gagner. L\u2019interaction est tr\u00e8s forte et directe\npuisqu\u2019elle est l\u2019essence m\u00eame du jeu. Ce titre est donc d\u00e9conseill\u00e9 si vous\nn\u2019aimez pas cela. L\u2019objectif premier est bien d\u2019aller pi\u00e9tiner les\nplates-bandes des adversaires pour en tirer profit.<\/p>\n\n\n\n<p>L\u2019\u00e9dition est tr\u00e8s bien pens\u00e9e gr\u00e2ce au syst\u00e8me de plateaux\nmultiples qui rendent le jeu agr\u00e9able quelle que soit le nombre de joueurs. Les\npaillotes et les tikis en 3 dimensions sont agr\u00e9ables \u00e0 manipuler, il ne manque\nplus que le cocktail pour s\u2019y croire vraiment&nbsp;!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"901\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0486-1024x901.jpg\" alt=\"\" class=\"wp-image-46393\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0486-1024x901.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0486-300x264.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0486-768x676.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0486-160x141.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0486-279x245.jpg 279w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/IMG_E0486-387x340.jpg 387w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Claire e Avec ce froid signifiant l\u2019arriv\u00e9e de l\u2019hiver, rien de tel pour se r\u00e9chauffer qu\u2019une partie de Maka Bana. Histoire de 60 mn, on est projet\u00e9 sur une \u00eele paradisiaque o\u00f9 la seule pr\u00e9occupation est de savoir dans quel endroit implanter sa paillote. Si&#46;&#46;&#46;<\/p>\n","protected":false},"author":10,"featured_media":46388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-46387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-2884","auteurs-francois-haffner","editeurs-sweet-november","illustrateurs-david-cochard","illustrateurs-jeremie-fleury","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","nombre_conseille-1321","mecanismes-bluff","mecanismes-deduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/46387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=46387"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/46387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/46388"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=46387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=46387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=46387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}