{"id":46603,"date":"2022-01-22T17:24:53","date_gmt":"2022-01-22T16:24:53","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=46603"},"modified":"2022-01-22T17:30:12","modified_gmt":"2022-01-22T16:30:12","slug":"les-sombres-royaumes-de-valeria-leveil-des-titans","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/01\/22\/les-sombres-royaumes-de-valeria-leveil-des-titans\/","title":{"rendered":"Les Sombres Royaumes de Val\u00e9ria: L&rsquo;Eveil des Titans"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"520\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-1.png\" alt=\"\" class=\"wp-image-46604\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-1.png 400w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-1-231x300.png 231w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-1-123x160.png 123w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-1-188x245.png 188w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-1-262x340.png 262w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/2985-Spiel-Essen-21-57-150x150.jpg\" alt=\"Swa\" class=\"wp-image-45273\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:  <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>L&rsquo;Eveil des Titans est la premi\u00e8re extension des <a href=\"https:\/\/www.vindjeu.eu\/2021\/10\/05\/les-sombres-royaumes-de-valeria\/\"><strong>Sombres Royaumes de Val\u00e9ria<\/strong><\/a>, un jeu qu&rsquo;on aime particuli\u00e8rement bien chez Vin d&rsquo;jeu. Elle se compose de<strong> 4 modules<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5-1024x768.jpg\" alt=\"\" class=\"wp-image-46612\" width=\"512\" height=\"384\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-5.jpg 1210w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#ad7141\" class=\"color\">Sanctuaire des Titans<\/span><\/h2>\n\n\n\n<p>Le Sanctuaire des Titans est un <strong>nouveau lieu d&rsquo;action<\/strong> qu&rsquo;on place au centre du plateau et o\u00f9 on d\u00e9pose un d\u00e9 apr\u00e8s avoir r\u00e9alis\u00e9 un stratag\u00e8me (le d\u00e9 plac\u00e9 est le d\u00e9 de valeur la plus \u00e9lev\u00e9e de ce stratag\u00e8me).  R\u00e9aliser l&rsquo;action du Sanctuaire des Titans consiste \u00e0 <strong>acheter les d\u00e9s<\/strong> qui s&rsquo;y trouvent avec un maximum de 3.  Rien de bien r\u00e9volutionnaire dans cette 7\u00e8me action mais un nouveau choix qui s&rsquo;offre \u00e0 vous, \u00e7a ne se refuse pas \ud83d\ude09<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2-1024x768.jpg\" alt=\"\" class=\"wp-image-46613\" width=\"550\" height=\"413\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-2.jpg 1210w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#ad7141\" class=\"color\">Grandes Batailles<\/span><\/h2>\n\n\n\n<p>Les grandes batailles sont des cartes qu&rsquo;on place \u00e0 c\u00f4t\u00e9 du plateau et qui demandent certains d\u00e9s.  Il y a toujours 2 cartes Grandes Batailles face visible \u00e0 c\u00f4t\u00e9 du plateau.  Apr\u00e8s avoir r\u00e9alis\u00e9 un stratag\u00e8me, vous pouvez <strong>envoyer un des d\u00e9s ayant servi au stratag\u00e8me <\/strong>dans une grande bataille \u00e0 condition que ce d\u00e9 soit bien demand\u00e9 par la bataille.  R\u00e9ussir \u00e0 envoyer ses d\u00e9s sur une grande bataille va permettre de <strong>gagner des petits bonus <\/strong>(ressources, d\u00e9s,&#8230;)<strong> et des points <\/strong>de victoire extras \u00e0 ne pas n\u00e9gliger.  Ces grandes batailles vont complexifier vos choix lorsque vous choisirez un stratag\u00e8me car il sera important de choisir des stratag\u00e8mes qui exigent les m\u00eames types de d\u00e9s que pour les batailles.  Et <strong>avec le Sanctuaire des Titans<\/strong>, ce choix devient encore plus difficile car il faudra compter sur le d\u00e9 parti au sanctuaire (toujours le d\u00e9 de valeur la plus \u00e9lev\u00e9e) pour savoir si vous savez toujours envoyer une troupe \u00e0 la bataille!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3-1024x768.jpg\" alt=\"\" class=\"wp-image-46614\" width=\"537\" height=\"403\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-3.jpg 1613w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#ad7141\" class=\"color\">Sorts Ancestraux<\/span><\/h2>\n\n\n\n<p>Les sorts ancestraux sont des <strong>cartes aux pouvoirs uniques<\/strong> dont 3 sont distribu\u00e9es \u00e0 chaque joueuse en d\u00e9but de partie. Les joueuses pourront d\u00e8s lors <strong>jouer ces 3 cartes<\/strong> en cours de partie pour qu&rsquo;elles apportent un de leurs 2 bonus (augmenter les points de force de vos d\u00e9s, relancer un de ses d\u00e9s pour gagner des ressources, gagner des ressources selon certaines conditions,&#8230;) au meilleur moment. Ces cartes apportent une certaine <strong>planification <\/strong>et de petits choix tactiques suppl\u00e9mentaires mais <strong>il aurait fallu pouvoir en piocher<\/strong> d&rsquo;autres en cours de partie pour que ce module puisse plus fondamentalement changer la physionomie des parties.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#ad7141\" class=\"color\">D\u00e9s Spectre<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4-1024x768.jpg\" alt=\"\" class=\"wp-image-46615\" width=\"501\" height=\"375\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3063-Sombres-Royaumes-eveil-des-titans-4.jpg 1210w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><\/figure><\/div>\n\n\n\n<p>Les d\u00e9s spectre sont des d\u00e9s <strong>joker <\/strong>qui ne prennent aucune place sur votre plateau, qui offrent de grandes r\u00e9ductions mais dont la force est limit\u00e9e \u00e0 3 maximum. C&rsquo;est le prix \u00e0 payer pour autant d&rsquo;avantages.  Eux \u00e9galement vont durcir la difficult\u00e9 de vos choix.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#ad7141\" class=\"color\">4 modules titanesques et ancestraux<\/span><\/h2>\n\n\n\n<p>L&rsquo;Eveil des Titans ne va donc pas changer \u00e9norm\u00e9ment \u00e0 <strong>la physionomie de vos parties<\/strong> des <a href=\"https:\/\/www.vindjeu.eu\/2021\/10\/05\/les-sombres-royaumes-de-valeria\/\"><strong>Sombres Royaumes de Val\u00e9ria<\/strong><\/a> mais va principalement <strong>complexifier ses choix tactiques<\/strong>: quelle action r\u00e9aliser avec le Sanctuaire des Titans comme action suppl\u00e9mentaire, comment bien planifier ses actions avec les bonus des Sorts Ancestraux, quels stratag\u00e8mes r\u00e9aliser pour optimiser l&rsquo;envoi de troupes dans les Grandes Batailles et quel d\u00e9 choisir avec la venue des D\u00e9s Spectres.  Tout cela va rendre <a href=\"https:\/\/www.vindjeu.eu\/2021\/10\/05\/les-sombres-royaumes-de-valeria\/\"><strong>Les Sombres Royaumes de Val\u00e9ria<\/strong><\/a> encore plus indispensable \ud83d\ude42<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-align:center\">Il est \u00e0 noter que cette extension n&rsquo;est actuellement disponible que sur le site de Lucky Duck Games (<a href=\"https:\/\/luckyduckgames.com\/shop\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"lien ici (opens in a new tab)\">lien ici<\/a>).<\/h4>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3-1024x683.jpg\" alt=\"\" class=\"wp-image-46743\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-3.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15.jpg\" alt=\"\" class=\"wp-image-46742\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3076-Sombres-royaumes-valeria-15-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p> L&rsquo;Eveil des Titans est la premi\u00e8re extension des Sombres Royaumes de Val\u00e9ria, un jeu qu&rsquo;on aime particuli\u00e8rement bien chez Vin d&rsquo;jeu. Elle se compose de 4 modules. Sanctuaire des Titans Le Sanctuaire des Titans est un nouveau lieu d&rsquo;action qu&rsquo;on place au centre du plateau et o\u00f9 on&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":46604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-46603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2884","auteurs-stan-kordonskiy","editeurs-lucky-duck-games","illustrateurs-mihajlo-dimitrievski","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","mecanismes-asymetrie-construite","mecanismes-multiples-bonus","mecanismes-objectifs-communs","mecanismes-objectifs-prives"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/46603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=46603"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/46603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/46604"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=46603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=46603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=46603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}