{"id":46703,"date":"2022-01-15T12:40:30","date_gmt":"2022-01-15T11:40:30","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=46703"},"modified":"2022-01-15T15:19:17","modified_gmt":"2022-01-15T14:19:17","slug":"tainted-grail-la-chute-davalon","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/01\/15\/tainted-grail-la-chute-davalon\/","title":{"rendered":"Tainted grail: La Chute d&rsquo;Avalon"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-1.jpg\" alt=\"\" class=\"wp-image-46705\" width=\"555\" height=\"600\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-1.jpg 832w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-1-277x300.jpg 277w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-1-768x831.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-1-148x160.jpg 148w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-1-226x245.jpg 226w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-1-314x340.jpg 314w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/2985-Spiel-Essen-21-48-150x150.jpg\" alt=\"\" class=\"wp-image-45267\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8\/10<\/span><\/h5>\n\n\n\n<p>Tainted Grail est un jeu coop\u00e9ratif et narratif dans un monde ouvert dans la lign\u00e9e du <a href=\"https:\/\/www.vindjeu.eu\/2018\/09\/18\/vin-djeu-dlannee-2018\/\"><strong>Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2018<\/strong><\/a>: <a href=\"https:\/\/www.vindjeu.eu\/2017\/09\/26\/the-7th-continent\/\"><strong>the 7th Continent<\/strong><\/a>.  Les deux jeux sont bien entendu tr\u00e8s diff\u00e9rents et<strong> l&rsquo;aspect narratif est beaucoup plus pouss\u00e9 <\/strong>dans Tainted Grail qui se voit dot\u00e9 d&rsquo;un cahier de narration mais <strong>les sensations des deux jeux sont assez proches<\/strong>.  Tainted grail est <strong>issu d&rsquo;une des campagnes de financement participatif<\/strong> les plus florissantes avec plus de 41.000 contributeurs et 4.900.000$ de r\u00e9colt\u00e9s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#846e1f\" class=\"color\">Le Graal entach\u00e9<\/span><\/h2>\n\n\n\n<p>Dans Tainted Grail chaque joueur va <strong>g\u00e9rer un personnage<\/strong> comme vous et moi qui se retrouve, avec ses comparses, un peu malgr\u00e9 lui, embarqu\u00e9 dans une histoire fantastique qui le d\u00e9passe. Ils vont devoir sortir de leur petit \u00ab\u00a0chez eux\u00a0\u00bb pour d\u00e9couvrir un monde immense, \u00e9pique et parfois dangereux. Il leur faudra s&rsquo;\u00e9quiper, se nourrir et bien soigner leurs blessures physiques et mentales pour s&rsquo;en sortir dans cette aventure sans r\u00e9pit.<\/p>\n\n\n\n<p>Chaque personnage va disposer de <strong>jetons action<\/strong> qui vont leur permettre d&rsquo;interagir avec le monde (ensemble ou s\u00e9par\u00e9s), de voyager, de r\u00e9colter des ressources, de se battre ou d&rsquo;user de diplomatie, de d\u00e9couvrir de nouveaux endroits,&#8230;  <\/p>\n\n\n\n<p>Tainted Grail se joue en <strong>campagne <\/strong>que vous allez devoir r\u00e9ussir en un certain nombre de tours.  Le jeu en comporte 15 et chaque campagne se joue en 3 heures environ.  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2-1024x768.jpg\" alt=\"\" class=\"wp-image-46708\" width=\"768\" height=\"576\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-2.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#846e1f\" class=\"color\">Menhirs<\/span><\/h2>\n\n\n\n<p>Tout le jeu va tourner autour des Menhirs. Un Menhir rend <strong>disponibles \u00e0 l&rsquo;exploration les cartes adjacentes<\/strong>. Mais un Menhir a un compteur interne qui diminue d&rsquo;un cran apr\u00e8s chaque tour et si son cran est \u00e0 0, il disparait de la partie rendant les cartes adjacentes indisponibles. Il vous faudra soit le r\u00e9activer soit en <strong>r\u00e9activer un autre<\/strong> pour garder des cartes disponibles et pouvoir continuer votre exploration. Vous allez comme \u00e7a voyager de Menhir en Menhir en veillant \u00e0 r\u00e9colter toutes les ressources n\u00e9cessaires \u00e0 l&rsquo;activation du prochain. Toute cette gestion des Menhirs et la recherche des ressources associ\u00e9es va <strong>prendre \u00e9norm\u00e9ment de temps<\/strong> dans vos parties et, \u00e0 mon sens, va alourdir inutilement le jeu. L&rsquo;aspect narratif et la g\u00e9niale histoire qui se cache derri\u00e8re ces 15 chapitres est un peu cach\u00e9e par toute cette gestion un peu superflue et peu imbriqu\u00e9e dans le th\u00e8me.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-3.jpg\" alt=\"\" class=\"wp-image-46709\" width=\"578\" height=\"434\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-3.jpg 800w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-3-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-3-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-3-453x340.jpg 453w\" sizes=\"auto, (max-width: 578px) 100vw, 578px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#846e1f\" class=\"color\">Qu\u00eates et t\u00e2ches <\/span><\/h2>\n\n\n\n<p>De nombreux \u00e9l\u00e9ments que vous allez d\u00e9couvrir vous proposeront de r\u00e9aliser des qu\u00eates et des t\u00e2ches.  Il est conseill\u00e9 de r\u00e9aliser ces diff\u00e9rentes qu\u00eates qui vous feront<strong> progresser dans l&rsquo;histoir<\/strong>e mais attention car <strong>\u00e0 trop vous \u00e9garer<\/strong> de votre but primaire, vous risquez de le rater.  C&rsquo;est une des difficult\u00e9s du jeu: pouvoir jauger de la n\u00e9cessit\u00e9 de chaque sous-mission qui vous est confi\u00e9e.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#846e1f\" class=\"color\">Rencontres<\/span><\/h2>\n\n\n\n<p>Vous allez \u00e9galement faire de nombreuses rencontres, certaines belliqueuses et d&rsquo;autres pas.  Il vous faudra<strong> bien vous pr\u00e9par<\/strong>er au combat et ne pas h\u00e9siter \u00e0 les fuir si l&rsquo;issue est trop incertaine car <strong>la mort<\/strong> de votre personnage \u00e9quivaut bien souvent \u00e0 l&rsquo;\u00e9chec de la campagne (sauf si vous jouez \u00e0 un mode plus facile que le mode standard).  J&rsquo;ai trouv\u00e9 les <strong>r\u00e8gles de combat inutilement compliqu\u00e9es<\/strong> bien que, gr\u00e2ce \u00e0 elles, les combats peuvent bien souvent se r\u00e9sumer en un casse-t\u00eate int\u00e9ressant.  De plus, ils impliquent la <strong>gestion de votre deck<\/strong> de cartes combat avec des notions de deckbuilding assez sympathiques.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#846e1f\" class=\"color\">L&rsquo;aventure c&rsquo;est l&rsquo;aventure<\/span><\/h2>\n\n\n\n<p>La grande force de Tainted Grail est <strong>son histoire<\/strong>, et quelle histoire! <strong>Vous allez vite \u00eatre scotch\u00e9<\/strong> \u00e0 elle et voudrez d\u00e9couvrir la suite. Certaines de vos actions vont avoir des <strong>cons\u00e9quences permanentes<\/strong> qui se traduiront par le remplacement de certaines cartes.  Et tout \u00e7a dans une m\u00e9canique de <strong>legacy non destructif<\/strong> vous permettant de rejouer au jeu entier autant de fois que vous le souhaiterez.  Et l&rsquo;histoire est tellement riche qu&rsquo;elle laisse la place \u00e0 plusieurs explorations tant les embranchements sont nombreux et nombreux sont ceux laiss\u00e9s non explor\u00e9s&#8230;  Et m\u00eame si les combats, certaines rencontres diplomatiques et la recherche des ressources n\u00e9cessaires \u00e0 l&rsquo;activation des Menhirs pourront sembler fastidieuses, l&rsquo;ensemble du jeu est scotchant et rel\u00e8ve d&rsquo;une grande maitrise de la narration, de l&rsquo;imagination, de la surprise et du suspense.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"485\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-11-1024x485.jpg\" alt=\"\" class=\"wp-image-46704\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-11-1024x485.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-11-300x142.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-11-768x363.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-11-160x76.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-11-518x245.jpg 518w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3072-Tainted-Grail-11-718x340.jpg 718w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#846e1f\" class=\"color\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"IST IST - It Stops Where It Starts\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Ih85-eFVZi8?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Tainted Grail est un jeu coop\u00e9ratif et narratif dans un monde ouvert dans la lign\u00e9e du Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2018: the 7th Continent. Les deux jeux sont bien entendu tr\u00e8s diff\u00e9rents et l&rsquo;aspect narratif est beaucoup plus pouss\u00e9 dans Tainted Grail qui se voit dot\u00e9 d&rsquo;un cahier de&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":46705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-46703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2884","auteurs-krzysztof-piskorski","auteurs-marcin-swierkot","editeurs-awaken-realms","editeurs-edge-entertainment","distributeurs-asmodee","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","mecanismes-cooperatif","mecanismes-deckbuilding","mecanismes-jets-de-des","mecanismes-narratif"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/46703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=46703"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/46703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/46705"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=46703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=46703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=46703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}