{"id":47237,"date":"2022-02-09T09:06:27","date_gmt":"2022-02-09T08:06:27","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=47237"},"modified":"2022-02-09T09:07:01","modified_gmt":"2022-02-09T08:07:01","slug":"momiji","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/02\/09\/momiji\/","title":{"rendered":"Momiji"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Box-Momiji-600x600.jpg\" alt=\"\" class=\"wp-image-47238\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Box-Momiji-600x600.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Box-Momiji-600x600-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Box-Momiji-600x600-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Box-Momiji-600x600-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Box-Momiji-600x600-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Box-Momiji-600x600-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Claire-hiver.jpg\" alt=\"\" class=\"wp-image-46833\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple : <\/span><span style=\"color:#cf2e2e\" class=\"color\">7.5\/10<\/span><\/h5>\n\n\n\n<p>Les feuilles mortes se ramassent \u00e0 la pelle clamait Jacques\nPr\u00e9vert et il avait bien raison. Dans <strong>Momiji<\/strong>,\nqui signifie \u00ab&nbsp;feuille d\u2019automne&nbsp;\u00bb en Japonais, non seulement vous\nallez les ramassez mais en plus vous allez les collectionner&nbsp;! Il y en a de\n6 diff\u00e9rentes sortes \u00e0 r\u00e9colter.<\/p>\n\n\n\n<p>Avec une main de huit cartes maximum, vous allez pouvoir\nsoit r\u00e9cup\u00e9rer des feuilles dans une rivi\u00e8re soit en poser dans votre\ncollection. Les cartes de la rivi\u00e8re sont class\u00e9es par type. Lors du ramassage\nde feuilles, il est obligatoire de prendre toute la colonne. Si vous en voulez\ntoujours plus, vous pouvez d\u00e9fausser un gland pour rajouter quatre cartes dans\nla rivi\u00e8re. Mais ne soyez pas trop gourmand&nbsp;: huit cartes en main seulement\nsont autoris\u00e9es&nbsp;! Quand vous voulez d\u00e9velopper votre collection vous\npouvez soit poser deux feuilles de la m\u00eame esp\u00e8ce, soit plusieurs d\u2019esp\u00e8ces\ndiff\u00e9rentes. Mais la valeur de la feuille pos\u00e9e doit toujours \u00eatre \u00e9gale ou\nsup\u00e9rieure \u00e0 celle de la feuille du dessous. En d\u00e9pensant des glands, il est\naussi possible d\u2019activer les pouvoirs des trois paysages que l\u2019on poss\u00e8de. Mais\nles glands donnant un point de victoire en fin de partie, leur utilisation doit\n\u00eatre bien r\u00e9fl\u00e9chie pour \u00eatre la plus efficace possible. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"120\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Cartes-300x120.png\" alt=\"\" class=\"wp-image-47239\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Cartes-300x120.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Cartes-768x307.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Cartes-160x64.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Cartes-520x208.png 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Cartes-720x288.png 720w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Cartes.png 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Momiji<\/strong> est un jeu\nde collection familial avec une m\u00e9canique assez traditionnelle. Il change un\npeu sur deux points&nbsp;: <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; les\nobjectifs de majorit\u00e9 de fin de partie ne sont pris en compte que s\u2019ils ont \u00e9t\u00e9\n\u00ab&nbsp;achet\u00e9s&nbsp;\u00bb par un joueur contre trois glands. Si le propri\u00e9taire est\nle majoritaire, il marque dix points mais la majorit\u00e9 peut aussi \u00eatre remport\u00e9e\npar les joueurs adverses&nbsp;qui marquent alors uniquement trois points. Il\nfaut donc bien s\u00fbr de son coup lorsque l\u2019on va chercher des objectifs afin de\nne pas laisser des points aux autres.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; le <em>scoring<\/em> des collections se calcule en\nmultipliant la carte du dessus de la collection par le nombre de cartes qu\u2019elle\ncontient. Comme la plus \u00e9lev\u00e9e est un trois, il va falloir chercher \u00e0 mettre un\nmaximum de cartes de valeur identique \u00e0 l\u2019int\u00e9rieur. Le seul probl\u00e8me c\u2019est que\nvous n\u2019allez pas \u00eatre le seul \u00e0 r\u00e9aliser cette technique.<\/p>\n\n\n\n<p><strong>Momiji<\/strong> est\nparfait pour les joueurs, et m\u00eame les enfants, qui d\u00e9butent avec les jeux de\ncollections. La simplicit\u00e9 des r\u00e8gles et le nombre r\u00e9duit de param\u00e8tres \u00e0\nprendre en compte, rendent l\u2019exp\u00e9rience agr\u00e9able pour des premiers pas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"514\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771-1024x514.jpg\" alt=\"\" class=\"wp-image-47240\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771-1024x514.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771-300x151.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771-768x386.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771-160x80.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771-488x245.jpg 488w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771-677x340.jpg 677w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Materiel-1536x771.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Claire e Les feuilles mortes se ramassent \u00e0 la pelle clamait Jacques Pr\u00e9vert et il avait bien raison. Dans Momiji, qui signifie \u00ab&nbsp;feuille d\u2019automne&nbsp;\u00bb en Japonais, non seulement vous allez les ramassez mais en plus vous allez les collectionner&nbsp;! Il y en a de 6&#46;&#46;&#46;<\/p>\n","protected":false},"author":10,"featured_media":47238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-47237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-3413","auteurs-dario-massarenti","auteurs-francesco-testini","editeurs-sylex","illustrateurs-apolline-etienne","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/47237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=47237"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/47237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/47238"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=47237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=47237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=47237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}