{"id":4736,"date":"2013-03-09T14:40:55","date_gmt":"2013-03-09T13:40:55","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=4736"},"modified":"2013-03-09T14:40:55","modified_gmt":"2013-03-09T13:40:55","slug":"sunrise-city","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2013\/03\/09\/sunrise-city\/","title":{"rendered":"Sunrise City"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-4735\" title=\"536 Sunrise city 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-1.jpg\" alt=\"\" width=\"349\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-1.jpg 499w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-1-299x300.jpg 299w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-1-149x150.jpg 149w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-1-400x400.jpg 400w\" sizes=\"auto, (max-width: 349px) 100vw, 349px\" \/><\/a><\/p>\n<p><span style=\"color: #333399;\"><strong>SwatSh<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 7\/10<\/strong><\/span><\/p>\n<p>Sunrise City est le second jeu de Clever Mojo Games, l&rsquo;\u00e9diteur d&rsquo;<a href=\"http:\/\/www.vindjeu.eu\/2012\/08\/11\/alien-frontiers\/\"><span style=\"color: #0000ff;\">Alien Frontiers<\/span><\/a>.<\/p>\n<p>Ce qui impressionne tout de suite lorsque l&rsquo;on ouvre la boite, c&rsquo;est son mat\u00e9riel somptueux. \u00a0Les tuiles b\u00e2timents sont d&rsquo;une \u00e9paisseur jamais vue, d&rsquo;au moins un demi centim\u00e8tre. \u00a0Les \u00e9toiles en bois sont magnifiques, les pions des joueurs en bois \u00e9pais sont tr\u00e8s agr\u00e9ables \u00e0 jouer, bref, le mat\u00e9riel donne une grande envie d&rsquo;y jouer.<\/p>\n<p>On d\u00e9chante l\u00e9g\u00e8rement par la qualit\u00e9 des illustrations: les b\u00e2timents sont moches et l&rsquo;illustration des terrains tr\u00e8s sommaire et le comble c&rsquo;est que les couleurs sont confondantes et pire encore, les couleurs des terrains ne correspondent pas tout \u00e0 fait \u00e0 la couleur des b\u00e2timents alors que c&rsquo;est l&rsquo;essence m\u00eame du jeu: il faudra placer nos b\u00e2timents de couleur sur un terrain de m\u00eame couleur. \u00a0Tout cela apporte de la confusion dans le jeu alors que justement, ses r\u00e8gles sont simples et les parties devraient \u00eatre assez fluides. \u00a0C&rsquo;est vraiment dommage que ces couleurs soient si proches les unes des autres (bonne chance pour distinguer le bleu du mauve du rouge (voir la photo du bas) et qu&rsquo;elles ne correspondent pas \u00e0 la couleur des b\u00e2timents. \u00a0Ca g\u00e2che un peu le jeu et on pourrait en attendre mieux d&rsquo;un jeu sorti en 2012! \u00a0D&rsquo;autant plus dommage que le reste du mat\u00e9riel est magnifique.<\/p>\n<p>Les r\u00e8gles de Sunrise City sont assez sympas et originales en ces temps de pose d&rsquo;ouvriers, de deckbuilding et de draft de cartes. \u00a0En effet, on commence le jeu par un unique draft de cartes \ud83d\ude00 \u00a0Ceci afin d&rsquo;avoir 3 cartes dont on en jouera une au d\u00e9but de chacune des 3 manches. \u00a0Ces cartes personnage donnent un petit bonus et d\u00e9terminent, par leur num\u00e9ro, l&rsquo;ordre du tour. \u00a0 La fa\u00e7on de gagner est originale et l\u00e9g\u00e8rement chanceuse: Le vainqueur est celui qui obtiendra le plus d&rsquo;\u00e9toile. \u00a0Lorsqu&rsquo;on gagne des PVs, on augmente son curseur sur l&rsquo;\u00e9chelle des PVs du nombre de PVs gagn\u00e9s (jusque l\u00e0 rien d&rsquo;original \ud83d\ude09 ). \u00a0Cette \u00e9chelle va de 1 \u00e0 10. \u00a0Lorsqu&rsquo;on passe 10, on retombe \u00e0 0 pour remonter l&rsquo;\u00e9chelle du nombre restant de PVs gagn\u00e9s. \u00a0A chaque fois qu&rsquo;on retombe \u00e0 0, on gagne une \u00e9toile. \u00a0Mais, si on arrive \u00e0 exactement 10 PVs, on gagne 2 \u00e9toiles. \u00a0Ce n&rsquo;est donc plus une course aux PVs comme d&rsquo;habitude mais une certaine pr\u00e9cision dans les PVs gagn\u00e9s qui d\u00e9cidera du vainqueur&#8230;<\/p>\n<p>Une manche comprend 4 grandes phases:<br \/>\n<strong><span style=\"color: #ff6600;\"> 1) \u00a0Distribution<\/span> <\/strong>al\u00e9atoire de 4 tuiles terrains &amp; 4 tuiles b\u00e2timents \u00e0 chaque joueur et r\u00e9v\u00e9lation de la carte personnage de chaque joueur pour cette manche. \u00a0Le chiffre sur la carte indique l&rsquo;ordre du jeu. \u00a0Le choix de la carte est assez sympa puisqu&rsquo;on va h\u00e9siter entre le bonus de la carte et sa place dans l&rsquo;ordre de jeu sachant qu&rsquo;\u00eatre premier offre un r\u00e9el d\u00e9savantage lors de la phase 3) mais qui est compens\u00e9 par le fait qu&rsquo;on d\u00e9bute la phase 4). \u00a0Evidemment, on ne conna\u00eet pas le chiffre des cartes adverses&#8230;<br \/>\n<strong><span style=\"color: #ff6600;\"> 2) Placement des terrains<\/span>:<\/strong> chacun \u00e0 son tour place un terrain selon certaines r\u00e8gles de construction tr\u00e8s simples: il faut qu&rsquo;au moins un des c\u00f4t\u00e9s du terrain aie un trottoir adjacent \u00e0 un trottoir d&rsquo;un terrain d\u00e9j\u00e0 pos\u00e9. \u00a0On gagne \u00a01 PV par terrain adjacent \u00e0 celui pos\u00e9 de m\u00eame couleur. \u00a0L\u00e0 aussi les choix ne sont pas simples car on va \u00eatre tent\u00e9 de placer des terrains de m\u00eame couleur adjacents les uns des autres afin de gagner des PVs tout en veillant \u00e0 former des doubles terrains compatibles avec les b\u00e2timents qu&rsquo;on devra construire (cfr phase 4)).<br \/>\n<strong><span style=\"color: #ff6600;\"> 3) Ench\u00e8re pour la propri\u00e9t\u00e9 des terrains<\/span>:<\/strong> chacun \u00e0 son tour place un de ses jetons sur un terrain ou sur un jeton adverse. \u00a0Lorsque 2 jetons de m\u00eame couleur sont l&rsquo;un sur l&rsquo;autre, plus personne ne peut poser de jeton sur ce terrain. \u00a0A la fin de cette phase, seuls comptent les jetons en haut des piles de jeton: ces terrains appartiennent au joueur dont le jeton se situe en haut de chaque pile. \u00a0L&rsquo;avantage est donc donn\u00e9 au dernier joueur qui a la possibilit\u00e9 de placer son dernier jeton au dessus des autres.<br \/>\n<strong><span style=\"color: #ff6600;\"> 4) Placement des b\u00e2timents<\/span>:<\/strong> Un b\u00e2timent a la taille de 2 terrains et est s\u00e9par\u00e9 en 2 parties g\u00e9n\u00e9ralement de couleur diff\u00e9rente. \u00a0Pour poser un b\u00e2timent, il faut que les couleurs du b\u00e2timent correspondent aux couleurs des 2 terrains sur lesquels il est pos\u00e9 et qu&rsquo;au moins un des 2 terrains contienne un jeton \u00e0 sa couleur. \u00a0On peut \u00e9galement placer un b\u00e2timent sur un b\u00e2timent existant en formant alors des \u00e9tages et en gagnant des PVs bonus en fonction du nombre d&rsquo;\u00e9tages. \u00a0Cette \u00e9tape est la plus importante car elle permet de gagner de nombreux PVs. \u00a0En effet, chaque b\u00e2timent donne des PVs \u00e0 celui qui l&rsquo;a construit + des PVs aux joueurs \u00e0 qui appartiennent les jetons plac\u00e9s sur les terrains sur lesquels est construit le b\u00e2timent. \u00a0Evidemment, un de ces jetons doit appartenir \u00e0 celui qui a construit le b\u00e2timent, il gagne donc les PVs du b\u00e2timents ainsi qu&rsquo;au minimum un des bonus terrains. \u00a0L&rsquo;ordre du jeu est ici d&rsquo;une extr\u00eame importance puisqu&rsquo;un joueur va pouvoir construire sur un jeton adverse \u00e0 condition que le jeton adjacent lui appartienne. \u00a0On va donc, par ce type d&rsquo;action, an\u00e9antir certains projets adverses rendant le jeu assez chaotique car rien n&rsquo;est pr\u00e9visible. \u00a0Vous avez beau avoir plac\u00e9 vos jetons sur certains terrains, un adversaire peut construire dessus et donc rendre vos propres constructions impossibles. \u00a0Ici, la strat\u00e9gie n&rsquo;est donc pas \u00e0 l&rsquo;honneur mais bien l&rsquo;optimisation de son tour en veillant non pas \u00e0 construire les b\u00e2timents rapportant un max de PVs mais bien \u00e0 construire les b\u00e2timents nous permettant d&rsquo;atteindre pr\u00e9cis\u00e9ment les 10 PVs apportant 2 \u00e9toiles comme expliqu\u00e9 plus haut.<\/p>\n<p>En conclusion, Sunrise City est un jeu au mat\u00e9riel fabuleux rendant le jeu tr\u00e8s agr\u00e9able malgr\u00e9 des illustrations de pi\u00e8tre qualit\u00e9 assombrissant la jouabilit\u00e9. \u00a0Les choix sont nombreux et pas toujours faciles et la construction des b\u00e2timents est originale bien qu&rsquo;assez impr\u00e9visible rendant le jeu tr\u00e8s tactique. \u00a0Le hasard dans le pioche n&rsquo;est pas du tout d\u00e9rangeant ni d\u00e9terminant pour la victoire.<\/p>\n<p><span style=\"color: #333399;\"><strong>Philrey212<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 7\/10<\/strong><\/span><\/p>\n<p>Ma curiosit\u00e9 pour Sunrise City \u00e9tait principalement pour le mat\u00e9riel. En effet, les tuiles de b\u00e2timent en carton sont tr\u00e8s \u00e9paisses (4 \u00e0 5 mm). Comme le jeu semble se d\u00e9velopper en hauteur, l&rsquo;effet doit \u00eatre g\u00e9nial avec de grosse tuiles comme \u00e7a.<\/p>\n<p>Et bien, je ne fut pas d\u00e9\u00e7u du mat\u00e9riel. Il est simplement de premi\u00e8re qualit\u00e9. Les jeton, les tuiles, les pions, tout est magnifique. Sauf, les couleurs. En effet, et c&rsquo;est un peu dommage, les couleurs sur les cartes terrain ne correspondent pas vraiment aux couleurs des tuiles b\u00e2timent. Que s&rsquo;est-il pass\u00e9 \u00e0 l&rsquo;impression?<\/p>\n<p>Quand au jeu, et bien il est\u00a0sympathique. Dommage que la construction ne se passe pas plus en hauteur! En effet, on marque plus de points on pla\u00e7ant ses b\u00e2timents au premier \u00e9tage, directement sur les terrains. On placera donc d&rsquo;abord l\u00e0 o\u00f9 on peut, sur ses jetons, puis, ceux qui nous restent, aux \u00e9tages sup\u00e9rieurs.<\/p>\n<p>Malgr\u00e9 une certaine \u00ab\u00a0routine\u00a0\u00bb dans les tours, pas trop heureusement car une partie ne se joue qu&rsquo;en trois manches, Sunrise City reste agr\u00e9able \u00e0 joueur.<\/p>\n<p><strong><\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4734\" title=\"536 Sunrise city 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-2-1024x768.jpg\" alt=\"\" width=\"819\" height=\"614\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4733\" title=\"536 Sunrise city 3\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-3.jpg\" alt=\"\" width=\"500\" height=\"355\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-3.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-3-300x213.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-3-150x106.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2012\/12\/536-Sunrise-city-3-400x284.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Sunrise City est le second jeu de Clever Mojo Games, l&rsquo;\u00e9diteur d&rsquo;Alien Frontiers. Ce qui impressionne tout de suite lorsque l&rsquo;on ouvre la boite, c&rsquo;est son mat\u00e9riel somptueux. \u00a0Les tuiles b\u00e2timents sont d&rsquo;une \u00e9paisseur jamais vue, d&rsquo;au moins un demi centim\u00e8tre. \u00a0Les \u00e9toiles en bois sont magnifiques, les&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":4735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[6,7],"class_list":["post-4736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-philrey212","tag-swatsh","annee-464","auteurs-isaias-vallejo","editeurs-clever-mojo-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/4736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=4736"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/4736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/4735"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=4736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=4736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=4736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}