{"id":4788,"date":"2013-03-27T22:21:36","date_gmt":"2013-03-27T21:21:36","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=4788"},"modified":"2013-05-29T21:59:42","modified_gmt":"2013-05-29T20:59:42","slug":"les-dames-de-troyes","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2013\/03\/27\/les-dames-de-troyes\/","title":{"rendered":"Les Dames de Troyes"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-4790\" style=\"margin-left: 5px; margin-right: 5px;\" title=\"543 Dames de Troyes 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-1.jpg\" alt=\"\" width=\"286\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-1.jpg 358w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-1-214x300.jpg 214w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-1-107x150.jpg 107w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><\/a><\/p>\n<p><span style=\"color: #333399;\"><strong>SwatSh<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 8,5\/10<\/strong><\/span><\/p>\n<p>Les Dames de Troyes, c&rsquo;est avant tout, une extension pour\u00a0<a href=\"http:\/\/www.vindjeu.eu\/2012\/03\/19\/troyes\/\"><span style=\"color: #0000ff;\">Troyes<\/span><\/a>! \u00a0Qui l&rsquo;eut cru? \u00a0\ud83d\ude09<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2012\/03\/19\/troyes\/\"><span style=\"color: #0000ff;\">Troyes<\/span><\/a> \u00e9tant un jeu magnifique et complet, je dois avouer que j&rsquo;\u00e9tais assez septique \u00e0 la sortie de cette extension. \u00a0Qu&rsquo;allait-elle apporter de plus \u00e0 un jeu aussi complet et \u00e9quilibr\u00e9? \u00a0N&rsquo;ajoutera-t-elle pas une complexit\u00e9 suppl\u00e9mentaire et inutile?<\/p>\n<p>Et bien la r\u00e9ponse s&rsquo;est vite fait ressentir: la baffe! \u00a0Oui, les Dames de Troyes apportent un r\u00e9el plus insoup\u00e7onn\u00e9 au jeu!<\/p>\n<p>Outre des cartes suppl\u00e9mentaires \u00e0 tous les niveaux apportant une encore plus grande vari\u00e9t\u00e9 au jeu, les Dames de Troyes apportent 2 nouvelles options int\u00e9ressantes:<br \/>\n<span style=\"color: #ff00ff;\"><strong>1) Les remparts<\/strong><\/span><br \/>\nIl existe maintenant une action suppl\u00e9mentaire que l&rsquo;on peut ex\u00e9cuter avec nos d\u00e9s: faire bouger le meeple de notre couleur le long des remparts de la ville. \u00a0Le long de la ronde, aux 4 portes de Troyes, sont ajout\u00e9s 4 petits plateaux. \u00a0Ces plateaux offrent un bonus non n\u00e9gligeable tel que: 4 points d&rsquo;influence \u00e0 chaque fois que vous placez un meeple dans un b\u00e2timent, contrer gratuitement l&rsquo;effet d&rsquo;une carte envahisseur ou annuler un d\u00e9 noir, relancer un d\u00e9 ou gagner des PVs. \u00a0Lorsque vous utilisez un d\u00e9 pour d\u00e9placer votre meeple, vous le faites avancer d&rsquo;un nombre de cases \u00e9gal ou inf\u00e9rieur \u00e0 la valeur du d\u00e9. \u00a0Les points du d\u00e9 non consomm\u00e9s servent \u00e0 placer des cubes de votre couleur sur ces plateaux annexes bonus \u00e0 condition que votre meeple ait d\u00e9j\u00e0 atteint la porte de Troyes s&rsquo;ouvrant sur ce plateau bonus. \u00a0A chaque fois qu&rsquo;on veut utiliser le bonus d&rsquo;un de ces plateaux, il faudra retirer un de ses propres cubes du plateau annexe. \u00a0Voil\u00e0, vraiment tr\u00e8s simple comme possibilit\u00e9, cela n&rsquo;alourdit en rien la m\u00e9canique mais offre des possibilit\u00e9s suppl\u00e9mentaires fort int\u00e9ressantes et les choix qui vont avec: <em>Est-ce que je d\u00e9place mon meeple maintenant pour b\u00e9n\u00e9ficier du bonus cr\u00e9\u00e9 pour le coup d&rsquo;apr\u00e8s que je pr\u00e9vois de r\u00e9aliser en prenant le risque que le coup d&rsquo;apr\u00e8s ne puisse pas avoir lieu \u00e0 cause de l&rsquo;achat de tel ou tel d\u00e9 par un adversaire? \u00a0Ou bien est-ce que je r\u00e9alise cette action tout de suite sans b\u00e9n\u00e9ficier alors du bonus?<\/em><br \/>\n<span style=\"color: #ff00ff;\"><strong>2) Le d\u00e9 mauve<\/strong><\/span><br \/>\nChaque joueur dispose d\u00e9sormais d&rsquo;un d\u00e9 mauve. \u00a0Ce d\u00e9 mauve a la particularit\u00e9 de ne pas pouvoir \u00eatre achet\u00e9 par un adversaire. \u00a0Ce petit d\u00e9tail offre des possibilit\u00e9s insoup\u00e7onn\u00e9es et est un r\u00e9el plus au jeu.<\/p>\n<p>Sans \u00eatre r\u00e9ellement originales, Les Dames De Troyes offrent des possibilit\u00e9s suppl\u00e9mentaires int\u00e9ressantes qui rendent l&rsquo;extension indispensable. \u00a0Sa grande force est ne n&rsquo;ajouter aucune nouvelle complexit\u00e9. \u00a0Ses r\u00e8gles sont rapidement assimilables et permettent d&rsquo;\u00eatre rejou\u00e9es sans devoir se replonger dans les r\u00e8gles. \u00a0Il me tarde de refaire une partie avec l&rsquo;extension. \u00a0C&rsquo;est dire si elle devient vite partie int\u00e9grante du jeu de base&#8230;<\/p>\n<p>Bravo.<\/p>\n<p><strong><span style=\"color: #800080;\">Nouvelle partie:<\/span><\/strong><\/p>\n<p>Cette nouvelle partie a \u00e9t\u00e9 \u00e9trange car nous avons utilis\u00e9 toutes les options de l&rsquo;extension et personne n&rsquo;a avanc\u00e9 le long des remparts.\u00a0 Je pense que la raison principale \u00e9tait le faible attrait de la porte 1: recevoir 4 deniers si un joueur utilise son bonhomme sur une carte activit\u00e9 \u00e0 condition d&rsquo;en avoir un sur la m\u00eame carte.\u00a0 Autant dire qu&rsquo;au d\u00e9but de notre partie, trop peu de bonhommes n&rsquo;\u00e9taient pr\u00e9sents sur les cartes activit\u00e9s, rendant cette option inint\u00e9ressante.\u00a0 Plus tard, l&rsquo;action devenait plus lucrative mais tous les joueurs avaient tr\u00e8s bien g\u00e9r\u00e9 leur argent rendant l&rsquo;option de gagner plus d&rsquo;argent inutile.\u00a0 Il fallait donc utiliser au minimum 2 actions pour arriver \u00e0 placer un cube sur la porte 2.\u00a0 Un peu trop cher \u00e0 ce moment du jeu.<\/p>\n<p>Je descends donc ma note d&rsquo;un demi point car l&rsquo;action rempart qui est la plus belle trouvaille de cette extension peut ne pas \u00eatre int\u00e9ressante dans certaines configurations.<\/p>\n<p><strong><span style=\"color: #0000ff;\">Philrey212:<\/span> <span style=\"color: #993300;\">5\/10<\/span><\/strong><\/p>\n<p>J&rsquo;avoue que je ne suis pas pour les extensions. En effet, je trouve que dans la majorit\u00e9 des cas, elles n&rsquo;apportent pas grand chose au jeu de base et sont m\u00eame parfois n\u00e9fastes. J&rsquo;\u00e9tais donc tr\u00e8s curieux de tester cette extension suite aux commentaires de mes amis.<\/p>\n<p>Et bien, est-ce \u00e0 cause de notre partie, mais cette extension confirme l&rsquo;opinion que j&rsquo;ai des extensions en g\u00e9n\u00e9rale. Dans notre partie, les remparts ne nous ont pas sembl\u00e9 int\u00e9ressant (mais peut-\u00eatre est-ce du \u00e0 notre partie) et le d\u00e9 mauve n&rsquo;apporte rien au jeu de base que je trouve excellent.<\/p>\n<p>Donc, \u00e0 part des cartes suppl\u00e9mentaires qui permettent de renouveler les parties de Troyes, rien d&rsquo;extra-ordinaire avec ces Dames de Troyes.<\/p>\n<p><strong><span style=\"color: #333399;\">Benoit<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a0\u00a0 6\/10<\/span><\/strong><\/p>\n<p>Je me dois de poser le contexte un peu particulier: je joue pour la premi\u00e8re fois \u00e0 Troyes contre des joueurs exp\u00e9riment\u00e9s (premi\u00e8re difficult\u00e9) et avec cette extension (deuxi\u00e8me difficult\u00e9).<\/p>\n<p>Dans cette partie, nous n&rsquo;utilisons absolument pas les remparts. Pas de critique de ce cot\u00e9 sauf que leur utilit\u00e9 ne nous a pas saut\u00e9 aux yeux.<\/p>\n<p>Les cartes activit\u00e9s suppl\u00e9mentaires sont int\u00e9ressantes, mais je n&rsquo;ai pas fait de partie sans&#8230;<\/p>\n<p>Par contre le d\u00e9 mauve me semble une aberration. En effet, on me tanne le cuir avec Troyes en m&rsquo;expliquant que le cot\u00e9 al\u00e9atoire des jets de d\u00e9 est maitrisable parce que l&rsquo;on peut acheter les d\u00e9s des autres joueurs&#8230; mais pas le mauve&#8230; N&rsquo;y a-t-il pas une contradiction quelque part?<\/p>\n<p>Enfin, la remise al\u00e9atoire des meeples dans le monast\u00e8re et dans la ferme m&rsquo;a achev\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #333399;\"><strong>Dan<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 9\/10<\/strong><\/span><\/p>\n<p>Rares sont les extensions qui apportent une r\u00e9elle plus-value \u00e0 un jeu, surtout quand celui-ci est d\u00e9j\u00e0 de qualit\u00e9.<\/p>\n<p>Et bien les belles Dames de Troyes sont une belle exception \u00e0 cette r\u00e8gle!<\/p>\n<p>Le d\u00e9 mauve qui ne peut \u00eatre achet\u00e9 et surtout les remparts apportent en effet une dimension tactique ind\u00e9niable au jeu.<\/p>\n<p>Les 27 cartes activit\u00e9 comblent en outre ce qui, selon moi, \u00e9tait un vrai d\u00e9faut (il n&rsquo;y avait que 27 cartes activit\u00e9 et donc peu de vari\u00e9t\u00e9 d&rsquo;une partie \u00e0 l&rsquo;autre).<\/p>\n<p>Il ne fait aucun doute que si vous poss\u00e9dez et aimez le jeu de base (excellent), cette extension devra le rejoindre dans votre ludoth\u00e8que!<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4789  aligncenter\" title=\"543 Dames de Troyes 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-2-768x1024.jpg\" alt=\"\" width=\"614\" height=\"819\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-2-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-2-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-2-112x150.jpg 112w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/543-Dames-de-Troyes-2-400x533.jpg 400w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Les Dames de Troyes, c&rsquo;est avant tout, une extension pour\u00a0Troyes! \u00a0Qui l&rsquo;eut cru? \u00a0\ud83d\ude09 Troyes \u00e9tant un jeu magnifique et complet, je dois avouer que j&rsquo;\u00e9tais assez septique \u00e0 la sortie de cette extension. \u00a0Qu&rsquo;allait-elle apporter de plus \u00e0 un jeu aussi complet et \u00e9quilibr\u00e9? \u00a0N&rsquo;ajoutera-t-elle pas une&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":4790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[8,502,6,7],"class_list":["post-4788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-benoit","tag-dan","tag-philrey212","tag-swatsh","annee-464","auteurs-alain-orban","auteurs-sebastien-dujardin","auteurs-xavier-georges","editeurs-pearl-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/4788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=4788"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/4788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/4790"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=4788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=4788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=4788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}