{"id":4800,"date":"2013-04-04T20:25:48","date_gmt":"2013-04-04T19:25:48","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=4800"},"modified":"2013-04-04T20:25:48","modified_gmt":"2013-04-04T19:25:48","slug":"gentlemen-cambrioleurs","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2013\/04\/04\/gentlemen-cambrioleurs\/","title":{"rendered":"Gentlemen Cambrioleurs"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-4802\" title=\"545 Cambriol 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-1.jpg\" alt=\"\" width=\"304\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-1.jpg 434w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-1-260x300.jpg 260w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-1-130x150.jpg 130w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-1-400x460.jpg 400w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/><\/a><\/p>\n<p><span style=\"color: #333399;\"><strong>SwatSh<\/strong><\/span>: <span style=\"color: #800000;\"><strong>7,5\/10<\/strong><\/span><\/p>\n<p>Gentlemen Cambrioleur est un jeu familial de 3 auteurs, trio d\u00e9j\u00e0 responsable d&rsquo;<a href=\"http:\/\/www.vindjeu.eu\/2010\/11\/08\/intrigo\/\"><span style=\"color: #0000ff;\">Intrigo<\/span><\/a> et dont un, <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/charles-chevallier\/\"><span style=\"color: #0000ff;\">Charles Chevallier<\/span><\/a>, est le co-auteur de <a href=\"http:\/\/www.vindjeu.eu\/2011\/02\/20\/le-secret-de-monte-cristo\/\"><span style=\"color: #0000ff;\">Monte Cristo<\/span><\/a>, jeu au m\u00e9canisme de billes original.<\/p>\n<p>Ce qui frappe d&rsquo;abord dans Gentlemen Cambrioleurs c&rsquo;est sa boite faisant partie int\u00e9grante du jeu (cfr photo du bas). \u00a0C&rsquo;est malin et \u00e7a apporte un plus \u00e0 l&rsquo;objet.<\/p>\n<p>Gentlemen Cambrioleurs est un jeu abstrait dont le th\u00e8me est peu pr\u00e9sent. \u00a0Le premier joueur du tour commence par d\u00e9finir les alliances: quelles couleurs sont alli\u00e9es \u00e0 quelles autres couleurs en sachant que chaque joueur est repr\u00e9sent\u00e9 secr\u00e8tement par une couleur. \u00a0L&rsquo;objectif est de former 2 clans: 1 clan de 3 couleurs et un autre de 2.<\/p>\n<p>A son tour, un joueur pioche un jeton objet qu&rsquo;il place autour d&rsquo;un des 5 lieux. \u00a0Chaque objet est d&rsquo;une couleur d&rsquo;un joueur et il existe 5 types d&rsquo;objets diff\u00e9rents. \u00a0D\u00e8s qu&rsquo;un lieu contient les 5 types d&rsquo;objet, on effectue son d\u00e9compte: Celle des 2 alliances qui contient le plus de jetons objets \u00e0 ses couleurs se partage le pactole du lieu.<\/p>\n<p>A la fin du jeu, on regarde la couleur qui a amass\u00e9 le plus grand pactole, les joueurs d\u00e9voilent alors leur couleur cach\u00e9e et celui poss\u00e9dant la couleur en question l&#8217;emporte.<\/p>\n<p>Gentlemen Cambrioleurs est un jeu l\u00e9ger et simple. \u00a0On va constamment faire attention aux alliances gagnantes des diff\u00e9rents lieux en avantageant l&rsquo;alliance dont on fait partie tout en compl\u00e9tant au plus vite les lieux o\u00f9 on est victorieux afin d&rsquo;atteindre les 5 objets diff\u00e9rents avant l&rsquo;alliance adverse. \u00a0La grande subtilit\u00e9 est dans le choix des alliances: si on joue \u00e0 moins de 5 joueurs, il faut d&rsquo;abord r\u00e9ussir \u00e0 deviner la ou les couleurs neutres puis deviner qui est qui. \u00a0Sur base de ces infos, essayer de placer le joueur en t\u00eate dans une alliance perdante et diff\u00e9rente de la n\u00f4tre pour pouvoir le rattraper. \u00a0C&rsquo;est vraiment une grande subtilit\u00e9 du jeu et si vous le faites bien, \u00e7a pourra vous rapporter gros tandis que si vous vous planter, \u00e7a peut co\u00fbter tr\u00e8s cher. \u00a0Malheureusement, on ne choisit\u00a0les alliances \u00a0que chacun \u00e0 son tour et seulement au d\u00e9but d&rsquo;un tour, ce qui veut dire que dans une partie \u00e0 4, on choisira environ 2 alliances pour toute la partie. \u00a0Ce qui est fort peu et qui peut donner un sentiment de peu de ma\u00eetrise.<\/p>\n<p>C&rsquo;est bien dans ce choix des alliances que se situe tout le fun de Gentleman Cambrioleurs. \u00a0C&rsquo;est vraiment tr\u00e8s gai de chercher \u00e0 savoir qui est qui tout au long de la partie et d&rsquo;arriver \u00e0 le deviner avant ses adversaires afin d&rsquo;en tirer le meilleur avantage. \u00a0Malgr\u00e9 un c\u00f4t\u00e9 peu ma\u00eetrisable, Gentlemen Cambrioleurs animera sympathiquement les soir\u00e9es entre amis gr\u00e2ce \u00e0 la suspicion constante durant la partie.<\/p>\n<p><span style=\"color: #333399;\"><strong>Benoit<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 7,5\/10<\/strong><\/span><\/p>\n<p>J&rsquo;ai beaucoup apprecie la dynamique de Gentleman Cambrioleurs et l&rsquo;ambiance de notre partie. Je trouve plutot\u00a0sympa de voir les alliances evoluer, mais cela rend le jeu difficilement maitrisable et la victoire finale un peu aleatoire.\u00a0Notre sort va souvent dependre d&rsquo;un autre joueur, d&rsquo;un\u00a0king maker!<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4801  aligncenter\" title=\"545 Cambriol 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-2-1024x681.jpg\" alt=\"\" width=\"819\" height=\"545\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-2-1024x681.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-2-300x199.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-2-150x99.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/01\/545-Cambriol-2-400x266.jpg 400w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Gentlemen Cambrioleur est un jeu familial de 3 auteurs, trio d\u00e9j\u00e0 responsable d&rsquo;Intrigo et dont un, Charles Chevallier, est le co-auteur de Monte Cristo, jeu au m\u00e9canisme de billes original. Ce qui frappe d&rsquo;abord dans Gentlemen Cambrioleurs c&rsquo;est sa boite faisant partie int\u00e9grante du jeu (cfr photo du&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":4802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[8,7],"class_list":["post-4800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-benoit","tag-swatsh","annee-464","auteurs-catherine-dumas","auteurs-charles-chevallier","auteurs-pascal-pelemans","editeurs-bombyx"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/4800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=4800"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/4800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/4802"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=4800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=4800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=4800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}