{"id":48233,"date":"2022-04-13T17:38:45","date_gmt":"2022-04-13T15:38:45","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=48233"},"modified":"2022-04-13T17:38:59","modified_gmt":"2022-04-13T15:38:59","slug":"les-gardiens-de-havresac","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/04\/13\/les-gardiens-de-havresac\/","title":{"rendered":"Les gardiens de Havresac"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79322-grande.jpg\" alt=\"\" class=\"wp-image-48234\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/Claire-Mer-1.jpg\" alt=\"\" class=\"wp-image-45425\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple : <\/span><span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Vous voici \u00e0 la t\u00eate d\u2019une troupe de valeureux h\u00e9ros ayant\npour but de prot\u00e9ger le royaume de Havresac. Au d\u00e9but de votre mission, votre\ntroupe ne compte que 5 gardiens mais d\u2019autres viendront l\u2019agrandir. <\/p>\n\n\n\n<p>Les gardiens de Havresac est un jeu dit de<em>&nbsp;bagbuilding<\/em> ce qui signifie que\nvos gardiens sont dans un sac et qu\u2019ils seront jou\u00e9s un \u00e0 un au fur et \u00e0 mesure\nque vous les piochez. Chaque joueur poss\u00e8de un grand plateau repr\u00e9sentant le\nroyaume. Le tour de jeu est simple&nbsp;: on pioche un gardien dans son sac et\non le pose, en respectant certaines r\u00e8gles, sur son royaume puis on le d\u00e9place\net on active son pouvoir. Cette phase se r\u00e9p\u00e8te jusqu\u2019\u00e0 ce que le sac soit\nvide. L\u2019objectif est de marquer le plus de points de gloire \u00e0 la fin du tour\ncar ils rapportent des points de victoire ainsi que de l\u2019or permettant\nd\u2019acheter de nouveaux gardiens.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Le royaume<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"274\" height=\"300\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1727-274x300.jpg\" alt=\"\" class=\"wp-image-48235\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1727-274x300.jpg 274w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1727-768x842.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1727-934x1024.jpg 934w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1727-146x160.jpg 146w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1727-223x245.jpg 223w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1727-310x340.jpg 310w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"215\" height=\"300\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1728-215x300.jpg\" alt=\"\" class=\"wp-image-48236\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1728-215x300.jpg 215w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1728-768x1072.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1728-733x1024.jpg 733w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1728-115x160.jpg 115w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1728-175x245.jpg 175w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1728-243x340.jpg 243w\" sizes=\"auto, (max-width: 215px) 100vw, 215px\" \/><\/figure><\/div>\n\n\n\n<p>Le plateau joueur est vraiment grand. Il comporte un ch\u00e2teau\nen son centre, des for\u00eats, des lacs ainsi que des villages. Les gardiens vont\nse d\u00e9placer dans ce royaume en utilisant les cases mais les \u00e9l\u00e9ments du d\u00e9cor\npourront modifier leurs avanc\u00e9es. Ce territoire est aussi parsem\u00e9 de coffres\nqui, une fois ouvert, apportent des bonus comme un d\u00e9placement suppl\u00e9mentaire,\ndes points de gloire, des points d\u2019attaque,\u2026<\/p>\n\n\n\n<p>Au d\u00e9but de chaque manche, on r\u00e9v\u00e8le cinq cartes Ennemi qui\nindiquent l\u2019emplacement et le type de monstres qui est ajout\u00e9 au plateau de\nchaque joueur. Cela va fortement influencer votre partie puisque le plus grand\npourvoyeur de point de gloire est le nombre de monstre \u00e9limin\u00e9. Il est aussi\npossible d\u2019en gagner pour chaque village reconstruit. En effet, les hameaux de\nHavresac ont \u00e9t\u00e9 compl\u00e9tement d\u00e9truits, \u00e0 chaque fois qu\u2019un gardien finit son\nd\u00e9placement dessus, il a la possibilit\u00e9 de le reconstruire. Plus vous r\u00e9alisez\ncette action, plus vous marquez des points \u00e0 chaque fin de manche. Attraper des\nf\u00e9es apporte aussi de la gloire, mais elles sont difficiles \u00e0 saisir, car elles\ndisparaissent \u00e0 chaque fin de tour. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"261\" height=\"300\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1731-261x300.jpg\" alt=\"\" class=\"wp-image-48237\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1731-261x300.jpg 261w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1731-768x884.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1731-889x1024.jpg 889w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1731-139x160.jpg 139w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1731-213x245.jpg 213w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/IMG_E1731-295x340.jpg 295w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/figure><\/div>\n\n\n\n<p>Ce jeu offre un syst\u00e8me de <em>scoring<\/em> que j\u2019appr\u00e9cie beaucoup car il intervient \u00e0 la fin de\nchaque manche. Les points de gloire obtenus sont compar\u00e9s \u00e0 une table de\nconversion qui octroie des points de victoire mais surtout de l\u2019or pour\nrecruter. Ce choix est corn\u00e9lien&nbsp;! Quel gardien int\u00e9grer \u00e0 son\ngroupe&nbsp;? Quelle comp\u00e9tence doit-on favoriser&nbsp;? Est-il judicieux\nd\u2019\u00e9conomiser l\u2019or de ce tour pour acheter un gardien encore inaccessible&nbsp;?\n<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Les gardiens<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"215\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande-300x215.jpg\" alt=\"\" class=\"wp-image-48238\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande-300x215.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande-768x549.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande-1024x732.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande-160x114.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande-343x245.jpg 343w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande-476x340.jpg 476w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79324-grande.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Le royaume d\u2019Havresac compte six guerriers aux comp\u00e9tences\nd\u2019action diff\u00e9rentes. Le voleur ouvre les coffres, le guide peut poser des\ncampements ou attraper des f\u00e9es gr\u00e2ce \u00e0 son filet \u00e0 papillon, la guerri\u00e8re\ncombat les monstres en corps \u00e0 corps, la chasseuse transperce \u00e0 distance les\nennemis, le druide ignore les contraintes li\u00e9es au terrain et la pr\u00eatresse peut\n\u00e9changer sa place avec un autre gardien qui retourne alors dans le sac. Pour\ncontribuer \u00e0 la rejouabilit\u00e9 du jeu, tous les h\u00e9ros poss\u00e8dent une fiche recto\nverso avec des sp\u00e9cificit\u00e9s diff\u00e9rentes. Au d\u00e9but de la partie, soit on tire au\nhasard ou on se met d\u2019accord sur le c\u00f4t\u00e9 de la fiche. Les faces Jour sont plus\nsimples \u00e0 utiliser que les faces Nuit. <\/p>\n\n\n\n<p>La strat\u00e9gie li\u00e9e au d\u00e9placement des personnages est\nimportante. En effet, quand un gardien est pioch\u00e9, il peut se placer soit sur le\nch\u00e2teau soit \u00e0 partir un campement positionn\u00e9 par le gardien, soit sur\nl\u2019emplacement d\u2019un autre gardien. L\u2019objectif est de r\u00e9ussir \u00e0 se d\u00e9placer loin\nsur le domaine pour atteindre des monstres, des coffres ou des villages. \u00c9videmment\nceux-ci ne se trouvent pas \u00e0 proximit\u00e9 du ch\u00e2teau&nbsp;! Il va donc falloir r\u00e9ussir\n\u00e0 \u00e9tablir une sorte de cha\u00eene humaine qui facilitera l\u2019avanc\u00e9e des gardiens. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>La paix<\/strong><\/h4>\n\n\n\n<p>\u00c0 la fin des cinq tours de jeu, vous avez normalement\nr\u00e9ussi \u00e0 pacifier Havresac. L\u2019exp\u00e9rience que propose ce jeu est vraiment\nsinguli\u00e8re car il n\u2019y a aucune, mais alors aucune interaction&nbsp;! Le jeu est\nidentique que vous soyez un, deux, trois ou quatre joueurs. Finalement vous\njouez en solo en face d\u2019autres joueurs solo. Cet aspect peut d\u00e9ranger certains\nmais nous l\u2019avons bien appr\u00e9ci\u00e9. <\/p>\n\n\n\n<p><strong>Les gardiens de\nHavresac<\/strong> n\u00e9cessite de la strat\u00e9gie dans le placement et dans le recrutement.\nIl faut bien conna\u00eetre le contenu de son sac pour anticiper les prochaines\nactions. Plus on poss\u00e8de de guerriers dans son sac, plus on peut faire d\u2019actions.\nLe jeu va donc monter en puissance au fur et \u00e0 mesure des manches. Plus vos\nrounds de jeu sont efficaces, plus vous obtiendrez des points de gloire, donc de\nl\u2019or qui permettra d\u2019acqu\u00e9rir de nouveaux guerriers et donc d\u2019augmenter\nl\u2019efficacit\u00e9 de la manche suivante CQFD. &nbsp;<br>\nIl est vrai que parfois c\u2019est vraiment frustrant de tirer le voleur\nimm\u00e9diatement alors que vous auriez eu besoin de la guerri\u00e8re&nbsp;! Seule la pr\u00eatresse\npermet d\u2019att\u00e9nuer un peu le hasard en offrant la possibilit\u00e9 de r\u00e9cup\u00e9rer un\nguerrier du plateau. J\u2019ai trouv\u00e9 que cet aspect al\u00e9atoire (pioche des\nguerriers, placement des coffres et r\u00e9v\u00e9lation des ennemis) apportait un vrai\nplus au jeu, sans lui, il serait trop r\u00e9p\u00e9titif. Il faut s\u2019adapter \u00e0 chaque\nsituation et tirer le meilleur de toutes les opportunit\u00e9s. Le mini Meeple a\nregrett\u00e9 que les ennemis ne poss\u00e8dent pas de phase d\u2019attaque ce qui aurait\nentrain\u00e9 une modification des plans. <\/p>\n\n\n\n<p>Le mat\u00e9riel est de bonne qualit\u00e9 et j\u2019ai surtout appr\u00e9ci\u00e9 la\npetite biographie de l\u2019auteur et de l\u2019illustratrice sur le pourtour de la\nbo\u00eete. <\/p>\n\n\n\n<p>Placement, chasse aux points et tranquillit\u00e9 sont les trois\nmots qui me viennent imm\u00e9diatement \u00e0 l\u2019esprit quand je pense Aux Gardiens de\nHavresac. Des parties de moins de 30mn, des r\u00e8gles tr\u00e8s accessibles et un\naspect strat\u00e9gique agr\u00e9able font que je joue toujours \u00e0 ce jeu avec plaisir.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande-1024x732.jpg\" alt=\"\" class=\"wp-image-48239\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande-1024x732.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande-300x215.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande-768x549.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande-160x114.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande-343x245.jpg 343w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande-476x340.jpg 476w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/les-gardiens-de-havresac-p-image-79325-grande.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Claire e Vous voici \u00e0 la t\u00eate d\u2019une troupe de valeureux h\u00e9ros ayant pour but de prot\u00e9ger le royaume de Havresac. Au d\u00e9but de votre mission, votre troupe ne compte que 5 gardiens mais d\u2019autres viendront l\u2019agrandir. Les gardiens de Havresac est un jeu dit&#46;&#46;&#46;<\/p>\n","protected":false},"author":10,"featured_media":48234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-48233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-3413","auteurs-frederic-guerard","editeurs-catch-up-games","illustrateurs-sabrina-miramon"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/48233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=48233"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/48233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/48234"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=48233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=48233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=48233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}