{"id":48565,"date":"2022-04-25T09:18:44","date_gmt":"2022-04-25T07:18:44","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=48565"},"modified":"2022-04-25T09:18:57","modified_gmt":"2022-04-25T07:18:57","slug":"root-the-marauder-expansion","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/04\/25\/root-the-marauder-expansion\/","title":{"rendered":"Root: The Marauder Expansion"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-1.jpg\" alt=\"\" class=\"wp-image-48567\" width=\"571\" height=\"447\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-1.jpg 766w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-1-300x235.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-1-160x125.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-1-313x245.jpg 313w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-1-434x340.jpg 434w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/Swa-52-150x150.jpg\" alt=\"\" class=\"wp-image-47932\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\"> 8\/10<\/span><\/h5>\n\n\n\n<p>The Marauder Expansion est la derni\u00e8re extension de l&rsquo;excellent <a href=\"https:\/\/www.vindjeu.eu\/2019\/07\/23\/root\/\"><strong>Root<\/strong><\/a>, votre <a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/23\/vin-djeu-dlannee-2019\/\"><strong>Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2019<\/strong><\/a>, fraichement sortie du financement participatif.  Elle n&rsquo;est pour le moment disponible qu&rsquo;en Anglais, et m\u00eame si elle n&rsquo;a pas encore \u00e9t\u00e9 annonc\u00e9e, il est fort probable que <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/matagot\/\"><strong>Matagot<\/strong><\/a> en sorte une version Fran\u00e7aise.  En attendant, ne boudons pas notre plaisir d&rsquo;aller marauder avec les blaireaux et les rats \ud83d\ude42<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#abb8c3\" class=\"color\">Les blaireaux gardiens en fer<\/span><\/h2>\n\n\n\n<p>Les blaireaux sont assez difficiles \u00e0 jouer. Ils vont allez <strong>creuser dans les forets<\/strong> pour en ressortir des reliques qu&rsquo;ils devront alors <strong>transporter jusqu&rsquo;\u00e0 leurs gares routi\u00e8res<\/strong> (leurs b\u00e2timents de construction) pour pouvoir enfin les r\u00e9cup\u00e9rer et les placer sur leur tableau afin de gagner des PVs. De plus, tout \u00e7a ne se fait pas sans difficult\u00e9s car ils devront <strong>contr\u00f4ler pas mal de clairi\u00e8res<\/strong> pour \u00e9viter de perdre des cartes. Pour leurs actions, ils fonctionnent un peu comme la dynastie des Aigles en pla\u00e7ant des cartes en face des actions qu&rsquo;ils veulent ex\u00e9cuter dans les clairi\u00e8res correspondantes aux cartes plac\u00e9es. C&rsquo;est \u00e9videmment une <strong>difficult\u00e9 de planification<\/strong> suppl\u00e9mentaire pour un peuple assez exigeant.<\/p>\n\n\n\n<p>Inutile de vous dire que vous n&rsquo;allez pas souvent gagner avec ce peuple tant il est difficile \u00e0 maitriser. Mais il est tr\u00e8s amusant \u00e0 jouer gr\u00e2ce \u00e0 son syst\u00e8me de <strong>pick-up &amp; delivery<\/strong> o\u00f9 vous allez explorer les for\u00eats de Root pour en ressortir vos reliques tant convoit\u00e9es (les autres gagnent 2 PVs quand ils arrivent \u00e0 d\u00e9truire une de vos reliques, vous ai-je dit qu&rsquo;il n&rsquo;\u00e9tait pas facile d&rsquo;\u00eatre un blaireau? \ud83d\ude00 ).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2-1024x683.jpg\" alt=\"\" class=\"wp-image-48580\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-2.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#d41424\" class=\"color\">Les Rats, Seigneurs des centaines<\/span><\/h2>\n\n\n\n<p>Les rats sont exactement l&rsquo;inverse des blaireaux: <strong>tr\u00e8s faciles \u00e0 jouer<\/strong>, vous gagnerez souvent avec eux, surtout dans vos parties \u00e0 peu de joueurs.  En effet, <strong>ils se prolif\u00e8rent assez rapidement<\/strong> et gagner des PVs gr\u00e2ce au nombre de clairi\u00e8res contr\u00f4l\u00e9es sans aucun ennemi pr\u00e9sent.  6 clairi\u00e8res contr\u00f4l\u00e9es donnent 4 PVs \u00e0 chaque tour aux rats.  Ca peut aller vite!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5-1024x683.jpg\" alt=\"\" class=\"wp-image-48582\" width=\"539\" height=\"360\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-5.jpg 1080w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/figure><\/div>\n\n\n\n<p>Pour leurs actions, ils ont droit en un<strong> nombre d&rsquo;actions d\u00e9pendant du nombre d&rsquo;objets<\/strong> et types d&rsquo;objets qu&rsquo;ils ont fabriqu\u00e9s. M\u00eame s&rsquo;ils ont la capacit\u00e9 d&rsquo;en d\u00e9couvrir sous les ruines, voil\u00e0 une faction qui va fabriquer beaucoup d&rsquo;objets pour devenir tr\u00e8s puissante. Mais pour construire ces objets, il faudra auparavant construire des bastions qui produiront des soldats \u00e0 chaque tour!<\/p>\n\n\n\n<p>Enfin, ils peuvent placer des jetons gangster qui, s&rsquo;ils ne sont pas \u00e9limin\u00e9s avant le d\u00e9but du prochain tour des rats, d\u00e9truisent  tout b\u00e2timent et jeton adverse.  D\u00e9vastateurs je vous dis ces rats!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#abb8c3\" class=\"color\">Marau<\/span><span style=\"color:#d41424\" class=\"color\">dons<\/span><\/h2>\n\n\n\n<p>Outre ces deux nouvelles factions, The Marauder Expansion offre quelques petits extras comme les mercenaires qui sont de petites factions qui vont apporter des combinaisons de pouvoirs surprenantes dans vos parties \u00e0 peu de joueuses.  J&rsquo;ai trouv\u00e9 dommage que ces deux nouvelles factions qui peuvent se jouer l&rsquo;une contre l&rsquo;autre \u00e0 2 soient si d\u00e9s\u00e9quilibr\u00e9es.  Mais malgr\u00e9 tout, il y a moyen de gagner en tant que blaireau et puis c&rsquo;est super chouette de jouer avec ces 2 nouvelles factions toutes les 2 apportant de nouvelles m\u00e9caniques et nouvelles strat\u00e9gies \u00e0 ce splendide jeu qu&rsquo;est <a href=\"https:\/\/www.vindjeu.eu\/2019\/07\/23\/root\/\"><strong>Root<\/strong><\/a>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1-1024x683.jpg\" alt=\"\" class=\"wp-image-48583\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-3-1.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/PhilRey10-150x150.jpg\" alt=\"\" class=\"wp-image-47839\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">PhilRey<\/span>:<span style=\"color:#cf2e2e\" class=\"color\">    8\/10<\/span><\/h5>\n\n\n\n<p>On profite d&rsquo;une extension pour rejouer \u00e0 Root. C&rsquo;est dommage, je sais, mais c&rsquo;est comme \u00e7a: beaucoup de jeux et choix souvent difficiles!<\/p>\n\n\n\n<p>Cette extension ajoute deux races suppl\u00e9mentaires, races que nous nous sommes empress\u00e9s de s\u00e9lectionner dans notre nouvelle partie \u00e0 deux joueurs. <\/p>\n\n\n\n<p>L&rsquo;avantage de cette extension est qu&rsquo;elle respecte immanquablement le jeu de base: m\u00eame philosophie d&rsquo;asym\u00e9trie. Les joueurs ne sont donc pas du tout d\u00e9pays\u00e9s et savent donc \u00e0 quoi s&rsquo;attendre. Y avait-il moyen d&rsquo;ajouter autre chose? Je n&rsquo;en sais rien mais certains resteront sur leur faim, c&rsquo;est certain!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4-1024x683.jpg\" alt=\"\" class=\"wp-image-48741\" width=\"628\" height=\"419\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-4.jpg 1080w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/figure><\/div>\n\n\n\n<p>Notre partie a \u00e9t\u00e9 assez rapide avec une victoire qui l&rsquo;est tout autant des Seigneurs des Centaines. Les Blaireaux ont m\u00eame rapidement subi la partie avec pr\u00e8s de 20 points d&rsquo;\u00e9cart en fin de partie. Sans doute a quelques erreurs du joueur mais aussi due la difficult\u00e9 de marquer des points. Les Blaireaux vont chercher des reliques \u00e9parpill\u00e9es sur le plateau. Tout d&rsquo;abord, pour prendre la relique, il y a une certaine prise de risque: les Blaireaux doivent contr\u00f4ler autant (ou plus) de clairi\u00e8res adjacentes \u00e0 la for\u00eat cibl\u00e9e que la valeur de la dite relique (valeur inconnue). Si ce n&rsquo;est pas le cas, les Blaireaux se saisissent quand m\u00eame de la relique mais perdent la carte \u00ab\u00a0action\u00a0\u00bb ainsi utilis\u00e9e. C&rsquo;est un co\u00fbt assez \u00e9lev\u00e9 que le joueur essaiera d&rsquo;\u00e9viter un maximum.<\/p>\n\n\n\n<p>Maintenant que les Blaireaux ont bien saisi la relique, il faut la d\u00e9placer\/transporter jusqu&rsquo;\u00e0 une gare routi\u00e8re correspondante. Et enfin, le joueur doit contr\u00f4ler autant de clairi\u00e8res de m\u00eame type que sa valeur avant d&rsquo;en tirer profit, c&rsquo;es \u00e0 dire marquer les pr\u00e9cieux points de victoire.<\/p>\n\n\n\n<p>Cela fait pas mal de contraintes et exige un bonne dose non seulement de planification mais \u00e9galement un certain d\u00e9tachement \u00e0 la \u00ab\u00a0possession\u00a0\u00bb de clairi\u00e8res inutiles. Et ce tout en contrant son adversaire.<\/p>\n\n\n\n<p>En face, les Seigneurs des Centaines sont plus accessibles, surtout \u00e0 deux joueurs. En effet, la premi\u00e8re t\u00e2che est de se r\u00e9pandre et construire leurs b\u00e2timents (bastions). Ceux-ci augmentent leur capacit\u00e9 de \u00ab\u00a0recrutement\u00a0\u00bb. De plus, ils peuvent placer un jeton gangster sur une clairi\u00e8re adjacente \u00e0 un autre jeton gangster. Et ces jetons rasent tout autre jeton sur cette clairi\u00e8re, b\u00e2timent aussi.<\/p>\n\n\n\n<p>L&rsquo;avantage de Root est que vous pouvez combinez les diff\u00e9rentes races, ce qui permet de peut-\u00eatre mieux \u00e9quilibrer certaines confrontations. Les combinaisons ne manquent pas et l&rsquo;extension Marauder augmente encore ce nombre!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15.jpg\" alt=\"\" class=\"wp-image-48566\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3181-Root-15-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> The Marauder Expansion est la derni\u00e8re extension de l&rsquo;excellent Root, votre Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2019, fraichement sortie du financement participatif. Elle n&rsquo;est pour le moment disponible qu&rsquo;en Anglais, et m\u00eame si elle n&rsquo;a pas encore \u00e9t\u00e9 annonc\u00e9e, il est fort probable que Matagot en sorte une version Fran\u00e7aise.&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":48567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-48565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-3413","auteurs-cole-wehrle","auteurs-patrick-leder","editeurs-leder-games","illustrateurs-kyle-ferrin","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","nombre_conseille-1321","mecanismes-combat"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/48565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=48565"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/48565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/48567"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=48565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=48565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=48565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}