{"id":48585,"date":"2022-05-21T22:36:58","date_gmt":"2022-05-21T20:36:58","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=48585"},"modified":"2022-05-28T19:17:53","modified_gmt":"2022-05-28T17:17:53","slug":"azul-le-jardin-de-la-reine","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/05\/21\/azul-le-jardin-de-la-reine\/","title":{"rendered":"Azul: le Jardin de la Reine"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"507\" height=\"600\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-1.jpg\" alt=\"\" class=\"wp-image-48586\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-1.jpg 507w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-1-254x300.jpg 254w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-1-135x160.jpg 135w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-1-207x245.jpg 207w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-1-287x340.jpg 287w\" sizes=\"auto, (max-width: 507px) 100vw, 507px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/03\/Swa-52-150x150.jpg\" alt=\"\" class=\"wp-image-47932\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:  <span style=\"color:#cf2e2e\" class=\"color\">9,5\/10<\/span><\/h5>\n\n\n\n<p>Le Jardin de la Reine est le quatri\u00e8me opus de <a href=\"https:\/\/www.vindjeu.eu\/?s=azul\"><strong>la saga Azul<\/strong><\/a>.  Alors qu&rsquo;on aurait pu s&rsquo;attendre \u00e0 ce que cette saga s&rsquo;essouffle, il n&rsquo;en est rien et Le Jardin de la Reine figure m\u00eame parmi les meilleurs!  <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/michael-kiesling\/\"><strong>Michael Kiesling<\/strong><\/a> est un g\u00e9nie et il le prouve une nouvelle fois avec cet opus.  J&rsquo;ai \u00e9t\u00e9 bluff\u00e9 par l&rsquo;\u00e9puration du jeu, sa relative simplicit\u00e9 et son \u00e9norme profondeur.  Jugez plut\u00f4t.<\/p>\n\n\n\n<p>Azul le Jardin de la Reine est le premier <a href=\"https:\/\/www.vindjeu.eu\/?s=azul\"><strong>Azul <\/strong><\/a>\u00e0 <strong>jouer et sur la couleur de la tuile et sur son dessin<\/strong>.  Le jeu comprend des tuiles de 6 couleurs diff\u00e9rentes et de 6 dessins diff\u00e9rents.  Et tout le jeu repose l\u00e0-dessus et uniquement l\u00e0-dessus!<\/p>\n\n\n\n<p>A votre tour vous pouvez soit prendre des tuiles et les placer dans votre stock soit prendre une tuile de votre stock et la placer sur votre plateau.  Pour<strong> prendre des tuile<\/strong>s, vous pouvez soit jouer sur la couleur, soit sur le dessin.  Alors c&rsquo;est simple, mais accrochez-vous:<br>-Soit vous prenez toutes les tuiles d&rsquo;une m\u00eame couleur mais de dessin diff\u00e9rent<br>-Soit vous prenez toutes les tuiles d&rsquo;un m\u00eame dessin mais de couleur diff\u00e9rente<\/p>\n\n\n\n<p>Et <strong>quand vous placez une tuile<\/strong> de votre stock \u00e0 votre plateau c&rsquo;est le m\u00eame topo sauf qu&rsquo;il vous faudra payer le co\u00fbt de la tuile pos\u00e9e:<br>-Soit avec des tuiles de la m\u00eame couleur mais de dessin diff\u00e9rent<br>-Soit avec des tuiles de m\u00eame dessin mais de couleur diff\u00e9rente<br>Et le co\u00fbt d&rsquo;une tuile \u00e9quivaut aux PVs qu&rsquo;elle rapporte: les arbres 1, les oiseaux 2, mes papillons 3, les fleurs 4, les plantes 5 et les lys 6.  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4-1024x683.jpg\" alt=\"\" class=\"wp-image-48591\" width=\"620\" height=\"414\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-4.jpg 1080w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/figure><\/div>\n\n\n\n<p>Et \u00e0 la fin du jeu on va <strong>gagner des PVs<\/strong> pour chaque groupe de minimum 3 tuiles adjacentes de m\u00eame couleur ou de m\u00eame dessin, une m\u00eame tuile pouvant compter pour 2 groupes diff\u00e9rents.<\/p>\n\n\n\n<p>Et voil\u00e0, c&rsquo;est quasi tout.  Ajoutez \u00e0 \u00e7a quelques petites astuces suppl\u00e9mentaires comme l&rsquo;obligation d&rsquo;augmenter la taille de son jardin, le gain de tuiles bonus lorsqu&rsquo;on entoure certaines parties de son jardin et la possibilit\u00e9 d&rsquo;avoir des points extras lorsqu&rsquo;on r\u00e9alise une s\u00e9rie de 6 et vous obtenez<strong> un jeu d&rsquo;une rare \u00e9l\u00e9gance<\/strong>.  Simple, \u00e9pur\u00e9 et tr\u00e8s profond o\u00f9 chaque choix sera difficile et n\u00e9cessitera des sacrifices.  Evidemment, face \u00e0 un jeu si \u00e9pur\u00e9, la variabilit\u00e9 des parties est assez limit\u00e9e.  De plus, les tuiles les plus lucratives sont \u00e9galement les plus ch\u00e8res ce qui les rend moins int\u00e9ressantes surtout en comparaison \u00e0 votre stock limit\u00e9.  Mais malgr\u00e9 \u00e7a, Azul Le Jardin de la Reine s\u00e9duit et impose le respect tant il rel\u00e8ve du g\u00e9nie.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5-1024x683.jpg\" alt=\"\" class=\"wp-image-49117\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-5.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/PhilRey10-150x150.jpg\" alt=\"\" class=\"wp-image-47839\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">PhilRey<\/span>:<span style=\"color:#cf2e2e\" class=\"color\">    8,5\/10<\/span><\/h5>\n\n\n\n<p>Une nouvelle version d&rsquo;Azul! A part Pavillons d&rsquo;\u00e9t\u00e9, j&rsquo;ai jou\u00e9 \u00e0 toutes les versions pr\u00e9c\u00e9dentes. Et c&rsquo;est le premier que j&rsquo;ai (et que je continue) le plus appr\u00e9ci\u00e9.<\/p>\n\n\n\n<p>J&rsquo;ai fait l&rsquo;acquisition de ce dernier opus \u00e0 Essen l&rsquo;ann\u00e9e pass\u00e9e (2021) car je ne voulais pas louper cette nouvelle sortie. Et bien m&rsquo;en a fait. Mais attention, ce n&rsquo;est pas la m\u00eame cat\u00e9gorie que le premier tout en restant quand m\u00eame accessible.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3-1024x683.jpg\" alt=\"\" class=\"wp-image-49116\" width=\"538\" height=\"359\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-3.jpg 1080w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/><\/figure><\/div>\n\n\n\n<p>Ici, il s&rsquo;ag\u00eet d&rsquo;agr\u00e9menter un jardin, j&rsquo;allais dire anglais mais non, il s&rsquo;ag\u00eet du jardin de la reine. Mais c&rsquo;est quand m\u00eame tr\u00e8s proche si on se base sur la reine &#8230; d&rsquo;Angleterre ;). <\/p>\n\n\n\n<p>Les tuiles sont r\u00e9parties sur 6 couleurs et 6 symboles (de fleurs, <\/p>\n\n\n\n<p>papillons et oiseaux). Le but est de grouper ces tuiles dans votre jardin par groupe de trois minimum: soit trois (ou plus) de m\u00eame couleur (peu importe le symbole), soit trois (ou plus) de m\u00eame symbole (peu importe la couleur cette fois). La seule restriction est de ne pas retourner la m\u00eame tuile (couleur et symbole) deux fois dans un m\u00eame groupe. En soi, c&rsquo;est assez simple! Seulement, la m\u00e9canique de \u00ab\u00a0pioche\u00a0\u00bb et de pose de tuiles reprend ce que l&rsquo;on trouve dans &#8230; Les Ch\u00e2teaux de Bourgogne. Et oui, une action consiste \u00e0 prendre des tuiles et les stocker sur votre plateau de stockage et une autre \u00e0 placer une (et une seule) tuile de votre stock vers votre jardin. Mais quelle excellente id\u00e9e!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4-1024x683.jpg\" alt=\"\" class=\"wp-image-49118\" width=\"518\" height=\"345\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/3182-Azul-Reine-4.jpg 1080w\" sizes=\"auto, (max-width: 518px) 100vw, 518px\" \/><\/figure><\/div>\n\n\n\n<p>Via une m\u00e9canique tr\u00e8s bien expliqu\u00e9e, des tuiles Extension sont \u00e9galement disponibles pour \u00e9tendre votre jardin. Et elles suivent le m\u00eame principe: d&rsquo;abord dans votre stock puis seulement dans votre jardin.<\/p>\n\n\n\n<p>Dernier \u00e9l\u00e9ment pour bien pimenter le tout: chaque tuile a un co\u00fbt. Il faut en effet d\u00e9penser d&rsquo;autres tuiles (de votre stock) pour en placer une dans votre jardin. Certaines sont (presque) gratuites mais ne rapporte que tr\u00e8s peu de points tandis que d&rsquo;autres exigent un lourd sacrifice mais rapportent jusqu&rsquo;\u00e0 6x plus. Et le co\u00fbt se fait en d\u00e9faussant d&rsquo;autres tuiles: soit de m\u00eame couleur mais avec des symboles tous diff\u00e9rents, soit de m\u00eame symbole mais avec des couleurs toutes diff\u00e9rentes. L&rsquo;auteur s&rsquo;est encore une fois surpass\u00e9!<\/p>\n\n\n\n<p>Et en fin de partie, passera en revues tous les groupes de minimum trois tuiles de m\u00eame couleur, ou de m\u00eame symbole, en sachant donc qu&rsquo;une tuile peut donc est compt\u00e9e deux fois. <\/p>\n\n\n\n<p>Azul, Le Jardin De La Reine est  donc un Azul  un peu moins accessible, pas point de vue r\u00e8gles mais bien point de vue r\u00e9flexion: les neurones vont surchauff\u00e9s!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15.jpg\" alt=\"\" class=\"wp-image-48588\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-15-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin-1024x683.jpg\" alt=\"\" class=\"wp-image-48587\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/04\/3182-Azul-Reine-16-vin.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>La Tour de By est un excellent M\u00e9doc, bien bois\u00e9 et bien profond qui se marie bien \u00e0 Azul.  Je le d\u00e9gusterais bien dans les jardins de la reine \ud83d\ude42<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Le Jardin de la Reine est le quatri\u00e8me opus de la saga Azul. Alors qu&rsquo;on aurait pu s&rsquo;attendre \u00e0 ce que cette saga s&rsquo;essouffle, il n&rsquo;en est rien et Le Jardin de la Reine figure m\u00eame parmi les meilleurs! Michael Kiesling est un g\u00e9nie et il le prouve&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":48586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[6,7],"class_list":["post-48585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-philrey212","tag-swatsh","annee-3413","auteurs-michael-kiesling","editeurs-next-move-games","illustrateurs-chris-quilliams","distributeurs-asmodee","nombre_conseille-1185","nombre_conseille-1210","mecanismes-abstrait","mecanismes-collection","mecanismes-placement-de-tuile"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/48585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=48585"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/48585\/revisions"}],"predecessor-version":[{"id":49120,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/48585\/revisions\/49120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/48586"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=48585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=48585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=48585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}