{"id":49103,"date":"2022-06-01T14:12:56","date_gmt":"2022-06-01T12:12:56","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=49103"},"modified":"2022-06-01T14:13:10","modified_gmt":"2022-06-01T12:13:10","slug":"jojo-le-pigeon-narcoleptique","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/06\/01\/jojo-le-pigeon-narcoleptique\/","title":{"rendered":"Jojo le pigeon narcoleptique"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/jojo2.png\" alt=\"\" class=\"wp-image-49104\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/Claire-Mer-1.jpg\" alt=\"\" class=\"wp-image-45425\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Claire et la famille Meeple<\/h5>\n\n\n\n<p>Il faut quand m\u00eame avouer qu\u2019\u00eatre un pigeon atteint de\nnarcolepsie, ce n\u2019est vraiment pas de chance. S\u2019endormir en plein vol est pour\nle moins risqu\u00e9. Cependant cela fait les affaires de Rizzo le chat qui attend\npatiemment que Jojo et ses amis d\u00e9butent leur sieste et tombent au sol. <\/p>\n\n\n\n<p>Ce titre est propos\u00e9 en financement participatif sur Ulule\net directement disponible en cliquant <a href=\"https:\/\/fr.ulule.com\/jojolepigeonnarcoleptique\/coming-soon\/\">Ici<\/a>.\nIl est disponible en format <em>print &amp;\nplay<\/em> ou en version physique. <\/p>\n\n\n\n<p>Jojo, le pigeon narcoleptique est un jeu d\u2019ambiance qui est\nrapide et o\u00f9 la chance est pr\u00e9sente \u00e0 100%. Pas besoin de r\u00e9fl\u00e9chir, il faut\njuste \u00eatre en veine. Pour vous soutenir dans votre partie, les tr\u00e8fles \u00e0 4\nfeuilles, les pattes de lapin ou autres grigris porte-bonheur sont les\nbienvenus. <\/p>\n\n\n\n<p>Le premier joueur lance de 1 \u00e0 4 d\u00e9s selon son bon vouloir\net surtout retient son score. Le joueur suivant jette le m\u00eame nombre de d\u00e9s ou\nplus que le joueur pr\u00e9c\u00e8dent. En fonction de son r\u00e9sultat, il se place \u00e0 gauche\nsi son score est plus faible ou \u00e0 droite s\u2019il est plus \u00e9lev\u00e9. Quand tous les\nparticipants ont jou\u00e9, Rizzo le chat mange le pigeon le plus \u00e0 gauche. Game\nOver pour le volatile trop lent&nbsp;! Mais alors pourquoi ne pas lancer 4 d\u00e9s\ntout le temps&nbsp;? Et bien c\u2019est que vous allez prendre un risque car si vous\nfaites un double, vous \u00eates pris d\u2019une crise de sommeil profond et vous tombez\nau pied du chat, c\u2019est la fin assur\u00e9e\u2026 Si vous r\u00e9alisez un triple, vous pouvez\nrelancer tous vos d\u00e9s. Et avec un quadruple, votre score augmente de 4 points. \u00c0\nvous de mesurer le risque que vous voulez prendre mais surtout que vous voulez\nimposer \u00e0 vos adversaires. <\/p>\n\n\n\n<p>La partie continue ainsi jusqu\u2019\u00e0 ce qu\u2019il ne reste plus\nqu\u2019un pigeon en jeu. Si les gla\u00e7ons n\u2019ont pas encore fondu ou si les braises ne\nsont pas encore assez chaudes, vous pouvez retenter votre chance. Les parties\nsont tellement rapides qu\u2019elles appellent forc\u00e9ment \u00e0 la revanche. Un jeu id\u00e9al\npour les amateurs de titres l\u00e9gers, simples, rapides, bas\u00e9s sur la chance. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"614\" height=\"375\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/jojo1.png\" alt=\"\" class=\"wp-image-49105\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/jojo1.png 614w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/jojo1-300x183.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/jojo1-160x98.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/jojo1-401x245.png 401w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/jojo1-557x340.png 557w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il faut quand m\u00eame avouer qu\u2019\u00eatre un pigeon atteint de narcolepsie, ce n\u2019est vraiment pas de chance. S\u2019endormir en plein vol est pour le moins risqu\u00e9. Cependant cela fait les affaires de Rizzo le chat qui attend patiemment que Jojo et ses amis d\u00e9butent leur sieste et tombent au sol.<br \/>\nCe titre est propos\u00e9 en financement participatif sur Ulule et directement disponible en cliquant Ici. Il est disponible en format print &#038; play ou en version physique.<\/p>\n","protected":false},"author":10,"featured_media":49104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1456],"tags":[],"class_list":["post-49103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crowdfunding","annee-3413","auteurs-phil-vizcarro","editeurs-cosmo-duck","illustrateurs-phil-vizcarro","mecanismes-jets-de-des"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=49103"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49103\/revisions"}],"predecessor-version":[{"id":49290,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49103\/revisions\/49290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/49104"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=49103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=49103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=49103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}