{"id":49365,"date":"2022-06-19T22:11:40","date_gmt":"2022-06-19T20:11:40","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=49365"},"modified":"2022-06-19T22:11:46","modified_gmt":"2022-06-19T20:11:46","slug":"the-great-wall-la-grande-muraille-extensions","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/06\/19\/the-great-wall-la-grande-muraille-extensions\/","title":{"rendered":"The Great Wall &#8211; La Grande Muraille + extensions"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall.jpg\" alt=\"\" class=\"wp-image-49366\" width=\"555\" height=\"555\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/06\/3225-the-great-wall-340x340.jpg 340w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/2985-Spiel-Essen-21-57-150x150.jpg\" alt=\"Swa\" class=\"wp-image-45273\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">9\/10<\/span><\/h5>\n\n\n\n<p>The Great Wall est <strong>un jeu issu d&rsquo;une des<\/strong> <strong>derni\u00e8res campagnes de financement monstrueuses<\/strong> <strong>organis\u00e9es par Awaken Realms<\/strong>. Pour The Great Wall, ils ont \u00e9t\u00e9 soutenus par plus de 15.000 contributeurs pour d\u00e9passer le million de dollar. Et m\u00eame si ce chiffre impressionne, ils ont d\u00e9j\u00e0 fait beaucoup plus fort avec <a href=\"https:\/\/www.vindjeu.eu\/2020\/11\/15\/nemesis\/\"><strong>Nemesis <\/strong><\/a>(41.000 souscripteurs et 5.000.000$ de r\u00e9colt\u00e9s), <a href=\"https:\/\/www.vindjeu.eu\/2022\/01\/15\/tainted-grail-la-chute-davalon\/\"><strong>Tainted Grail<\/strong><\/a> (41.000 souscripteurs et 4.900.000$ de r\u00e9colt\u00e9s) ou ISS Vanguard (28.000 souscripteurs et 4.900.000$) pour n&rsquo;en citer que quelques uns. <\/p>\n\n\n\n<p>Le jeu, ainsi que ses 3 extensions (Monstres Antiques, Stretch goals et Poudre Noire) est maintenant disponible dans les magasins et c&rsquo;est l&rsquo;occasion pour nous de vous en reparler.<\/p>\n\n\n\n<p>Il n&rsquo;y a pas \u00e0 dire, Awaken Realms sait y faire pour r\u00e9aliser des jeux exceptionnels. On adore <a href=\"https:\/\/www.vindjeu.eu\/2020\/11\/15\/nemesis\/\"><strong>Nemesis <\/strong><\/a>(<a href=\"https:\/\/www.vindjeu.eu\/2021\/09\/22\/vin-djeu-dlannee-2021\/\"><strong>Vin d&rsquo;jeu d&rsquo;coup d&rsquo;coeur 2021<\/strong><\/a>), est-ce que The Great Wall est de la m\u00eame veine? Oui et non&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#a02121\" class=\"color\">Non<\/span><\/h2>\n\n\n\n<p>Non car il s&rsquo;agit d&rsquo;un tout autre jeu beaucoup <strong>plus orient\u00e9 Eurogame<\/strong> que le reste de leur ligne \u00e9ditoriale plus tourn\u00e9 vers l&rsquo;aventure, le narratif et l&rsquo;Am\u00e9ritrash.<\/p>\n\n\n\n<p>The Great Wall est en effet un jeu de <strong>placement d&rsquo;ouvriers<\/strong> qui vont <strong>r\u00e9colter des ressources<\/strong> leur permettant de <em>construire <\/em>le grand mur, de construire des barricades et de <strong>former des unit\u00e9s militaires<\/strong> qui iront combattre les Mongols ennemis dans des combats simples, math\u00e9matiques, sans hasard et o\u00f9 la majorit\u00e9 est r\u00e9compens\u00e9e.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-3.jpg\" alt=\"\" class=\"wp-image-46694\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-3.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#a02121\" class=\"color\">Cartes action<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-4.jpg\" alt=\"\" class=\"wp-image-46695\" width=\"614\" height=\"409\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-4.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/figure><\/div>\n\n\n\n<p>Le placement des ouvri\u00e8res se fait dans un petit twist sympa car chaque joueuse dispose des m\u00eames <strong>6 cartes action<\/strong> leur permettant d&rsquo;envoyer un certain nombre de leurs ouvri\u00e8res sur les diff\u00e9rentes cases action. Ces cartes action vont \u00e9galement <strong>b\u00e9n\u00e9ficier aux autres<\/strong> joueuses et apporter un petit <strong>bonus <\/strong>si certaines d&rsquo;entre elles ont jou\u00e9 une carte action sp\u00e9cifique. Il va y avoir un petit guessing pour optimiser au mieux sa carte action et profiter au mieux de celles adverses.<\/p>\n\n\n\n<p>Le second twist sympa de ces cartes est qu&rsquo;elles se jouent chacune \u00e0 son tour. La premi\u00e8re joueuse va jouer sa carte action et <strong>placera directement toutes les ouvri\u00e8res<\/strong> qu&rsquo;elle peut placer avant que ses adversaires ne placent les leurs. On n&rsquo;est pas dans le classique \u00ab\u00a0chacune place une ouvri\u00e8re \u00e0 son tour\u00a0\u00bb mais plut\u00f4t, \u00ab\u00a0chacune place tout ce qu&rsquo;elle peut \u00e0 son tour\u00a0\u00bb \ud83d\ude42 J&rsquo;aime autant vous dire que l&rsquo;ordre du tour est important&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-2.jpg\" alt=\"\" class=\"wp-image-46696\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-2.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#a02121\" class=\"color\">R\u00e9coltons, combattons et construisons<\/span><\/h2>\n\n\n\n<p><strong>Les actions sont quant \u00e0 elles plus classiques <\/strong>puisqu&rsquo;elles consisteront essentiellement \u00e0 r\u00e9colter des ressources et \u00e0 les utiliser pour construire le mur et des barricades qui prot\u00e9geront la ville contre les attaques Mongoles et qui feront gagner des PVs. Vous pourrez \u00e9galement changer l&rsquo;ordre du tour, acheter des cartes tactiques permettant de gagner des PVs en cours de partie si on arrive \u00e0 atteindre leur objectif ou \u00e0 acheter des cartes conseillers qui vous apporteront de petits pouvoirs asym\u00e9triques tr\u00e8s sympathiques. Les ressources serviront \u00e9galement \u00e0 former des unit\u00e9s arm\u00e9es qui seront envoy\u00e9es pour combattre les ennemis.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-5.jpg\" alt=\"\" class=\"wp-image-46697\" width=\"555\" height=\"370\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-5.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/figure><\/div>\n\n\n\n<p>Cerise sur le g\u00e2teau, <strong>les combats se d\u00e9roulent sans une once de hasard<\/strong>. Vous connaissez \u00e0 l&rsquo;avance la force, l&rsquo;endurance et la capacit\u00e9 sp\u00e9ciale de chaque ennemi. Vous savez \u00e9galement <strong>le b\u00e9n\u00e9fice<\/strong> que vous gagnerez pour <strong>chaque coup<\/strong> apport\u00e9 \u00e0 l&rsquo;ennemi. Vaincre n&rsquo;est pas toujours un objectif en soi mais gagner les bonus de ses attaques l&rsquo;est certainement \ud83d\ude42 .  Cela va rendre ces <strong>combats tr\u00e8s th\u00e9matiques<\/strong> o\u00f9 les joueurs s&rsquo;uniront pour combattre ensemble les ennemis \u00e0 leurs portes.  <strong>Un jeu de majorit\u00e9<\/strong> dont les \u00e9galit\u00e9s sont bris\u00e9es par l&rsquo;ordre du tour (vous ai-je d\u00e9j\u00e0 dit qu&rsquo;il \u00e9tait important \ud83d\ude09 ) vient apporter une petite saveur suppl\u00e9mentaire apportant un bonus au joueur ayant le plus combattu l&rsquo;ennemi vaincu. Et les ennemis non vaincus, s&rsquo;ils sont assez forts pour passer la grande muraille, non seulement tueront toute unit\u00e9 sur leur passage mais apporteront de <strong>la honte<\/strong> aux joueurs les moins combattifs, honte dont il faudra se d\u00e9faire si on veut ne pas trop en subir les PVs n\u00e9gatifs.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-6.jpg\" alt=\"\" class=\"wp-image-46698\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-6.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-6-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-6-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-6-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-6-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-6-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#a02121\" class=\"color\">Monstres Antiques, Stretch goals et Poudre Noire <\/span><\/h2>\n\n\n\n<p>Poudre Noire \u00e9tend encore plus vos choix puisque vous aurez l&rsquo;occasion de construire des tours de d\u00e9fense ainsi que des armes de d\u00e9fense d\u00e9vastatrices comme des engins de si\u00e8ge, des canons et des lances rocket.  Mais attention car les mongols sont maintenant mieux arm\u00e9s et il ne sera toujours pas facile de les contrer.  Heureusement, gr\u00e2ce \u00e0 vos nouveaux soldats d&rsquo;\u00e9lite au pouvoir unique, vous pourrez contrer leurs attaques.  Monstres Antiques apporte 12 nouveaux conseill\u00e9s.  Quant \u00e0 la boite des stretch goals elle permet d&rsquo;y jouer jusque 5 et apporte 3 mini-extensions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#a02121\" class=\"color\">Oui<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-8.jpg\" alt=\"\" class=\"wp-image-46699\" width=\"528\" height=\"352\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-8.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/figure><\/div>\n\n\n\n<p>Alors oui, la Grande Muraille est un jeu tout \u00e0 fait digne de la ligne \u00e9ditoriale d&rsquo;Awaken Realms. Certes il est beaucoup <strong>plus eurogame<\/strong> que les autres, certes il est assez classique malgr\u00e9 ses <strong>petites trouvailles m\u00e9caniques<\/strong>, mais il est extr\u00eamement plaisant \u00e0 jouer et seuls <strong>les plus fins strat\u00e8ges<\/strong> pourront briguer la victoire. M\u00eame s&rsquo;il est bien \u00e9quilibr\u00e9, j&rsquo;ai trouv\u00e9 <strong>certaines actions plus faibles<\/strong> que d&rsquo;autres (on ne va jamais aller acheter beaucoup de cartes conseillers vu leur co\u00fbt croissant ni beaucoup de nouvelles cartes tactiques ni m\u00eame beaucoup de nouveaux ouvriers). Mais malgr\u00e9 \u00e7a, The Great Wall plait beaucoup. L&rsquo;air de rien, ses petites trouvailles m\u00e9caniques lui donnent des <strong>sensations nouvelles<\/strong> qui le rendent attachant et addictif. <strong>La rejouabilit\u00e9 est assur\u00e9e<\/strong> par des d\u00e9parts asym\u00e9triques gr\u00e2ce aux capacit\u00e9s uniques de votre g\u00e9n\u00e9ral de d\u00e9part (il y en a 8 en tout) et des conseillers de d\u00e9part et\/ou \u00e0 acqu\u00e9rir en cours de partie. On aurait aim\u00e9 une plus grande vari\u00e9t\u00e9 dans les objectifs communs (3 objectifs sont tir\u00e9s au hasard parmi 5 pour chaque partie, c&rsquo;est peu). Il apporte \u00e9galement une <strong>belle courbe d&rsquo;apprentissage<\/strong> qui, avec la variabilit\u00e9 et son th\u00e8me assez combattif, nous donne clairement l&rsquo;envie de <strong>prendre notre revanche<\/strong> \ud83d\ude09<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19.jpg\" alt=\"\" class=\"wp-image-46688\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/12\/3071-Great-Wall-19-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#a02121\" class=\"color\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">La vid\u00e9o de nos amis d&rsquo;Expert Game Award<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"The Great Wall\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/1lGT4LipuxE?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#a02121\" class=\"color\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"The KVB - Unit\u00e9\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/RPFbVQx_iYE?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> The Great Wall est un jeu issu d&rsquo;une des derni\u00e8res campagnes de financement monstrueuses organis\u00e9es par Awaken Realms. Pour The Great Wall, ils ont \u00e9t\u00e9 soutenus par plus de 15.000 contributeurs pour d\u00e9passer le million de dollar. Et m\u00eame si ce chiffre impressionne, ils ont d\u00e9j\u00e0 fait beaucoup&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":49366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[3989],"class_list":["post-49365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-vf","annee-3413","auteurs-kamil-sanex-ciesla","auteurs-lukasz-wlodarczyk","auteurs-robert-plesowicz","editeurs-awaken-realms","illustrateurs-piotr-gacek","distributeurs-asmodee","mecanismes-asymetrie","mecanismes-gestion-de-ressources","mecanismes-majorite","mecanismes-objectifs-communs","mecanismes-objectifs-prives","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=49365"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49365\/revisions"}],"predecessor-version":[{"id":49368,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49365\/revisions\/49368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/49366"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=49365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=49365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=49365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}