{"id":49653,"date":"2022-07-18T17:25:02","date_gmt":"2022-07-18T15:25:02","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=49653"},"modified":"2022-08-03T16:43:54","modified_gmt":"2022-08-03T14:43:54","slug":"trinidad-2","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/07\/18\/trinidad-2\/","title":{"rendered":"Trinidad"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/05\/2413-Trinidad-1.jpg\" alt=\"\" class=\"wp-image-35827\" width=\"585\" height=\"463\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/05\/2413-Trinidad-1.jpg 757w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/05\/2413-Trinidad-1-300x238.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/05\/2413-Trinidad-1-160x127.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/05\/2413-Trinidad-1-309x245.jpg 309w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/05\/2413-Trinidad-1-429x340.jpg 429w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/05\/Swa-36.1-150x150.jpg\" alt=\"\" class=\"wp-image-35828\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8\/10<\/span><\/h5>\n\n\n\n<p>Trinidad c&rsquo;est d&rsquo;abord et avant tout le dernier jeu de <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/michele-quondam\/\"><strong>Michele Quondam<\/strong><\/a>, le boss de <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/giochix-it\/\"><strong>Giochix.it<\/strong><\/a>, auteur de <a href=\"https:\/\/www.vindjeu.eu\/2017\/03\/04\/virus-aide-video\/\"><strong>Virus<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2014\/05\/22\/romolo-o-remo-aide-de-jeu\/\"><strong>Romolo O Remo<\/strong><\/a> et <a href=\"https:\/\/www.vindjeu.eu\/2012\/03\/10\/the-forgotten-planet\/\"><strong>Forgotten Planet<\/strong><\/a>).  Autant dire tout de suite qu&rsquo;on est dans le bon gros jeu expert comme on l&rsquo;aime chez Vin d&rsquo;jeu.<\/p>\n\n\n\n<p>Et Trinidad ne fait pas exception \u00e0 cette cat\u00e9gorie puisque <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/michele-quondam\/\"><strong>Michele Quondam<\/strong><\/a> s&rsquo;est inspir\u00e9 de <a href=\"https:\/\/www.vindjeu.eu\/2011\/01\/09\/rio-de-la-plata\/\"><strong>Rio de la Plata<\/strong><\/a>, un de ses premiers gros jeux pour le r\u00e9aliser. Il n&rsquo;est donc pas parti d&rsquo;une feuille blanche et a d\u00e9marr\u00e9 sur base de <a href=\"https:\/\/www.vindjeu.eu\/2011\/01\/09\/rio-de-la-plata\/\"><strong>Rio de la Plata<\/strong><\/a> en y apportant un grand nombre de modifications, assez d&rsquo;ailleurs pour en changer son nom de Trinidad. A l&rsquo;\u00e9poque de sa sortie, il y a d\u00e9j\u00e0 10 ans, on avait bien appr\u00e9ci\u00e9 le jeu bien qu&rsquo;on lui avait fait quelques reproches \u00e9galement. Voyons ensemble si ceux-ci ont disparu dans Trinidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">La base<\/span><\/h2>\n\n\n\n<p>Et c&rsquo;est donc sans grand \u00e9tonnement qu&rsquo;on d\u00e9couvre des similitudes entre les deux jeux.  Le plateau d&rsquo;abord qui y ressemble assez et le th\u00e8me de la construction de Buenos Aires qu&rsquo;on retrouve \u00e9galement.  Les pirates seront \u00e9galement de la partie et, avec les indiens autochtones, viendront de temps en temps tenter de piller la ville.  Les joueurs devront donc s&rsquo;allier temporairement pour les repousser et ensuite retourner \u00e0 ses pr\u00e9occupations plus personnelles dans ce jeu comp\u00e9titif.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-2.jpg\" alt=\"\" class=\"wp-image-49655\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-2.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">Points d&rsquo;action<\/span><\/h2>\n\n\n\n<p>La m\u00e9canique de base de Trinidad est une m\u00e9canique de points d&rsquo;action.  Le jeu se joue en 12 d\u00e9cades (= tours) r\u00e9parties en 3 \u00e8res, 4 d\u00e9cades par \u00e8re.  Chaque joueuse dispose de 6 jetons action \u00e0 chaque d\u00e9cade et les r\u00e9partit entre les actions disponibles.  Chacune va choisir une action et y placer un ou plusieurs jetons pour la r\u00e9aliser.  Ensuite, la joueuse suivante fera de m\u00eame et on tournera comme \u00e7a jusque quand chaque joueuse aura d\u00e9pens\u00e9 ses 6 jetons action.  Certaines actions n\u00e9cessitent entre 1 et 3 jetons action.  Il est donc possible de ne r\u00e9aliser que 2 actions en une d\u00e9cade ou, au contraire, d&rsquo;en r\u00e9aliser 6.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">Constructions communes<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-3.jpg\" alt=\"\" class=\"wp-image-49656\" width=\"604\" height=\"403\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-3.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/figure><\/div>\n\n\n\n<p>De plus, certaines actions vont n\u00e9cessiter de laisser ses jetons action plusieurs tours avant de pouvoir les r\u00e9cup\u00e9rer. Il s&rsquo;agit des constructions communes des b\u00e2timents majeurs. Les joueurs vont pouvoir construire, ensemble, des b\u00e2timents communs comme la Cath\u00e9drale, le Fort, le Port, les Murailles ou les Routes. Pour cela, ils vont devoir placer un ou plusieurs jetons action sur la construction en question et les laisser l\u00e0 tant que la construction n&rsquo;est pas termin\u00e9e. Les joueurs disposent en fait de 8 jetons action mais ne peuvent en d\u00e9penser que 6 \u00e0 chaque d\u00e9cade. Ce surplus leur permet de laisser 2 jetons sur les constructions communes sans en p\u00e2tir puisqu&rsquo;ils pourront toujours d\u00e9penser 6 jetons action \u00e0 chaque tour. Evidemment un joueur peut placer plus de deux jetons action sur une construction commune mais si celle-ci n&rsquo;est pas directement termin\u00e9e, il disposera alors de moins de 6 jetons action \u00e0 ses tours suivants ce qui peut \u00eatre fort pr\u00e9judiciable. Un peu comme dans <a href=\"https:\/\/www.vindjeu.eu\/2011\/01\/09\/rio-de-la-plata\/\"><strong>Rio de la Plata<\/strong><\/a>, cette m\u00e9canique va rendre les joueurs fort prudents dans l&rsquo;investissement des constructions communes. Heureusement, quelques m\u00e9caniques annexes vont les aider. Les joueurs peuvent en effet maintenant retirer leurs jetons action des constructions communes avant leur ach\u00e8vement, certains effets vont ajouter des jetons neutres pour acc\u00e9l\u00e9rer les constructions et rappelons-le, les joueurs disposent maintenant de 2 jetons actions suppl\u00e9mentaires pouvant servir \u00e0 ces constructions sans pr\u00e9judice.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">Construction de Buenos Aires<\/span><\/h2>\n\n\n\n<p>Les actions vont essentiellement concerner la construction des b\u00e2timents de la ville de Buenos Aires.  Vous aurez pour cela besoin d&rsquo;un petit tableau bien pratique (pour le moment disponible que dans les r\u00e8gles du jeu) qui indique le co\u00fbt de construction de chaque b\u00e2timent, les PVs qu&rsquo;ils rapportent, la condition n\u00e9cessaire \u00e0 leur construction et l&rsquo;effet qu&rsquo;ils procurent lorsqu&rsquo;on les active.  Quand on construit un b\u00e2timent, on doit donc payer son co\u00fbt et respecter ses conditions de construction.  On le place alors adjacent \u00e0 l&rsquo;une de ses maisons et on gagne ses PVs.  Dor\u00e9navant, on va pouvoir b\u00e9n\u00e9ficier de ses effets en l&rsquo;activant.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">On ne vit pas seul \u00e0 Buenos Aires<\/span><\/h2>\n\n\n\n<p>Mais attention, on ne vit pas seul \u00e0 Buenos Aires \ud83d\ude09 On n&rsquo;est donc pas le seul \u00e0 pouvoir profiter de l&rsquo;effet de ses b\u00e2timents. N&rsquo;importe quelle autre joueuse disposant d&rsquo;une maison adjacente \u00e0 un b\u00e2timent peut profiter de ses effets, peu importe qui l&rsquo;a construit. Et les effets ne sont pas des moindres puisque ce sont eux qui vont vous apporter la majorit\u00e9 des ressources (via la production, l&rsquo;achat ou l&rsquo;\u00e9change). Pourquoi alors construire un b\u00e2timent si les autres peuvent en profiter me direz-vous? Et bien car les b\u00e2timents sont limit\u00e9s. A deux joueurs par exemple, il n&rsquo;y a qu&rsquo;une seule carri\u00e8re permettant de gagner de la pierre et une seule menuiserie produisant du bois. Autant construire soi-m\u00eame ces b\u00e2timents pour \u00eatre sur d&rsquo;y avoir acc\u00e8s plut\u00f4t que de laisser un opposant le faire quitte \u00e0 ce qu&rsquo;il le rende inaccessible\u2026<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">Les cartes<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-5-1.jpg\" alt=\"\" class=\"wp-image-49659\" width=\"605\" height=\"403\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-5-1.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-5-1-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-5-1-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-5-1-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-5-1-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-5-1-510x340.jpg 510w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/figure><\/div>\n\n\n\n<p>Une des grandes nouveaut\u00e9s de Trinidad est l&rsquo;introduction des cartes. Le jeu propose maintenant une grosse cinquantaine de cartes toutes diff\u00e9rentes et toutes apportant des effets tr\u00e8s vari\u00e9s. Il y a d&rsquo;abord les cartes personnages dont chaque joueur recevra 2 exemplaires lors de la mise en place et devra en choisir un pour sa partie. Ces cartes vont rapporter des PVs suppl\u00e9mentaires en fonction de certaines conditions. Elles sont vraiment bienvenues car vont accentuer l&rsquo;aspect strat\u00e9gique du jeu en orientant les joueurs vers des pistes diff\u00e9rentes. Certaines cartes vont rapporter plus de PVs que d&rsquo;autres mais j&rsquo;ai trouv\u00e9 l&rsquo;\u00e9quilibre entre elles assez bien r\u00e9alis\u00e9 vu la diff\u00e9rence de difficult\u00e9 entre elles. Une carte qui rapporte plus de PVs sera g\u00e9n\u00e9ralement plus difficile \u00e0 atteindre qu&rsquo;une autre en rapportant moins et donnant d\u00e8s lors plus de libert\u00e9 pour r\u00e9aliser d&rsquo;autres actions lucratives.<\/p>\n\n\n\n<p>Outre ces cartes personnages, les joueuses auront la possibilit\u00e9 d&rsquo;acqu\u00e9rir des cartes action leur donnant des avantages divers de r\u00e9duction de c\u00fbt, de gain de ressource, de possibilit\u00e9s normalement non autoris\u00e9es,&#8230; Ces cartes, m\u00eame si elles co\u00fbtent assez cher, sont clairement bienvenues dans ce jeu plut\u00f4t froid en apportant pas mal de vari\u00e9t\u00e9 et de fun et rendant, d\u00e8s lors, Trinidad plus \u00ab\u00a0chaud\u00a0\u00bb \ud83d\ude42  Un peu de chaleur \u00e0 Buenos Aires ne fait pas de tort \ud83d\ude00<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">La guerre<\/span><\/h2>\n\n\n\n<p>A la fin de chaque d\u00e9cade, en fonction des ressources prises par chaque joueur, on va avancer le marqueur de col\u00e8re des indiens et des pirates. D\u00e8s que ces marqueurs d\u00e9passent certains seuils, ils annoncent une guerre lors du prochain tour. Lors d&rsquo;une guerre, en fonction du degr\u00e9 d&rsquo;avancement de ces marqueurs et du nombre de joueurs, un certain nombre d&rsquo;ennemis vont attaquer la ville. Il sera alors tr\u00e8s lucratif de la d\u00e9fendre et mieux vaut participer \u00e0 sa d\u00e9fense pour ne pas voir les PVs adverses filer \u00e0 votre d\u00e9triment. Les combats se d\u00e9roulent de mani\u00e8re semi al\u00e9atoire puisqu&rsquo;on connaitra la force d&rsquo;un adversaire qu&rsquo;apr\u00e8s avoir tir\u00e9 une carte au hasard. Nos cartes action vont alors pouvoir nous aider en ajoutant des points de force aux soldats qu&rsquo;on aura envoy\u00e9s au front. Ce hasard n&rsquo;est d\u00e8s lors pas du tout g\u00eanant car il est assez ais\u00e9 de pr\u00e9voir suffisamment de cartes en r\u00e9serve pour faire face aux impr\u00e9vus. Et c&rsquo;est d&rsquo;ailleurs ce qui va vous encourager \u00e0 gagner des cartes malgr\u00e9 leur co\u00fbt \u00e9lev\u00e9. Et donc, oputre pour les combats, ces cartes vous aideront dans vos autres actions.  Ca se tient bien \ud83d\ude09<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">La fin d&rsquo;une \u00e8re<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-6.jpg\" alt=\"\" class=\"wp-image-49660\" width=\"660\" height=\"440\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-6.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-6-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-6-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-6-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-6-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-6-510x340.jpg 510w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure><\/div>\n\n\n\n<p>A la fin de chaque \u00e8re, des PVs bonus vont \u00eatre distribu\u00e9s en fonction des 8 quartiers de la ville.  En effet, Buenos Aires est divis\u00e9e en 8 quartiers.  Les maisons des joueurs vont rapporter des PVs en fonction des b\u00e2timents pr\u00e9sents sur le quartier correspondant.  Les b\u00e2timents de production vont vous faire perdre des PVs tandis que les b\u00e2timents de prestige ainsi que les b\u00e2timents communs vont vous rapporter des PVs suppl\u00e9mentaires.  C&rsquo;est l\u00e0 o\u00f9 le syst\u00e8me de majorit\u00e9 va jouer puisque vous allez tenter de construire des b\u00e2timents de prestige dans les quartiers o\u00f9 vous \u00eates plus pr\u00e9sents que vos adversaires et tenter d&rsquo;augmenter le nombre de vos maisons dans les quartiers les plus lucratifs.  Et vu les contraintes de construction, tout cela va se faire avec des blocages et des courses aux endroits int\u00e9ressant.  Autant vous dire qu&rsquo;une des grandes forces de Trinidad est son interaction.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">Les salades Argentines <\/span><\/h2>\n\n\n\n<p>Et ce n&rsquo;est pas tout car Trinidad permet de nombreuses strat\u00e9gies diff\u00e9rentes vu les fa\u00e7ons diff\u00e9rentes possibles de gagner des PVs. Sans \u00eatre face \u00e0 une salade de points, il y a en effet pas mal de fa\u00e7on de gagner des PVs: en construisant des b\u00e2timents, en participant aux constructions communes, en combattant les ennemis, en envoyant des ressources \u00e0 l&rsquo;\u00e9tranger, en vendant des ressources, en profitant des cartes, en visant les majorit\u00e9s de fin d&rsquo;\u00e8re,&#8230; Trinidad est clairement un jeu riche et profond. Et cette richesse impose une certaine lourdeur. Les r\u00e8gles sont complexes et il vous faudra de nombreuses heures pour les maitriser. De plus, \u00e0 l&rsquo;heure du proto, peu d&rsquo;endroits donnent des rappels de r\u00e8gles ce qui va vous obliger \u00e0 replonger de temps \u00e0 autre dans les r\u00e8gles lors de vos premi\u00e8res parties surtout que les exceptions et petits d\u00e9tails ne sont pas rares.  Il est \u00e0 noter que Giochix nous a assur\u00e9s qu&rsquo;ils travaillaient encore sur ces aides.  Ils vont certainement am\u00e9liorer le plateau personnel ainsi que certains icones sur le plateau central.  <\/p>\n\n\n\n<p>La construction commune des b\u00e2timents majeurs est une m\u00e9canique tr\u00e8s int\u00e9ressante qui fonctionne beaucoup mieux dans Trinidad que dans Rio de la Plata gr\u00e2ce aux diff\u00e9rentes possibilit\u00e9s d&rsquo;en acc\u00e9l\u00e9rer l&rsquo;ach\u00e8vement. Il n&#8217;emp\u00eache que cette m\u00e9canique est toujours assez risqu\u00e9e et la n\u00e9gociation entre joueurs devra y jouer un r\u00f4le. Encourager un joueur \u00e0 vous aider en lui filant quelques ressources est autoris\u00e9 et avantageux. Trinidad fonctionne pour cela beaucoup mieux \u00e0 3 joueurs minimum. L&rsquo;aspect n\u00e9gociation (l&rsquo;\u00e9change de ressources est \u00e9galement autoris\u00e9), qui est primordial dans le jeu, disparait \u00e0 2. Outre la n\u00e9gociation, l&rsquo;interaction est \u00e9galement tr\u00e8s forte dans Trinidad. Depuis <a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/26\/barrage\/\"><strong>Barrage<\/strong><\/a>, la forte interaction revient \u00e0 la mode dans les jeux plus costauds et c&rsquo;est clairement une des grandes forces de Trinidad. On va se bloquer, se battre pour \u00eatre le premier \u00e0 construire certains b\u00e2timents, \u00e0 placer ceux-ci \u00e0 certains endroits, \u00e0 r\u00e9colter certaines ressources tant qu&rsquo;elles sont encore disponibles, \u00e0 gagner les majorit\u00e9s, \u00e0 gagner les cartes les plus int\u00e9ressantes, \u00e0 combattre les attaquants rapportant le plus de PVs,&#8230; De plus, \u00e0 la fin de chaque \u00e8re, les joueurs vont pouvoir voter pour ou contre une loi propos\u00e9e parmi un choix limit\u00e9 par le premier joueur (faire perdre des PVs \u00e0 un joueur, d\u00e9truire un b\u00e2timent, imposer la paix,&#8230;). Celui qui aura d\u00e9pens\u00e9 des actions pour obtenir des jetons de vote ou qui pourra influencer les autres gr\u00e2ce \u00e0 la n\u00e9gociation aura certainement un avantage&#8230; M\u00eame s&rsquo;il se veut \u00eatre un tout nouveau jeu, Trinidad reste une version am\u00e9lior\u00e9e de Rio de la Plata. M\u00eame s&rsquo;il garde sa lourdeur et sa difficult\u00e9 dans les constructions communes, Il corrige pas mal de ses \u00e9cueils, y ajoute pas mal de m\u00e9caniques int\u00e9ressantes et apporte un nouveau mat\u00e9riel somptueux, peut \u00eatre l\u00e9g\u00e8rement superflu, mais qui ne pourra qu&rsquo;attirer l&rsquo;\u0153il des geeks que nous sommes \ud83d\ude09<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-7.jpg\" alt=\"\" class=\"wp-image-49661\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-7.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-7-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-7-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-7-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-7-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-7-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">Nouvelles parties<\/span><\/h2>\n\n\n\n<p>Commen\u00e7ons par ce qui f\u00e2che le plus&nbsp;: la longueur et la\ncomplexit\u00e9.&nbsp; Trinidad est un jeu tr\u00e8s exigeant.&nbsp; Ses r\u00e8gles sont\ntouffues, complexes tout en pr\u00e9sentant certains manquements.&nbsp; Vous allez\ndevoir passer de nombreuses heures pour bien les connaitre et pour chercher\ncertaines pr\u00e9cisions disponibles que sur les forums.&nbsp; Et malgr\u00e9 \u00e7a, vous\ndevrez vous y r\u00e9f\u00e9rer durant vos premi\u00e8res parties ce qui va occasionner des\npauses plus ou moins longues dans le jeu.&nbsp; Trinidad aurait clairement\ngagn\u00e9 \u00e0 \u00eatre plus \u00e9pur\u00e9 surtout qu\u2019une partie dure ais\u00e9ment 5 heures.&nbsp;\nC\u2019est long&nbsp;!&nbsp; Si vous devez en plus expliquer les r\u00e8gles avant, ayez\nbien 6h30 devant vous avant de commencer une partie.&nbsp; Et son \u00e9puration\naurait fait gagner en fluidit\u00e9.&nbsp; Le jeu propose tellement de choix qu\u2019un\npeu moins de possibilit\u00e9s l\u2019aurait rendu plus digeste.&nbsp; De plus, il faut\n\u00e9viter le jeu \u00e0 2 ou en solo.&nbsp; Le jeu gagne \u00e0 \u00eatre jou\u00e9 \u00e0 3 ou 4.&nbsp; A\ndeux, le \u00ab&nbsp;robot&nbsp;\u00bb est indispensable mais apporte aussi beaucoup de\nlourdeur au jeu.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-8.jpg\" alt=\"\" class=\"wp-image-49662\" width=\"606\" height=\"404\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-8.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/><\/figure><\/div>\n\n\n\n<p>Mais si cette exigence ne vous fait pas peur, Trinidad est un pur bonheur.&nbsp; Il offre des choix strat\u00e9giques nombreux et difficiles.&nbsp; Et tout comme dans <strong><a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/26\/barrage\/\">Barrage<\/a><\/strong>, son interaction est au top&nbsp;!&nbsp; Vous allez vous battre sur tout&nbsp;: les meilleurs emplacements sur la carte, les ressources limit\u00e9es, les b\u00e2timents \u00e0 construire (m\u00eame si tout le monde peut en profiter \u00e0 condition d\u2019y \u00eatre adjacent\u2026&nbsp;: les blocages vont \u00eatre nombreux pour emp\u00eacher vos adversaires de pouvoir les atteindre) et les diff\u00e9rents jeux de majorit\u00e9 sur l\u2019argent, la foi et le militaire.&nbsp; Il y a \u00e9galement un jeu entre les joueurs pour d\u00e9clencher une guerre au meilleur moment, quand vous \u00eates suffisamment \u00e9quip\u00e9s alors que vos adversaires non\u2026&nbsp; Et toutes ces possibilit\u00e9s strat\u00e9giques sont fantastiques&nbsp;: viser les majorit\u00e9s, construire les meilleurs b\u00e2timents, faire voter les meilleures lois, optimiser les points apport\u00e9s par son leader, remplir les objectifs des banni\u00e8res, remporter les guerres, gagner les influences des quartiers, construire les gros b\u00e2timents,\u2026&nbsp; <\/p>\n\n\n\n<p>J\u2019adore Trinidad qui est un des jeux qui apporte le plus de profondeur et le plus de possibilit\u00e9s.&nbsp; Dommage juste qu\u2019il soit si exigeant et trop peu \u00e9pur\u00e9 car \u00e7a le rend beaucoup plus difficile \u00e0 sortir.&nbsp; Et si vous n\u2019enchainez pas les parties, il risque de rester longtemps sur vos \u00e9tag\u00e8res avant d\u2019\u00eatre ressorti.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/04\/Phil-7-150x150.jpg\" alt=\"\" class=\"wp-image-41799\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">PhilRey<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Trinidad est une r\u00e9\u00e9dition de Rio de La Plata, un jeu qu\u2019on avait bien appr\u00e9ci\u00e9 \u00e0 sa sortie il y a une dizaine d\u2019ann\u00e9e. Le jeu, malgr\u00e9 les am\u00e9liorations par rapport \u00e0 son ain\u00e9, n\u2019est pas d\u00e9pourvu de d\u00e9fauts. Et je vais commencer par eux.<\/p>\n\n\n\n<p>Le premier, temporaire, consiste en des r\u00e8gles pas toujours tr\u00e8s claires avec quelques illustrations mais pas \u00e9norme compar\u00e9e \u00e0 d\u2019autres. Le point le plus compliqu\u00e9 touche les r\u00e8gles concernant le joueur virtuel. En effet, seul ou \u00e0 deux, un joueur fictif, avec ses propres cartes, participe \u00e0 la partie. Et c\u2019est une bonne id\u00e9e en soi. Seulement, pas mal d\u2019int\u00e9rogation quant au placement des b\u00e2timent o\u00f9 des cas de figure ne sont pas bien expliqu\u00e9s. Dans ces cas-l\u00e0, il faut avantager le joueur fictif mais c\u2019est potentiellement sujet \u00e0 interpr\u00e9tation entre les deux joueurs pr\u00e9sents.Maintenant, le jeu est complexe et j\u2019imagine qu\u2019il n\u2019est pas \u00e9vident de pondre des r\u00e8gles pour ce genre de jeu.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-10.jpg\" alt=\"\" class=\"wp-image-49904\" width=\"611\" height=\"407\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-10.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-10-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-10-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-10-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-10-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-10-510x340.jpg 510w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/><\/figure><\/div>\n\n\n\n<p>Ensuite, la longueur d\u2019une partie est importante: comptez plusieurs heures, surtout lors de vos premi\u00e8res parties. Trinidad ne sera donc pas facile \u00e0 sortir car il faudra pr\u00e9voir une longue soir\u00e9e ou une apr\u00e8s-midi pluvieuse. Surtout si les r\u00e8gles doivent \u00e9galement \u00eatre expliqu\u00e9es \u00e0 certains joueurs. Alors oui, il y a moyen de racourcir en ne jouant que 2 \u00e8res (au lieu de 3) mais je pense (car je n\u2019ai pas essay\u00e9) qu\u2019on perd pas mal de chose. Notemment la construction des grands b\u00e2timents qui seront alors plus difficiles.<\/p>\n\n\n\n<p>N\u00e9anmoins, malgr\u00e9 ces deux points n\u00e9gatifs, Trinidad a pas mal d\u2019autres choses positives \u00e0 offrir.<\/p>\n\n\n\n<p>D\u2019abord, et c\u2019est quelquechose que j\u2019appr\u00e9cie beaucoup, le plateau de construction est central et commun \u00e0 tous les joueurs. Certes, ce n\u2019est pas le premier jeu \u00e0 offrir cela mais c\u2019est assez rare. En effet, souvent les joueurs d\u00e9veloppent sur leur plateau individuel, dans le coin.&nbsp;Ce plateau central augmente d\u2019autant l\u2019interaction entre les joueurs. Plus encore par le fait que les b\u00e2timents de production n\u2019appartiennent \u00e0 aucun joueur et chacun peut en b\u00e9n\u00e9ficier. Le placeent de ses lotissements et maisons prennent nettement plus d\u2019importance.<\/p>\n\n\n\n<p>Ensuite, et c\u2019est sans doute une des m\u00e9caniques au coeur de Trinidad: la gestion des ressources. Le bois, la pierre, l\u2019or et les pi\u00e8ces (de bronze et d\u2019argent) sont limit\u00e9s \u00e0 ce qui est disponible sur le plateau. Une ressource peut donc devenir rare et cela peut \u00eatre une tactique \u00e0 avoir \u00e0 certains moments contre ses adversaires. Faut-il \u00e9puiser totalement une grille de pierre afin qu\u2019elle soit alimenter \u00e0 nouveau \u00e0 la fin de l\u2019\u00e8re? Ou plut\u00f4t laisser une minable pierre pour justement \u00e9viter d\u2019en avoir en abondance lors de l\u2019\u00e8re suivante? Cette gestion de ressources est vraiment succulente.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-9.jpg\" alt=\"\" class=\"wp-image-49905\" width=\"608\" height=\"405\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-9.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-9-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-9-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-9-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-9-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-9-510x340.jpg 510w\" sizes=\"auto, (max-width: 608px) 100vw, 608px\" \/><\/figure><\/div>\n\n\n\n<p>Autre \u00e9l\u00e9ment, peut-\u00eatre un peu plus classique mais quand m\u00eame li\u00e9 \u00e0 la gestion de ressources (ce qui d\u00e9montre l\u2019imbrication des m\u00e9canismes): les Natifs et les Pirates. Les deux vont attaquer Trinidad d\u00e8s que leur marqueur de Tension atteint un certain niveau sur leur \u00e9chelle de puissance. Pour les Natifs, le jeton avance d\u2019une case pour chaque grille de ressource vide (pierre et bois). Pour le th\u00e8me, ils n\u2019appr\u00e9cient gu\u00e8re que l\u2019on pie leurs ressources naturelles. Pour les Pirates, le jeton avance d\u2019une case par grille d\u2019or et pile de pi\u00e8ces vide. Dans le th\u00e8me, les pirates sont attir\u00e9s par tout ce qui brille (or, argent, etc.). Ici aussi, un joueur mieux arm\u00e9 peut justement alimenter cette tension (en vidant les ressources) pour p\u00e9naliser un ou plusieurs adversaires.<\/p>\n\n\n\n<p>Trinidad offre encore plein d\u2019autres m\u00e9caniques bas\u00e9es sur le placement de jetons Action (souvent exigeant des ressources), l\u2019activation de cartes ou encore des actions gratuites. Les actions sont reprises sur le plateau personnel de chaque joueur (identiques pour tous) et permettent de construire des b\u00e2timents: carri\u00e8res (production de pierres), Menuiserie (production de bois), lotissement (pour activer les b\u00e2timents adjacents); d\u2019activer des b\u00e2timents (pour produire des ressources, enr\u00f4ler des miliciens ou les former en soldat), etc. Le plateau central permet de construire des b\u00e2timents majeurs qui rapportent des PVs mais bloquent des jetons Action jusqu\u2019\u00e0 ce que la construction soit compl\u00e9t\u00e9e (Cath\u00e9drale, Port, H\u00f4tel de Ville, etc.), commercer avec l\u2019Espagne (une mani\u00e8re de r\u00e9colter du m\u00e9tal).<br>On retrouve aussi un petit tableau d\u2019am\u00e9liorationssur 4 cat\u00e9gories: cartes, PVs, ouvriers et construction). Ici aussi, il faudra choisir car chaque joueur ne poss\u00e8de que deux jetons Status. Et ces m\u00eames jetons peuvent aussi servir \u00e0 marquer certains b\u00e2timents.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-4.jpg\" alt=\"\" class=\"wp-image-49657\" width=\"637\" height=\"425\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-4.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 637px) 100vw, 637px\" \/><\/figure><\/div>\n\n\n\n<p>Enfin, \u00e0 la fin de chaque d\u00e9cennie, plein de chose se passe encore.C\u2019est maintenant que votre navire revient d\u2019Espagne avec votre cargaison (si vous avez fait cette action). C\u2019est maintenant seulement que vous pouvez r\u00e9activer vos cartes (uniquement si vous avez utiliser l\u2019action le permettant). C\u2019est aussi en fin d\u2019\u00e8re qu\u2019on v\u00e9rifie le niveau de tension de pirates et des natifs et que les attaques se d\u00e9clenchent. On r\u00e9approvisionne les grilles et piles de ressources et pi\u00e8ces vides (et uniquement celles qui sont compl\u00e8tement vides).&nbsp;Et si c\u2019est la fin de l\u2019\u00e8re, on proc\u00e8de \u00e0 un d\u00e9compte:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>PVs pour le joueur le plus riche<\/li><li>PVs pour le joueur le plus avanc\u00e9 militairement (c\u2019est \u00e0 dire avec l\u2019unit\u00e9 la plus forte en sa possession)<\/li><li>PVs pour le joueur avec le plus de jeton de Foix<\/li><li>PVs pour les s\u00e9ries de cartes de m\u00eame type<\/li><li>PVs par district (ce sont les maisons ici qui permettent de marquer des points)<\/li><\/ul>\n\n\n\n<p>A noter, et c\u2019est peut-\u00eatre un autre point n\u00e9gatif, les trois premiers peuvent donner la victoire. En effet, il s\u2019ag\u00eet de gagner 7 PVs x l\u2019\u00e8re en cours. Si un joueur parvient \u00e0 \u00eatre majoritaire dans les trois (riche, Foix et militaire), il peut se faire 21 x 2 \u00e0 la fin de l\u2019\u00e8re II (42 PVs) et m\u00eame 21 x 3 \u00e0 la fin de l\u2019\u00e8re III (soit 63 points). Certainement \u00e0 ne pas n\u00e9gliger!<\/p>\n\n\n\n<p>Malgr\u00e9 les d\u00e9fauts soulign\u00e9s plus haut, Trinidad est vraiment un jeu exigeant mais profond, tactique mais offrant diverses strat\u00e9gies, et en ne p\u00e9nalisant pas l\u2019interaction entre les joueurs! <\/p>\n\n\n\n<p>Allez, y\u2019plus qu\u2019\u00e0 sortir des r\u00e8gles plus \u00ab&nbsp;buvables&nbsp;\u00bb et il ne restera que la dur\u00e9e comme gros b\u00e9mol!<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15.jpg\" alt=\"\" class=\"wp-image-49654\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/3238-Trinidad-15-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#366ce3\" class=\"color\">Vin d&rsquo;jeu d&rsquo;vid\u00e9os<\/span><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Explication &amp; d\u00e9gustation du proto en 25 minutes partie 1<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Trinidad (Explication et d\u00e9gustation du jeu partie 1)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/2rxFghtr_SA?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Explication et d\u00e9gustation du proto en 15 minutes partie 2<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Trinidad (Explication et d\u00e9gustation du jeu partie 2)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Ug4y_xfpLPY?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles du jeu publi\u00e9 par Philrey<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Trinidad (Explication des r\u00e8gles et d\u00e9gustation du jeu)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/KTvXg1QZwbg?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Trinidad c&rsquo;est d&rsquo;abord et avant tout le dernier jeu de Michele Quondam, le boss de Giochix.it, auteur de Virus, Romolo O Remo et Forgotten Planet). Autant dire tout de suite qu&rsquo;on est dans le bon gros jeu expert comme on l&rsquo;aime chez Vin d&rsquo;jeu. Et Trinidad ne fait&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":35827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[],"class_list":["post-49653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","annee-3413","auteurs-michele-quondam","editeurs-giochix-it","illustrateurs-fabio-porfidia","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","mecanismes-asymetrie","mecanismes-gestion-de-ressources","mecanismes-majorite","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=49653"}],"version-history":[{"count":7,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49653\/revisions"}],"predecessor-version":[{"id":49929,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49653\/revisions\/49929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/35827"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=49653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=49653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=49653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}