{"id":49828,"date":"2022-08-09T21:38:02","date_gmt":"2022-08-09T19:38:02","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=49828"},"modified":"2022-08-09T21:38:35","modified_gmt":"2022-08-09T19:38:35","slug":"papillons-celestes","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/08\/09\/papillons-celestes\/","title":{"rendered":"Papillons celestes"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80290-grande.jpg\" alt=\"\" class=\"wp-image-49829\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/Claire-Flip.jpg\" alt=\"\" class=\"wp-image-49822\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple :<\/span> <span style=\"color:#cf2e2e\" class=\"color\">7\/10<\/span><\/h5>\n\n\n\n<p>Dans ce jeu, exclusivement pour deux, on incarne un l\u00e9pidopt\u00e9riste.\nCe mot savant, qui permet de marquer des points au scrabble, signifie que vous\ncollectionnez et \u00e9tudiez les papillons. Il y a en tout cinq esp\u00e8ces diff\u00e9rentes\nqui, en fonction du nombre d\u2019exemplaire en votre possession, rapportent plus ou\nmoins de points. Toute la strat\u00e9gie d\u00e9coule de leur acquisition. <\/p>\n\n\n\n<p>Au d\u00e9but de la partie, une carte Disposition indiquant la\nmise en place, est pioch\u00e9e. Comme dans le jeu <a href=\"https:\/\/www.vindjeu.eu\/2015\/12\/22\/7-wonders-duel\/\">7 wonders duel<\/a>,\nl\u2019acquisition des cartes repose sur le principe de Mahjong mais avec certaines\ncartes qui sont face cach\u00e9e. C\u2019est-\u00e0-dire que l\u2019on ne peut r\u00e9cup\u00e9rer une carte\nque si elle n\u2019est pas chevauch\u00e9e par une autre. Cet aspect offre une strat\u00e9gie\nint\u00e9ressante puisqu\u2019en enlevant une carte, vous pouvez en lib\u00e9rer une que votre\nadversaire peut prendre. Il faut donc trouver un juste \u00e9quilibre entre choisir\nles papillons pour compl\u00e9ter sa propre collection sans trop favoriser l\u2019autre\njoueur. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80288-grande-300x200.jpg\" alt=\"\" class=\"wp-image-49830\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80288-grande-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80288-grande-768x513.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80288-grande-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80288-grande-367x245.jpg 367w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80288-grande-509x340.jpg 509w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/papillons-celestes-p-image-80288-grande.jpg 904w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La partie s\u2019ach\u00e8ve quand un participant a trois victoires. Il y a donc au minimum trois mises en place diff\u00e9rentes.<br><\/p>\n\n\n\n<p>Le scoring des papillons est simple et tr\u00e8s explicite sur\nles cartes. Il n\u2019y a que le Grand Bolina qui a une fonction diff\u00e9rente\npuisqu\u2019il permet de le placer sur l\u2019emplacement de la carte r\u00e9cup\u00e9r\u00e9e, bloquant\nainsi les papillons de dessous pour l\u2019adversaire. Mais il faut le jouer avec\nprudence car celui qui le poss\u00e8de remporte toutes les \u00e9galit\u00e9s. <\/p>\n\n\n\n<p>Papillons c\u00e9lestes est parfait pour d\u00e9buter avec les jeux de collection car le nombre r\u00e9duit de sp\u00e9cimen permet de diminuer les axes strat\u00e9giques. Nous aurions aim\u00e9 que ce jeu poss\u00e8de aussi une version pour des joueurs connaisseurs.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/IMG_E3317-768x1024.jpg\" alt=\"\" class=\"wp-image-49831\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/IMG_E3317-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/IMG_E3317-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/IMG_E3317-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/IMG_E3317-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/07\/IMG_E3317-255x340.jpg 255w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans ce jeu, exclusivement pour deux, on incarne un l\u00e9pidopt\u00e9riste qui collectionne les papillons. Il y a en tout cinq esp\u00e8ces diff\u00e9rentes qui, en fonction du nombre d\u2019exemplaire en votre possession, rapportent plus ou moins de points. Toute la strat\u00e9gie d\u00e9coule de leur acquisition. <\/p>\n","protected":false},"author":10,"featured_media":49829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-49828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-3413","auteurs-joel-lewis","editeurs-lucky-duck-games","illustrateurs-dejana-louise-watson","nombre_conseille-1185"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=49828"}],"version-history":[{"count":1,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49828\/revisions"}],"predecessor-version":[{"id":49832,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/49828\/revisions\/49832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/49829"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=49828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=49828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=49828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}