{"id":50233,"date":"2022-09-22T19:42:34","date_gmt":"2022-09-22T17:42:34","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=50233"},"modified":"2022-09-22T19:43:00","modified_gmt":"2022-09-22T17:43:00","slug":"sans-filtre","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/09\/22\/sans-filtre\/","title":{"rendered":"Sans filtre"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre.jpg\" alt=\"\" class=\"wp-image-50234\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre.jpg 800w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/Claire-desert.jpg\" alt=\"\" class=\"wp-image-49027\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple :<\/span> <span style=\"color:#cf2e2e\" class=\"color\">6\/10<\/span><\/h5>\n\n\n\n<p>Vous est-il arriv\u00e9 d\u2019avoir du mal \u00e0 rester bienveillant et\ncalme quand vos gentils bambins vous poussent \u00e0 bout&nbsp;? Ce n\u2019est pas\ntoujours simple et il est possible que des remarques cinglantes vous passent\npar la t\u00eate. <strong>Sans filtre<\/strong> est un jeu\npour les parents qui ont besoin de \u00ab&nbsp;vider leur sac&nbsp;\u00bb loin des\noreilles de vos charmantes t\u00eates blondes (brunes ou rousses d\u2019ailleurs). <\/p>\n\n\n\n<p>Dans <strong>Sans filtre<\/strong>,\nchaque participant poss\u00e8de six cartes Sans filtre qui sont en r\u00e9alit\u00e9 des\nremarques acerbes. Le joueur actif pioche une carte Casse-bonbons repr\u00e9sentant\nune demande de nos enfants. Chacun doit alors choisir une r\u00e9ponse parmi celles\nqu\u2019il a en main. Le joueur actif choisit alors le participant qui remporte le\nCasse-bonbons gr\u00e2ce \u00e0 sa meilleure r\u00e9partie.<\/p>\n\n\n\n<p>Clairement, ce n\u2019est pas un jeu auquel je jouerais tous les\nsoirs et c\u2019est pour cela que je ne lui mets qu\u2019un 6. Mais je dois reconna\u00eetre\nque j\u2019ai bien ri quand m\u00eame. C\u2019est parfois m\u00e9chant mais pouvoir expurger ses\nmauvaises pens\u00e9es avec des amis qui ont les m\u00eames, s\u2019av\u00e8re un bon exutoire.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1.jpg\" alt=\"\" class=\"wp-image-50235\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1.jpg 800w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/parent-epuise-sans-filtre-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous est-il arriv\u00e9 d\u2019avoir du mal \u00e0 rester bienveillant et calme quand vos gentils bambins vous poussent \u00e0 bout ? Ce n\u2019est pas toujours simple et il est possible que des remarques cinglantes vous passent par la t\u00eate.<\/p>\n","protected":false},"author":10,"featured_media":50234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-50233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-3413","auteurs-parent-epuise","editeurs-funomenum","distributeurs-asmodee","mecanismes-jeu-dambiance"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/50233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=50233"}],"version-history":[{"count":1,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/50233\/revisions"}],"predecessor-version":[{"id":50236,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/50233\/revisions\/50236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/50234"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=50233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=50233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=50233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}