{"id":51060,"date":"2022-11-05T12:40:51","date_gmt":"2022-11-05T11:40:51","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=51060"},"modified":"2022-11-05T12:42:23","modified_gmt":"2022-11-05T11:42:23","slug":"east-india-companies","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/11\/05\/east-india-companies\/","title":{"rendered":"East India Companies"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-1.jpg\" alt=\"\" class=\"wp-image-51062\" width=\"534\" height=\"532\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-1.jpg 602w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-1-246x245.jpg 246w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-1-341x340.jpg 341w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/Swa-70-FBA-III-1-150x150.jpg\" alt=\"\" class=\"wp-image-50967\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>East India Companies est le second jeu de Pascal Ribrault qui pr\u00e9sente d\u00e9j\u00e0 un CV ludique impressionnant puisque son premier jeu n&rsquo;est rien d&rsquo;autre que l&rsquo;excellent <a href=\"https:\/\/www.vindjeu.eu\/2021\/12\/30\/virtu\/\"><strong>Virt\u00f9<\/strong><\/a>!  <\/p>\n\n\n\n<p>East India Companies est un jeu tr\u00e8s particulier. J&rsquo;ai envie de dire que c&rsquo;est un peu <strong>la porte d&rsquo;entr\u00e9e aux jeux 18XX<\/strong> (en jeu expert quand m\u00eame) m\u00eame s&rsquo;il a peu \u00e0 voir avec ce type de jeu puisqu&rsquo;il n&rsquo;y a pas de ligne de train dans East India Companies \ud83d\ude09 J&rsquo;oserais m\u00eame dire qu&rsquo;il repr\u00e9sente le chainon manquant entre les 18XX et <a href=\"https:\/\/www.vindjeu.eu\/2019\/11\/28\/brass-lancashire-vf\/\"><strong>Brass<\/strong><\/a>!!! (mais non je ne fais pas de comparaison audacieuse \ud83d\ude09 ).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Stock exchange<\/span><\/h2>\n\n\n\n<p>En effet, dans East India Companies, vous allez g\u00e9rer une compagnie navale qui va aller en Inde acheter des ressources pour les revendre en Europe. Vous d\u00e9tenez des actions de cette compagnie et vous allez \u00eatre amen\u00e9s \u00e0 <strong>acheter et vendre des actions<\/strong> des compagnies adverses et m\u00eame des v\u00f4tres. La valeur de ces actions va fluctuer en fonction de l&rsquo;efficacit\u00e9 de son gestionnaire \ud83d\ude09 Et plus la valeur d&rsquo;une action sera \u00e9lev\u00e9e, plus les <strong>dividendes <\/strong>que la compagnie devra distribuer seront \u00e9lev\u00e9s (et troueront ses caisses \ud83d\ude42 ).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Market<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2-1024x768.jpg\" alt=\"\" class=\"wp-image-51065\" width=\"564\" height=\"423\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-2.jpg 1210w\" sizes=\"auto, (max-width: 564px) 100vw, 564px\" \/><\/figure><\/div>\n\n\n\n<p>A cela vient s&rsquo;ajouter un jeu d&rsquo;<strong>achat et vente de ressources<\/strong> et de fluctuation du march\u00e9. Une carte march\u00e9 va indiquer le nombre de ressources produites en Inde et une autre indiquera le nombre de ressources demand\u00e9es en Europe. Les joueurs devront acheter les ressources en fonction de cette offre et cette demande <strong>sans les connaitre \u00e0 l&rsquo;avance<\/strong> car elles seront d\u00e9voil\u00e9es apr\u00e8s. C&rsquo;est ce qui me chagrine le plus dans East India Companies. On man\u0153uvre un peu trop \u00e0 l&rsquo;aveugle dans ce march\u00e9 m\u00eame si deux actions permettent de mieux le maitriser mais tout le monde ne pourra pas les r\u00e9aliser. J&rsquo;aurais aim\u00e9 un syst\u00e8me plus \u00e9l\u00e9gant surtout qu&rsquo;il va bien <strong>influencer sur les b\u00e9n\u00e9fices<\/strong> des compagnies et donc sur l&rsquo;argent que les joueurs auront \u00e0 leur disposition pour acheter de nouvelles actions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Workers<\/span><\/h2>\n\n\n\n<p>Les actions du jeu pourront \u00eatre r\u00e9alis\u00e9es gr\u00e2ce \u00e0 un syst\u00e8me de <strong>placement d&rsquo;ouvriers<\/strong> assez classique bien que l&rsquo;endroit o\u00f9 chaque ouvrier se situe va influencer sur les actions qu&rsquo;il pourra r\u00e9aliser au tour d&rsquo;apr\u00e8s. Vous allez pouvoir acheter des <strong>fr\u00e9gates <\/strong>qui iront plus ou moins vite et qui auront une calle plus ou moins grande afin d&rsquo;\u00eatre sur place avant les autres et de pouvoir acheter ou vendre un nombre de denr\u00e9es plus ou moins important.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#7bdcb5\" class=\"color\">Innovative<\/span><\/h2>\n\n\n\n<p>Au final, East India Compagnies apporte un vent de fraicheur aux <strong>jeux d&rsquo;investissements et de fluctuation de march\u00e9<\/strong>. M\u00eame si j&rsquo;ai moins aim\u00e9 l&rsquo;al\u00e9a des march\u00e9s et son manque de contr\u00f4le, le jeu surprend tant il propose des <strong>r\u00e8gles simples<\/strong> qui s&rsquo;expliquent en 25 minutes et une belle profondeur dans des m\u00e9canismes qu&rsquo;on a moins l&rsquo;habitude de jouer dans les eurogames actuels. <strong>La variabilit\u00e9 des parties<\/strong> n&rsquo;est pas non plus le grand fort du jeu puisqu&rsquo;aucun m\u00e9canisme d&rsquo;objectif de partie, de bonus multiples ou de capacit\u00e9s asym\u00e9triques n&rsquo;intervient dans le jeu, ce qui est assez perturbant pour des eurogamers comme nous \ud83d\ude09 On y perd ses rep\u00e8res et c&rsquo;est bien la preuve d&rsquo;un jeu innovant et int\u00e9ressant.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1412\" height=\"1059\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15.jpg\" alt=\"\" class=\"wp-image-51061\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15.jpg 1412w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3323-East-India-Comp-15-453x340.jpg 453w\" sizes=\"auto, (max-width: 1412px) 100vw, 1412px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> East India Companies est le second jeu de Pascal Ribrault qui pr\u00e9sente d\u00e9j\u00e0 un CV ludique impressionnant puisque son premier jeu n&rsquo;est rien d&rsquo;autre que l&rsquo;excellent Virt\u00f9! East India Companies est un jeu tr\u00e8s particulier. J&rsquo;ai envie de dire que c&rsquo;est un peu la porte d&rsquo;entr\u00e9e aux jeux&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":51062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[4057],"class_list":["post-51060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-essen-2022","annee-3413","auteurs-pascal-ribrault","editeurs-atalia","editeurs-huch","editeurs-rd-games","illustrateurs-guillaume-tavernier","distributeurs-atalia","nombre_conseille-1210","nombre_conseille-1355","mecanismes-marche","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=51060"}],"version-history":[{"count":6,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51060\/revisions"}],"predecessor-version":[{"id":51276,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51060\/revisions\/51276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/51062"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=51060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=51060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=51060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}