{"id":51691,"date":"2022-12-21T15:07:22","date_gmt":"2022-12-21T14:07:22","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=51691"},"modified":"2022-12-22T14:18:28","modified_gmt":"2022-12-22T13:18:28","slug":"mysterium-kids-le-tresor-du-capitaine-bouh","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/12\/21\/mysterium-kids-le-tresor-du-capitaine-bouh\/","title":{"rendered":"Mysterium Kids : Le tr\u00e9sor du capitaine Bouh"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/mysterium-kids-le-tresor-du-capitaine-bouh-p-image-82930-grande.jpg\" alt=\"\" class=\"wp-image-51692\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/01\/Claire-hiver.jpg\" alt=\"\" class=\"wp-image-46833\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple :<\/span> <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Apr\u00e8s<a href=\"https:\/\/www.vindjeu.eu\/2015\/04\/13\/mysterium\/\"> Mysterium<\/a> et<a href=\"https:\/\/www.vindjeu.eu\/2020\/11\/09\/mysterium-park\/\"> Mysterium Park<\/a>, gr\u00e2ce \u00e0<a href=\"https:\/\/www.vindjeu.eu\/?s=space+cow\"> Space Cow<\/a> les enfants ont enfin leur version, avec des r\u00e8gles simplifi\u00e9es certes, mais en gardant cette bonne ambiance. Le tr\u00e8s beau mat\u00e9riel repr\u00e9sente un manoir sur lequel sont plac\u00e9es cinq cartes Objet. Les enfants ont six tours pour retrouver un maximum de tr\u00e9sors. Pour cela, ils vont incarner le fant\u00f4me \u00e0 tour de r\u00f4le. Dans cette version, il n&rsquo;y a pas de ma\u00eetre de jeu.<\/p>\n\n\n\n<p>Le r\u00f4le du fant\u00f4me est d\u2019aider ses partenaires \u00e0 retrouver l\u2019objet associ\u00e9 au jeton Fant\u00f4me qu\u2019il a pioch\u00e9. Contrainte de taille, il ne doit ni dessiner ni mimer mais seulement utiliser un tambourin pour reproduire le bruit de l\u2019objet. Succ\u00e8s garanti, tout le monde se bat pour \u00eatre le fant\u00f4me ! Si l\u2019objet est identifi\u00e9, un tr\u00e9sor est pioch\u00e9. Au bout des six tours, on compte le nombre d\u2019\u00e9toiles pr\u00e9sentes sur les tr\u00e9sors et on compare le score \u00e0 un tableau de r\u00e9ussite.<\/p>\n\n\n\n<p><strong>Mysterium Kids : Le tr\u00e9sor du capitaine Bouh<\/strong> est vraiment tr\u00e8s simple et se destine aux enfants \u00e0 partir de 5\/6 ans. Je trouve un peu dommage que la fin consiste simplement \u00e0 consulter le tableau de r\u00e9ussite car cela ne parle pas vraiment aux petits mais c\u2019est vrai que cela ne les d\u00e9range pas trop, l\u2019essentiel pour eux \u00e9tant d\u2019incarner le fant\u00f4me. Par contre, il n&rsquo;est pas toujours \u00e9vident de deviner l\u2019objet car imiter le bruit d\u2019une allumette sur un tambourin n\u2019est pas chose ais\u00e9e.<\/p>\n\n\n\n<p>J\u2019ai quand m\u00eame une question : le tambourin \u00e9tait-il vraiment n\u00e9cessaire ? Je n\u2019imaginais pas qu\u2019une petite araign\u00e9e puisse faire autant de bruit !<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"984\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E44011-1024x984.jpg\" alt=\"\" class=\"wp-image-51696\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E44011-1024x984.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E44011-300x288.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E44011-768x738.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E44011-160x154.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E44011-255x245.jpg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E44011-354x340.jpg 354w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s Mysterium et Mysterium Park, gr\u00e2ce \u00e0 Space Cow les enfants ont enfin leur version, avec des r\u00e8gles simplifi\u00e9es certes, mais en gardant cette bonne ambiance. <\/p>\n","protected":false},"author":10,"featured_media":51692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3354],"tags":[],"class_list":["post-51691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enfant","annee-3413","auteurs-antonin-boccara","editeurs-libellud","illustrateurs-yves-hirschfeld","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","nombre_conseille-1321","mecanismes-cooperatif","mecanismes-deduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=51691"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51691\/revisions"}],"predecessor-version":[{"id":51697,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51691\/revisions\/51697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/51692"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=51691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=51691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=51691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}