{"id":51699,"date":"2022-12-21T15:08:44","date_gmt":"2022-12-21T14:08:44","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=51699"},"modified":"2022-12-22T18:34:35","modified_gmt":"2022-12-22T17:34:35","slug":"le-tresor-de-davy-jones","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2022\/12\/21\/le-tresor-de-davy-jones\/","title":{"rendered":"Le tr\u00e9sor de Davy Jones"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81220-grande.jpg\" alt=\"\" class=\"wp-image-51701\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/Claire-Mer-1.jpg\" alt=\"\" class=\"wp-image-45425\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple : <\/span><span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Les origines de la l\u00e9gende de Davy Jones sont obscures.\nCependant les fans de Pirates des Cara\u00efbes se rappellent sans aucun doute de ce\nprotagoniste des deuxi\u00e8me et troisi\u00e8me films. <\/p>\n\n\n\n<p>Dans le jeu <strong>Le tr\u00e9sor\nde Davy Jones<\/strong>, les joueurs collaborent pour fouiller, r\u00e9cup\u00e9rer les tr\u00e9sors\net surtout sortir du bateau du c\u00e9l\u00e8bre pirate. Avec un mat\u00e9riel de tr\u00e8s bonne\nqualit\u00e9, l\u2019immersion est assez r\u00e9ussie.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0 l\u2019abordage<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"243\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4411-300x243.jpg\" alt=\"\" class=\"wp-image-51702\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4411-300x243.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4411-768x622.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4411-1024x829.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4411-160x130.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4411-303x245.jpg 303w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4411-420x340.jpg 420w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption>Plateau joueur<\/figcaption><\/figure><\/div>\n\n\n\n<p>Tout d\u00e9bute par l\u2019accostage du Sk\u00e9lit, dans lequel est\namass\u00e9 le fabuleux tr\u00e9sor de Davy Jones. Ce dernier est en flamme, il va donc\nfalloir agir vite pour r\u00e9cup\u00e9rer les butins et tous ressortir. Chaque joueur\nchoisit un des sept pirates disponibles et l\u2019\u00e9quipe d\u2019un objet au choix parmi\nsept. Chaque pirate a un avantage unique qui, combin\u00e9 \u00e0 un objet, permet une\ngrande vari\u00e9t\u00e9. \u00c0 son tour, on commence par placer une nouvelle pi\u00e8ce du\nbateau et \u00e0 piocher un jeton \u00c9v\u00e8nement, puis on r\u00e9alise plusieurs\nactions en d\u00e9faussant l\u2019un de ses cinq jetons. Il est possible de se d\u00e9placer\nen marchant ou en courant, de combattre l\u2019incendie, d\u2019\u00e9liminer un damn\u00e9,\nramasser des objets, augmenter sa force de combat, ou de boire du rhum pour\nr\u00e9duire sa fatigue. La gestion de la fatigue est un \u00e9l\u00e9ment important car elle\naugmente \u00e0 chaque fois qu\u2019un personnage entre dans un lieu avec un incendie\nplus fort que celui qu\u2019il quitte. Cela n\u2019a l\u2019air de rien, mais une grande\nfatigue limite les possibilit\u00e9s de d\u00e9placement et peut m\u00eame aller jusqu\u2019\u00e0 la\nmort. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"145\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4413-300x145.jpg\" alt=\"\" class=\"wp-image-51703\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4413-300x145.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4413-768x372.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4413-1024x497.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4413-160x78.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4413-505x245.jpg 505w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4413-701x340.jpg 701w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption>Cartes Ch\u00e2timent<\/figcaption><\/figure><\/div>\n\n\n\n<p>Quand le pirate actif a termin\u00e9 ses actions, une carte\nCh\u00e2timent est r\u00e9v\u00e9l\u00e9e. Le bateau se d\u00e9fend de deux mani\u00e8res&nbsp;: en\naugmentant les incendies dans certaines zones et\/ou en ajoutant des damn\u00e9s, et en\nd\u00e9pla\u00e7ant des squelettes. Lorsque l\u2019on rentre dans une pi\u00e8ce o\u00f9 se trouve un\nsquelette ou un garde, il faut obligatoirement se battre avant de faire toute\nautre action. Les combats se d\u00e9roulent de fa\u00e7on assez traditionnelle par un jet\nde d\u00e9s auquel on ajoute la force inscrite sur le plateau du joueur. Les\nsquelettes vaincus apportent des armes ou du rhum alors que les gardes\nprot\u00e8gent les fameux tr\u00e9sors que l\u2019on doit r\u00e9cup\u00e9rer. Les damn\u00e9s sont plus\nfaciles \u00e0 combattre puisqu\u2019il faut juste utiliser une action mais il ne faut\npas n\u00e9gliger leur capacit\u00e9 de nuire. Ils prolif\u00e8rent \u00e0 grande vitesse et d\u00e8s\nqu\u2019il y en a trois dans une pi\u00e8ce, on ne peut plus y p\u00e9n\u00e9trer. <br>\nLe feu est aussi un grand danger sur le navire, car s\u2019il augmente la fatigue,\nil peut surtout faire exploser les pi\u00e8ces qui atteignent une temp\u00e9rature trop\n\u00e9lev\u00e9e. Pour g\u00e9rer cet aspect, les auteurs ont eu recours \u00e0 un syst\u00e8me simple\net efficace&nbsp;: les d\u00e9s \u00e0 six faces. Il est donc facile de modifier la\ntemp\u00e9rature de la pi\u00e8ce. Si elle atteint 6, elle explose en emportant tout avec\nelle. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><span style=\"color:#ff6900\" class=\"color\">Chaud devant <\/span><\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"300\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4412-288x300.jpg\" alt=\"\" class=\"wp-image-51705\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4412-288x300.jpg 288w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4412-768x801.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4412-981x1024.jpg 981w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4412-153x160.jpg 153w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4412-235x245.jpg 235w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/IMG_E4412-326x340.jpg 326w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><\/figure><\/div>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nLe\ntr\u00e9sor de Davy Jones est un collaboratif qui n\u2019est pas simple \u00e0 r\u00e9ussir. De\nnombreux facteurs difficilement pr\u00e9visibles peuvent venir enrayer la\nprogression&nbsp;comme la pioche des nouvelles pi\u00e8ces du bateau ou des cartes\nCh\u00e2timent ou le r\u00e9sultat des jets de d\u00e9s lors des combats. Cet aspect al\u00e9atoire\noffre des parties diff\u00e9rentes \u00e0 chaque fois mais il peut g\u00e9n\u00e9rer de la\nfrustration pour ceux qui n\u2019appr\u00e9cient gu\u00e8re le facteur Chance. Comme il n\u2019y a\npas de sc\u00e9narios, il faut toujours r\u00e9ussir le m\u00eame challenge&nbsp;: mettre \u00e0\nl\u2019abri les tr\u00e9sors.<br>\nJ\u2019ai appr\u00e9ci\u00e9 la gestion de la fatigue qui demande d\u2019\u00eatre vigilant. Si jamais\nun pirate d\u00e9c\u00e8de, un autre prend sa place jusqu\u2019\u00e0 ce qu\u2019il n\u2019y en ait plus en\nstock. Cela est bien pens\u00e9 et th\u00e9matiquement cr\u00e9dible, et permet de continuer\nde jouer m\u00eame en cas d\u2019accident de parcours. S\u2019il n\u2019y a plus de pirates pour\nprendre la rel\u00e8ve, la partie est perdue&nbsp;!<br><br><\/p>\n\n\n\n<p>Si un joueur n\u2019utilise pas toutes ses actions, il peut\ntransmettre son reliquat au prochain. Ce m\u00e9canisme est assez rare pour \u00eatre mis\nen valeur. Il est souvent tr\u00e8s utile d\u2019offrir plus d\u2019actions \u00e0 un comparse en\ndifficult\u00e9 ou bien parti pour \u00e9vacuer un tr\u00e9sor. <\/p>\n\n\n\n<p>Dans <strong>le tr\u00e9sor de Davy Jones<\/strong>, il y a un \u00e9quilibre \u00e0 trouver. L\u2019objectif est de r\u00e9cup\u00e9rer les tr\u00e9sors mais la gestion du feu et des damn\u00e9s me semble primordiale pour l\u2019emporter. Les nouvelles pi\u00e8ces du navire sont obligatoirement ajout\u00e9es \u00e0 chaque d\u00e9but de tour entra\u00eenant une acc\u00e9l\u00e9ration du rythme du jeu. Le feu se propage tr\u00e8s vite et il est difficile d\u2019\u00eatre au four et au moulin\u00a0! <br> Pour mon go\u00fbt personnel, il y a un soup\u00e7on de hasard en trop, mais pour ceux qui aiment les configurations de ce type, vous allez vous r\u00e9galer\u00a0: une seule mani\u00e8re de gagner mais quatre fa\u00e7ons de perdre\u00a0! Bon courage.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande.jpg\" alt=\"\" class=\"wp-image-51706\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande.jpg 1000w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/12\/le-tresor-de-davy-jones-p-image-81221-grande-340x340.jpg 340w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les origines de la l\u00e9gende de Davy Jones sont obscures. Cependant les fans de Pirates des Cara\u00efbes se rappellent sans aucun doute de ce protagoniste des deuxi\u00e8me et troisi\u00e8me films.<br \/>\nDans le jeu Le tr\u00e9sor de Davy Jones, les joueurs collaborent pour fouiller, r\u00e9cup\u00e9rer les tr\u00e9sors et surtout sortir du bateau du c\u00e9l\u00e8bre pirate. Avec un mat\u00e9riel de tr\u00e8s bonne qualit\u00e9, l\u2019immersion est assez r\u00e9ussie.<\/p>\n","protected":false},"author":10,"featured_media":51701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-51699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-3413","auteurs-kane-klenko","editeurs-origames","illustrateurs-chris-ortrowski","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","mecanismes-cooperatif"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=51699"}],"version-history":[{"count":3,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51699\/revisions"}],"predecessor-version":[{"id":51915,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/51699\/revisions\/51915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/51701"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=51699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=51699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=51699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}