{"id":52196,"date":"2023-01-18T12:03:21","date_gmt":"2023-01-18T11:03:21","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=52196"},"modified":"2025-12-17T18:04:35","modified_gmt":"2025-12-17T17:04:35","slug":"great-western-trail-argentine","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/01\/18\/great-western-trail-argentine\/","title":{"rendered":"Great Western Trail: Argentine"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"1023\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-1.jpg\" alt=\"\" class=\"wp-image-52199\" style=\"width:545px;height:605px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-1.jpg 921w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-1-270x300.jpg 270w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-1-768x853.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-1-144x160.jpg 144w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-1-221x245.jpg 221w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-1-306x340.jpg 306w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3308-Essen-Spiel-2022-53-150x150.jpg\" alt=\"\" class=\"wp-image-50745\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">9,5\/10<\/span><\/h5>\n\n\n\n<p>Great Western Trail Argentine est \u00e0 <a href=\"https:\/\/www.vindjeu.eu\/2022\/06\/20\/great-western-trail-seconde-edition\/\"><strong>Great Western Trail<\/strong><\/a> (\u00e9lu <a href=\"http:\/\/www.vindjeu.eu\/2017\/09\/19\/vin-djeu-dlannee-2017\/\"><strong>Vin d&rsquo;jeu Expert de l&rsquo;ann\u00e9e 2017<\/strong><\/a>) un peu ce qu&rsquo;est <a href=\"https:\/\/www.vindjeu.eu\/2019\/12\/04\/brass-birmingham-vf\/\"><strong>Brass Birmingham<\/strong><\/a> \u00e0 <a href=\"https:\/\/www.vindjeu.eu\/2019\/11\/28\/brass-lancashire-vf\/\"><strong>Brass Lancaster<\/strong><\/a>, une pale copie \ud83d\ude00 Non je rigole, pas du tout d&rsquo;ailleurs, je dirais plut\u00f4t une nouvelle version du jeu tr\u00e8s int\u00e9ressante \ud83d\ude00 !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#131a3a\" class=\"color\">Nouvelle version<\/span><\/h2>\n\n\n\n<p>C&rsquo;est assez rare qu&rsquo;on voit un jeu sortir dans une nouvelle version. On voit beaucoup plus souvent des extensions sortir que des nouvelles versions. Et quand je dis nouvelle version, je ne parle pas d&rsquo;une version reth\u00e9matis\u00e9e ou avec mat\u00e9riel plus joli, non je parle d&rsquo;<strong>un jeu diff\u00e9rent ayant les m\u00eames bases<\/strong> mais diff\u00e9rent. Comme <a href=\"https:\/\/www.vindjeu.eu\/2019\/12\/04\/brass-birmingham-vf\/\"><strong>Brass Birmingham<\/strong><\/a> vs <a href=\"https:\/\/www.vindjeu.eu\/2009\/06\/06\/brass\/\"><strong>Brass <\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2019\/12\/09\/caylus-1303\/\"><strong>Caylus 1303<\/strong><\/a> vs <a href=\"https:\/\/www.vindjeu.eu\/2009\/12\/24\/caylus\/\"><strong>Caylus<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2018\/10\/25\/sid-meiers-civilization-une-aube-nouvelle\/\"><strong>Sid Meier&rsquo;s Civilization Une Aube Nouvelle<\/strong><\/a> vs <a href=\"https:\/\/www.vindjeu.eu\/2011\/10\/05\/sid-meiers-civilization-aide-de-jeu\/\"><strong>Sid Meier&rsquo;s Civilization<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2019\/02\/06\/twilight-imperium-iv\/\"><strong>Twilight Imperium IV<\/strong><\/a> vs <a href=\"https:\/\/www.vindjeu.eu\/2010\/09\/16\/twilight-imperium-third-edition\/\"><strong>III <\/strong><\/a>ou <a href=\"https:\/\/www.vindjeu.eu\/2018\/01\/19\/wildcatters-version-2017\/\"><strong>Wildcatters 2017<\/strong><\/a> vs <a href=\"https:\/\/www.vindjeu.eu\/2014\/06\/02\/wildcatters\/\"><strong>Wildcatters<\/strong><\/a> (il y en a encore d&rsquo;autres mais ils ne sont pas l\u00e9gions!), Great Western Trail Argentine est un jeu diff\u00e9rent de son ain\u00e9. <\/p>\n\n\n\n<p>Cette nouvelle version se base sur les m\u00e9canismes du premier opus. Vous allez toujours transporter votre troupeau de vaches le long du parcours, engager de nouveaux sp\u00e9cialistes, acheter de nouvelles vaches, construire de nouveaux b\u00e2timents,&#8230; La diff\u00e9rence est, un peu comme dans <a href=\"https:\/\/www.vindjeu.eu\/2019\/12\/04\/brass-birmingham-vf\/\"><strong>Brass Birmingham<\/strong><\/a>, l&rsquo;ajout d&rsquo;<strong>une nouvelle ressource<\/strong>: le grain. Ce grain, vous allez l&rsquo;<strong>envoyer \u00e0 l&rsquo;export<\/strong> pour b\u00e9n\u00e9ficier d&rsquo;une nouvelle strat\u00e9gie et gagner, d&rsquo;une autre fa\u00e7on, pi\u00e8ces et PVs. Pour vous y soutenir, vous pourrez engager un nouvel ouvrier, <strong>le fermier<\/strong>, qui vous aidera \u00e0 r\u00e9colter plus de grain mais qu&rsquo;il faudra payer bonbon \ud83d\ude09 . Le train vous permettra d&#8217;emprunter des <strong>raccourcis <\/strong>pour arriver plus rapidement \u00e0 la fin du parcours \u00e0 condition de l&rsquo;avoir avanc\u00e9 assez loin.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2-1024x768.jpg\" alt=\"\" class=\"wp-image-52203\" style=\"width:768px;height:576px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-2.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#131a3a\" class=\"color\"><a href=\"https:\/\/www.vindjeu.eu\/2022\/06\/20\/great-western-trail-seconde-edition\/\">Great Western Trail<\/a><\/span><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3-1024x768.jpg\" alt=\"\" class=\"wp-image-52204\" style=\"width:581px;height:436px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-3.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Le reste du jeu est <strong>tr\u00e8s similaire<\/strong> \u00e0 la petite p\u00e9pite qu&rsquo;est <a href=\"https:\/\/www.vindjeu.eu\/2022\/06\/20\/great-western-trail-seconde-edition\/\"><strong>Great Western Trail<\/strong><\/a>. Un tour de jeu est assez simple, vous commencez par <strong>d\u00e9placer votre cowboy<\/strong> d&rsquo;un nombre maximum de cases que sa capacit\u00e9 de d\u00e9placement puis vous <strong>ex\u00e9cutez la ou les actions<\/strong> que vous pouvez r\u00e9aliser sur la tuile d&rsquo;arriv\u00e9e. Enfin, vous <strong>piochez <\/strong>dans votre pioche suffisamment de cartes pour arriver \u00e0 votre maximum de cartes en main. Les actions possibles vont vous permettre de <strong>gagner des ressources<\/strong> en fonction de certains \u00e9l\u00e9ments comme des cartes qu&rsquo;on d\u00e9fausse, un nombre d&rsquo;ouvriers sp\u00e9cialis\u00e9s qu&rsquo;on poss\u00e8de, les endroits o\u00f9 ont \u00e9t\u00e9 construits vos b\u00e2timents,&#8230; Vous allez \u00e9galement pouvoir d\u00e9penser vos ressources pour <strong>construire des b\u00e2timents<\/strong> qui vous feront gagner des PVs et ajouteront des actions possibles le long du parcours juste pour vous. Vous pourrez aussi <strong>engager de nouveaux ouvriers sp\u00e9cialis\u00e9s<\/strong> qui vont augmenter la puissance de vos actions. <strong>Acheter des vaches<\/strong> vous permettra de les vendre au bout du parcours plus cher et de gagner plus de PVs durant cette livraison. Faire <strong>avancer votre train<\/strong> vous permettra de gagner des PVs ainsi, des r\u00e9ductions pour certaines actions et des raccourcis sur le parcours. Vous aurez \u00e9galement la possibilit\u00e9 de <strong>gagner des cartes contrats<\/strong> qui vous apporteront des PVs suppl\u00e9mentaires si vous satisfaites \u00e0 leurs conditions (poss\u00e9der tels types de vaches, engager autant de fermiers, construire autant de b\u00e2timents,&#8230;). A la fin du parcours vous allez <strong>livrer du grain ainsi que les vaches<\/strong> que vous aurez en main pour gagner de l&rsquo;argent et des PVs. Ensuite, vous d\u00e9butez \u00e0 nouveau le parcours pour refaire un tour des actions disponibles.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4-1024x768.jpg\" alt=\"\" class=\"wp-image-52205\" style=\"width:768px;height:576px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-4.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#131a3a\" class=\"color\">Buenos Aires<\/span><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5-1024x768.jpg\" alt=\"\" class=\"wp-image-52210\" style=\"width:567px;height:426px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-5.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Tout \u00e7a donne <strong>un jeu immens\u00e9ment strat\u00e9gique<\/strong> avec une once de hasard sur la pioche des cartes vache mais vous disposez de nombreux effets vous aidant \u00e0 maitriser ce hasard en vous permettant de d\u00e9fausser et piocher de nouvelles cartes. Et Argentine vous apporte de <strong>nouvelles possibilit\u00e9s<\/strong> par rapport au jeu original. <strong>Le grain<\/strong> est tr\u00e8s int\u00e9ressant et vous permet d&rsquo;aller livrer dans les villes portuaires vous offrant une nouvelle voie vers la victoire et donc de nouveaux choix. Encore plus que dans le jeu original, Great Western Trail Argentine ne vous permet pas de tout faire. Et si vous vous perdez \u00e0 vouloir tout faire, vous n&rsquo;arriverez \u00e0 rien \ud83d\ude42 Les choix sont encore plus cruciaux, <strong>l&rsquo;erreur encore plus punitive<\/strong> et la coh\u00e9rence doit encore plus vous guider. Evidemment, ces nouvelles possibilit\u00e9s vont augmenter d&rsquo;autant plus <strong>la complexit\u00e9 du jeu<\/strong>. En soit, \u00e7a ne g\u00eane pas, Great Western Trail \u00e9tant d\u00e9j\u00e0 orient\u00e9 expert, Great Western Trail Argentine l&rsquo;est encore plus \ud83d\ude42<\/p>\n\n\n\n<p>Alors la question qui tue: <strong>lequel des deux je pr\u00e9f\u00e8re?<\/strong>  Les deux \ud83d\ude42  Bon, je dirais qu&rsquo;Argentine va encore <strong>plus loin<\/strong> que Great Western Trail et propose plus de choix strat\u00e9giques.  Pour \u00e7a, Argentine est encore mieux.  Par contre, m\u00eame s&rsquo;il s&rsquo;agit d&rsquo;une nouvelle version, les deux jeux ne sont <strong>pas si diff\u00e9rents<\/strong>.  Les sensations ludiques sont assez semblables et on retrouve la majorit\u00e9 des r\u00e9flexes qu&rsquo;on avait acquis avec la version originale.  Et Argentine apporte finalement <strong>une nouvelle couche de complexit\u00e9<\/strong> qui emp\u00eachera de le sortir aussi facilement que son ain\u00e9, un peu plus \u00e9pur\u00e9.  Un homme traditionnel comme moi pr\u00e9f\u00e8re toujours son premier amour \ud83d\ude09 m\u00eame si la beaut\u00e9 du renouveau l&rsquo;attire fortement \ud83d\ude00<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6-1024x768.jpg\" alt=\"\" class=\"wp-image-52211\" style=\"width:768px;height:576px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-6.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/07\/1306-0-Thierry-150x150.jpg\" alt=\"\" class=\"wp-image-14175\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Thierry<\/span>: <span style=\"color:#cf2e2e\" class=\"color\"> 10\/10<\/span><\/h5>\n\n\n\n<p>Super exp\u00e9rience, top jeu strat\u00e9gique avec pose d\u2019ouvriers, pl\u00e9thore de choix tactiques et strat\u00e9giques, deck building, \u2026. R\u00e8gles assez longues mais fluides et ais\u00e9es \u00e0 ma\u00eetriser. Un must. <br><br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1331\" height=\"998\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15.jpg\" alt=\"\" class=\"wp-image-52197\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15.jpg 1331w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3397-Great-Western-trail-Argentine-15-453x340.jpg 453w\" sizes=\"auto, (max-width: 1331px) 100vw, 1331px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#131a3a\" class=\"color\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par SwatSh<\/h4>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Great Western trail Argentine (Explication des r\u00e8gles et d\u00e9gustation du jeu)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/u6hrub0qyUk?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par Chaps<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Great Western Trail Argentine : Explication et analyse du jeu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/YQZ2yX7XqgY?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Great Western Trail Argentine est \u00e0 Great Western Trail (\u00e9lu Vin d&rsquo;jeu Expert de l&rsquo;ann\u00e9e 2017) un peu ce qu&rsquo;est Brass Birmingham \u00e0 Brass Lancaster, une pale copie \ud83d\ude00 Non je rigole, pas du tout d&rsquo;ailleurs, je dirais plut\u00f4t une nouvelle version du jeu tr\u00e8s int\u00e9ressante \ud83d\ude00 !&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":52199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[4255],"class_list":["post-52196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-nouvelle-version","annee-3413","auteurs-alexander-pfister","editeurs-eggertspiele","illustrateurs-chris-quilliams","distributeurs-asmodee","recompenses-vin-djeu-dcoups-dcoeur","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-contrats","mecanismes-deplacement-douvriers","mecanismes-gestion-de-main-de-cartes","mecanismes-gestion-de-ressources"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=52196"}],"version-history":[{"count":14,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52196\/revisions"}],"predecessor-version":[{"id":64882,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52196\/revisions\/64882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/52199"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=52196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=52196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=52196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}