{"id":52469,"date":"2023-02-25T11:55:54","date_gmt":"2023-02-25T10:55:54","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=52469"},"modified":"2025-11-26T20:41:01","modified_gmt":"2025-11-26T19:41:01","slug":"voyageurs-du-tigre-du-sud","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/02\/25\/voyageurs-du-tigre-du-sud\/","title":{"rendered":"Voyageurs du Tigre du Sud"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"814\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-1-e1674939112490.jpg\" alt=\"\" class=\"wp-image-52471\" style=\"width:529px;height:547px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-1-e1674939112490.jpg 788w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-1-e1674939112490-290x300.jpg 290w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-1-e1674939112490-768x793.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-1-e1674939112490-155x160.jpg 155w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-1-e1674939112490-237x245.jpg 237w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-1-e1674939112490-329x340.jpg 329w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/Swa-71-Ben-150x150.jpg\" alt=\"\" class=\"wp-image-52473\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Apr\u00e8s sa trilogie sur la Mer du Nord et celle qu&rsquo;il vient de cl\u00f4turer sur le Royaume de l&rsquo;Ouest (sa meilleure), <strong><a href=\"https:\/\/www.vindjeu.eu\/auteurs\/shem-phillips\/\">Shem Philips<\/a><\/strong> se lance, avec son pote <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/s-j-macdonald\/\"><strong>S J Macdonald<\/strong><\/a>, dans une nouvelle trilogie, celle du Tigre du Sud!  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#b6aa43\" class=\"color\">Continuit\u00e9<\/span><\/h2>\n\n\n\n<p>Voyageurs du Tigre du Sud se place <strong>dans le prolongement de la s\u00e9rie du Royaume de l&rsquo;Ouest<\/strong>, elle aussi issue des esprits des deux m\u00eames auteurs. On retrouve ce qui a fait le succ\u00e8s de leurs jeux et ce qui nous pla\u00eet: de nombreuses cartes diff\u00e9rentes, de multiples bonus \u00e0 grapiller et \u00e0 optimiser, des capacit\u00e9s permanentes \u00e0 acqu\u00e9rir, des nouvelles conditions de PVs \u00e0 gagner, le tout support\u00e9 par des r\u00e8gles limpides, parfaitement iconographi\u00e9 et illustr\u00e9 majestueusement par le ma\u00eetre <strong><a href=\"https:\/\/www.vindjeu.eu\/illustrateurs\/mihajlo-dimitrievski\/\">Mihajlo Dimitrievski<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#b6aa43\" class=\"color\">D\u00e9s d&rsquo;action<\/span><\/h2>\n\n\n\n<p>L\u00e0 o\u00f9 Voyageurs du Tigre du Sud se distingue de ses ain\u00e9s est dans sa m\u00e9canique de choix d&rsquo;action. Chaque joueur dispose de ses propres d\u00e9s d&rsquo;action, les lance, en choisit un \u00e0 chaque tour \u00e0 placer sur une case action de son plateau et r\u00e9alise l&rsquo;action en question. Quand il n&rsquo;a plus de d\u00e9 \u00e0 placer, il doit passer un tour \u00e0 les relancer &amp; b\u00e9n\u00e9ficier des bonus de relance qu&rsquo;il aura gagn\u00e9s.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2-1024x768.jpg\" alt=\"\" class=\"wp-image-52487\" style=\"width:768px;height:576px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-2.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>La grande originalit\u00e9 du jeu est que <strong>la valeur de d\u00e9 n&rsquo;importe pas<\/strong>. Les emplacements de d\u00e9 ont des exigences, non pas en terme de valeur, mais en terme d&rsquo;icone. Voyageurs du Tigre du Sud offre <strong>un syst\u00e8me de personnalisation des faces de d\u00e9s<\/strong> assez original. A chaque valeur de d\u00e9 correspond 0 ou 1 icone. Par exemple, au d\u00e9but de la partie, chaque \u00ab\u00a01\u00a0\u00bb \u00e9quivaut \u00e0 un chameau. Certains emplacements de d\u00e9 exigent un chameau. Vous pourrez y placer un \u00ab\u00a01\u00a0\u00bb pour r\u00e9aliser l&rsquo;action. Mais au fur et \u00e0 mesure de l&rsquo;avanc\u00e9e du jeu, vous allez placer des tuiles sur votre tableau de valeurs du d\u00e9 pour que certaines valeurs vous apportent les icones qui vous int\u00e9ressent. Ainsi, vous allez personnaliser les faces de vos d\u00e9s, chaque face pouvant apporter un ou plusieurs icones diff\u00e9rents.  Et, en cours de partie, plusieurs valeurs de d\u00e9 peuvent, par exemple, apporter un chameau que seul le \u00ab\u00a01\u00a0\u00bb permettait en d\u00e9but de partie!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3-1024x768.jpg\" alt=\"\" class=\"wp-image-52491\" style=\"width:547px;height:410px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-3.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #b6aa43;\" class=\"color\"> Les cartes &amp; les ouvriers<\/span><\/h2>\n\n\n\n<p>Outre l&rsquo;acquisition des 2 ressources du jeu (toujours la nourriture ou l&rsquo;argent) ou de tuiles de personnalisation de d\u00e9, <strong>l&rsquo;essentiel des actions va vous permettre de gagner 1 des 6 types de carte<\/strong> des Voyageurs du Tigre Sud: les cartes terre, mer et ciel accompagn\u00e9es de cartes bonus qui s&rsquo;annexent \u00e0 chacun de ces types. Et c&rsquo;est dans ces cartes que se situe le c\u0153ur du jeu. Non seulement elles sont votre plus grande source de PVs gr\u00e2ce \u00e0 un syst\u00e8me plus traditionnel de collection mais, en plus, elles vont vous procurer divers bonus (imm\u00e9diats, permanents, de fin de jeu, de nouvelles cases action,&#8230;) qu&rsquo;il vous faudra bien combiner et optimiser.<\/p>\n\n\n\n<p>Et ce n&rsquo;est pas tout, <strong>ces cartes vont vous apporter des ouvriers<\/strong> que vous pourrez jouer en tant qu&rsquo;action pour gagner d&rsquo;autres bonus. M\u00eame si ils ne sont pas essentiels au jeu, le truc sympa avec ces ouvriers est qu&rsquo;ils sont disponibles dans <strong>un vase clos<\/strong>. Les joueuses ne vont pouvoir en gagner que tr\u00e8s peu et ce sont les ouvriers qu&rsquo;elles placeront qui seront susceptibles d&rsquo;\u00eatre gagn\u00e9s par les adversaires. En effet, quand on joue un ouvrier, on le place sur une carte et la joueuse qui r\u00e9cup\u00e8re la carte gagner l&rsquo;ouvrier plac\u00e9 dessus&#8230;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4-1024x768.jpg\" alt=\"\" class=\"wp-image-52493\" style=\"width:768px;height:576px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-4.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #b6aa43;\" class=\"color\">Le voyage<\/span><\/h2>\n\n\n\n<p>Le tout est visualis\u00e9 par un parcours o\u00f9 les joueurs vont voyager et <strong>progresser de case en case \u00e0 condition de satisfaire aux conditions plac\u00e9es entre elles<\/strong>.  J&rsquo;ai trouv\u00e9 ce parcours l\u00e9g\u00e8rement d\u00e9s\u00e9quilibr\u00e9.  Il offre la possibilit\u00e9 de progresser plus vite en passant certaines \u00e9tapes.  A confirmer avec plus de parties mais les quelques parties que j&rsquo;ai jou\u00e9es tendent \u00e0 montrer qu&#8217;emprunter ces raccourcis semble \u00eatre la panac\u00e9e.  Et m\u00eame si on peut saluer cette m\u00e9canique car elle autorise aux joueurs de rusher ou de temporiser, g\u00e9n\u00e9ralement, <strong>c&rsquo;est celui qui rush qui gagne<\/strong> \ud83d\ude42<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5-1024x768.jpg\" alt=\"\" class=\"wp-image-52492\" style=\"width:541px;height:406px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-5.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#b6aa43\" class=\"color\">Les Royaumes du Sud<\/span><\/h2>\n\n\n\n<p>Voyageurs du Tigre du Sud se situe clairement <strong>dans la lign\u00e9e de la trilogie du Royaume de l&rsquo;Ouest<\/strong> et plus sp\u00e9cialement des <a href=\"https:\/\/www.vindjeu.eu\/2020\/01\/01\/paladins-du-royaume-de-louest\/\"><strong>Paladins<\/strong><\/a>. Les fans de la s\u00e9rie seront en milieu connu et retrouveront les sensations ludiques de ses ain\u00e9s. C&rsquo;est bien mais un peu dommage aussi. On aurait aim\u00e9 un peu plus d&rsquo;originalit\u00e9 et de surprise m\u00eame si <strong>la personnalisation des d\u00e9s<\/strong> est assez unique. Et m\u00eame si on peut avoir certains doutes sur la piste des voyages, <strong>l&rsquo;ensemble du jeu est de tr\u00e8s grande qualit\u00e9 et offre une tr\u00e8s belle rejouabilit\u00e9<\/strong>. On n&rsquo;est jamais d\u00e9\u00e7u d&rsquo;un <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/shem-phillips\/\"><strong>Shem <\/strong><\/a>\ud83d\ude42<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-150x150.jpg\" alt=\"\" class=\"wp-image-14812\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Chaps<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Voil\u00e0 un nouveau jeu dans la lign\u00e9e des paladins\net autres architectes du royaume de l\u2019Ouest mais cette fois dans le sud.<\/p>\n\n\n\n<p>Est-ce mon pr\u00e9f\u00e9r\u00e9 ? Peut-\u00eatre bien. Je sais\npourquoi le jeu m\u2019a plu, on y construit un tableau de cartes mais aussi un\npetit tableau de tuiles, avec combo \u00e0 la clef. Rien de plus plaisant que de\nconstruire cela et de voir sa partie se d\u00e9bloquer gr\u00e2ce \u00e0 ce que l\u2019on a mis en\nplace. Et comme les joueurs d\u00e9clenchent la fin de partie on a le temps que l\u2019on\nse donne pour le faire. Bingo !<\/p>\n\n\n\n<p>Cela me plait beaucoup et marche tr\u00e8s bien.<\/p>\n\n\n\n<p>Sinon on est dans du vrai Euro \u00e0 th\u00e8me bien\nplaqu\u00e9. Mais les illustrations et le fait de cr\u00e9er un paysage de mer ou \u00e0\nl\u2019int\u00e9rieur des terres avec un ciel \u00e9toil\u00e9, \u00ab&nbsp;com\u00e9t\u00e9&nbsp;\u00bb ou\n\u00ab&nbsp;plan\u00e9t\u00e9&nbsp;\u00bb nous rappelle le th\u00e8me&nbsp;\nparfaitement et plonge donc les joueurs dans une vraie ambiance que cr\u00e9e\nle jeu. Car aussi plaqu\u00e9 soit-ils le th\u00e8me est tout de m\u00eame parfaitement\nimpl\u00e9ment\u00e9.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6-1024x768.jpg\" alt=\"\" class=\"wp-image-52606\" style=\"width:768px;height:576px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-6.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>J\u2019ai particuli\u00e8rement appr\u00e9ci\u00e9 le moyen de jouer\navec les d\u00e9s. Comme quoi un jeu avec un hasard de lanc\u00e9 (brrr\u2026) peut\nparfaitement ne pas tomber dans le hasard pur et m\u00e9chant, sauf si vous vous y\nprenez mal mais l\u00e0 c\u2019est de votre faute\u2026 Les tuiles bien plac\u00e9es sur la\ncaravane nous construisent une v\u00e9ritable machine \u00e0 utiliser les d\u00e9s selon leurs\nvaleurs, vous pourrez m\u00eame faire en sorte de ne pas jouer avec certaines\nvaleurs les transformant automatiquement en d\u2019autres bien plus efficaces pour\nvos actions gr\u00e2ce aux bien que ces d\u00e9s d\u00e9clenchent. Et r\u00e9servant les valeurs\nnon utilis\u00e9es aux tuiles ne servant que pour les ic\u00f4nes PV fin de partie.<\/p>\n\n\n\n<p>La m\u00e9canique des cartes bien connue marche\nparfaitement avec les bonus villageois\/am\u00e9lioration de cartes espace \u00e0 PV.\nC\u2019est tr\u00e8s plaisant et m\u00eame si notre strat\u00e9gie d\u00e9pend des cartes qui sortent et\nqu\u2019il y aura donc une part d\u2019opportunisme et de tactique le jeu n\u2019en demeure\npas moins strat\u00e9gique, juste comme il faut sans bruler \u00e0 l\u2019exc\u00e8s les neurones.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7-1024x768.jpg\" alt=\"\" class=\"wp-image-52607\" style=\"width:549px;height:412px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-7.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Enfin le \u00ab&nbsp;journal&nbsp;\u00bb la piste centrale\napporte une anticipation indispensable si l\u2019on veut progresser et\n\u00e9ventuellement une petit course en effet cela d\u00e9pendra des parties, car c\u2019est\nelle qui met fin \u00e0 la partie quand on le souhaite, mais avancer apporte des\nbonus toujours meilleurs et qu\u2019il nous faut comme les d\u00e9s suppl\u00e9mentaires ou la\nmultiplication part 2 des PVs des cartes espaces.<\/p>\n\n\n\n<p>Donc le jeu aurait bien pu avoir 9. Alors pourquoi\npas ? D\u2019abord la construction de ma caravane m\u2019a beaucoup plu mais je crains de\nfaire un peu toujours pareil \u00e0 chaque partie, quelques valeurs avec des ic\u00f4nes\nde bien et des ic\u00f4nes pour modifier la valeur du d\u00e9 sur d\u2019autres, si c\u2019est le\ncas je vais perdre un peu du plaisir de ma premi\u00e8re partie.<\/p>\n\n\n\n<p>Ensuite les cartes am\u00e9liorations de PVs des cartes\nespaces ne sont pas du tout \u00e9quilibr\u00e9es, c\u2019est sans doute voulu et on peut\nrefuser une carte espace pour faire une action \u00e0 la place. Mais devoir poss\u00e9der\n3 tuiles jaunes par exemple est toujours jouable si on d\u00e9cide de le faire, mais\navoir 4 ic\u00f4nes de livres est hautement al\u00e9atoire selon la sortie des cartes.\nDonc il y a des conditions facile \u00e0 remplir et qui combottent quand d\u2019autres\nseront purement opportunistes si le tirage des cartes est all\u00e9 dans leur sens.\nJ\u2019ai vu un joueur un peu grincer de ne pas avoir eu l\u2019opportunit\u00e9 d\u2019avoir les\nic\u00f4nes des 4 livres quand moi j\u2019ai pu prendre la carte demandant 3 tuiles\njaunes et j\u2019en avais d\u00e9j\u00e0 2\u2026<\/p>\n\n\n\n<p>Sinon des bricoles : un thermoformage curieusement\nfait, par exemple 4 emplacements pour des cartes quand il y en a 5 types\ndiff\u00e9rents + les cartes solo. Un thermoformage sans couvercle, donc la boite\nverticale entraine que tous les pions se baladent\u2026 Enfin s\u2019il n\u2019y a, tr\u00e8s\nlogiquement, pas de piste de point de victoire (tous les Pvs se font \u00e0 la fin)\nil n\u2019y a pas de calepin pour noter ces PVs \u00e0 la fin\u2026 Pourquoi ? Petite\nmesquinerie \u00e0 mon go\u00fbt.<\/p>\n\n\n\n<p>Donc \u00e0 rejouer mais je ne cache pas ma curiosit\u00e9\nde voir si la variabilit\u00e9 et la richesses inh\u00e9rente \u00e0 cette variabilit\u00e9 sont\nbien pr\u00e9sentes. Mais bon je viens de dire, \u00e0 rejouer, voil\u00e0 qui est bon signe.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8-1024x768.jpg\" alt=\"\" class=\"wp-image-52608\" style=\"width:616px;height:462px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3410-Voyageurs-du-tigre-du-sud-8.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><em>La notation de Chaps :<\/em><\/p>\n\n\n\n<p><em>&lt; 7 : Je ne\npublierais pas d<\/em><em>\u2019<\/em><em>avis, il s<\/em><em>\u2019<\/em><em>agit de\njeux qui ont pour moi des d\u00e9fauts r\u00e9dhibitoires.<\/em><\/p>\n\n\n\n<p><em>7,5 : Un jeu qui a\npour moi des d\u00e9fauts qui me g\u00eanent vraiment, m\u00ea<\/em><em>me si ce n<\/em><em>\u2019<\/em><em>est pas\nforc\u00e9ment le cas pour tout le monde et s<\/em><em>\u2019<\/em><em>ils ne sont pas r\u00e9dhibitoires.<\/em><\/p>\n\n\n\n<p><em>8 : Un bon jeu mais \u00e0\nqui il manque quelque chose pour moi,<\/em><em> que j<\/em><em>\u2019<\/em><em>explicite, mais le jeu est bien et poss<\/em><em>\u00e8<\/em><em>de de vraies qualit\u00e9s.<\/em><\/p>\n\n\n\n<p><em>8,5 : Un bon jeu qui\ncorrespond \u00e0 ce que j<\/em><em>\u2019<\/em><em>aime.<\/em><\/p>\n\n\n\n<p><em>9 : Un excellent jeu,\nau-dessus de la moyenne de ce que je rencontre et que j<\/em><em>\u2019<\/em><em>appr<\/em><em>\u00e9cie. Bonne envie\nd<\/em><em>\u2019<\/em><em>y revenir au plus vite.<\/em><\/p>\n\n\n\n<p><em>9,5 : Whaou, l<\/em><em>\u00e0 excellente\nsurprise, la perfection n<\/em><em>\u2019<\/em><em>est pas loin.<\/em><\/p>\n\n\n\n<p><em>10 : Y-a-t<\/em><em>\u2019<\/em><em>il encore\ndes jeux qui me conviennent si parfaitement, un whaou sans fin pour moi face \u00e0\nl<\/em><em>\u2019<\/em><em>excellence ludique.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/10\/PhilReyMonopoli-150x150.jpg\" alt=\"\" class=\"wp-image-64033\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/10\/PhilReyMonopoli-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/10\/PhilReyMonopoli-80x80.jpg 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/10\/PhilReyMonopoli-320x320.jpg 320w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">PhilRey<\/span>: <span class=\"color\" style=\"color:#cf2e2e\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Une belle d\u00e9couverte que ce Tigre du Sud!<\/p>\n\n\n\n<p>Compar\u00e9 aux autres de l\u2019Ouest, il est selon moi nettement plus accessible.<\/p>\n\n\n\n<p>Et c\u2019est peut-\u00eatre \u00e7a qui m\u2019a plu dans Voyageurs du Tigre du Sud. Alors oui, il y a encore pas mal d\u2019iconographie avec laquelle se familiariser mais il me semble plus accessible.<\/p>\n\n\n\n<p>Ce qui m\u2019a s\u00e9duit aussi c\u2019est qu\u2019il y a autre chose que simplement les cartes. Il y a cette course sur le plateau central, qui n\u00e9cessite des cartes, certes, mais qui change du placement d\u2019ouvriers que l\u2019on a l\u2019habitude de voir. Il y a ces d\u00e9s qui nous permettent de faire des actions. Ces d\u00e9s que l\u2019on peut \u00ab&nbsp;am\u00e9liorer&nbsp;\u00bb afin que telle valeur offre plus de choix d\u2019action. Et il a toujours le placement d\u2019ouvriers, une m\u00e9canique que j\u2019appr\u00e9cie particuli\u00e8rement.<\/p>\n\n\n\n<p>Je n\u2019ai qu\u2019une seule partie au compteur pour l\u2019instant mais elle m\u2019a bien emball\u00e9. H\u00e2te d\u2019en refaire une prochainement. Et du coup, curieux des 2 autres jeux de la trilogie du Sud.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1331\" height=\"998\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15.jpg\" alt=\"\" class=\"wp-image-52470\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15.jpg 1331w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/3410-Voyageurs-du-tigre-du-sud-15-453x340.jpg 453w\" sizes=\"auto, (max-width: 1331px) 100vw, 1331px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#b6aa43\" class=\"color\">Vin d&rsquo;jeu d&rsquo;vid\u00e9os<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par Pardieu d&rsquo;Expert Game Award<\/h4>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Wayfarers of the South Tigris (Voyageurs du Tigre du Sud)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/sL15yGbGeKw?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par Chaps<\/h4>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Voyageurs du Tigre du sud : Explication et analyse du jeu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/W_JigK7yvUI?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Apr\u00e8s sa trilogie sur la Mer du Nord et celle qu&rsquo;il vient de cl\u00f4turer sur le Royaume de l&rsquo;Ouest (sa meilleure), Shem Philips se lance, avec son pote S J Macdonald, dans une nouvelle trilogie, celle du Tigre du Sud! Continuit\u00e9 Voyageurs du Tigre du Sud se place&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":52471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[4290],"class_list":["post-52469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-des","annee-3637","auteurs-s-j-macdonald","auteurs-shem-phillips","editeurs-pixie-games","illustrateurs-mihajlo-dimitrievski","distributeurs-pixie-games","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-collection","mecanismes-jets-de-des","mecanismes-multiples-bonus"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=52469"}],"version-history":[{"count":9,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52469\/revisions"}],"predecessor-version":[{"id":64590,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52469\/revisions\/64590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/52471"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=52469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=52469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=52469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}