{"id":52746,"date":"2023-03-18T15:46:42","date_gmt":"2023-03-18T14:46:42","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=52746"},"modified":"2023-03-18T15:46:59","modified_gmt":"2023-03-18T14:46:59","slug":"shogun-no-katana","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/03\/18\/shogun-no-katana\/","title":{"rendered":"Shogun No Katana"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-1.jpg\" alt=\"\" class=\"wp-image-52748\" width=\"513\" height=\"565\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-1.jpg 535w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-1-272x300.jpg 272w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-1-145x160.jpg 145w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-1-223x245.jpg 223w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-1-309x340.jpg 309w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/Swa-71-Ben-150x150.jpg\" alt=\"\" class=\"wp-image-52473\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8\/10<\/span><\/h5>\n\n\n\n<p>Shogun No Katana est le dernier jeu de <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/placentia-games\/\"><strong>Placentia Games &amp; Post Scriptum<\/strong><\/a> qui ont fait les excellents <a href=\"https:\/\/www.vindjeu.eu\/2017\/10\/20\/wendake\/\"><strong>Wendake <\/strong><\/a>&amp; <a href=\"https:\/\/www.vindjeu.eu\/2015\/10\/05\/bretagne\/\"><strong>Bretagne <\/strong><\/a>et distribu\u00e9 en Fran\u00e7ais par <a href=\"https:\/\/www.vindjeu.eu\/distributeurs\/atalia\/\"><strong>Atalia <\/strong><\/a>(<a href=\"https:\/\/www.vindjeu.eu\/2022\/11\/05\/east-india-companies\/\"><strong>East India Companies<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2021\/10\/28\/witchstone\/\"><strong>Witchstone<\/strong><\/a>,&#8230;) qui est de nouveau l\u00e0 sur un bon coup \ud83d\ude09<\/p>\n\n\n\n<p><strong>Shogun No Katana<\/strong> est un jeu classique de pose d&rsquo;ouvriers, de gestion de ressources et de r\u00e9alisation de contrats, le tout saupoudr\u00e9 par des bonus \u00e0 glaner et surtout par un syst\u00e8me ing\u00e9nieux de fabrication de sabre&#8230;<\/p>\n\n\n\n<p>Le jeu se joue en <strong>4 manches<\/strong> et, \u00e0 chaque manche, les joueuses, \u00e0 leur tour, placent une de leurs ouvri\u00e8res sur un des <strong>emplacements d&rsquo;action disponibles<\/strong> sur le plateau central ou autour de leur plateau personnel afin d&rsquo;ex\u00e9cuter une action. A la place de placer une de leurs ouvri\u00e8res, les joueuses peuvent aussi <strong>louer les services d&rsquo;un moine<\/strong> pour un prix de plus en plus \u00e9lev\u00e9 en fonction du num\u00e9ro de manche en cours. Ces moines fonctionnent comme des ouvri\u00e8res mais procurent, pour chaque action, un bonus suppl\u00e9mentaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#8e2211\" class=\"color\">Que faire?<\/span><\/h2>\n\n\n\n<p>Les actions que vous allez pouvoir r\u00e9aliser sont diverses. Vous allez pouvoir <strong>r\u00e9cup\u00e9rer des commandes de sabre<\/strong> aupr\u00e8s des grandes familles des Daimyo. Chaque sabre command\u00e9 va repr\u00e9senter une suite logique de ressources que le joueur devra fournir pour le fabriquer. La famille du Daimyo qui a command\u00e9 son sabre a la grande bont\u00e9 de vous payer \u00e0 l&rsquo;avance et, avec cet argent, vous allez pouvoir aller acheter des ressources. Mais attention, <strong>les familles des Daimyo sont assez radines<\/strong> et ne vous donneront pas assez de sous pour vous procurer les ressources n\u00e9cessaires. Il va falloir trouver d&rsquo;autres moyens pour gagner des sous ou pour gagner des ressources \u00e0 moindre prix&#8230; Et chaque fois que vous <strong>achetez des ressources<\/strong>, vous recevrez une carte bonus qui vous rapportera un bonus instantan\u00e9 et un second permanent \u00e0 chaque fois que vous respectez sa condition (livrer un sabre \u00e0 un certain endroit).<\/p>\n\n\n\n<p>Vous allez \u00e9galement pouvoir <strong>envoyer jusqu&rsquo;\u00e0 3 membres de votre famille sur des cartes bonus<\/strong> qui vous rapporteront leurs bonus imm\u00e9diats (ou permanents) \u00e0 chaque fois que vous r\u00e9aliserez l&rsquo;action ou qu&rsquo;une adversaire le fera! Vous pourrez \u00e9galement <strong>embellir vos sabres<\/strong> ce qui vous rapportera argent et PVs.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6-1024x768.jpg\" alt=\"\" class=\"wp-image-52758\" width=\"768\" height=\"576\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-6.jpg 1089w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#8e2211\" class=\"color\">Katana<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2-1024x768.jpg\" alt=\"\" class=\"wp-image-52759\" width=\"586\" height=\"440\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-2.jpg 1089w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/figure><\/div>\n\n\n\n<p>La derni\u00e8re action que vous allez pouvoir r\u00e9aliser est la plus originale et la plus amusante du jeu: <strong>forger vos Katanas<\/strong> (vos sabres)! Pour cela, vos sabres (= les commandes des familles de Daimyo) vont <strong>se d\u00e9placer sur votre plateau damier pour chaque ressource que vous y ajouterez<\/strong>. Ces d\u00e9placements sont simples mais ing\u00e9nieux et quand vous placez un de vos ouvriers sur une ligne ou colonne de votre forge, vous activerez tous les sabres de la ligne ou colonne correspondante afin qu&rsquo;ils se d\u00e9placent vers la prochaine ressource demand\u00e9e (\u00e0 condition de l&rsquo;avoir \ud83d\ude09 ). Et c&rsquo;est l\u00e0 o\u00f9 Shogun No Katana devient magique car vous allez devoir <strong>optimiser tout \u00e7a<\/strong> pour activer un maximum de sabres \u00e0 l&rsquo;aide d&rsquo;un minimum d&rsquo;ouvriers. Et une fois un sabre r\u00e9alis\u00e9 (= sa ligne de ressources est compl\u00e8te), vous allez pouvoir le placer sur votre <strong>plateau Washitsu<\/strong>. Les sabres vous rapporteront plus de points au plus tard vous les r\u00e9aliserez mais, plus t\u00f4t vous le faites, plus t\u00f4t vous allez pouvoir utiliser les ouvriers qu&rsquo;ils vont d\u00e9bloquer&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#8e2211\" class=\"color\">Shogun<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10-1024x768.jpg\" alt=\"\" class=\"wp-image-52760\" width=\"508\" height=\"381\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-10.jpg 1089w\" sizes=\"auto, (max-width: 508px) 100vw, 508px\" \/><\/figure><\/div>\n\n\n\n<p>De plus, vous allez pouvoir copier une ou deux ressources de chaque Katana r\u00e9alis\u00e9 pour pouvoir lancer, quand vous le d\u00e9ciderez et quand vous aurez les ressources n\u00e9cessaires, <strong>la fabrication de votre Shogun No Katana<\/strong> qui est le sabre qui vous rapportera le plus de points \u00e0 condition de le lancer assez t\u00f4t dans la partie.<\/p>\n\n\n\n<p>C&rsquo;est ce Sabre Du Shogun (=Shogun No Katana) qui est le nom et le coeur du jeu car si vous \u00e9chouez \u00e0 le fabriquer, vous aurez de grandes difficult\u00e9s \u00e0 l&#8217;emporter m\u00eame si c&rsquo;est possible. Il est n\u00e9anmoins clair que fabriquer un Shogun No Katana suffisamment beau et grand sera votre plus grand atout pour l&#8217;emporter. On est \u00e9videmment en plein dans le th\u00e8me m\u00eame si on peut regretter n&rsquo;avoir pas plus de voies diff\u00e9rentes vers la victoire. Il n&#8217;emp\u00eache qu&rsquo;on reste baba devant la simplicit\u00e9 et l&rsquo;ing\u00e9niosit\u00e9 du syst\u00e8me de fabrication des sabres qui est l&rsquo;\u00e9l\u00e9ment central du jeu et qui propose un grand plaisir ludique et une m\u00e9canique unique au sein d&rsquo;un jeu de placement d&rsquo;ouvriers, de gestion de ressources et de r\u00e9alisation de contrat plut\u00f4t classique mais tr\u00e8s bien foutu et \u00e9quilibr\u00e9.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1331\" height=\"998\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15.jpg\" alt=\"\" class=\"wp-image-52747\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15.jpg 1331w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/02\/3426-Shogun-No-Katana-15-453x340.jpg 453w\" sizes=\"auto, (max-width: 1331px) 100vw, 1331px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#8e2211\" class=\"color\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par SwatSh<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Shogun No katana (Explication des r\u00e8gles et d\u00e9gustation du jeu)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ebXkK9rvRqc?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Shogun No Katana est le dernier jeu de Placentia Games &amp; Post Scriptum qui ont fait les excellents Wendake &amp; Bretagne et distribu\u00e9 en Fran\u00e7ais par Atalia (East India Companies, Witchstone,&#8230;) qui est de nouveau l\u00e0 sur un bon coup \ud83d\ude09 Shogun No Katana est un jeu classique&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":52748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[4219],"class_list":["post-52746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-japon","annee-3637","auteurs-frederico-randazzo","auteurs-p-s-martensen","editeurs-placentia-games","editeurs-post-scriptum","illustrateurs-giorgia-lanza","distributeurs-atalia","nombre_conseille-1210","nombre_conseille-1355","mecanismes-gestion-de-ressources","mecanismes-ouvriers-specialises","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=52746"}],"version-history":[{"count":6,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52746\/revisions"}],"predecessor-version":[{"id":52818,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/52746\/revisions\/52818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/52748"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=52746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=52746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=52746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}