{"id":53295,"date":"2023-05-11T14:07:15","date_gmt":"2023-05-11T12:07:15","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=53295"},"modified":"2023-05-11T14:13:59","modified_gmt":"2023-05-11T12:13:59","slug":"miller-zoo","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/05\/11\/miller-zoo\/","title":{"rendered":"Miller zoo"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/RANMZ01FR-Miller-Zoo.png\" alt=\"\" class=\"wp-image-53296\" width=\"339\" height=\"473\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/RANMZ01FR-Miller-Zoo.png 700w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/RANMZ01FR-Miller-Zoo-215x300.png 215w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/RANMZ01FR-Miller-Zoo-115x160.png 115w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/RANMZ01FR-Miller-Zoo-175x245.png 175w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/RANMZ01FR-Miller-Zoo-243x340.png 243w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><\/h5>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait.jpg\" alt=\"\" class=\"wp-image-52332\" width=\"92\" height=\"102\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-270x300.jpg 270w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-144x160.jpg 144w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-220x245.jpg 220w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-306x340.jpg 306w\" sizes=\"auto, (max-width: 92px) 100vw, 92px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color: #cf2e2e;\" class=\"color\">Serval<\/span> : <span style=\"color: #0693e3;\" class=\"color\">8\/10<\/span><\/h5>\n\n\n\n<p>Tir\u00e9 de l&rsquo;histoire des propri\u00e9taires d&rsquo;un zoo en Bauce au Qu\u00e9bec&nbsp;\u00c9milie et Cliffort Miller ont propos\u00e9 \u00e0  Thomas Dagenais-Lesp\u00e9rance, l&rsquo;auteur du c\u00e9l\u00e8bre D\u00e9crypto de donner vie \u00e0 ce jeu.<\/p>\n\n\n\n<p><br>Vous incarnerez donc dans ce jeu coop\u00e9ratif , la famille Miller, g\u00e9rante d&rsquo;un zoo. Ce parc pourra ouvrir au public \u00e0 partir du moment o\u00f9 tous les animaux seront accueillis sereinement dans l&rsquo;enceinte. Diff\u00e9rents impr\u00e9vus vont retarder cette mission et ce sera \u00e0 tous de g\u00e9rer au mieux ces conflits, voire ces crises !<\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p>Le plateau de jeu repr\u00e9sente diff\u00e9rents lieux, la zone d&rsquo;accueil des animaux que les joueurs devront int\u00e9grer au zoo, les trois habitats o\u00f9 seront dispers\u00e9s ces nouveaux venus et o\u00f9 vivent d\u00e9j\u00e0 des animaux dont il faut s&rsquo;occuper pr\u00e9cieusement. <br>Un entrep\u00f4t servant de garde cartes, ainsi qu&rsquo;une cantine comme point de ralliement compl\u00e8tent ce plateau.<\/p>\n\n\n\n<p><br>Trois types de cartes tr\u00f4nent sur ce dernier ; des cartes \u00ab\u00a0ressources\u00a0\u00bb , \u00ab\u00a0besoins\u00a0\u00bb et le paquet de 7 cartes des animaux \u00e0 accueillir, 4 d&rsquo;entre eux sont d&rsquo;ores et d\u00e9j\u00e0 pr\u00eats \u00e0 recevoir vos bons soins pour rejoindre les habitats.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1-868x1024.png\" alt=\"\" class=\"wp-image-53538\" width=\"266\" height=\"314\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1-868x1024.png 868w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1-254x300.png 254w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1-768x906.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1-136x160.png 136w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1-208x245.png 208w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1-288x340.png 288w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/341759662_1290814628528994_8936022952509040876_n-1.png 1553w\" sizes=\"auto, (max-width: 266px) 100vw, 266px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"blob:https:\/\/www.vindjeu.eu\/e4ebd006-03d6-47aa-91f2-82c50a3f59d1\" alt=\"\"\/><\/figure>\n\n\n\n<p><br><br><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Chaque jour suffit sa peine &#x1f43a;<\/h5>\n\n\n\n<p>Miller zoo se joue en plusieurs jours, chaque jour est jou\u00e9 en quatre phases :<\/p>\n\n\n\n<p>&#x1f313; L&rsquo;aube : Tous les joueurs piochent 4 cartes ressources et les placent faces visibles devant eux. <br>Ces cartes repr\u00e9sentent les solutions \u00e0 apporter pour r\u00e9pondre aux besoins r\u00e9currents des animaux dans les habitats (ceux d\u00e9j\u00e0 pr\u00e9sents) et permettront \u00e9galement d&rsquo;int\u00e9grer les nouveaux animaux.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources-1024x729.png\" alt=\"\" class=\"wp-image-53528\" width=\"209\" height=\"149\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources-1024x729.png 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources-300x214.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources-768x547.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources-160x114.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources-344x245.png 344w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources-478x340.png 478w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/Ressources.png 1138w\" sizes=\"auto, (max-width: 209px) 100vw, 209px\" \/><\/figure><\/div>\n\n\n\n<p><br>On trouve p\u00eale-m\u00eale soif, faim, entretien, bris, m\u00e9dical et enrichissement identifi\u00e9s par des icones simples oui doubles sur les cartes ressources. On trouve \u00e9galement sur chaque carte une ic\u00f4ne \u00ab\u00a0d\u00e9placement\u00a0\u00bb<\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p>&#x1f314; Le matin : Tous les joueurs piochent 1 carte \u00ab\u00a0besoin\u00a0\u00bb et doivent assigner des jetons \u00ab\u00a0Probl\u00e8mes\u00a0\u00bb sur les animaux situ\u00e9s dans les 3 habitats dont l\u2019ic\u00f4ne de besoin correspond \u00e0 celui indiqu\u00e9 sur la carte;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1-896x1024.png\" alt=\"\" class=\"wp-image-53545\" width=\"133\" height=\"152\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1-896x1024.png 896w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1-262x300.png 262w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1-768x878.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1-140x160.png 140w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1-214x245.png 214w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1-297x340.png 297w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343565556_633319511480825_2349021222306879107_n-1.png 1516w\" sizes=\"auto, (max-width: 133px) 100vw, 133px\" \/><\/figure><\/div>\n\n\n\n<p><br>Le cartes \u00ab\u00a0besoins\u00a0\u00bb ont les m\u00eames icones que les cartes ressources (simples ou doubles) .<\/p>\n\n\n\n<p>&#x1f316; L&rsquo;apr\u00e8s midi : Phase coll\u00e9giale o\u00f9 tous les joueurs vont r\u00e9fl\u00e9chir ensemble sur les actions \u00e0 mener parmi : se d\u00e9placer, r\u00e9gler des probl\u00e8mes et accueillir des animaux. <br><br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>  Se d\u00e9placer : sur chaque carte \u00ab\u00a0ressources\u00a0\u00bb, une ic\u00f4ne \u00ab\u00a0d\u00e9placement\u00a0\u00bb permet d&rsquo;utiliser la carte non comme une ressource mais bien pour d\u00e9placer un joueur vers une des zones du plateau de jeu.<br>Un joueur peut se d\u00e9placer sur une zone habitat ou une des 4 zones d&rsquo;accueil des nouveaux animaux. en d\u00e9faussant une carte ressource. La dite \u00ab\u00a0ressource\u00a0\u00bb sera perdue au profit de l&rsquo;action d\u00e9placement. <\/li><li>R\u00e9gler les probl\u00e8mes : seule solution pour enlever les jetons \u00ab\u00a0probl\u00e8mes\u00a0\u00bb des animaux pr\u00e9sents dans les habitats, d\u00e9fausser autant de cartes ressources que de jetons probl\u00e8mes pr\u00e9sents.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n-753x1024.png\" alt=\"\" class=\"wp-image-53533\" width=\"141\" height=\"192\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n-753x1024.png 753w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n-220x300.png 220w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n-768x1045.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n-118x160.png 118w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n-180x245.png 180w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n-250x340.png 250w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343571521_636489611825268_5117801842625044968_n.png 1156w\" sizes=\"auto, (max-width: 141px) 100vw, 141px\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Accueillir de nouveau animaux : les nouveaux venus ont eux aussi des besoins pour int\u00e9grer un des leur habitats. Un joueur peut donc apr\u00e8s un d\u00e9placement jouer autant de carte qu&rsquo;il peut pour assouvir ces besoins en une ou plusieurs fois. D\u00e8s que l&rsquo;animal \u00e0 obtenu toutes les ressources n\u00e9cessaires ce dernier se d\u00e9place dans son nouvel habitat. C&rsquo;est certes une bonne nouvelle (c&rsquo;est tout de m\u00eame la finalit\u00e9 du jeu) mais amener de nouveaux animaux dans les habitats va probablement g\u00e9n\u00e9rer de nouveaux besoin \u00e0 r\u00e9soudre l&rsquo;apr\u00e8s midi de la prochaine journ\u00e9e.<\/li><\/ul>\n\n\n\n<p>Toutes ces actions (d\u00e9placement\/ressources) peuvent \u00eatre jou\u00e9es dans un ordre quelconque parmi tous les joueurs. C&rsquo;est ici que la notion de coop\u00e9ration est la plus sensible. G\u00e9rer l&rsquo;apr\u00e8s midi est loin d&rsquo;\u00eatre une mince affaire.<\/p>\n\n\n\n<p>&#x1f318; Le soir : Retour \u00e0 la cantine du zoo et gestion de crise \u00e9ventuelle.<\/p>\n\n\n\n<p>Une fois le travail de sape de l&rsquo;apr\u00e8s midi effectu\u00e9 , les joueurs v\u00e9rifient si il reste encore des jetons \u00ab\u00a0besoin\u00a0\u00bb sur les animaux pr\u00e9sents dans les habitats et rentrent \u00e0 la cantine.<br>Si c&rsquo;est le cas, une gestion de crise s&rsquo;active : les joueurs piochent et d\u00e9faussent autant de cartes \u00ab\u00a0ressources\u00a0\u00bb n\u00e9cessaires pour assouvir tous les besoins des animaux encore pr\u00e9sents.<br>Si plus aucune carte \u00ab\u00a0ressources\u00a0\u00bb n&rsquo;est disponible :<strong> la partie est perdue !<\/strong><br>Une fois la crise r\u00e9solue, tous les joueurs peuvent \u00ab\u00a0sauvegarder\u00a0\u00bb leur cartes ressources non utilis\u00e9es dans l&rsquo;entrep\u00f4t mais les places sont limit\u00e9es \u00e0 3 cartes maximum !<br>Ces cartes s\u00e9viront ainsi pour la prochaine journ\u00e9e.<\/p>\n\n\n\n<p>Si les 7 nouveaux animaux ont int\u00e9gr\u00e9 le zoo apr\u00e8s la soir\u00e9e , alors la partie est gagn\u00e9e imm\u00e9diatement. <br>Six enveloppes scell\u00e9es permettront aux joueurs de d\u00e9couvrir d&rsquo;autres facettes du jeu (cartes, sticker, r\u00e8gles etc&#8230;)  amenant ainsi un peu plus de piquant \u00e0 chaque nouvelle partie r\u00e9ussie ou manqu\u00e9e !<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Un parc attractif ! &#x1f981;<\/h5>\n\n\n\n<p>Un vrai jeu coop\u00e9ratif sur le th\u00e8me du zoo attire forc\u00e9ment les enfants, ici pas de comp\u00e9tition et des animaux chatoyants ! Du pur familial.<br>Une r\u00e8gle de jeu tr\u00e8s claire et toute aussi color\u00e9e (pour les aides de jeu) permet de maintenir l&rsquo;attention des plus jeunes, tout s&rsquo;explique en 10 petites minutes.<\/p>\n\n\n\n<p>Miller Zoo est l&rsquo;arch\u00e9type m\u00eame du jeu d&rsquo;entr\u00e9e pour toute la famille en mode coop\u00e9ratif et l\u00e9gacy. <br>R\u00e9ussir \u00e0 passer quelques tours sans encombre, travailler ensemble la logique de coordination sur la gestion des d\u00e9fis permanents et d\u00e9couvrir de nouvelles aventures avec ces 6 enveloppes que les plus jeunes lorgnent avidement vont permettre, enfin,  aux enfants frustr\u00e9s de voir leurs parents se creuser a t\u00eate sur une partie d&rsquo;Ark Nova de s&rsquo;approprier un temps la gestion d&rsquo;un zoo tr\u00e8s intriguant.<\/p>\n\n\n\n<p><br><br><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br><br><\/p>\n\n\n\n<p><br><br><br><\/p>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"797\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n-1024x797.png\" alt=\"\" class=\"wp-image-53548\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n-1024x797.png 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n-300x233.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n-768x598.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n-160x125.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n-315x245.png 315w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n-437x340.png 437w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/04\/343590377_711202244112579_9083061994958239725_n.png 1961w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Tir\u00e9 de l&rsquo;histoire des propri\u00e9taires d&rsquo;un zoo en Bauce au Qu\u00e9bec&nbsp;\u00c9milie et Cliffort Miller ont propos\u00e9 \u00e0 Thomas Dagenais-Lesp\u00e9rance, l&rsquo;auteur du c\u00e9l\u00e8bre D\u00e9crypto de donner vie \u00e0 ce jeu. Vous incarnerez donc dans ce jeu coop\u00e9ratif , la famille Miller, g\u00e9rante d&rsquo;un zoo. Ce parc pourra ouvrir&#46;&#46;&#46;<\/p>\n","protected":false},"author":9,"featured_media":53296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[4370,4369],"class_list":["post-53295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-animaux","tag-zoo","annee-3637","auteurs-thomas-dagenais-lesperance","editeurs-randolph","illustrateurs-jocelyne-bouchard","illustrateurs-marjorie-gros","nombre_conseille-1355","mecanismes-cooperatif"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/53295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=53295"}],"version-history":[{"count":41,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/53295\/revisions"}],"predecessor-version":[{"id":53706,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/53295\/revisions\/53706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/53296"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=53295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=53295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=53295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}