{"id":53890,"date":"2023-06-03T17:57:32","date_gmt":"2023-06-03T15:57:32","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=53890"},"modified":"2023-06-03T17:57:35","modified_gmt":"2023-06-03T15:57:35","slug":"ruse-instincts-de-la-taniere-je-pledge-ou-pas","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/06\/03\/ruse-instincts-de-la-taniere-je-pledge-ou-pas\/","title":{"rendered":"Ruse Instincts de la Tani\u00e8re: Je pledge ou pas?"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/05\/Ruse.jpg\" alt=\"\" class=\"wp-image-53891\" width=\"509\" height=\"509\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/05\/Ruse.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/05\/Ruse-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/05\/Ruse-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/05\/Ruse-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/05\/Ruse-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/05\/Ruse-340x340.jpg 340w\" sizes=\"auto, (max-width: 509px) 100vw, 509px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-align:center\"><a href=\"https:\/\/www.kickstarter.com\/projects\/guime\/ruse-boardgame\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Voir la campagne (opens in a new tab)\">Voir la campagne<\/a><\/h4>\n\n\n\n<p>Apr\u00e8s \u00ab\u00a0<a href=\"https:\/\/www.vindjeu.eu\/2023\/06\/01\/carson-city-big-box-je-pledge-ou-pas\/\"><strong>Carson City Big Box: Je pledge ou pas?<\/strong><\/a>\u00ab\u00a0, et vu vos encouragements, nous avons d\u00e9cid\u00e9 de prologer l&rsquo;exp\u00e9rience de ce type d&rsquo;article avec <strong>Ruse, Instincts de la Tani\u00e8re.<\/strong><\/p>\n\n\n\n<p>Ruse est le premier jeu de son <strong>self made man<\/strong>, auteur\/\u00e9diteur\/illustrateur: \u00ab\u00a0Guime\u00a0\u00bb.  Et pourtant, on d\u00e9couvre beaucoup de professionnalisme et d&rsquo;exp\u00e9rience derri\u00e8re ce jeu.  Cela fait en effet 4 ans qu&rsquo;il est en d\u00e9veloppement et \u00e7a se voit!<\/p>\n\n\n\n<p>Ruse est un jeu de <strong>placement <\/strong><del>d&rsquo;ouvriers<\/del> <strong>de d\u00e9s<\/strong>. Il se joue en 4 manches et chaque manche est divis\u00e9e en phases. La premi\u00e8re consiste \u00e0 <strong>jeter un d\u00e9<\/strong> qui va indiquer s&rsquo;il s&rsquo;agit d&rsquo;un tour <strong>jour ou nuit<\/strong>. La diff\u00e9rence est que la nuit, les renards se d\u00e9placent plus vite, soit, d&rsquo;une case en plus. Le d\u00e9 indique \u00e9galement une valeur de 1 \u00e0 6. Si, lors de la phase suivante, lorsque vous jetterez vos d\u00e9s action, vous obtenez la m\u00eame valeur que celle du d\u00e9 jour\/nuit, vous gagnez alors un petit bonus int\u00e9ressant. Voil\u00e0 un hasard heureux ou malheureux qui m&rsquo;a un peu g\u00ean\u00e9 dans Ruse surtout qu&rsquo;il est impossible de l&rsquo;influencer.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-2-768x1024.jpeg\" alt=\"\" class=\"wp-image-53957\" width=\"335\" height=\"447\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-2-768x1024.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-2-225x300.jpeg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-2-120x160.jpeg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-2-184x245.jpeg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-2-255x340.jpeg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-2.jpeg 908w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/figure><\/div>\n\n\n\n<p>Le reste du jeu est, par contre, tr\u00e8s bon. <strong> Vous jetez <\/strong>(roulez \ud83d\ude09 ) <strong>vos d\u00e9s ouvrie<\/strong>r et selon la valeur obtenue vous gagnez plus ou moins de points de croissance.  Plus la valeur du d\u00e9 sera \u00e9lev\u00e9e, moins de <strong>points de croissance<\/strong> vous recevrez (<em>attention n\u00e9anmoins, ce n&rsquo;est pas 100% juste et math\u00e9matique comme dans <strong><a href=\"https:\/\/www.vindjeu.eu\/2022\/11\/15\/tiletum\/\">Tiletum<\/a><\/strong>: sur un 1-2 vous gagnez 4 points de croissance (soit 5-6 au total), sur un 3-4 vous en gagnez 3 (soit 6-7 au total et sur un 5-6 vous en gagnez 2 (soit 7-8 au total), mais les points de croissance semblent plus int\u00e9ressants que les points de d\u00e9&#8230;<\/em>).  Et les 2 s&rsquo;\u00e9quilibrent bien puisque plus la valeur de votre d\u00e9 sera \u00e9lev\u00e9e, plus vous pourrez faire des actions sur le plateau central mais moins vous aurez de points de croissance n\u00e9cessaires pour votre d\u00e9veloppement personnel.  Et ce <strong>d\u00e9veloppement personnel<\/strong> vous permettra non seulement de gagner de nombreux PVs mais aussi de gagner des d\u00e9s ouvriers suppl\u00e9mentaires ainsi que des capacit\u00e9s sp\u00e9ciales permanentes.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-3-768x1024.jpeg\" alt=\"\" class=\"wp-image-53958\" width=\"301\" height=\"401\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-3-768x1024.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-3-225x300.jpeg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-3-120x160.jpeg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-3-184x245.jpeg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-3-255x340.jpeg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-3.jpeg 908w\" sizes=\"auto, (max-width: 301px) 100vw, 301px\" \/><\/figure><\/div>\n\n\n\n<p>Sur le plateau central semi modulaire (les tuiles se placent al\u00e9atoirement mais il n&rsquo;y en a pas plus que celles sur le plateau), vous aurez l&rsquo;occasion de <strong>d\u00e9placer votre renard<\/strong> sur un des types de terrain (plaine, champ, for\u00eat, mar\u00e9cage et montagne) afin de r\u00e9aliser diverses actions comme r\u00e9colter des ressources, monter sur des \u00e9chelles qui donnent des bonus \u00e0 chaque \u00e9tape ou marquer son territoire obligeant les adversaires \u00e0 vous payer s&rsquo;ils veulent s&rsquo;arr\u00eater par l\u00e0 \ud83d\ude42<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-5-768x1024.jpeg\" alt=\"\" class=\"wp-image-53959\" width=\"312\" height=\"416\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-5-768x1024.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-5-225x300.jpeg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-5-120x160.jpeg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-5-184x245.jpeg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-5-255x340.jpeg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-5.jpeg 908w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/figure><\/div>\n\n\n\n<p>Le tout est encadr\u00e9 par des cartes <strong>objectifs personnels<\/strong>.  Vous en recevez 3 en d\u00e9but de partie et serez amen\u00e9s \u00e0 en piocher d&rsquo;autres.  R\u00e9ussir un objectif consiste g\u00e9n\u00e9ralement \u00e0 payer des ressources et \u00e0 atteindre un certain niveau sur une des 4 \u00e9chelles relatives aux 4 types de terrain du plateau.  La vari\u00e9t\u00e9 des cartes objectif vous obligera bien souvent \u00e0 devoir explorer un peu tous les terrains.  Surtout que r\u00e9aliser des objectifs vous permettra de vous d\u00e9velopper et de gagner des PVs.  Ne pas en r\u00e9aliser vous en fera perdre!  A voir s&rsquo;ils ne sont pas trop directifs&#8230;  De plus, 3 <strong>objectifs communs<\/strong> parmi 8 viendront encourager la comp\u00e9tition entre joueuses surtout que la premi\u00e8re \u00e0 en atteindre un gagnera plus de PVs que la seconde qui en gagnera plus que la 3\u00e8me,&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-6-768x1024.jpeg\" alt=\"\" class=\"wp-image-53960\" width=\"313\" height=\"417\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-6-768x1024.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-6-225x300.jpeg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-6-120x160.jpeg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-6-184x245.jpeg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-6-255x340.jpeg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-6.jpeg 1059w\" sizes=\"auto, (max-width: 313px) 100vw, 313px\" \/><\/figure><\/div>\n\n\n\n<p>Sous ses faux airs de <a href=\"https:\/\/www.vindjeu.eu\/2022\/11\/03\/the-wolves\/\"><strong>The Wolves<\/strong><\/a>, Ruse Instincts de la Tani\u00e8re sent tr\u00e8s bon.  Le hasard des jets de d\u00e9s ouvriers semble bien \u00e9quilibr\u00e9 et apporte un petit al\u00e9a obligeant les joueurs \u00e0 s&rsquo;adapter.  J&rsquo;ai par contre trouv\u00e9 dommage ce syst\u00e8me de jet de d\u00e9 jour\/nuit en d\u00e9but de manche apportant un avantage hasardeux dont le jeu se serait bien pass\u00e9.  Comme l&rsquo;ordre du tour est fix\u00e9 par les PVs (le joueur avec le plus de PVs joue en premier), j&rsquo;ai un peu peur d&rsquo;un effet win to win mais il est vrai que les joueurs \u00e0 la traine re\u00e7oivent une compensation.  Le reste est super excitant, avec un superbe mat\u00e9riel, un th\u00e8me original, des capacit\u00e9s asym\u00e9triques de d\u00e9part et des bonus \u00e0 glaner \u00e0 tous les \u00e9tages offrant de multiples choix aux joueurs dans leur strat\u00e9gie dict\u00e9e par les diff\u00e9rents objectifs et leurs capacit\u00e9s sp\u00e9ciales qu&rsquo;ils auront r\u00e9ussi \u00e0 d\u00e9bloquer.  R\u00e9sultat:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"text-align:center\"><span style=\"color:#459244\" class=\"color\">Je pledge!<\/span><\/h2>\n\n\n\n<p style=\"text-align:center\"><strong><a href=\"https:\/\/www.kickstarter.com\/projects\/guime\/ruse-boardgame\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Lien vers la page de la campagne (opens in a new tab)\">Lien vers la page de la campagne<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-10-768x1024.jpeg\" alt=\"\" class=\"wp-image-53956\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-10-768x1024.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-10-225x300.jpeg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-10-120x160.jpeg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-10-184x245.jpeg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/06\/3589-Ruse-10-255x340.jpeg 255w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voir la campagne Apr\u00e8s \u00ab\u00a0Carson City Big Box: Je pledge ou pas?\u00ab\u00a0, et vu vos encouragements, nous avons d\u00e9cid\u00e9 de prologer l&rsquo;exp\u00e9rience de ce type d&rsquo;article avec Ruse, Instincts de la Tani\u00e8re. Ruse est le premier jeu de son self made man, auteur\/\u00e9diteur\/illustrateur: \u00ab\u00a0Guime\u00a0\u00bb. Et pourtant, on d\u00e9couvre beaucoup de&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":53891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1456],"tags":[],"class_list":["post-53890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crowdfunding"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/53890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=53890"}],"version-history":[{"count":7,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/53890\/revisions"}],"predecessor-version":[{"id":53961,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/53890\/revisions\/53961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/53891"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=53890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=53890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=53890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}