{"id":54523,"date":"2023-07-16T18:03:47","date_gmt":"2023-07-16T16:03:47","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=54523"},"modified":"2023-08-03T18:12:26","modified_gmt":"2023-08-03T16:12:26","slug":"les-jeux-video-les-plus-attendus-de-lete-2023","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/07\/16\/les-jeux-video-les-plus-attendus-de-lete-2023\/","title":{"rendered":"Les jeux vid\u00e9o les plus attendus de l\u2019\u00e9t\u00e9 2023"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<p>Traditionnellement, l\u2019\u00e9t\u00e9 est une p\u00e9riode assez calme au niveau des sorties jeux vid\u00e9o. Ce n\u2019est toutefois pas le cas de cet \u00e9t\u00e9 2023. De nombreux hits sont en effet attendus tout au long de l\u2019\u00e9t\u00e9. Voici donc les jeux les plus attendus pour la p\u00e9riode estivale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Baldur\u2019s Gate III : le retour d\u2019un mythe<\/h2>\n\n\n\n<p>Bas\u00e9e sur l\u2019univers de Donjons et Dragons, la saga Baldur\u2019s Gate a connu un succ\u00e8s retentissant \u00e0 la fin des ann\u00e9es 90 et au d\u00e9but des ann\u00e9es 2000. Toutefois, le troisi\u00e8me opus de la s\u00e9rie se sera fait attendre. En effet, alors que Baldur\u2019s Gate II est sorti en 2000, il aura fallu attendre le 31 ao\u00fbt 2023 pour mettre la main sur la version compl\u00e8te de Baldur\u2019s Gate III. Depuis fin 2020, il est toutefois possible de jouer \u00e0 sa version anticip\u00e9e. Ce titre est un savant m\u00e9lange entre jeu de r\u00f4le et hack and slash. Vous parcourez en effet un monde m\u00e9di\u00e9val, dans lequel vous devez remplir diff\u00e9rentes missions et venir \u00e0 bout de hordes d\u2019ennemis.<\/p>\n\n\n\n<p>L\u2019une des principales sp\u00e9cificit\u00e9s de ce titre est la forte pr\u00e9sence de loot. Il s\u2019agit de pi\u00e8ces d\u2019\u00e9quipements que vous pouvez utiliser pour am\u00e9liorer votre personnage. Vous pouvez les recevoir apr\u00e8s avoir accompli une qu\u00eate ou abattu un ennemi. Ces r\u00e9compenses sont al\u00e9atoires, leur efficacit\u00e9 et leur raret\u00e9 pouvant fortement varier. Ce loot peut alors procurer une adr\u00e9naline assez semblable \u00e0 celle que l\u2019on peut rencontrer dans un casino. Obtenir un \u00e9quipement particuli\u00e8rement rare est alors comme remporter le jackpot sur une machine \u00e0 sous. D\u2019ailleurs, si vous appr\u00e9ciez les jeux de hasard, vous pouvez<a href=\"https:\/\/fr-slotsup.com\/bonus-de-casino\/sans-depot\"> essayer de choisir ici<\/a> un casino avec bonus sans d\u00e9p\u00f4t en France. Enfin, veuillez noter que si le titre est disponible sur PC, il le sera aussi sur Playstation 5.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Final Fantasy XVI : pour commencer l\u2019\u00e9t\u00e9 en fanfare<\/h2>\n\n\n\n<p>L\u2019une des principales sorties de l\u2019\u00e9t\u00e9 2023 sera disponible d\u00e8s le 22 juin. Il s\u2019agit de Final Fantasy XVI, un action-RPG qui offre de nombreuses promesses. Uniquement disponible sur Playstation 5, il parvient \u00e0 exploiter pleinement les capacit\u00e9s de la derni\u00e8re console de Sony. C\u2019est notamment un titre qui propose de magnifiques graphismes et une ambiance tr\u00e8s cin\u00e9matographique. Les environnements sont en effet magnifiques et tr\u00e8s vari\u00e9s. En ce qui concerne le syst\u00e8me de jeu, il rappelle fortement celui de Final Fantasy XV. Tr\u00e8s dynamique, il vous permet de vous sentir au c\u0153ur de l\u2019action.<\/p>\n\n\n\n<p>L\u2019histoire s\u2019annonce \u00e9galement tr\u00e8s prenante. Vous incarnez Clive Rosfield, un \u00e9missaire capable de contr\u00f4ler diff\u00e9rents Primordiaux. Ces derniers correspondent aux chim\u00e8res qu\u2019on retrouve dans tous les \u00e9pisodes de la saga. Vous devez alors prendre part \u00e0 une grande guerre, qui d\u00e9cidera de l\u2019avenir des cristaux, tr\u00e8s important dans toute la s\u00e9rie. C\u2019est aussi un titre qui offre une excellente dur\u00e9e de vie. S\u2019il faut compter environ 35 heures pour terminer l\u2019histoire principale, le finir \u00e0 100 % devrait prendre entre 70 et 80 heures. Enfin, si vous voulez l\u2019essayer avant de l\u2019acheter, une d\u00e9mo est d\u00e9j\u00e0 disponible sur le PS Store.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pikmin 4 : un vent de fra\u00eecheur sur Switch<\/h2>\n\n\n\n<p>Moins connue que les licences Mario ou Zelda, celle de Pikmin est tout de m\u00eame tr\u00e8s appr\u00e9ci\u00e9e, notamment par les fans historiques de Nintendo. Le quatri\u00e8me \u00e9pisode de la s\u00e9rie sera d\u2019ailleurs disponible sur Nintendo Switch le 21 juillet prochain. Il s\u2019agit d\u2019un jeu de strat\u00e9gie, dans lequel vous devez guider des Pikmins pour d\u00e9jouer diff\u00e9rents pi\u00e8ges. Les Pikmins sont de petites b\u00eates de diff\u00e9rentes couleurs. Chaque couleur permet de d\u00e9finir leurs sp\u00e9cificit\u00e9s. Vous devez donc coordonner les diff\u00e9rentes comp\u00e9tences de vos Pikmins pour pouvoir avancer dans le jeu. Vous commencez votre partie en cr\u00e9ant votre personnage et en voyant son vaisseau s\u2019\u00e9craser sur une plan\u00e8te inconnue, sur laquelle se trouvent les Pikmins.<\/p>\n\n\n\n<p>Parmi les nouveaut\u00e9s de son titre, on peut citer l\u2019apparition de nouveaux alli\u00e9s. C\u2019est notamment le cas du Pikmin de glace, mais aussi du chien Oatchi. Ce dernier est particuli\u00e8rement puissant. Vous pouvez alors l\u2019utiliser pour casser ou d\u00e9placer des objets lourds. Il permet aussi de transporter tous vos Pikmins dans les eaux profondes. L\u2019une des autres caract\u00e9ristiques de ce titre, qu\u2019on retrouve \u00e9galement dans tous les opus de la s\u00e9rie, est un parfait \u00e9quilibre entre accessibilit\u00e9 et challenge. C\u2019est notamment parce qu\u2019on peut progresser assez facilement dans le jeu, mais d\u00e9couvrir tous ses secrets s\u2019av\u00e8re bien plus difficile.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Starfield : le nouveau bijou de Bethesda<\/h2>\n\n\n\n<p>Bethesda est un studio notamment connu pour ses jeux de r\u00f4les particuli\u00e8rement immersifs. C\u2019est par exemple le cas des s\u00e9ries Fallout ou The Elder Scrolls. Donc, lorsque ce studio annonce un jeu de r\u00f4le se d\u00e9roulant dans l\u2019espace, cela devient un des jeux les plus attendus de l\u2019ann\u00e9e. En outre, comme c\u2019est le cas depuis le rachat de ce studio par Microsoft, Starfield sera disponible dans le Xbox Game Pass d\u00e8s le jour de sa sortie, c\u2019est-\u00e0-dire le 6 septembre 2023. C\u2019est un titre nouvelle g\u00e9n\u00e9ration qui sera exclusif \u00e0 l\u2019\u00e9cosyst\u00e8me Microsoft. Il ne sortira donc que sur PC et Xbox Series S\/X.<\/p>\n\n\n\n<p>Starfield propose une aventure dans laquelle vous pouvez visiter plus de 1 000 plan\u00e8tes. Cela vous assure de vivre une aventure vari\u00e9e et unique. Vous \u00eates en effet libre de choisir l\u2019ordre dans lequel vous visitez chacune de ces plan\u00e8tes. En outre, c\u2019est un titre qui offre beaucoup de libert\u00e9s en termes de personnalisation. Si vous pouvez cr\u00e9er le personnage que vous souhaitez, vous pouvez aussi d\u00e9finir son pass\u00e9 et ses origines. Enfin, de nombreuses possibilit\u00e9s de crafting s\u2019offrent \u00e0 vous. Vous pouvez par exemple recruter une \u00e9quipe qui pourra extraire les principales ressources des diff\u00e9rentes plan\u00e8tes. Vous pouvez ensuite utiliser ses ressources de diff\u00e9rentes mani\u00e8res.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un \u00e9t\u00e9 riche en jeux<\/h2>\n\n\n\n<p>Comme vous avez d\u00e9j\u00e0 pu vous en rendre compte, de nombreux jeux vid\u00e9o int\u00e9ressants vont sortir au cours de la saison estivale. C\u2019est notamment le cas de Baldur\u2019s Gate III, de Final Fantasy XVI, de Pikmin 4 et de Sarfield. Toutefois, d\u2019autres jeux int\u00e9ressants sortent aussi lors de cet \u00e9t\u00e9 2023. C\u2019est par exemple le cas d\u2019ARK : Survival Ascended, de Mortal Kombat 1 ou de Lies of P.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Traditionnellement, l\u2019\u00e9t\u00e9 est une p\u00e9riode assez calme au niveau des sorties jeux vid\u00e9o. Ce n\u2019est toutefois pas le cas de cet \u00e9t\u00e9 2023. De nombreux hits sont en effet attendus tout au long de l\u2019\u00e9t\u00e9. Voici donc les jeux les plus attendus pour la p\u00e9riode estivale. Baldur\u2019s Gate III :&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3636],"tags":[],"class_list":["post-54523","post","type-post","status-publish","format-standard","hentry","category-casino"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/54523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=54523"}],"version-history":[{"count":1,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/54523\/revisions"}],"predecessor-version":[{"id":54524,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/54523\/revisions\/54524"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=54523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=54523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=54523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}