{"id":54638,"date":"2023-09-05T21:02:16","date_gmt":"2023-09-05T19:02:16","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=54638"},"modified":"2023-09-05T21:03:03","modified_gmt":"2023-09-05T19:03:03","slug":"vengeance-roll-fight-episode-1-2","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/09\/05\/vengeance-roll-fight-episode-1-2\/","title":{"rendered":"Vengeance Roll &#038; Fight : \u00e9pisode 1 &#038; 2"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-1024x731.jpg\" alt=\"\" class=\"wp-image-54639\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/05\/Claire-desert.jpg\" alt=\"\" class=\"wp-image-49027\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple : <\/span><span style=\"color:#cf2e2e\" class=\"color\">7,5\/10<\/span><\/h5>\n\n\n\n<p>La lecture du synopsis m\u2019a emball\u00e9e. Il nous promet un jeu\ndigne d\u2019un film d\u2019actions en deux \u00e9pisodes dont on est le h\u00e9ros. Pour cela on\ndoit \u00e9liminer les gangs qui s\u00e9vissent en ville gr\u00e2ce \u00e0 des lancers de d\u00e9s en\ntemps r\u00e9el. L\u00e0 je dois admettre que j\u2019ai \u00e9t\u00e9 un peu d\u00e9\u00e7ue car je m\u2019attendais \u00e0\nune sorte de legacy et ce n\u2019est vraiment pas le cas. <strong>Vengeance roll &amp; fight<\/strong> propose un roll &amp; write original\navec des d\u00e9s et des plateaux effa\u00e7ables. Les deux bo\u00eetes, avec les nombreux\nplateaux Repaire et les diff\u00e9rents Big-Boss offrent une grande vari\u00e9t\u00e9 de\nsituations sans corr\u00e9lation entre elles.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Quand on arrive en ville<\/strong><\/h4>\n\n\n\n<p>Ce titre est asym\u00e9trique et comp\u00e9titif mais avec peu\nd\u2019interactions entre les joueurs. Chacun incarne un personnage avec ses\nparticularit\u00e9s et qui \u00e9volue dans son quartier. Une partie se d\u00e9roule en quatre\nmanches de quatre phases, toutes jou\u00e9es en simultan\u00e9. Le vainqueur est celui\nqui aura le plus de points. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"124\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7544-300x124.jpg\" alt=\"\" class=\"wp-image-54640\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7544-300x124.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7544-768x319.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7544-1024x425.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7544-160x66.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7544-520x216.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7544-720x299.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p><strong>La premi\u00e8re phase<\/strong>\nconsiste \u00e0 lancer trois d\u00e9s blancs et \u00e0 en appliquer les effets sur son plateau\nPersonnage. Il y a quatre actions possibles&nbsp;: <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211;\ns\u2019entrainer, ce qui permet d\u2019augmenter sa piste d\u2019exp\u00e9rience et donne la\npossibilit\u00e9 d\u2019acheter de nouvelles comp\u00e9tences et de marquer des points en fin\nde partie<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; activer\ndes objets en notre possession. Chaque participant en poss\u00e8de quatre qui ne\nsont activables que trois fois chacun. <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; &nbsp;soigner ses blessures ou augmenter sa jauge de\nvie<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; anticiper\nune action pour la phase suivante ce qui \u00e9vitera de lui assigner des d\u00e9s pour\nla r\u00e9aliser<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211; de\ncollecter un butin ou bien de faire l\u2019une des quatre actions pr\u00e9c\u00e9dentes.<\/p>\n\n\n\n<p>On applique le r\u00e9sultat des trois d\u00e9s + une des quatre\npremi\u00e8res actions cit\u00e9es au choix.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"97\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7545-300x97.jpg\" alt=\"\" class=\"wp-image-54641\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7545-300x97.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7545-768x249.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7545-1024x332.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7545-160x52.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7545-520x169.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7545-720x234.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p><strong>La deuxi\u00e8me phase<\/strong>\nest celle des lancers. Chaque comp\u00e9tence de d\u00e9placement ou de combat est\ncaract\u00e9ris\u00e9e par une combinaison de deux, trois ou quatre d\u00e9s. Chacun lance\nquatre d\u00e9s et choisit de les affecter \u00e0 l\u2019une d\u2019elle en fonction de ce qu\u2019il\npense faire \u00e0 la phase suivante. C\u2019est l\u00e0 que l\u2019interaction intervient puisque m\u00eame\nsi les joueurs ne peuvent lancer que quatre d\u00e9s, lorsqu\u2019ils ont r\u00e9alis\u00e9 une\ncomp\u00e9tence, ils peuvent en reprendre dans le pot commun, dans la limite de\nquatre. Une course s\u2019installe alors entre les participants afin de pouvoir\nr\u00e9cup\u00e9rer le plus de d\u00e9s possible et ainsi faire le plus d\u2019actions. Pour\ns\u2019activer, les comp\u00e9tences requi\u00e8rent des symboles sp\u00e9cifiques ce qui n\u00e9cessite\nsouvent plusieurs jets pour y arriver. Mais attention car on peut r\u00e9colter des\nblessures qui peuvent s\u2019av\u00e9rer fatales. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"231\" height=\"300\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7546-231x300.jpg\" alt=\"\" class=\"wp-image-54642\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7546-231x300.jpg 231w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7546-768x995.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7546-790x1024.jpg 790w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7546-123x160.jpg 123w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7546-189x245.jpg 189w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/IMG_E7546-262x340.jpg 262w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><\/figure><\/div>\n\n\n\n<p><strong>La troisi\u00e8me phase<\/strong>\nest celle de la r\u00e9solution des jets de d\u00e9s. Chacun r\u00e9alise, dans l\u2019ordre de son\nchoix, les comp\u00e9tences activ\u00e9es. Gr\u00e2ce \u00e0 elles, on va pouvoir se d\u00e9placer dans\nle quartier et attaquer les sbires des gangs. Chaque malfrat a des sp\u00e9cificit\u00e9s\nqu\u2019il convient d\u2019analyser afin de les combattre efficacement. Comme dans tout gang,\nun Big-Boss plus compliqu\u00e9 \u00e0 abattre, dirige cette fine \u00e9quipe. <\/p>\n\n\n\n<p><strong>La quatri\u00e8me et\nderni\u00e8re phase<\/strong> est la r\u00e9solution. Elle permet de nettoyer son plateau, de\nr\u00e9colter des butins, de marquer des points pour la r\u00e9ussite d\u2019objectifs dans\ncertaines salles. Mais on peut aussi r\u00e9colter des blessures si certains sbires\nsont encore dans les parages. &nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Tout le monde change de trottoir<\/strong><\/h4>\n\n\n\n<p>Le&nbsp; nombre d\u2019actions\nque l\u2019on peut r\u00e9aliser lors de son tour va d\u00e9pendre de la chance, de la\nrapidit\u00e9 \u00e0 lancer ses d\u00e9s mais surtout \u00e0 prendre des d\u00e9cisions pour les\naffecter. Cet aspect donne le sentiment de jouer en temps r\u00e9el et bien s\u00fbr, pourrait\nd\u00e9plaire \u00e0 ceux qui aiment prendre le temps de r\u00e9fl\u00e9chir. Comme dans <a href=\"https:\/\/www.vindjeu.eu\/2021\/03\/09\/dice-throne\/\">Dice\nThrone<\/a>, il faut r\u00e9ussir \u00e0 r\u00e9aliser des combinaisons de d\u00e9s pour\nactiver ses futures actions. Si un symbole Blessure sort, il immobilise le d\u00e9\nrendant plus compliqu\u00e9 l\u2019assemblage des d\u00e9s restant. La pression du temps r\u00e9el\naugmente le risque d\u2019erreur tactique, il faut mieux avoir un plan bien \u00e9tabli\ndans sa t\u00eate avant de d\u00e9buter cette phase de jet\u2026 mais savoir aussi changer de\nplan si la chance n\u2019est pas au rendez-vous.<\/p>\n\n\n\n<p>J\u2019ai trouv\u00e9 que les r\u00e8gles n\u00e9cessitaient une lecture\nminutieuse car il faut bien faire attention aux termes employ\u00e9s. Avec la\nrapidit\u00e9 g\u00e9n\u00e9r\u00e9e par le jeu, les erreurs sont fr\u00e9quentes et comme tout le monde\njoue en m\u00eame temps, il n\u2019y a pas la possibilit\u00e9 de se faire corriger. J\u2019ai\nappr\u00e9ci\u00e9 de pouvoir acheter de nouvelles comp\u00e9tences mais j\u2019ai trouv\u00e9 dommage\nde ne pas pouvoir changer ses objets.<\/p>\n\n\n\n<p>Dans ce jeu, il est difficile de faire des points pour\ngagner. La possibilit\u00e9 qui appara\u00eet imm\u00e9diatement est de combattre le Big-Boss\nmais ce n\u2019est pas la seule. Les objectifs inscrits sur les plateaux Repaire\npermettent d\u2019en marquer beaucoup et souvent de faire la diff\u00e9rence. Les points\napport\u00e9s par les butins et la piste d\u2019entra\u00eenement semblent moins d\u00e9cisifs dans\nune partie. En quatre manches seulement, on ne peut vraiment pas glaner la\ntotalit\u00e9 des points, il faut alors faire des choix. L\u00e0, j\u2019ai trouv\u00e9 que c\u2019\u00e9tait\ndifficile car on ne sait pas o\u00f9 en sont les adversaires. Le nez coll\u00e9 sur son\nplateau, on \u00e9value difficilement sa position dans le classement. <\/p>\n\n\n\n<p>Vengeance Roll &amp; Fight propose un jeu rapide et tactique\ndans lequel il faut r\u00e9ussir \u00e0 prendre le meilleur chemin sur sa carte pour\nmarquer le plus de points tout en exploitant les particularit\u00e9s de son\npersonnage. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-roll-fight-episode-.jpg\" alt=\"\" class=\"wp-image-54643\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-roll-fight-episode-.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-roll-fight-episode--150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-roll-fight-episode--300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-roll-fight-episode--160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-roll-fight-episode--245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/08\/vengeance-roll-fight-episode--340x340.jpg 340w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vengeance roll &#038; fight propose un roll &#038; write original avec des d\u00e9s et des plateaux effa\u00e7ables. Il nous promet un jeu digne d\u2019un film d\u2019actions en deux \u00e9pisodes dont on est le h\u00e9ros. Pour cela on doit \u00e9liminer les gangs qui s\u00e9vissent en ville gr\u00e2ce \u00e0 des lancers de d\u00e9s en temps r\u00e9el.<\/p>\n","protected":false},"author":10,"featured_media":54639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[],"class_list":["post-54638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","annee-3637","auteurs-david-turczi","auteurs-gordon-calleja","auteurs-noralie-lubbers","editeurs-dont-panic-games","illustrateurs-axel-torvenius","illustrateurs-robert-sammelin","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/54638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=54638"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/54638\/revisions"}],"predecessor-version":[{"id":54645,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/54638\/revisions\/54645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/54639"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=54638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=54638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=54638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}