{"id":55261,"date":"2023-10-16T21:03:50","date_gmt":"2023-10-16T19:03:50","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=55261"},"modified":"2023-10-16T21:03:43","modified_gmt":"2023-10-16T19:03:43","slug":"vers-linfini-mais-pas-au-dela","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/10\/16\/vers-linfini-mais-pas-au-dela\/","title":{"rendered":"Vers l&rsquo;infini mais pas au-del\u00e0"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3678-vers-l-infini-mais-pas-au-dela.jpg\" alt=\"\" class=\"wp-image-55262\" width=\"372\" height=\"372\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3678-vers-l-infini-mais-pas-au-dela.jpg 372w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3678-vers-l-infini-mais-pas-au-dela-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3678-vers-l-infini-mais-pas-au-dela-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3678-vers-l-infini-mais-pas-au-dela-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3678-vers-l-infini-mais-pas-au-dela-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3678-vers-l-infini-mais-pas-au-dela-340x340.jpg 340w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3308-Essen-Spiel-2022-65-150x150.jpg\" alt=\"\" class=\"wp-image-55263\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span><\/strong><span style=\"color:#0693e3\" class=\"color\">&nbsp;<\/span>:&nbsp; <strong><span style=\"color:#cf2e2e\" class=\"color\">7\/10<\/span><\/strong><\/h5>\n\n\n\n<p>Apr\u00e8s, entre autre (dur de suivre leur rythme de sortie), l&rsquo;excellent <strong><a href=\"https:\/\/www.vindjeu.eu\/2023\/04\/10\/evergreen\/\">Evergreen<\/a><\/strong><a href=\"https:\/\/www.vindjeu.eu\/2023\/04\/10\/evergreen\/\"> <\/a>(<strong><a href=\"https:\/\/www.vindjeu.eu\/2023\/09\/28\/vin-djeu-dlannee-2023\/\">Vin d&rsquo;jeu d&rsquo;coup d&rsquo;coeur 2023<\/a><\/strong>), <strong><a href=\"https:\/\/www.vindjeu.eu\/2022\/12\/17\/my-shelfie\/\">My Shelfie<\/a><\/strong> et <strong><a href=\"https:\/\/www.vindjeu.eu\/2023\/03\/27\/qawale\/\">Qawale<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/editeurs\/gigamic\/\">Gigamic<\/a><\/strong><a href=\"https:\/\/www.vindjeu.eu\/editeurs\/gigamic\/\"> <\/a>sort un nouveau jeu d\u2019ambiance&nbsp;: Vers l\u2019infini mais pas au-del\u00e0&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Je suis une patate mari\u00e9e<\/strong><\/h2>\n\n\n\n<p>Le clin d\u2019\u0153il \u00e0 Toy Story est sympa mais le titre\n\u00ab&nbsp;Vers l\u2019infini mais pas au-del\u00e0&nbsp;\u00bb r\u00e9sume \u00e9galement bien ce qu\u2019est le\njeu.&nbsp; Il s\u2019agit d\u2019un quizz o\u00f9 on va lire une question \u00ab&nbsp;combien de\ntoilettes y a-t-il \u00e0 Buckingham Palace&nbsp;?&nbsp;\u00bb.&nbsp; Tous les meeples\ndes joueuses sont alors dans la navette.&nbsp; La premi\u00e8re joueuse va alors\nestimer une r\u00e9ponse&nbsp;: \u00ab&nbsp;20&nbsp;\u00bb et va placer son meeple aux\ncommandes de la navette.&nbsp; Les autres joueuses, \u00e0 leur tour, on alors le\nchoix entre&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Faire confiance \u00e0 la commandante et rester dans la navette<\/li><li>Penser que la commandante a donn\u00e9 un chiffre trop haut et quitter la navette<\/li><li>Faire une proposition plus haute \u00ab&nbsp;25&nbsp;\u00bb et prendre la place de commandante en pla\u00e7ant l\u2019ancienne commandante sur un si\u00e8ge passag\u00e8re de la navette&nbsp;&#x1f60a;<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tomber avec panache<\/strong><\/h2>\n\n\n\n<p>Quand revient le tour de la commandante (personne n\u2019a donc <strong>surench\u00e9rit<\/strong>),\non regarde la r\u00e9ponse et soit&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La commandante a dit une r\u00e9ponse en dessous (ou \u00e9gale) de la vraie r\u00e9ponse&nbsp;: elle gagne 4 points et les membres d\u2019\u00e9quipage en gagnent 2 (celles qui ont quitt\u00e9 le      vaisseau n\u2019en gagnent pas).<\/li><li>La commandante a d\u00e9pass\u00e9      la vraie r\u00e9ponse&nbsp;: elle perd 1 point, les passag\u00e8res n\u2019en perdent pas      et celles qui ont quitter le vaisseau en gagnent 2.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tu n\u2019es qu\u2019un jeu<\/strong><\/h2>\n\n\n\n<p>Le syst\u00e8me de cotation dans Vers l\u2019infini mais pas au-del\u00e0\nest vraiment bien fait car il vous encourage \u00e0 surench\u00e9rir (la commandante peut\ngagner 4 points ou, au pire, en perdre 1).&nbsp; Et il n\u2019est pas rare de voir\nles joueuses surench\u00e9rir bien au-del\u00e0 du raisonnable.&nbsp; Heureusement qu\u2019il\ny en a qui ont les pieds encore sur terre et qui pr\u00e9f\u00e8rent quitter le navire\ntant qu\u2019il en est encore temps&nbsp;&#x1f60a;&nbsp; Et \u00e9videmment, on\nne connait jamais la r\u00e9ponse (sauf quand on \u00e9coute encore l\u2019album blanc des\nBeatles et qu\u2019on connait le nombre exact de chansons qui le composent&nbsp;&#x1f609;\n).&nbsp; On doit alors faire appel \u00e0 son bon sens pour se dire que non\nvraiment, \u00e0 Buckingham Palace, il ne doit pas y avoir plus de 50 toilettes, il\nne faut pas exag\u00e9rer tout de m\u00eame (et bien si&nbsp;?)&nbsp;\ud83d\ude00<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini.jpg\" alt=\"\" class=\"wp-image-55526\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini.jpg 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/10\/3688-Vers-infini-340x340.jpg 340w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Vin d&rsquo;jeu d&rsquo;music<\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"The Beatles - Back In The U.S.S.R. (2018 Mix \/ Lyric Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/nS5_EQgbuLc?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Apr\u00e8s, entre autre (dur de suivre leur rythme de sortie), l&rsquo;excellent Evergreen (Vin d&rsquo;jeu d&rsquo;coup d&rsquo;coeur 2023), My Shelfie et Qawale, Gigamic sort un nouveau jeu d\u2019ambiance&nbsp;: Vers l\u2019infini mais pas au-del\u00e0&nbsp;! Je suis une patate mari\u00e9e Le clin d\u2019\u0153il \u00e0 Toy Story est sympa mais le titre&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":55262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[4094],"class_list":["post-55261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-devinette","annee-3637","auteurs-darrell-cannon","editeurs-gigamic","illustrateurs-sam-ailey","distributeurs-gigamic","nombre_conseille-1355","nombre_conseille-1217","nombre_conseille-1321","nombre_conseille-1919","mecanismes-devinettes","mecanismes-jeu-dambiance"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/55261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=55261"}],"version-history":[{"count":4,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/55261\/revisions"}],"predecessor-version":[{"id":55527,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/55261\/revisions\/55527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/55262"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=55261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=55261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=55261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}