{"id":5547,"date":"2013-08-20T21:29:42","date_gmt":"2013-08-20T20:29:42","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=5547"},"modified":"2013-08-20T21:29:42","modified_gmt":"2013-08-20T20:29:42","slug":"steam-map-expansion-2-china","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2013\/08\/20\/steam-map-expansion-2-china\/","title":{"rendered":"Steam : Map Expansion #2 China"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-5549\" style=\"margin: 5px;\" title=\"607 Steam ext 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-1.jpg\" alt=\"\" width=\"400\" height=\"245\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-1-300x183.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-1-150x91.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-1-400x244.jpg 400w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a07,5 \/10<\/span><\/strong><\/p>\n<p>Steam map expansion #2 est la seconde extension officielle pour <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2010\/07\/28\/steam\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Steam<\/span><\/a><\/span>, dont l&rsquo;auteur, <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/morgan-dontanville\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Morgan Dontanville<\/span><\/a>, est le m\u00eame que pour la <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2012\/07\/08\/steam-map-expansion-1-belgium-luxembourg\/\" target=\"_blank\"><span style=\"color: #0000ff;\">premi\u00e8re extension <\/span><\/a><\/span>mais est certainement diff\u00e9rent de l&rsquo;auteur du jeu de base, le grand <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/auteurs\/martin-wallace\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Martin Wallace <\/span><\/a><\/span>bien \u00e9videmment!<\/p>\n<p>3 cartes dans cette extension: la Chine, la Grande Bretagne et la Californie.\u00a0 Nous n&rsquo;avons pour le moment jou\u00e9 que sur la carte de Chine qui permet, contrairement au jeu de base, d&rsquo;y jouer \u00e0 2.<\/p>\n<p>Outre la physionomie de la carte, la Chine offre\u00a03 originalit\u00e9s:<br \/>\n1) A son tour, on ne peut <span style=\"color: #800080;\">construire que 2 morceaux<\/span> de voie au lieu de 3.\u00a0 Cette modification correspond bien \u00e0 la carte qui est petite et fort ramass\u00e9e.\u00a0 La majorit\u00e9s des cit\u00e9s peuvent se joindre en 1 ou\u00a02 voies.\u00a0 Mais ne vous y trompez pas, ce n&rsquo;est pas pour autant une ballade de sant\u00e9.\u00a0 La majorit\u00e9 des terrains sont occup\u00e9s par des rivi\u00e8res ou des colines ce qui rend vos constructions tr\u00e8s ch\u00e8res.<br \/>\n2) La meilleure trouvaille de cette extension est pour moi le changement effectu\u00e9 aux <span style=\"color: #800080;\">tuiles d&rsquo;ordre<\/span>.\u00a0 L&rsquo;ordre des num\u00e9ros a \u00e9t\u00e9 revu et pour y jouer \u00e0 2, seules 4 tuiles ordre sur les 7 sont disponibles chaque tour aux joueurs.\u00a0 Ceci rend les choix et l&rsquo;ordre du jeu plus importants.\u00a0 Tr\u00e8s bonne id\u00e9e.\u00a0 Elle a rendu notre partie \u00e0 2 plus passionnante que ce qu&rsquo;elle aurait pu \u00eatre avec les 7 tuiles ordre dispos.<br \/>\n3) <span style=\"color: #800080;\">Les inondations des 2 fleuves<\/span>.\u00a0 Cette modification aux r\u00e8gles est assez anecdotique et apporte fun et un l\u00e9ger hasard au jeu.\u00a0 On dispose 4 jetons jaunes et 4 bruns dans le sac noir.\u00a0 A chaque tour, apr\u00e8s la construction des voies, on tire 2 jetons au hasard.\u00a0 S&rsquo;ils sont de couleur diff\u00e9rente, rien ne se passe.\u00a0 Si par contre ils sont de m\u00eame couleur, le fleuve de cette couleur d\u00e9borde et inonde les villes adjacentes.\u00a0 Chaque fleuve inonde 2 villes.\u00a0 Si ces villes ont des yuans dessus, on en retire un.\u00a0 Sinon, la ville est inond\u00e9e.\u00a0 Durant la phase de construction des voies, les joueurs peuvent ajouter des yuans sur ces villes afin de la prot\u00e9ger de l&rsquo;inondation.\u00a0\u00a0Aucun cube ne peut passer, partir de ou arriver dans une ville inond\u00e9e.\u00a0 Pour faire passer un cube qui passe par une ville non inond\u00e9e mais dont le fleuve a d\u00e9bord\u00e9, le joueur\u00a0doit payer une pi\u00e8ce.\u00a0 C&rsquo;est sympa, \u00e7a peut faire couiner un joueur en pestant sur la malchance mais ce n&rsquo;est pas tr\u00e8s pr\u00e9pond\u00e9rant.\u00a0 Dans notre partie, \u00e7a s&rsquo;est pass\u00e9 2 fois sur les 8 tours.<\/p>\n<p>La carte de Chine est n\u00e9anmoins assez <span style=\"color: #ff6600;\">st\u00e9r\u00e9otyp\u00e9e<\/span>.\u00a0 En effet, il semble assez \u00e9vident, m\u00eame si les cubes ne sont pas tr\u00e8s avantageux, de commencer par le nord de la carte, l\u00e0 o\u00f9 les constructions de voies sont bon march\u00e9 pour au fil du jeu s&rsquo;\u00e9tendre vers le sud et vers les r\u00e9gions plus montagneuses du nord.\u00a0 C&rsquo;est dommage car on risque de se lasser de cette carte assez rapidement.\u00a0 Heureusement qu&rsquo;il y en a 2 autres dans cette extension!<\/p>\n<p>Enfin, j&rsquo;ai trouv\u00e9 le <span style=\"color: #ff6600;\">mat\u00e9riel<\/span> un peu cheap.\u00a0 Non que la carte et les jetons soient de tr\u00e8s bonne facture mais plut\u00f4t qu&rsquo;il est dommage que pour 20 Eur on n&rsquo;ait pas une petite boite pour ranger le mat\u00e9riel.\u00a0 R\u00e9sultat, il faut tout ranger dans la boite de base et apr\u00e8s 2 extensions, elle commence m\u00e9chamment \u00e0 gonfler&#8230;<\/p>\n<p>L&rsquo;extension #2 de Steam est donc une extension apportant plus de vari\u00e9t\u00e9 \u00e0 vos parties et permet surtout d&rsquo;y jouer \u00e0 2 ce qui est un plus ind\u00e9niable.\u00a0 Les originalit\u00e9s de cette extension sont tr\u00e8s bien trouv\u00e9es, dommage juste que la carte de la Chine soit si st\u00e9r\u00e9otyp\u00e9e.<\/p>\n<p style=\"text-align: center;\">_______________<\/p>\n<p><strong><span style=\"color: #333399;\">Philrey212<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a07\/10<\/span><\/strong><\/p>\n<p>Cette 2\u00e8me extension de Steam m&rsquo;a un peu d\u00e9\u00e7ue. Je rejoins l&rsquo;avis de SwatSh en ce qui concerne les deux nouveaut\u00e9s: inondation des fleuves et les tuiles ordre du tour qui ne sont pas toutes disponibles.<\/p>\n<p>Par contre, je pense que le premier joueur a un grand avantage due \u00e0 la physionomie de la carte. En effet, il sera le premier \u00e0 construire l\u00e0 o\u00f9 c&rsquo;est meilleur march\u00e9. Ce d\u00e9marrage l&rsquo;avantagera tout au long de la partie et rendra la t\u00e2che du deuxi\u00e8me joueur plus ardue.<\/p>\n<p>En r\u00e9sum\u00e9, cela reste Steam, excellent jeu, \u00a0mais cette extension n&rsquo;apporte pas suffisamment pour la rendre \u00ab\u00a0indispensable\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5548\" title=\"607 Steam ext 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-2-1024x768.jpg\" alt=\"\" width=\"819\" height=\"614\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/07\/607-Steam-ext-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Steam map expansion #2 est la seconde extension officielle pour Steam, dont l&rsquo;auteur, Morgan Dontanville, est le m\u00eame que pour la premi\u00e8re extension mais est certainement diff\u00e9rent de l&rsquo;auteur du jeu de base, le grand Martin Wallace bien \u00e9videmment! 3 cartes dans cette extension: la Chine, la Grande&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":5549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-5547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-464","auteurs-morgan-dontanville","editeurs-mayfair-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/5547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=5547"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/5547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/5549"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=5547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=5547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=5547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}