{"id":56285,"date":"2023-12-28T15:02:03","date_gmt":"2023-12-28T14:02:03","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=56285"},"modified":"2023-12-28T15:02:13","modified_gmt":"2023-12-28T14:02:13","slug":"age-of-galaxy-vf","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2023\/12\/28\/age-of-galaxy-vf\/","title":{"rendered":"Age of Galaxy (VF)"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-1.jpg\" alt=\"\" class=\"wp-image-50673\" width=\"551\" height=\"368\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-1.jpg 899w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-1-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-1-768x513.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-1-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-1-367x245.jpg 367w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-1-509x340.jpg 509w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/09\/Swa-56-150x150.jpg\" alt=\"\" class=\"wp-image-50226\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh&nbsp;<\/span>:<span style=\"color:#cf2e2e\" class=\"color\"> 9,5\/10<\/span><\/h5>\n\n\n\n<p>Age of Galaxy, c\u2019est un peu la suite d\u2019<strong><a href=\"https:\/\/www.vindjeu.eu\/2020\/01\/22\/age-of-civilization\/\">Age of Civilization<\/a> <\/strong>m\u00eame si les 2 jeux n\u2019ont rien \u00e0 voir\u2026 ou presque.&nbsp; En effet, les 2 jeux ont quelques points communs&nbsp;: <strong>m\u00eame auteur<\/strong>, <strong>m\u00eame \u00e9diteur<\/strong>, m\u00eame volont\u00e9 de r\u00e9aliser un jeu riche et profond dans une petite boite et un th\u00e8me en toute continuit\u00e9.<\/p>\n\n\n\n<p>La m\u00e9canique de base d\u2019Age of Galaxy est une m\u00e9canique de <strong>choix\nd\u2019action<\/strong>.&nbsp; Vous avez le choix entre <strong>14 actions<\/strong> \u00e0\nr\u00e9aliser&nbsp;(sans compter les actions bonus)!&nbsp; Ca va du gain ou de\nl\u2019\u00e9change de ressources\/PVs \u00e0 l\u2019achat de nouvelles technologies (= capacit\u00e9s),\n\u00e0 l\u2019exploration et la conqu\u00eate spatiale, \u00e0 la protection de ses zones ou \u00e0 la\nconqu\u00eate des zones adverses.&nbsp; Le tout agr\u00e9ment\u00e9 de bonus \u00e0 glaner par-ci\npar-l\u00e0, et d\u2019une petite course aux espaces disponibles.&nbsp; <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2-1024x576.jpg\" alt=\"\" class=\"wp-image-50674\" width=\"586\" height=\"329\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2-1024x576.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2-300x169.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2-768x432.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2-160x90.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2-436x245.jpg 436w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2-604x340.jpg 604w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-2.jpg 1536w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/figure><\/div>\n\n\n\n<p>Ce qui plait le plus dans Age of Galaxy c\u2019est sa <strong>gestion de cartes<\/strong>.&nbsp; Au d\u00e9but de la partie, chaque joueuse re\u00e7oit 7 cartes pioch\u00e9es au hasard et peut en d\u00e9fausser jusque 3 pour les remplacer par de nouvelles.&nbsp; A partir de cette <strong>main de d\u00e9part<\/strong>, elles vont <strong>se construire une strat\u00e9gie<\/strong>.&nbsp; En effet, chacune de ces cartes va apporter une capacit\u00e9 sp\u00e9ciale qu\u2019il vous faudra optimiser car vous ne pourrez b\u00e9n\u00e9ficier des <strong>effets permanents<\/strong> que de 3 de vos 7 cartes.&nbsp; Les autres pourront vous servir pour <strong>gagner des PVs<\/strong> extras en fin de partie en fonction de certains \u00e9l\u00e9ments (encore un choix strat\u00e9gique) ou des bonus imm\u00e9diats \u2026 au bon moment&nbsp;&#x1f60a;&nbsp; Et \u00e9videmment, <strong>les capacit\u00e9s se combinent<\/strong>\u2026&nbsp; Avoir une carte qui rapporte quelque chose quand vous faites une certaine action et une autre qui vous permet de faire cette action quand vous en faites une autre peut mener \u00e0 des effets en cascade assez impressionnants.&nbsp; Et ce qui est bluffant dans tout \u00e7a c\u2019est que <strong>l\u2019\u00e9quilibre est magnifiquement maintenu<\/strong> et m\u00eame si vous n\u2019avez pas la chance d\u2019avoir la combinaison qui tue, optimiser votre strat\u00e9gie en fonction de vos cartes peut vous mener au succ\u00e8s. Age of Galaxy r\u00e9ussit son pari de nous procurer <strong>un jeu riche et profond dans une petite boite<\/strong>.&nbsp; M\u00eame si on peut regretter son <strong>mat\u00e9riel<\/strong> un peu cheap, c\u2019est le prix \u00e0 payer pour une petite boite pas ch\u00e8re&nbsp;&#x1f609;&nbsp; Ses 30 cartes faction, toutes bien diff\u00e9rentes vont vous apporter <strong>un plaisir strat\u00e9gique \u00e0 chaque fois renouvel\u00e9<\/strong>.&nbsp; Le reste du jeu, m\u00eame s\u2019il est moins novateur qu\u2019<strong><a href=\"https:\/\/www.vindjeu.eu\/2020\/01\/22\/age-of-civilization\/\">Age of Civilization<\/a><\/strong>, est passionnant gr\u00e2ce principalement \u00e0 la recherche constante d\u2019optimisation, \u00e0 ses multiples voies strat\u00e9giques et la course aux emplacements entre les joueurs.&nbsp;  <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/PhilRey10-150x150.jpg\" alt=\"\" class=\"wp-image-47839\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">PhilRey<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8\/10<\/span><\/h5>\n\n\n\n<p>J&rsquo;avoue ne pas savoir quoi ajouter de plus que ce que dit SwatSh ci-dessus: c&rsquo;est tr\u00e8s bien r\u00e9sum\u00e9. <\/p>\n\n\n\n<p>Age of Galaxy est en effet tr\u00e8s profond avec des choix dans tous les sens (14 actions, je vous le rappelle). Si vous n&rsquo;appr\u00e9ciez pas trop les brises neurones, je vous conseille de passer votre chemin sur cette petite bo\u00eete car c&rsquo;est l&rsquo;\u00e9l\u00e9ment que je retiens ici: il faut tenir compte de plein de trucs. J&rsquo;\u00e9tais constamment en doute sur mes cartes \u00e0 jouer, voulant en jouer plus qu&rsquo;il n&rsquo;en faut!<\/p>\n\n\n\n<p>Une excellente surprise dans une si petit bo\u00eete! Chapeau!<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1291\" height=\"968\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18.jpg\" alt=\"\" class=\"wp-image-50672\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18.jpg 1291w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2022\/10\/3295-Age-of-galaxy-18-453x340.jpg 453w\" sizes=\"auto, (max-width: 1291px) 100vw, 1291px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Age of Galaxy, c\u2019est un peu la suite d\u2019Age of Civilization m\u00eame si les 2 jeux n\u2019ont rien \u00e0 voir\u2026 ou presque.&nbsp; En effet, les 2 jeux ont quelques points communs&nbsp;: m\u00eame auteur, m\u00eame \u00e9diteur, m\u00eame volont\u00e9 de r\u00e9aliser un jeu riche et profond dans une petite boite&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":50673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[4111],"class_list":["post-56285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-localisation","annee-3637","auteurs-jeffrey-cch","editeurs-pixie-games","illustrateurs-roxy-dai","illustrateurs-samuel-horowitz","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-asymetrie","mecanismes-choix-daction","mecanismes-draft"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/56285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=56285"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/56285\/revisions"}],"predecessor-version":[{"id":56459,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/56285\/revisions\/56459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/50673"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=56285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=56285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=56285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}