{"id":56475,"date":"2024-01-15T21:13:09","date_gmt":"2024-01-15T20:13:09","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=56475"},"modified":"2024-01-15T21:13:52","modified_gmt":"2024-01-15T20:13:52","slug":"cascadia-paysages","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/01\/15\/cascadia-paysages\/","title":{"rendered":"Cascadia Paysages"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-1.jpg\" alt=\"\" class=\"wp-image-56477\" width=\"582\" height=\"683\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-1.jpg 716w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-1-256x300.jpg 256w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-1-136x160.jpg 136w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-1-209x245.jpg 209w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-1-290x340.jpg 290w\" sizes=\"auto, (max-width: 582px) 100vw, 582px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/Swa-77-150x150.jpg\" alt=\"\" class=\"wp-image-56447\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>L&rsquo;extension Paysages pour le g\u00e9niallissime <strong><a href=\"https:\/\/www.vindjeu.eu\/2021\/12\/10\/cascadia\/\">Cascadia<\/a><\/strong> apporte diff\u00e9rents nouveaux \u00e9l\u00e9ments au jeu.  Outre de nouveaux sc\u00e9narios, il apporte de nouveaux jetons et tuiles pour pouvoir y jouer \u00e0<strong> 5 ou 6 joueuse<\/strong>s.  C&rsquo;est \u00e9videmment chouette de pouvoir y jouer \u00e0 autant mais \u00e7a rallonge la dur\u00e9e de jeu (comptez 20 minutes par joueuse suppl\u00e9mentaire).<\/p>\n\n\n\n<p>Mais l&rsquo;apport essentiel de Cascadia Paysages consiste en ses paysages \ud83d\ude00  Il s&rsquo;agit de cartes<strong> bonus associ\u00e9es \u00e0 chacun des 5 types de paysage<\/strong>.  Lors de la mise en place, on installe autant de cartes de chaque type que de joueurs face visible.  Dans une partie \u00e0 4 joueurs par exemple, vous aurez 4 joueurs x 5 types = <strong>20 cartes face visible \u00e0 lire<\/strong>.  C&rsquo;est un peu fastidieux (j&rsquo;en avais d&rsquo;ailleurs peur \u00e0 la lecture des r\u00e8gles) mais moins qu&rsquo;il n&rsquo;y parait car les illustrations sont tr\u00e8s bien faites et on retrouve souvent le m\u00eame type d&rsquo;effet d&rsquo;un paysage \u00e0 l&rsquo;autre.<\/p>\n\n\n\n<p>D\u00e8s qu&rsquo;une joueuse place la <strong>5\u00e8me tuile adjacente<\/strong>, ou plus, d&rsquo;un des types de paysage, elle peut <strong>r\u00e9clamer une des cartes paysage<\/strong> de ce type. Si elle le fait, elle gagne son bonus mais doit aussi <strong>placer une figurine de ce type de paysage<\/strong> sur la tuile qu&rsquo;elle vient de placer. Autrement dit, vous gagnez un bonus mais devez sacrifier un emplacement. Le choix ne sera pas toujours \u00e9vident et il arrivera que vous privil\u00e9gierez un emplacement animal et d&rsquo;autres fois un emplacement paysage. J&rsquo;ai vraiment bien aim\u00e9 ce type de dilemme, nouveau pour <strong><a href=\"https:\/\/www.vindjeu.eu\/2021\/12\/10\/cascadia\/\">Cascadia<\/a><\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4-1024x768.jpg\" alt=\"\" class=\"wp-image-56480\" width=\"768\" height=\"576\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-4.jpg 1440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>J&rsquo;ai trouv\u00e9, par contre, les <strong>bonus <\/strong>assez plats revenant bien souvent \u00e0 <strong>environ 3 PVs suppl\u00e9mentaires<\/strong>: pouvoir associer 2 groupes de terrain du m\u00eame type pour le d\u00e9compte des majorit\u00e9s, ajouter 2 tuiles virtuelles pour le m\u00eame d\u00e9compte, gagner 3 PVs, ajouter un point par animal de tel type pr\u00e9sent sur ce type de terrain, gagner 6 points -1 point par groupe diff\u00e9rent de tuiles de ce type de terrain,&#8230;<\/p>\n\n\n\n<p>Cascadia Paysages apporte un chouette nouvel \u00e9l\u00e9ment au jeu fantastique qu&rsquo;est <strong><a href=\"https:\/\/www.vindjeu.eu\/2021\/12\/10\/cascadia\/\">Cascadia<\/a><\/strong>. Ces paysages vont offrir de nouveaux choix menant \u00e0 des dilemmes difficiles. Dommage qu&rsquo;il n&rsquo;y ai pas plus de vari\u00e9t\u00e9 de bonus que de simples ajouts de PVs mais ces simples ajouts peuvent faire la diff\u00e9rence!<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10.jpg\" alt=\"\" class=\"wp-image-56476\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10.jpg 1440w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/12\/3777-Cascadia-paysages-10-453x340.jpg 453w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> L&rsquo;extension Paysages pour le g\u00e9niallissime Cascadia apporte diff\u00e9rents nouveaux \u00e9l\u00e9ments au jeu. Outre de nouveaux sc\u00e9narios, il apporte de nouveaux jetons et tuiles pour pouvoir y jouer \u00e0 5 ou 6 joueuses. C&rsquo;est \u00e9videmment chouette de pouvoir y jouer \u00e0 autant mais \u00e7a rallonge la dur\u00e9e de jeu&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":56477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[4634],"class_list":["post-56475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-nature","annee-3637","auteurs-molly-johnson","auteurs-randy-flynn","auteurs-robert-melvin","auteurs-shawn-stankewich","editeurs-lucky-duck-games","illustrateurs-beth-sobel","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/56475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=56475"}],"version-history":[{"count":4,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/56475\/revisions"}],"predecessor-version":[{"id":56646,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/56475\/revisions\/56646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/56477"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=56475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=56475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=56475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}