{"id":57246,"date":"2024-04-23T11:47:48","date_gmt":"2024-04-23T09:47:48","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=57246"},"modified":"2024-04-23T11:48:03","modified_gmt":"2024-04-23T09:48:03","slug":"the-castles-of-burgundy-special-edition","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/04\/23\/the-castles-of-burgundy-special-edition\/","title":{"rendered":"The Castles of Burgundy: Special Edition"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-1.jpg\" alt=\"\" class=\"wp-image-57248\" width=\"520\" height=\"520\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-1.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/Swa-80-150x150.jpg\" alt=\"\" class=\"wp-image-57249\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:<span style=\"color:#cf2e2e\" class=\"color\">  9\/10<\/span><\/h5>\n\n\n\n<p><strong>SwatSh:&nbsp;9\/10<\/strong><\/p>\n\n\n\n<p>Au fil du temps, et \u00e0 force d\u2019y prendre du plaisir \u00e0 chaque partie, \u00e0 force de voir les joueuses en redemander,&nbsp;<strong><a href=\"https:\/\/www.vindjeu.eu\/2011\/06\/19\/burgund-les-chateaux-de-bourgogne\/\">Castles of Burgundy<\/a><\/strong>&nbsp;est devenu un incontournable.&nbsp; Ze chef d\u2019\u0153uvre de Stefan Feld.&nbsp;<\/p>\n\n\n\n<p>Et quand on joue \u00e0 cette version deluxe surproduite, force est\nd\u2019avouer que le plaisir est encore plus grand m\u00eame si c\u2019est pas bien dans ce\nmonde de surconsommation.&nbsp;<\/p>\n\n\n\n<p>La version deluxe comprend quelques modules d\u2019extension dont celui, in\u00e9dit, des vignes. Il consiste \u00e0 acheter ou prendre des doubles tuiles vignes qu\u2019on place sur un plateau annexe pour gagner diff\u00e9rents bonus assez puissants et surtout beaucoup de points si on arrive \u00e0 placer beaucoup de vignes de m\u00eame c\u00e9page adjacentes les unes aux autres. Ces vignes changent du jeu de base et offrent plus de possibilit\u00e9s et de choix. Je les ai n\u00e9anmoins trouv\u00e9es trop fortes et gagner sans s\u2019y investir a fond est quasi de l\u2019ordre de l\u2019impossible.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2-1024x768.jpg\" alt=\"\" class=\"wp-image-57430\" width=\"768\" height=\"576\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-2.jpg 1440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/02\/Lucas-2-150x150.jpg\" alt=\"\" class=\"wp-image-56973\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">LOukas<\/span>: <span style=\"color:#cf2e2e\" class=\"color\"> 9,5\/10<\/span><\/h5>\n\n\n\n<p>Castles Of\nBurgundy est un jeu formidablement amusant! Expliquer et comprendre les r\u00e8gles\ndu jeu ne prend pas beaucoup de temps. Cependant, dans le jeu, il y a de\nnombreuses possibilit\u00e9s d&rsquo;actions, surtout avec l&rsquo;extension du jeu que nous\navons jou\u00e9e avec les vignobles. <\/p>\n\n\n\n<p>Beaucoup\nd\u00e9pend des d\u00e9s que vous lancez, donc il y a un peu de chance impliqu\u00e9e. Mais\nvous pouvez augmenter ou diminuer le nombre sur vos d\u00e9s avec vos ouvriers, ce\nqui vous donne quand m\u00eame quelques options suppl\u00e9mentaires. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4-1024x768.jpg\" alt=\"\" class=\"wp-image-57431\" width=\"553\" height=\"415\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-4.jpg 1440w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/><\/figure><\/div>\n\n\n\n<p>De plus, il\nest toujours agr\u00e9able dans le jeu de contrarier les autres et de ne pas\nseulement jouer \u00e0 votre propre jeu sans contact avec les autres. Dans ce jeu, il y a peu de tuiles de\nmines et de tuiles de ch\u00e2teaux \u00e0 prendre sur le plateau commun. Cela signifie que vous devez \u00eatre\nrapide pour les prendre si vous le souhaitez. Vous pourriez vouloir prendre\ncertaines tuiles dans ce jeu, mais alors le joueur avant vous prend justement\ncelle que vous vouliez. Dans ce cas, tout votre plan s&rsquo;effondre, mais ne vous\ninqui\u00e9tez pas, il y a beaucoup d&rsquo;options dans ce jeu. <\/p>\n\n\n\n<p>En r\u00e9sum\u00e9,\nce jeu \u00e9tait simple mais toutefois intelligent en raison des nombreuses\nd\u00e9cisions que vous aviez \u00e0 prendre. L&rsquo;art consiste alors \u00e0 faire les bons choix\npour obtenir le plus de points de victoire possible. Je n&rsquo;ai pas encore jou\u00e9 \u00e0\nbeaucoup de jeux d&rsquo;experts, mais celui-ci fait certainement partie de mes\nfavoris!<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/Thierry-1-e1484155191437-150x150.jpg\" alt=\"\" class=\"wp-image-16153\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Thierry<\/span>:  <span style=\"color:#cf2e2e\" class=\"color\">8,5\/10<\/span><\/h5>\n\n\n\n<p>Si l\u2019extension est int\u00e9ressante, perso j\u2019avais un meilleur souvenir du jeu de d\u00e9part, plus \u00e9quilibr\u00e9. L\u2019extension d\u00e9nature un peu trop le jeu, m\u00eame si elle pr\u00e9sente des variantes d\u2019actions et strat\u00e9gies sympas. Bon, le jeu de base \u00e9tant vraiment excellent, vous appr\u00e9cierez de toute fa\u00e7on cette derni\u00e8re version.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15.jpg\" alt=\"\" class=\"wp-image-57247\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15.jpg 1440w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3810-Castle-of-Burgundy-15-453x340.jpg 453w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Vin d&rsquo;jeu d&rsquo;music<\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Twin Tribes - Monolith (Official Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-XEavwcHU78?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Au fil du temps, et \u00e0 force d\u2019y prendre du plaisir \u00e0 chaque partie, \u00e0 force de voir les joueuses en redemander,&nbsp;Castles of Burgundy&nbsp;est devenu un incontournable.&nbsp; Ze chef d\u2019\u0153uvre de Stefan Feld.&nbsp; Et quand on joue \u00e0 cette version deluxe surproduite, force est d\u2019avouer que le&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":57248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[3951],"class_list":["post-57246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-reedition","annee-3637","auteurs-stefan-feld","editeurs-awaken-realms","editeurs-ravensburger","illustrateurs-jakub-dzikowski","illustrateurs-patryk-jedraszek","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-jets-de-des","mecanismes-multiples-bonus","mecanismes-placement-de-tuile"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=57246"}],"version-history":[{"count":3,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57246\/revisions"}],"predecessor-version":[{"id":57432,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57246\/revisions\/57432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/57248"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=57246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=57246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=57246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}