{"id":57287,"date":"2024-04-25T20:56:36","date_gmt":"2024-04-25T18:56:36","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=57287"},"modified":"2024-04-25T20:56:15","modified_gmt":"2024-04-25T18:56:15","slug":"cuzco-2","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/04\/25\/cuzco-2\/","title":{"rendered":"Cuzco"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-1.jpg\" alt=\"\" class=\"wp-image-57289\" width=\"515\" height=\"515\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-1.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/Swa-80-150x150.jpg\" alt=\"\" class=\"wp-image-57249\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:&nbsp;<span style=\"color:#cf2e2e\" class=\"color\">9\/10<\/span><\/strong><\/h5>\n\n\n\n<p>Cuzco c\u2019est la reth\u00e9matisation de l\u2019excellent&nbsp;<strong><a href=\"https:\/\/www.vindjeu.eu\/2013\/06\/05\/bora-bora\/\">Bora Bora<\/a><\/strong>&nbsp;du g\u00e9nie qu\u2019est&nbsp;<strong><a href=\"https:\/\/www.vindjeu.eu\/auteurs\/stefan-feld\/\">Stefan Feld<\/a><\/strong>.&nbsp; Les deux jeux sont les m\u00eames si ce n\u2019est que la mani\u00e8re de scorer les ressources est, avec les plumes, plus contraignante dans Cuzco. Le th\u00e8me et le design des deux jeux sont diff\u00e9rents, \u00e0 vous a voir lequel des deux vous pr\u00e9f\u00e9rez \ud83d\ude42<\/p>\n\n\n\n<p>Ce qui est incroyable quand on joue \u00e0 Cuzco aujourd\u2019hui, c\u2019est\nqu\u2019on remarque que&nbsp;<strong>le jeu n\u2019a pas pris une ride<\/strong>. Le jeu aurait pu\nsortir aujourd\u2019hui sans que personne ne le traite d\u2019old fashion :-).&nbsp; Il y\na tout ce qu\u2019on aime dans les jeux de soci\u00e9t\u00e9 modernes dans Cuzco: des choix,\nde la variabilit\u00e9, des axes strat\u00e9giques, une asym\u00e9trie construite, des objectifs\npersonnels, de l\u2019interaction, des contrats,\u2026<\/p>\n\n\n\n<p>Cuzco se joue en 6 manches divis\u00e9es chacune en 3 phases dont la\npremi\u00e8re est la plus importante. Les joueuses commencent par y&nbsp;<strong>lancer\nleurs 3 d\u00e9s<\/strong>&nbsp;puis \u00e0 en placer, chacune \u00e0 leur tour, un dans une case\naction pour la r\u00e9aliser.&nbsp; L\u2019astuce c\u2019est qu\u2019en g\u00e9n\u00e9ral, plus la valeur\nd\u2019un d\u00e9 est forte, plus l\u2019action est puissante. Mais, si un autre d\u00e9 se trouve\ndans la case action que vous voulez r\u00e9aliser, votre d\u00e9 devra \u00eatre de valeur\ninf\u00e9rieure. Vous allez donc, g\u00e9n\u00e9ralement, placer vos d\u00e9s de plus fortes\nvaleurs au d\u00e9but tant que les cases action ne sont pas occup\u00e9es par des d\u00e9s\ninf\u00e9rieurs. L\u2019ordre du tour est \u00e9videmment tr\u00e8s important et les joueuses\npeuvent l\u2019influencer en progressant sur la piste ordre du tour qui rapporte des\npoints et qui se r\u00e9initialise \u00e0 la fin de chaque manche.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2-1024x768.jpg\" alt=\"\" class=\"wp-image-57290\" width=\"768\" height=\"576\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-2.jpg 1440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>Ce syst\u00e8me de d\u00e9s est assez g\u00e9nial m\u00eame si j\u2019ai trouv\u00e9 dommage que, contrairement aux&nbsp;<strong><a href=\"https:\/\/www.vindjeu.eu\/2019\/12\/07\/the-castles-of-burgundy-edition-2019\/\">Ch\u00e2teaux de Bourgogne<\/a><\/strong>, il n\u2019y ait&nbsp;<strong>aucun moyen de changer leur valeur<\/strong>. Pour certaines actions que vous voudrez faire, atteindre une certaine valeur de d\u00e9 est indispensable et si votre jet ne fournit aucun d\u00e9 de cette valeur, vous devrez vous rabattre sur une autre action en \u00e9tant oblig\u00e9 de changer vos plans. Quelques fois un jet poisseux peut faire tr\u00e8s mal et provoquer de la frustration.&nbsp; Il faut donc accepter de devoir s\u2019adapter \u00e0 ses jets sans \u00eatre trop d\u00e9pendant d\u2019une strat\u00e9gie pr\u00e9d\u00e9finie.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3-1024x768.jpg\" alt=\"\" class=\"wp-image-57291\" width=\"588\" height=\"441\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-3.jpg 1440w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/figure><\/div>\n\n\n\n<p>Les actions sont assez originales et vont consister \u00e0&nbsp;<strong>explorer\nle plateau<\/strong>&nbsp;pour r\u00e9cup\u00e9rer des plumes et gagner des PVs pour chaque\nvillage visit\u00e9 dans lequel vous serez le dernier \u00e0 \u00eatre pass\u00e9 \u00e0 la fin du\njeu.&nbsp; Ce syst\u00e8me de \u00ab dernier pass\u00e9, premier servi en PVs \u00bb est assez\nchouette car il engendre pas mal d\u2019interaction et est une strat\u00e9gie en soi. De\nplus, visiter les villages va vous lib\u00e9rer des emplacements sur votre plateau\npersonnel qui pourront&nbsp;<strong>accueillir des tuiles pouvoirs<\/strong>&nbsp;qui vous\nrapporteront d\u00e9s bonus \u00e0 chaque tour. On terminera g\u00e9n\u00e9ralement la partie avec\nune petite dizaine de ces tuiles pouvoir assurant une grande variabilit\u00e9 de\nparties tant ces pouvoirs sont diff\u00e9rents et combinatoires. Cette variabilit\u00e9\nest d\u00e9cupl\u00e9e gr\u00e2ce aux&nbsp;<strong>tuiles objectif<\/strong>&nbsp;personnel de fin de\nmanche que vous pourrez r\u00e9aliser 9 fois (pour 9 objectifs diff\u00e9rents), du\nmoins, si votre strat\u00e9gie est orient\u00e9e \u00ab objectif \u00bb.&nbsp;<\/p>\n\n\n\n<p>Cuzco permet de&nbsp;<strong>nombreuses strat\u00e9gies diff\u00e9rentes<\/strong>&nbsp;focalis\u00e9es sur un des aspects du jeu: les objectifs, l\u2019exploration de la carte, les tuiles capacit\u00e9, les plumes,\u2026. Mais chacune de ces strat\u00e9gies est assez difficile \u00e0 r\u00e9aliser jusqu\u2019au bout et vous r\u00e9aliserez des parties sans y arriver. Le jeu est en effet assez difficile et peut apporter, ici aussi, une certaine frustration ou, du moins, une certaine d\u00e9ception de ne pas y \u00eatre arriv\u00e9. Cela vous encouragera, \u00e9videmment, \u00e0 en refaire une autre pour y arriver \ud83d\ude42  <strong>Cuzco<\/strong>&nbsp;est un jeu passionnant avec certains d\u00e9s\u00e9quilibres pas trop g\u00eanants et un peu de frustration qui ne pourra vous donner qu\u2019une tr\u00e8s grosse envie d\u2019y revenir.&nbsp; Le jeu a tout pour nous plaire tant il est riche, original et profond.&nbsp; C\u2019est, \u00e0 nouveau, un excellent&nbsp;<strong><a href=\"https:\/\/www.vindjeu.eu\/auteurs\/stefan-feld\/\">Feld<\/a><\/strong><a href=\"https:\/\/www.vindjeu.eu\/auteurs\/stefan-feld\/\">&nbsp;<\/a>qui reste d\u2019actualit\u00e9 malgr\u00e9 son \u00e2ge.&nbsp; Je parle \u00e9videmment de l\u2019\u00e2ge du jeu et non de son auteur \ud83d\ude09 ).&nbsp; <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"640\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-4.jpg\" alt=\"\" class=\"wp-image-57292\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-4.jpg 853w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-4-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-4-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-4-453x340.jpg 453w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/02\/Lucas-2-150x150.jpg\" alt=\"\" class=\"wp-image-56973\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">LOukas<\/span>:<span style=\"color:#cf2e2e\" class=\"color\"> 8,5\/10<\/span><\/h5>\n\n\n\n<p>Cuzco est un jeu agr\u00e9able \u00e0 jouer, mais peut\nparfois \u00eatre un peu frustrant. Tout d\u00e9pend en effet des d\u00e9s que vous lancez \u00e0\nchaque tour. Si ceux-ci ne vous sont pas favorables, toute votre strat\u00e9gie peut\n\u00eatre mise \u00e0 mal.<\/p>\n\n\n\n<p>Dans un autre jeu du cr\u00e9ateur Stefan Feld,\nCastle of Burgundy, nous avons la possibilit\u00e9 de diminuer ou d&rsquo;augmenter la\nValeur d\u2019un d\u00e9. Ceci n&rsquo;est pas le cas dans Cuzco. Nous pouvons d\u00e9placer les d\u00e9s\nqui nous g\u00eanent avec des cartes, mais cela n&rsquo;augmente pas la valeur de notre\nd\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5-1024x768.jpg\" alt=\"\" class=\"wp-image-57476\" width=\"544\" height=\"408\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-5.jpg 1440w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><\/figure><\/div>\n\n\n\n<p>\u00c0 mon avis, Cuzco trouve un \u00e9quilibre parfait\nentre jouer son propre jeu et interagir avec les autres joueurs. Vous pouvez\nsaboter quelqu&rsquo;un d&rsquo;une mani\u00e8re qui vous avantage \u00e9galement. Avec seulement 3\nd\u00e9s et donc 3 actions par tour, sacrifier un d\u00e9 pour entraver quelqu&rsquo;un peut\nvous co\u00fbter cher, mais si vous en tirez \u00e9galement avantage, je ne vois aucune\nraison de douter.<\/p>\n\n\n\n<p>Il existe aussi plusieurs fa\u00e7ons de gagner\ndes points de victoire suppl\u00e9mentaires \u00e0 la fin du jeu. Celles-ci semblent\nr\u00e9alisables, mais attention, en obtenir plusieurs est un grand d\u00e9fi.<\/p>\n\n\n\n<p>Dans l&rsquo;ensemble, Cuzco est donc un jeu\ndivertissant avec beaucoup d&rsquo;interaction, mais il existe de nombreuses\nopportunit\u00e9s de gagner des points de victoire, donc choisir une strat\u00e9gie d\u00e8s\nle d\u00e9part est crucial. Assurez-vous \u00e9galement de bien comprendre les actions\ndes cartes et des tuiles, car les illustrations peuvent parfois cr\u00e9er de la\nconfusion.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15.jpg\" alt=\"\" class=\"wp-image-57288\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15.jpg 1440w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/3812-Cuzco-15-453x340.jpg 453w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Cuzco c\u2019est la reth\u00e9matisation de l\u2019excellent&nbsp;Bora Bora&nbsp;du g\u00e9nie qu\u2019est&nbsp;Stefan Feld.&nbsp; Les deux jeux sont les m\u00eames si ce n\u2019est que la mani\u00e8re de scorer les ressources est, avec les plumes, plus contraignante dans Cuzco. Le th\u00e8me et le design des deux jeux sont diff\u00e9rents, \u00e0 vous a voir lequel&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":57289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[4290],"class_list":["post-57287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-des","annee-3637","auteurs-stefan-feld","editeurs-queen-games","illustrateurs-klemens-franz","illustrateurs-marek-blaha","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-jets-de-des"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=57287"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57287\/revisions"}],"predecessor-version":[{"id":57477,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57287\/revisions\/57477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/57289"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=57287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=57287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=57287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}