{"id":57606,"date":"2024-05-17T17:15:13","date_gmt":"2024-05-17T15:15:13","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=57606"},"modified":"2024-05-17T17:15:18","modified_gmt":"2024-05-17T15:15:18","slug":"viking-raiders","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/05\/17\/viking-raiders\/","title":{"rendered":"Viking Raiders"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-1.jpg\" alt=\"\" class=\"wp-image-57608\" width=\"402\" height=\"636\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-1.jpg 511w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-1-190x300.jpg 190w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-1-101x160.jpg 101w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-1-155x245.jpg 155w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-1-215x340.jpg 215w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/04\/Swa-81-150x150.jpg\" alt=\"\" class=\"wp-image-57447\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:<span style=\"color:#cf2e2e\" class=\"color\">  7,5\/10<\/span><\/h5>\n\n\n\n<p>Viking Raiders est un petit jeu de cartes familial \u00e9dit\u00e9 en Fran\u00e7ais par <strong><a href=\"https:\/\/www.vindjeu.eu\/editeurs\/matagot\/\">Matagot <\/a><\/strong>qui sort un petit peu du lot car il a re\u00e7u <strong>le prix du meilleur jeu de cartes<\/strong> \u00e0 l&rsquo;UK Games Expo de 2023.<\/p>\n\n\n\n<p>Viking Raiders est <strong>une course<\/strong> \u00e0 la joueuse qui aura r\u00e9ussi la premi\u00e8re \u00e0 obtenir des cartes totalisant le nombre de PVs n\u00e9cessaires \u00e0 la partie dans chacune des 3 cat\u00e9gories du jeu: navires, clan et butin.  Chacune de ces cat\u00e9gories doit contenir des cartes totalisant le nombre requis de PVs.  Pour y arriver, les joueuses devront <strong>r\u00e9colter des ressources<\/strong> pour <strong>acheter les cartes<\/strong> du march\u00e9 qui leurs manquent et <strong>jouer des cartes action<\/strong> qui leur permettront d&rsquo;en gagner d&rsquo;autres voire m\u00eame d&rsquo;en voler \u00e0 leurs adversaires&#8230;<\/p>\n\n\n\n<p>Le jeu se d\u00e9roule avec <strong>deux pioches de cartes communes<\/strong> \u00e0 tous les joueurs.  Ceux-ci vont piocher al\u00e9atoirement des cartes dans chacune de ces pioches apportant pas mal de hasard au jeu.  Oui, les plus experts d&rsquo;entre vous pourront trouver \u00e7a rebutant mais ce simple syst\u00e8me donne au jeu un aspect tr\u00e8s l\u00e9ger permettant de <strong>le sortir tr\u00e8s facilement<\/strong> et avec n&rsquo;importe qui.  Et puis, c&rsquo;est toujours amusant de piocher des cartes et d&rsquo;\u00eatre (tr\u00e8s) content ou (tr\u00e8s) d\u00e9\u00e7u du r\u00e9sultat \ud83d\ude09<\/p>\n\n\n\n<p>Une joueuse commence d&rsquo;ailleurs toujours son tour par <strong>piocher 2 cartes<\/strong> dans le paquet des cartes vikings. Ensuite, elle peut <strong>jouer une carte action<\/strong> de sa main. Ces actions vont lui permettre de faire des raids et de voler une carte chez une voisine (oui, les vikings vont faire grincer les dents \ud83d\ude09 ). Mais heureusement, Viking Raiders est un jeu amusant et tous les raids ne r\u00e9ussissent pas. Quand on fait un raid sur une adversaire, on choisit une de ses 3 cat\u00e9gories de cartes (navires, clans ou butin), on prend toutes ses cartes de cette cat\u00e9gorie, on y ajoute 2 cartes protection, on m\u00e9lange le tout et on en tire une au hasard. Si c&rsquo;est une carte de protection, le raid \u00e9choit. D&rsquo;autres cartes actions vont, par exemple, permettre d&rsquo;annuler une action d&rsquo;une adversaire, piocher plus de cartes, voler des cartes \u00e0 un adversaire (sans raid donc), gagner plus de protection ou en faire perdre, jouer plus d&rsquo;actions, acheter plus de cartes du march\u00e9,&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-2-1024x683.jpeg\" alt=\"\" class=\"wp-image-57619\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-2-1024x683.jpeg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-2-300x200.jpeg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-2-768x512.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-2-160x107.jpeg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-2-368x245.jpeg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-2-510x340.jpeg 510w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>Apr\u00e8s ou avant avoir r\u00e9alis\u00e9 une action, vous allez pouvoir <strong>acheter une carte<\/strong> du march\u00e9. Ce sont ces cartes qui vont vous apporter des PVs dans chacune des 3 cat\u00e9gories. Pour acheter une carte, il faudra vous <strong>d\u00e9fausser des cartes ressources<\/strong> (que vous aurez pr\u00e9c\u00e9demment pioch\u00e9es) demand\u00e9es par cette carte. Il y a 5 ressources diff\u00e9rentes dans le jeu, ce ne sera pas toujours facile d&rsquo;avoir les ressources n\u00e9cessaires \u00e0 l&rsquo;achat des cartes que vous convoitez mais il est toujours possible d&rsquo;en d\u00e9fausser 2 diff\u00e9rentes pour obtenir la ressource de son choix. Dans chaque cat\u00e9gorie, <strong>on doit toujours commencer par acheter la carte valant 1 PV<\/strong>. On ne pourra acheter une carte valant 2 PVs que si on poss\u00e8de une carte valant 1 PV dans la m\u00eame cat\u00e9gorie. Idem pour la 3 PVs. De plus, le march\u00e9 propose \u00e9galement des <strong>cartes capacit\u00e9s permanentes<\/strong> qui, si vous arrivez \u00e0 les acheter pour les 5 ressources diff\u00e9rentes, vont vous permettre de mieux vous d\u00e9fendre, de r\u00e9ussir plus facilement vos raids, de diminuer les conditions de victoire ou de r\u00e9duire le co\u00fbt de vos achats. Mais attention, celles-ci peuvent \u00e9galement \u00eatre vol\u00e9es&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-3-1024x683.jpeg\" alt=\"\" class=\"wp-image-57620\" width=\"564\" height=\"377\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-3-1024x683.jpeg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-3-300x200.jpeg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-3-768x512.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-3-160x107.jpeg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-3-368x245.jpeg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-3-510x340.jpeg 510w\" sizes=\"auto, (max-width: 564px) 100vw, 564px\" \/><\/figure><\/div>\n\n\n\n<p>Et pour enfin ajouter une bonne part de chaos \u00e0 tout \u00e7a, <strong>deux cartes<\/strong> sont m\u00e9lang\u00e9es au paquet march\u00e9 et <strong>vont tout chambouler<\/strong> lorsqu&rsquo;elles seront tir\u00e9es. La premi\u00e8re oblige tous les joueurs \u00e0 d\u00e9fausser toutes leurs cartes, \u00e0 donner leurs cartes capacit\u00e9 permanente \u00e0 leur voisin et \u00e0 voler une carte de leur voisin. La seconde oblige les joueurs \u00e0 donner leur main de cartes et leurs capacit\u00e9s permanentes \u00e0 leur voisin. Elles sont ensuite retir\u00e9es du jeu (ouf).<\/p>\n\n\n\n<p>Le jeu permet \u00e9galement des <strong>d\u00e9parts asym\u00e9triques<\/strong> avec des capacit\u00e9s de d\u00e9part pour chaque joueuse. Enfin, chose assez exceptionnelle et qu&rsquo;on ne retrouve que dans trop peu de jeux comme dans la s\u00e9rie <strong><a href=\"https:\/\/www.vindjeu.eu\/?s=unlock\">Unlock<\/a><\/strong>, Viking Raiders comprend un <strong>tutoriel <\/strong>assez bien fait. Surtout ne m\u00e9langez pas les cartes la premi\u00e8re fois que vous d\u00e9ballez le jeu. Piochez-les au fur et \u00e0 mesure pour apprendre, ensemble, toutes les r\u00e8gles du jeu!<\/p>\n\n\n\n<p>Dans <strong>Viking Raiders<\/strong> vous n&rsquo;\u00eates jamais s\u00fbrs de la situation. On peut toujours vous attaquer, annuler une de vos actions, une carte chaos peut venir tout chambouler et quand vous pensez \u00eatre proche de la victoire, un adversaire pourrait jouer une carte surprise lui accordant un PV bonus qui lui permettrait de remporter la course sur la ligne d&rsquo;arriv\u00e9e \ud83d\ude09  Vous l&rsquo;aurez compris, ce ne seront pas les plus fins strat\u00e8ges qui remporteront la majorit\u00e9 des parties de Viking Raiders mais bien <strong>le fun<\/strong> \ud83d\ude42  Oui, ce jeu est amusant et quand on le prend pour ce qu&rsquo;il est, on s&rsquo;y amuse constamment.  A son tour, on a toujours quelque chose \u00e0 faire et <strong>on ne s&rsquo;ennuie jamais<\/strong> dans une partie de Viking Raiders.  Et m\u00eame si Odin ne semble pas \u00eatre avec vous, vous pouvez toujours esp\u00e9rer un bon coup du Valhalla pour l&#8217;emporter sous les \u00e9clats de rire \ud83d\ude42<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-5-1024x683.jpeg\" alt=\"\" class=\"wp-image-57607\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-5-1024x683.jpeg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-5-300x200.jpeg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-5-768x512.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-5-160x107.jpeg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-5-368x245.jpeg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/3842-Viking-Raiders-5-510x340.jpeg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Viking Raiders est un petit jeu de cartes familial \u00e9dit\u00e9 en Fran\u00e7ais par Matagot qui sort un petit peu du lot car il a re\u00e7u le prix du meilleur jeu de cartes \u00e0 l&rsquo;UK Games Expo de 2023. Viking Raiders est une course \u00e0 la joueuse qui aura&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":57608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[4033],"class_list":["post-57606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-cartes","annee-4502","auteurs-morten-billcliff","editeurs-matagot","mecanismes-collection","mecanismes-gestion-de-main-de-cartes","mecanismes-marche"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=57606"}],"version-history":[{"count":11,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57606\/revisions"}],"predecessor-version":[{"id":57624,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57606\/revisions\/57624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/57608"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=57606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=57606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=57606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}