{"id":57696,"date":"2024-05-25T12:34:14","date_gmt":"2024-05-25T10:34:14","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=57696"},"modified":"2024-05-25T12:34:22","modified_gmt":"2024-05-25T10:34:22","slug":"scotland-yard-junior","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/05\/25\/scotland-yard-junior\/","title":{"rendered":"Scotland Yard junior"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450-1024x699.jpg\" alt=\"\" class=\"wp-image-57697\" width=\"500\" height=\"500\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2021\/10\/Claire-Mer-1.jpg\" alt=\"\" class=\"wp-image-45425\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Claire et la famille Meeple :<\/span> <span style=\"color:#cf2e2e\" class=\"color\">7,5\/10<\/span><\/h5>\n\n\n\n<p>Scotland yard est un jeu qui n\u2019est pas tout jeune puisqu\u2019il\ndate de 1983&nbsp;! C\u2019est donc avec \u00e9tonnement que je viens de d\u00e9couvrir que\nRavensburger l\u2019a adapt\u00e9 en version pour enfant. L\u2019objectif est le m\u00eame&nbsp;:\nattraper le fuyard qui parcourt les rues de Londres. Pour cela, lui, comme les\npoliciers, peuvent utiliser le m\u00e9tro, le bateau, le bus ou le taxi. Pour\ngagner, les d\u00e9tectives doivent le capturer trois fois. Si le malfrat r\u00e9ussit \u00e0\nleur \u00e9chapper neuf fois, c\u2019est lui qui emporte la partie.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"281\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0440-300x281.jpg\" alt=\"\" class=\"wp-image-57698\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0440-300x281.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0440-768x719.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0440-1024x959.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0440-160x150.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0440-262x245.jpg 262w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0440-363x340.jpg 363w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Ce jeu se pratique toujours avec les trois personnages et c\u2019est toujours le fuyard qui joue en premier afin de se cacher dans les rues de Londres. Pour cela il doit utiliser secr\u00e8tement l\u2019un des quatre moyens de transport \u00e0 sa disposition en le cachant dans sa main mais sans bouger son pion pour le moment&nbsp;! Les d\u00e9tectives ont eux aussi un ticket pour les quatre moyens de transport et ils doivent en emprunter un pour essayer de tomber sur la m\u00eame case que leur proie. Ils ont le droit de discuter entre eux afin d\u2019\u00e9tablir des plans. Lorsqu\u2019ils ont d\u00e9plac\u00e9 leur pion, le fuyard r\u00e9v\u00e8le sa position. S\u2019il n\u2019est pas sur la m\u00eame case qu\u2019un agent, il remporte une victoire. Les joueurs reprennent alors leur ticket et recommence un tour en d\u00e9marrant de leur nouvelle position.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c9l\u00e9mentaire mon cher Watson&nbsp;!<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0441-300x225.jpg\" alt=\"\" class=\"wp-image-57699\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0441-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0441-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0441-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0441-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0441-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/IMG_E0441-453x340.jpg 453w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Les enfants comprennent tr\u00e8s vite la m\u00e9canique du jeu. Ils\ndoivent apprendre \u00e0 \u00e9mettre des hypoth\u00e8ses afin de trouver le chemin qui\ncorrespond le mieux \u00e0 leur objectif. Lors des premi\u00e8res parties, les policiers\nen herbes ont d\u00fb mal \u00e0 comprendre qu\u2019il faut r\u00e9ussir \u00e0 cerner l\u2019adversaire. Mais\nil faut se m\u00e9fier car il peut rester sur place. <br>\nJ\u2019ai trouv\u00e9 dommage les options sont relativement restreintes car \u00e0 la longue,\non suit trop souvent le m\u00eame chemin. Il n\u2019y a que 12 trajets diff\u00e9rents dont un\nseul pour le bateau, qui n\u2019est d\u2019ailleurs pas empruntable au premier tour. Le\njeu aurait pu poss\u00e9der une seconde carte afin de renouveler les parties. C\u00f4t\u00e9\n\u00e9dition, j\u2019aurai pr\u00e9f\u00e9r\u00e9 une bo\u00eete plus petite qui soit plus simple \u00e0 emporter.\nL\u2019utilisation de visi\u00e8res pour cacher le regard du fugitif est une bonne id\u00e9e\nmais devoir les attacher avec un n\u0153ud n\u2019est pas tr\u00e8s pratique avec des enfants.<\/p>\n\n\n\n<p>Malgr\u00e9 ces petits d\u00e9fauts, Scotland Yard pla\u00eet beaucoup aux\nenfants. Les jeux de \u00ab&nbsp;attrape-moi si tu peux&nbsp;\u00bb ont toujours un vif\nsucc\u00e8s aupr\u00e8s des enfants. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2.jpg\" alt=\"\" class=\"wp-image-57700\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/22450_2-340x340.jpg 340w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Scotland yard est un jeu qui n\u2019est pas tout jeune puisqu\u2019il date de 1983 ! C\u2019est donc avec \u00e9tonnement que je viens de d\u00e9couvrir que Ravensburger l\u2019a adapt\u00e9 en version pour enfant. L\u2019objectif est le m\u00eame : attraper le fuyard qui parcourt les rues de Londres. Pour cela, lui, comme les policiers, peuvent utiliser le m\u00e9tro, le bateau, le bus ou le taxi. Pour gagner, les d\u00e9tectives doivent le capturer trois fois. Si le malfrat r\u00e9ussit \u00e0 leur \u00e9chapper neuf fois, c\u2019est lui qui emporte la partie.<\/p>\n","protected":false},"author":10,"featured_media":57697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3354,5],"tags":[],"class_list":["post-57696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enfant","category-famille","annee-4502","auteurs-michael-schacht","editeurs-ravensburger","illustrateurs-gregor-forster","illustrateurs-studio-hive","nombre_conseille-1185","nombre_conseille-1210","mecanismes-deduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=57696"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57696\/revisions"}],"predecessor-version":[{"id":57807,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57696\/revisions\/57807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/57697"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=57696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=57696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=57696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}