{"id":57830,"date":"2024-07-04T02:59:03","date_gmt":"2024-07-04T00:59:03","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=57830"},"modified":"2024-07-04T03:00:16","modified_gmt":"2024-07-04T01:00:16","slug":"joyeux-anniversaire-a-val-noa-et-a-ominae","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/07\/04\/joyeux-anniversaire-a-val-noa-et-a-ominae\/","title":{"rendered":"Joyeux anniversaire \u00e0 Val Noa et \u00e0 Ominae!"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"260\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/07-03-Ominae.jpg\" alt=\"\" class=\"wp-image-57831\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/07-03-Ominae.jpg 250w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/07-03-Ominae-154x160.jpg 154w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/07-03-Ominae-236x245.jpg 236w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><figcaption>Ominae<\/figcaption><\/figure><\/div>\n\n\n\n<p>A cette occasion, Ominae se pr\u00e9sente \u00e0 vous comme ceci:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je suis tomb\u00e9 dans les jeux de soci\u00e9t\u00e9 d\u00e8s mon plus jeune \u00e2ge avec des jeux aussi vari\u00e9s qu&rsquo;Intrigue \u00e0 Venise, Enigmako, les Myst\u00e8res de Pekin, etc (sans oublier les classiques comme la belote, les \u00e9checs ou les dames).. puis j&rsquo;ai grandi avec la g\u00e9n\u00e9ration Magic, Carcassonne, Catan, avant de sombrer avec l&rsquo;apparition de jeux plus complexes (kubenbois\/expert) qui inondent mes armoires et remplissent mes week end !<br>Une de mes citations pr\u00e9f\u00e9r\u00e9es est de George Bernard Shaw :<br>\u00ab\u00a0Nous ne nous arr\u00eatons pas de jouer parce que nous vieillissons, mais nous vieillissons parce que nous nous arr\u00eatons de jouer.\u00a0\u00bb<br>Parmi mes auteurs (style de jeu) pr\u00e9f\u00e9r\u00e9s on retrouve entre autres, Vital Lacerda, Uwe Rosenberg, Stefen Feld et Matt Leacock, Vlaada Chv\u00e1til et Friedemann Friese.<br>Cordialement<\/p><\/blockquote>\n\n\n\n<p>C&rsquo;est s\u00fbr qu&rsquo;il a bon go\u00fbt Ominae \ud83d\ude42<\/p>\n\n\n\n<p>Merci \u00e0 vous deux pour votre soutien lors de notre derni\u00e8re campagne de financement, sant\u00e9 et amusez-vous bien en ce jour festif \ud83d\ude42<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cette occasion, Ominae se pr\u00e9sente \u00e0 vous comme ceci: Je suis tomb\u00e9 dans les jeux de soci\u00e9t\u00e9 d\u00e8s mon plus jeune \u00e2ge avec des jeux aussi vari\u00e9s qu&rsquo;Intrigue \u00e0 Venise, Enigmako, les Myst\u00e8res de Pekin, etc (sans oublier les classiques comme la belote, les \u00e9checs ou les dames).. puis&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":57831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-57830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vin-djeu"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=57830"}],"version-history":[{"count":1,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57830\/revisions"}],"predecessor-version":[{"id":57832,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57830\/revisions\/57832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/57831"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=57830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=57830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=57830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}