{"id":57982,"date":"2024-06-19T18:03:04","date_gmt":"2024-06-19T16:03:04","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=57982"},"modified":"2024-06-19T18:03:35","modified_gmt":"2024-06-19T16:03:35","slug":"artefacts-est-sur-kickstarter","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/06\/19\/artefacts-est-sur-kickstarter\/","title":{"rendered":"Artefacts est sur Kickstarter"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS-1024x576.jpg\" alt=\"\" class=\"wp-image-57983\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS-1024x576.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS-300x169.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS-768x432.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS-160x90.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS-436x245.jpg 436w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS-604x340.jpg 604w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/06\/3864-Artefacts-KS.jpg 1184w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"text-align:center\"><a href=\"https:\/\/www.kickstarter.com\/projects\/fabulist-factory\/artefacts\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Vers la campagne (opens in a new tab)\">Vers la campagne<\/a><\/h2>\n\n\n\n<p>Artefacts se lance une derni\u00e8re fois sur Kickstarter, ce serait dommage de passer \u00e0 c\u00f4t\u00e9 de ce jeu hors norme&#8230;<\/p>\n\n\n\n<p>Savez-vous qu&rsquo;on a vraiment \u00e9t\u00e9 bluff\u00e9 par ce jeu hors du commun quand on y a jou\u00e9 quelques tours avec son auteur?  Voici ce qu&rsquo;on \u00e9crivait \u00e0 l&rsquo;\u00e9poque:<\/p>\n\n\n\n<p><em>Artefacts est bel et bien un monster game!&nbsp;&nbsp;Ce jeu est un r\u00e9el OLNI. Heureusement, gr\u00e2ce \u00e0 ses 21 formules, on va pouvoir l\u2019apprivoiser progressivement.<\/em><\/p>\n\n\n\n<p><em>Outre le jeu sorti d\u2019on ne sait quel vaisseau extraterrestre, j\u2019ai \u00e9t\u00e9 touch\u00e9 par la d\u00e9marche tr\u00e8s sinc\u00e8re et sans concession de son auteur. Il est tr\u00e8s attach\u00e9 \u00e0 son jeu et en est tr\u00e8s fier. Il tient tr\u00e8s fort \u00e0 ce qu\u2019il soit publi\u00e9 tel qu\u2019il est. Peut \u00eatre pas parfait mais comme lui l\u2019a imagin\u00e9. Il m\u2019a dit avoir \u00e9t\u00e9 approch\u00e9 par de tr\u00e8s gros \u00e9diteurs Kickstarter qui ont d\u00fb faire face au refus de collaborer de Franck car ceux-ci voulaient revoir certaines m\u00e9caniques du jeu ce qui est inconcevable aux yeux de son auteur. Et son refus de concession va encore plus loin. Vous l\u2019aurez vite compris, le mat\u00e9riel d\u2019Art\u00e9facts est pl\u00e9thorique! Il est hors de question n\u00e9anmoins de faire des concessions sur la qualit\u00e9 du mat\u00e9riel et le jeu sera de la qualit\u00e9 qu\u2019il voudra. Le prix sera en cons\u00e9quence mais c\u2019est comme \u00e7a qu\u2019il veut son jeu!<\/em><\/p>\n\n\n\n<p><em>De plus, Franck Bovet a quasi tout fait pour son jeu. Il en a r\u00e9alis\u00e9 les r\u00e8gles, le mat\u00e9riel, certains graphismes,\u2026 m\u00eame la programmation de la version Tabletop Simulator est de lui!!! Tout le monde fonctionne par passion autour de ce jeu et c\u2019est une d\u00e9marche honn\u00eate et sinc\u00e8re qu\u2019on respecte, appr\u00e9cie et soutient chez Vin d\u2019jeu.<\/em><\/p>\n\n\n\n<p><em>Art\u00e9facts est un jeu improbable demandant un investissement cons\u00e9quent des joueurs pour apprendre, maitriser et progresser dans les multiples r\u00e8gles du jeu. Le jeu est issu d\u2019un r\u00e9elle d\u00e9marche artistique et sans concession comme on en rencontre trop peu de nos jours. Artefacts est un monster game r\u00e9alis\u00e9 avec passion et pr\u00e9cision comme une symphonie men\u00e9e \u00e0 la baguette par son auteur, une symphonie unique et originale, une symphonie comme, croyez moi, dans votre vie de joueur, vous n\u2019en entendrez que tr\u00e8s rarement.<\/em><\/p>\n\n\n\n<p>Vous voulez en savoir plus?  <strong><a href=\"https:\/\/www.vindjeu.eu\/2021\/08\/17\/artefacts\/\">Lien vers notre article complet<\/a><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vers la campagne Artefacts se lance une derni\u00e8re fois sur Kickstarter, ce serait dommage de passer \u00e0 c\u00f4t\u00e9 de ce jeu hors norme&#8230; Savez-vous qu&rsquo;on a vraiment \u00e9t\u00e9 bluff\u00e9 par ce jeu hors du commun quand on y a jou\u00e9 quelques tours avec son auteur? Voici ce qu&rsquo;on \u00e9crivait \u00e0&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":57983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1456],"tags":[],"class_list":["post-57982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crowdfunding"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=57982"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57982\/revisions"}],"predecessor-version":[{"id":57988,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/57982\/revisions\/57988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/57983"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=57982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=57982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=57982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}