{"id":5814,"date":"2013-10-20T13:37:13","date_gmt":"2013-10-20T12:37:13","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=5814"},"modified":"2013-10-20T13:37:13","modified_gmt":"2013-10-20T12:37:13","slug":"struggle-of-empires","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2013\/10\/20\/struggle-of-empires\/","title":{"rendered":"Struggle of Empires"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-5820\" style=\"margin: 5px;\" title=\"626 Struggle of Empire 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-1.jpg\" alt=\"\" width=\"286\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-1.jpg 358w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-1-214x300.jpg 214w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-1-107x150.jpg 107w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:\u00a0\u00a0<strong><span style=\"color: #800000;\"> 8,5 \/10<\/span><\/strong><\/p>\n<p>Ha, \u00e7a faisait longtemps que je n&rsquo;avais plus jou\u00e9 \u00e0 un bon vieux <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/auteurs\/martin-wallace\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Wallace<\/span><\/a><\/span>!\u00a0 Cela fait en effet plus de 9 ans que Struggle of Empire est sorti, et, honte sur moi, je n&rsquo;y avais pas encore jou\u00e9.\u00a0\u00a0 Bon, j&rsquo;avais d\u00e9j\u00e0 jou\u00e9 \u00e0 <a href=\"http:\/\/www.vindjeu.eu\/2009\/05\/30\/conquest-of-the-empire\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Conquest of the\u00a0Empire<\/span><\/a>, jeu qui s&rsquo;\u00e9tait inspir\u00e9 de Struggle of Empire mais sans jouer au jeu original&#8230;<\/p>\n<p>Struggle of Empire est une sorte de wargame l\u00e9ger.\u00a0 Pourquoi l\u00e9ger?<br \/>\n1) Parce qu&rsquo;il n&rsquo;existe que <span style=\"color: #993366;\">3 types d&rsquo;unit\u00e9s<\/span> militaires dont le nombre de capacit\u00e9s est limit\u00e9: Les arm\u00e9es, les flottes et les forts.<br \/>\n2) De plus, <span style=\"color: #993366;\">les d\u00e9placements sont tr\u00e8s rapides<\/span>: 1 flottes peut se d\u00e9placer de n&rsquo;importe quelle mer vers n&rsquo;importe quelle autre et pour faire simple, une arm\u00e9e peut se d\u00e9placer de n&rsquo;importe quel territoire vers n&rsquo;importe quel autre \u00e0 condition d&rsquo;avoir une flotte bordant les c\u00f4tes du territoire de destination.<br \/>\n3) <span style=\"color: #993366;\">Les combats sont tr\u00e8s simples<\/span> aussi: on lance 2 d\u00e9s et on prend la diff\u00e9rence entre ces 2 d\u00e9s, \u00e0 laquelle on ajoute le nombre d&rsquo;unit\u00e9s pr\u00e9sentes sur le territoire.\u00a0 Le perdant perd 1 unit\u00e9 et si l&rsquo;attaquant a gagn\u00e9 le combat, il remplace le jeton de contr\u00f4le du perdant par un des siens.\u00a0 Un peu de chance est donc n\u00e9cessaire bien qu&rsquo;apr\u00e8s de nombreux lanc\u00e9s la chance diminue pour plus faire place \u00e0 de l&rsquo;incertitude et du suspense.<\/p>\n<p>Struggle of Empire apporte n\u00e9anmoins son lot d&rsquo;originalit\u00e9s qui le rend indispensable \u00e0 tout amateur du genre:<br \/>\n<span style=\"color: #993366;\">1) Les marqueurs d&rsquo;insatisfaction<\/span>.\u00a0 L&rsquo;argent est illimit\u00e9 dans Struggle of Empire.\u00a0 Si vous en avez besoin, pour une ench\u00e8re ou pour une technologie, vous prenez l&rsquo;argent simplement de la banque accompagn\u00e9 d&rsquo;un marqueur d&rsquo;insatisfaction par 2 pi\u00e8ces prises.\u00a0\u00a0 A la fin du jeu, vous perdez\u00a0tous vos PVs si vous avez 20 marqueurs d&rsquo;insatisfaction ou plus\u00a0et\u00a0si vous en avez moins, celui qui en a le plus perd 7 PVs et le second perd 4 PVs.\u00a0 Autant \u00e9viter d&rsquo;en piocher trop&#8230;<br \/>\n<span style=\"color: #993366;\">2) Les tuiles technologiques<\/span> qui peuvent \u00eatre achet\u00e9es lors de la phase d&rsquo;action.\u00a0 A leur tour, les joueurs peuvent effectuer 2 actions.\u00a0 Ensuite on passe au joueur suivant.\u00a0 Et ce 6 fois.\u00a0 Autrement dit, chaque joueur va effectuer 12 actions durant une guerre et le jeu dure 3 guerres.\u00a0 Les actions sont assez classiques: construire des unit\u00e9s, les d\u00e9placer, attaquer et &#8230; acheter des technologies.\u00a0 Les joueurs peuvent donc acheter des tuiles technologiques apportant divers bonus en terme d&rsquo;aptitudes aux combats, de r\u00e9colte d&rsquo;argent, de capacit\u00e9 de d\u00e9placement, d&rsquo;actions gratuites suppl\u00e9mentaires, de diminution du nombre de marqueur d&rsquo;insatisfaction,&#8230;\u00a0 Ces tuiles sont donc tr\u00e8s int\u00e9ressantes mais co\u00fbtent doublement: elles co\u00fbtent de l&rsquo;argent (bien que certaines soient gratuites) mais \u00e9galement et surtout une action.\u00a0 Il va donc falloir bien poser le pour et le contre d&rsquo;avoir l&rsquo;un ou l&rsquo;autre bonus au prix d&rsquo;une action qui aurait pu servir \u00e0 la construction d&rsquo;unit\u00e9s, au d\u00e9placement d&rsquo;unit\u00e9s\u00a0ou \u00e0 attaquer&#8230;<\/p>\n<p>Struggle of Empire est donc un wargame all\u00e9g\u00e9 qui pr\u00e9sente\u00a0les d\u00e9fauts du genre: hasard des combats et \u00ab\u00a0tapage\u00a0\u00bb sur le joueur le plus avanc\u00e9 sur la piste de score.\u00a0 Struggle of Empire propose n\u00e9anmoins de belles\u00a0trouvailles et des originalit\u00e9s (ce n&rsquo;est pas un <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/auteurs\/martin-wallace\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Wallace <\/span><\/a><\/span>pour rien) qui en font un des musts du genre pour tout amateur <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/auteurs\/martin-wallace\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Wallacien<\/span><\/a><\/span>.<\/p>\n<p style=\"text-align: center;\">_____________<\/p>\n<p><strong><span style=\"color: #333399;\">Philrey212<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a08\/10<\/span><\/strong><\/p>\n<p>SwatSh arrive avec la bo\u00eete sous le bras (non, en fait, la bo\u00eete \u00e9tait dans un sac ;). On lui demande comme \u00e7a, pour savoir, la dur\u00e9e d&rsquo;une partie. R\u00e9ponse: \u00ab\u00a0Et bien c&rsquo;est indiqu\u00e9 3 heures mais franchement, je ne sais pas pourquoi car il n&rsquo;y a que 3 tours de jeu\u00a0\u00bb. Et bien maintenant on sait \ud83d\ude09<\/p>\n<p>Struggle of Empires est bien un long jeu. Les r\u00e8gles ne sont pas sp\u00e9cialement compliqu\u00e9es mais il faut quand m\u00eame expliquer les diff\u00e9rentes tuiles \u00ab\u00a0technologiques\u00a0\u00bb afin qu&rsquo;on sache un peu comment \u00e9tablir sa strat\u00e9gie.<\/p>\n<p>Struggle of Empires se joue en 3 guerres: Apr\u00e8s chaque guerre, il y a un d\u00e9compte de PV. Et bien apr\u00e8s la premi\u00e8re SwatSh en t\u00eate, les autres derri\u00e8re (mais pas trop trop loin non plus). Apr\u00e8s la 2\u00e8 guerre, c&rsquo;est PhilRey qui est en t\u00eate et SwatSh avant dernier \u00e0 plus de 10 points. La raison est simple, PhilRey a principalement attaqu\u00e9 SwatSh afin de r\u00e9duire ses PVs. Et personne n&rsquo;a attaqu\u00e9 PhilRey. C&rsquo;est clair que la troisi\u00e8me guerre fut ax\u00e9e contre PhilRey (qui a d&rsquo;ailleurs bien r\u00e2l\u00e9 ;). En fin de 3\u00e8 (et derni\u00e8re guerre), PhilRey reste bien devant et les 3 autres joueurs sont \u00e0 \u00e9galit\u00e9 de PV. C&rsquo;est assez cocasse d&rsquo;ailleurs car personne ne s&rsquo;attendait \u00e0 voir 3 joueurs terminer 2\u00e8 (ou dernier \ud83d\ude09<\/p>\n<p>Struggle of Empires a une l\u00e9g\u00e8re dose de hasard car les combats sont r\u00e9solus aux d\u00e9s. Et si vous n&rsquo;avez pas trop de chance au d\u00e9but, vous maudissez les d\u00e9s. N\u00e9anmoins, le jeu offre pas mal de bonnes choses pour pouvoir quand m\u00eame \u00e9tablir une strat\u00e9gie. Strat\u00e9gie ax\u00e9e principalement \u00e0 court terme, c\u00e0d en vue de la fin de la guerre et du prochain d\u00e9compte. A plus long terme, c&rsquo;est plus difficile car les forces en jeu varient ainsi que les alliances.<\/p>\n<p>Pour ma part, j&rsquo;ai assez bien appr\u00e9ci\u00e9 Struggle of Empires mais certains moments sont longs. De plus, cette manie de toujours \u00ab\u00a0taper\u00a0\u00bb sur le potentiel vainqueur, c&rsquo;est parfois \u00e9nervant (encore plus lorsqu&rsquo;il y a influence entre les joueurs); Mais comme l&rsquo;a si bien dit SwatSh ce soir, c&rsquo;est le cas de (presque?) tous les jeux de baston.<\/p>\n<p style=\"text-align: center;\">_____________<\/p>\n<p><strong><span style=\"color: #333399;\">Cindy<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a0\u00a08 \/10<\/span><\/strong><\/p>\n<p>Struggle of the Empire &#8230; un jeu de baston &#8230; tout ce que j&rsquo;aime ! Donc j&rsquo;ai d\u00e9but\u00e9 la partie en me disant bof bof bof &#8230;<\/p>\n<p>Le jeu se d\u00e9roule en trois \u00ab\u00a0guerres\u00a0\u00bb et chacune d&rsquo;elles en 6 phases durant lesquelles chaque joueur fait deux actions.<\/p>\n<p>Trois tactiques possibles: l&rsquo;attaque, la d\u00e9fense ou bien se faire oublier dans un coin &#8230; Le gros avantage de cette derni\u00e8re c&rsquo;est de jouer avec Phil et Swatsh&#8230; ils se tapent dessus et moi pompompom, je me fais discr\u00e8te.<\/p>\n<p>La partie respecte le timing annonc\u00e9 de 2-3h. Ce qui prends le plus de temps c&rsquo;est la phase de r\u00e9flexion (surtout celle de Phil \ud83d\ude09 ).<\/p>\n<p>Le jeu est assez \u00e9quilibr\u00e9 selon moi mais il faut quand m\u00eame penser \u00e0 pas mal d&rsquo;\u00e9l\u00e9ments.<\/p>\n<p>En d\u00e9but de guerre, on d\u00e9termine d&rsquo;abord les alliances aux ench\u00e8res &#8230; Les alli\u00e9s ne peuvent donc pas s&rsquo;attaquer et l&rsquo;un des deux peut demander (moyennant finance) l&rsquo;aide du second en cas d&rsquo;attaque.<\/p>\n<p>Sur le continent pas de soucis, les r\u00e8gles de d\u00e9placement sont simple. Pour les colonies, il faut d&rsquo;abord avoir un bateau avant de pouvoir conqu\u00e9rir.<\/p>\n<p>Apr\u00e8s chaque guerre, il y a un d\u00e9compte de PV. Celui qui est majoritaire sur un territoire, r\u00e9colte les PV associ\u00e9s. En cas d&rsquo;\u00e9galit\u00e9 dans un territoire, tous le monde re\u00e7oit le max de PV pour ce territoire.<\/p>\n<p>Pour attaquer il faut payer et les liquidit\u00e9s re\u00e7ues en d\u00e9but de partie sont minimes &#8230; donc en fin de guerre, le d\u00e9compte pr\u00e9voit une distribution mais attention, chaque bateau ou chaque bataillon co\u00fbte \u00e9galement. Il se peut donc que l&rsquo;on doive payer et non recevoir.<\/p>\n<p>Que faire si l&rsquo;on souhaite attaquer alors que l&rsquo;on pas mes moyens ? Emprunter \u00e9videmment (attention emprunter de l&rsquo;argent co\u00fbte aussi de l&rsquo;argent ! Sauf dans ce cas, o\u00f9 cela peut co\u00fbter des PV). Donc pour chaque emprunt, on re\u00e7oit des point de m\u00e9contentement.<\/p>\n<p>On peut se d\u00e9barrasser des points de m\u00e9contentement en achetant la tuile ad\u00e9quate (c&rsquo;est bien mais bon c&rsquo;est une action de sacrifi\u00e9e)<\/p>\n<p>Les batailles se jouent aux d\u00e8s donc il faut un peu de chance et seigneur que je n&rsquo;ai pas eu de chance cette fois !!!<\/p>\n<p>Des d\u00e8s et des ench\u00e8res mais assez peu de hasard au final!<\/p>\n<p>Voil\u00e0 pour le reste les deux grands ma\u00eetres ont d\u00e9j\u00e0 tout d\u00e9taill\u00e9, donc pas la peine de faire un roman<\/p>\n<p>En fin de compte, je trouve que j&rsquo;ai assez mal (pour ne pas dire tr\u00e8s mal) jou\u00e9 mais j&rsquo;ai trouv\u00e9 le jeu tr\u00e8s chouette pour un jeu de baston.<\/p>\n<p style=\"text-align: center;\">_____________<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5819\" title=\"626 Struggle of Empire 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-2-1024x768.jpg\" alt=\"\" width=\"819\" height=\"614\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/08\/626-Struggle-of-Empire-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Ha, \u00e7a faisait longtemps que je n&rsquo;avais plus jou\u00e9 \u00e0 un bon vieux Wallace!\u00a0 Cela fait en effet plus de 9 ans que Struggle of Empire est sorti, et, honte sur moi, je n&rsquo;y avais pas encore jou\u00e9.\u00a0\u00a0 Bon, j&rsquo;avais d\u00e9j\u00e0 jou\u00e9 \u00e0 Conquest of the\u00a0Empire, jeu&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":5820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-5814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-71","auteurs-martin-wallace"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/5814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=5814"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/5814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/5820"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=5814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=5814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=5814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}