{"id":58505,"date":"2024-08-30T17:01:29","date_gmt":"2024-08-30T15:01:29","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=58505"},"modified":"2024-09-06T09:36:49","modified_gmt":"2024-09-06T07:36:49","slug":"golden-cup","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/08\/30\/golden-cup\/","title":{"rendered":"Golden Cup"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-1.jpg\" alt=\"\" class=\"wp-image-58507\" width=\"466\" height=\"466\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-1.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-align:center\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.craniocreations.it\/en\/catalogue\" target=\"_blank\">Vers les pre-orders pour Essen de Cranio Creations<\/a><\/strong><br>(Jeux en Anglais) <\/h4>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/07\/1P1-Swa-150x150.jpg\" alt=\"\" class=\"wp-image-14279\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\">7\/10<\/span><\/h5>\n\n\n\n<p>Nous avons eu la chance de jouer, en avant premi\u00e8re d&rsquo;Essen, \u00e0 la premi\u00e8re nouveaut\u00e9 annonc\u00e9e par <strong><a href=\"https:\/\/www.vindjeu.eu\/editeurs\/cranio-creation\/\">Cranio Cr\u00e9ations<\/a><\/strong>: Golden Cup! A l&rsquo;image de nombreux jeux de l&rsquo;\u00e9diteur, Golden Cup a pour co-auteur, le l\u00e9gendaire <strong><a href=\"https:\/\/www.vindjeu.eu\/auteurs\/simone-luciani\/\">Simone Luciani<\/a><\/strong> vainqueur de notre dernier Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e avec le sublime <strong><a href=\"https:\/\/www.vindjeu.eu\/2023\/05\/10\/darwins-journey\/\">Darwin&rsquo;s Journey<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#cf2e2e\" class=\"color\">Pioche<\/span><\/h2>\n\n\n\n<p>Un peu comme le d\u00e9routant <strong><a href=\"https:\/\/www.vindjeu.eu\/2023\/01\/13\/challengers\/\">Challengers<\/a><\/strong>, Golden Cup est un <strong>jeu de combats en duel<\/strong> qui peut se jouer jusqu&rsquo;\u00e0 6!  Le jeu se joue en 6 manches et \u00e0 chacune d&rsquo;entre elles, les joueurs commencent par d\u00e9fausser entre 0 et toutes leurs cartes puis \u00e0 en piocher dans une des pioches communes pour arriver \u00e0 3 cartes en main.  Il existe en effet <strong>3 pioches<\/strong> communes, la bronze, l&rsquo;argent et l&rsquo;or et, comme aux jeux Olympiques \ud83d\ude09 plus on va vers l&rsquo;or, plus les cartes sont puissantes.  Les joueurs vont devoir am\u00e9liorer leurs capacit\u00e9s personnelles pour avoir le droit de piocher leurs cartes dans les paquets argent ou or.  Cette pioche hasardeuse ne m&rsquo;a pas plus d\u00e9rang\u00e9e que \u00e7a car elle offre toujours pas mal de choix.  Un peu comme dans <strong><a href=\"https:\/\/www.vindjeu.eu\/2016\/11\/26\/terraforming-mars-video-2\/\">Terraforming Mars<\/a><\/strong> (je sais, la comparaison est os\u00e9e \ud83d\ude09 ),  ce ne sont pas les cartes pioch\u00e9es qui importent mais ce qu&rsquo;on en fait&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#cf2e2e\" class=\"color\">Achats<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2-1024x768.jpg\" alt=\"\" class=\"wp-image-58543\" width=\"583\" height=\"438\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-2.jpg 1440w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/figure><\/div>\n\n\n\n<p>Durant la phase d&rsquo;achat, vous d\u00e9cidez ce que vous allez faire avec votre argent (votre revenu est de 4 sous en d\u00e9but de partie).  Pour 3 sous, vous pouvez <strong>jouer une de vos cartes<\/strong> <strong>champion <\/strong>(peu importe qu&rsquo;elle soit de bronze, d&rsquo;argent ou d&rsquo;or) sur votre plateau.  Elle participera d\u00e8s lors \u00e0 tous les combats en apportant ses bonus* (*j&rsquo;y reviens).  Vous pouvez \u00e9galement <strong>augmenter votre revenu<\/strong> \u00e0 chaque manche d&rsquo;1 sou en en payant 3 ou moins en fonction de la manche ou bien <strong>changer de paquet pour la pioche des cartes champion<\/strong> au prix de 3 sous par niveau.  Vous avez aussi la possibilit\u00e9 de piocher d&rsquo;autres cartes ou d&rsquo;augmenter la valeur d&rsquo;attaque ou de d\u00e9fense de votre \u00e9quipe.  <\/p>\n\n\n\n<p>Cette phase  d&rsquo;achat repr\u00e9sente <strong>le c\u0153ur du jeu<\/strong> et c&rsquo;est l\u00e0 o\u00f9 les joueuses auront<strong> les choix les plus difficiles<\/strong>: mieux vaut-il augmenter le niveau de pioche, le revenu ou jouer une nouvelle championne et si oui laquelle?  Autant de choix assez int\u00e9ressants et qui seront cruciaux pour pouvoir gagner vos combats.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#cf2e2e\" class=\"color\">Les matchs<\/span><\/h2>\n\n\n\n<p>La <strong>derni\u00e8re phase<\/strong> de chacune des manches consiste \u00e0 <strong>s&rsquo;affronter <\/strong>entre joueurs, un contre un.  Si on est 4 par exemple, 2 matchs auront lieu.  La d\u00e9signation des joueurs qui s&rsquo;affronteront sera d\u00e9termin\u00e9e gr\u00e2ce \u00e0 une tuile.  Lorsqu&rsquo;on est un nombre impair, un joueur affrontera un automa.<\/p>\n\n\n\n<p>Un peu comme dans <strong><a href=\"https:\/\/www.vindjeu.eu\/2023\/01\/13\/challengers\/\">Challengers<\/a><\/strong>, le hasard est assez important durant les matchs.  Chaque joueur s&rsquo;affrontant va d\u00e9poser ses <strong>jetons combats dans un sac<\/strong>.  On va ensuite les piocher un par un.  Lorsqu&rsquo;on pioche un jeton d\u00e9fense, on le place sur le terrain de combat.  Lorsqu&rsquo;on pioche un jeton attaque, on regarde si l&rsquo;attaque est un succ\u00e8s en additionnant les jetons d\u00e9fenses face visible adverse et en les soustrayant \u00e0 la valeur de combat.  Si le r\u00e9sultat de la soustraction est positif, l&rsquo;attaque est un succ\u00e8s et le joueur gagne un point de combat \u00e0 condition que le jet d&rsquo;un d\u00e9 le confirme.  On retourne alors les jetons d\u00e9fense utilis\u00e9s face cach\u00e9e de telle sorte qu&rsquo;ils ne servent qu&rsquo;\u00e0 un seul combat.  Ce syst\u00e8me favorise l&rsquo;attaque mais il est contrebalanc\u00e9 par la valeur des jetons.  Les jetons d\u00e9fense sont moins chers que les jetons attaque ce qui va encourager les joueurs \u00e0 se blinder en d\u00e9fense tout en ne n\u00e9gligeant pas les jetons attaque car c&rsquo;est eux qui les feront gagner!  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4-1024x768.jpg\" alt=\"\" class=\"wp-image-58545\" width=\"583\" height=\"437\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-4.jpg 1440w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Le hasard<\/strong> est \u00e9videmment bien pr\u00e9sent dans ce syst\u00e8me de pioche al\u00e9atoire car si on commence par piocher vos jetons attaque avant de piocher un quelconque jeton d\u00e9fense, vous gagnerez vos combats ais\u00e9ment.  De plus, le jet d&rsquo;un d\u00e9 (un peu inutile je trouve) doit confirmer le succ\u00e8s.<\/p>\n\n\n\n<p>La majorit\u00e9 des <strong>points de victoire<\/strong> proviendra de ces matchs mais les cartes jou\u00e9es, les objectifs personnels r\u00e9alis\u00e9s et le d\u00e9veloppement personnel de chaque joueur apporteront des PVs suppl\u00e9mentaires qui peuvent faire la diff\u00e9rence.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#cf2e2e\" class=\"color\">* Les bonus des cartes<\/span><\/h2>\n\n\n\n<p>Les choix les plus int\u00e9ressants dans Golden Cup sont les choix des <strong>cartes champion<\/strong> \u00e0 jouer et vous le ferez en fonction des <strong>bonus qu&rsquo;ils vous apporteront<\/strong>.  Ils vont non seulement vous permettre de gagner de nouveaux jetons attaque et d\u00e9fense mais \u00e9galement vous permettre d&rsquo;augmenter leur valeur, ils vous donneront des bonus si vous jouez certains types de champion, des d\u00e9s additionnels \u00e0 pouvoir jeter, augmenteront ves revenus \u00e0 chaque manche, vous donneront des PVs, des bonus suppl\u00e9mentaires lorsqu&rsquo;on augmente son revenu ou sa pioche de cartes champion, une d\u00e9fense ou une attaque suppl\u00e9mentaire permanente, la possibilit\u00e9 de retirer un jeton adverse du sac, la facult\u00e9 d&rsquo;ignorer certains jetons d\u00e9fense,&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#cf2e2e\" class=\"color\">La coupe est pleine<\/span><\/h2>\n\n\n\n<p>Et c&rsquo;est dans tous ces bonus que le fun de Golden Cup se r\u00e9v\u00e8le. On s&rsquo;amuse \u00e0 profiter des bonus \u00e9ph\u00e9m\u00e8res, permanents ou conditionnels de ses diff\u00e9rentes cartes. Et avant \u00e7a, on s&rsquo;amuse \u00e0 choisir les cartes qui apporteront les effets les plus int\u00e9ressants en fonction de la physionomie du match. Car oui, il faut bien observer ce que vos adversaires feront et pour gagner contre un ultra d\u00e9fensif, il faudra une tactique diff\u00e9rente que contre un ultra offensif.  Evidemment, m\u00eame la meilleure tactique pourra \u00eatre contr\u00e9e ou soutenue par un hasard omnipr\u00e9sent surtout dans les combats.  Mais cet hasard permet \u00e0 tout le monde d&rsquo;avoir une chance et provoquera des cris de joie lorsque vos enfants vous battront alors qu&rsquo;ils ne l&rsquo;auront pas m\u00e9rit\u00e9 \ud83d\ude09<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9.jpg\" alt=\"\" class=\"wp-image-58506\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9.jpg 1440w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/08\/3892-Golden-Cup-9-453x340.jpg 453w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par SwatSh<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Golden Cup (Explication et d\u00e9gustation du jeu)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/3gdmFvTMBHY?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Vin d&rsquo;jeu d&rsquo;music<\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"JO PARIS 2024 - Philippe Katerine, tout bleu, rend hommage \u00e0 Dyonisos\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/fSUD-KCve8o?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vers les pre-orders pour Essen de Cranio Creations(J Nous avons eu la chance de jouer, en avant premi\u00e8re d&rsquo;Essen, \u00e0 la premi\u00e8re nouveaut\u00e9 annonc\u00e9e par Cranio Cr\u00e9ations: Golden Cup! A l&rsquo;image de nombreux jeux de l&rsquo;\u00e9diteur, Golden Cup a pour co-auteur, le l\u00e9gendaire Simone Luciani vainqueur&#46;&#46;&#46;<\/p>\n","protected":false},"author":12,"featured_media":58507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[4613],"class_list":["post-58505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-combats","annee-4502","auteurs-gabriele-bubola","auteurs-simone-luciani","editeurs-cranio-creation","illustrateurs-alessandro-costa","nombre_conseille-1185","nombre_conseille-1355","nombre_conseille-1321"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/58505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=58505"}],"version-history":[{"count":11,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/58505\/revisions"}],"predecessor-version":[{"id":58860,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/58505\/revisions\/58860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/58507"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=58505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=58505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=58505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}