{"id":59296,"date":"2024-11-17T12:07:20","date_gmt":"2024-11-17T11:07:20","guid":{"rendered":"https:\/\/www.vindjeu.eu\/prd\/?p=59296"},"modified":"2024-11-17T12:07:20","modified_gmt":"2024-11-17T11:07:20","slug":"inori","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/11\/17\/inori\/","title":{"rendered":"Inori"},"content":{"rendered":"\n<figure class=\"wp-block-gallery alignleft has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"494\" data-id=\"59590\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/inori-1.png\" alt=\"\" class=\"wp-image-59590\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/inori-1.png 380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/inori-1-231x300.png 231w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/figure>\n<\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"520\" height=\"578\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait.jpg\" alt=\"\" class=\"wp-image-52332\" style=\"width:114px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-270x300.jpg 270w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-144x160.jpg 144w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-220x245.jpg 220w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2023\/01\/portrait-306x340.jpg 306w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-9b5dfcbc0ff1d1fbcd2f940a0fa2353e\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Serval: <\/mark><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">7\/10<\/mark><\/h5>\n\n\n\n<p><br><br>Inori est un village construit sur un arbre sacr\u00e9. Votre mission est de g\u00e2ter les esprits qui cohabitent sur cet arbre afin obtenir le r\u00f4le supr\u00eame de gardien de ce lieu enchant\u00e9 !<br><br>Ce jeu de placement d&rsquo;offrandes se d\u00e9roule en 4 saisons, chaque joueur pla\u00e7ant successivement un des ses pion offrande (voire une rune) jusqu&rsquo;\u00e0 \u00e9puisement de ces derniers d\u00e9clenchant donc une fin de saison.<br><br>A chaque tour de jeu , un joueur peut donc placer son jeton sur une des 3 cartes \u00ab\u00a0voyages\u00a0\u00bb disponibles d\u00e8s le d\u00e9but de la partie.<\/p>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-3ed1a65d90b2d73893f4f6cbb2501a16\">&#8230;<\/p>\n\n\n\n<p><br><br>Sur ce type de carte au nombre de places limit\u00e9es, est g\u00e9n\u00e9ralement indiqu\u00e9e l&rsquo;effet obtenu apr\u00e8s placement.<\/p>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-7d728cad9021eda9c9569fe346c41dbe\">&#8230;<br>&#8230;<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"312\" height=\"209\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Sans-titre-3.png\" alt=\"\" class=\"wp-image-59617\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Sans-titre-3.png 312w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Sans-titre-3-300x201.png 300w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/figure>\n<\/div>\n\n\n<p><br>En r\u00e8gle g\u00e9n\u00e9rale il s&rsquo;agit du type de ressource r\u00e9colt\u00e9e (ici des jetons faveur de 6 couleurs diff\u00e9rentes) mais il est \u00e9galement possible d&rsquo;obtenir des runes et des points de victoire selon certains crit\u00e8res. Outre les ressources obtenues, un course \u00e0 la majorit\u00e9 est lanc\u00e9e jusqu&rsquo;\u00e0 la fin d&rsquo;une saison.<br>On peut voir sur la carte ci-contre que l&rsquo;on peut obtenir soit des jetons faveurs de deux couleurs diff\u00e9rentes, identiques ou une rune sachant que chaque emplacement ne peut recevoir qu&rsquo;un seul pion offrande.<br><br>\u26a0\ufe0fCertaines cases ont potentiellement un cout de pose.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-luminous-vivid-orange-color has-text-color has-link-color wp-elements-da774ac705bcefc7d1df644039b695e4\"><br><br>\ud83c\udf84 L&rsquo;Arbre sacr\u00e9<\/h4>\n\n\n\n<p><br><br> Il est \u00e9galement possible de placer un de ses jetons offrande sur le fameux Grand Arbre , la m\u00e9canique est ici un peu diff\u00e9rente puisque le twist principal du jeu r\u00e9side dans ce placement.<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"423\" height=\"367\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Sans-titre-5.jpg\" alt=\"\" class=\"wp-image-59633\" style=\"width:371px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Sans-titre-5.jpg 423w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Sans-titre-5-300x260.jpg 300w\" sizes=\"auto, (max-width: 423px) 100vw, 423px\" \/><\/figure>\n<\/div>\n\n\n<p>En effet , le premier joueur \u00e0 placer son pion offrande sur une des 6 cases disponibles placera une tuile \u00ab\u00a0Autel\u00a0\u00bb correspondant \u00e0 une couleur d&rsquo;esprit et ce de fa\u00e7on d\u00e9finitive pour toute la partie. <br>Au bout de chaque case un d\u00e9compte de majorit\u00e9 en fin de partie sur le type de couleur aura lieu.<br>A noter le placement sur les deux premi\u00e8res cases du grand arbre sont payantes.<br>Evidemment, chaque placement d&rsquo;esprit va provoquer un gain &#8230; de jetons faveurs, de points de victoires, de tuile rune, de pose de pions offrandes neutres &#8230;.<br>\ud83d\udd18 Quid des tuiles \u00ab\u00a0Runes\u00a0\u00bb ?  Au nombre de 15 , ces tuiles sont jouables pendant le tour d&rsquo;un joueur et ont diff\u00e9rentes facult\u00e9s tels un gain de jetons faveurs permanents ou des modifications de placement des jetons offrandes. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-e302f7d0f53fe39d542b211fc3660ad4\">..<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569491_1292650928596823_896596757548574825_n-768x1024.jpg\" alt=\"\" class=\"wp-image-59749\" style=\"width:305px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569491_1292650928596823_896596757548574825_n-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569491_1292650928596823_896596757548574825_n-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569491_1292650928596823_896596757548574825_n-1152x1536.jpg 1152w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569491_1292650928596823_896596757548574825_n.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-1f586d8582c97e41900c4934def09349\">\u2744\ufe0f Fin de saison <\/h4>\n\n\n\n<p>D\u00e8s que l&rsquo;int\u00e9gralit\u00e9 des pions offrandes sont pos\u00e9s , une r\u00e9solution de fin de saison \u00e0 lieu.<br>\ud83c\udfb4 \u2714\ufe0f Pour toutes les cartes voyages compl\u00e8tes (toutes les cases sont occup\u00e9es), chaque joueur ayant au moins un marqueur offrande plac\u00e9 marque 1 point par jeton offrande qu&rsquo;il poss\u00e8de dans la couleur indiqu\u00e9e en haut \u00e0 droite de la carte.<br>la carte voyage est remplac\u00e9e par une carte de la m\u00eame couleur<br>\ud83c\udfb4 \u274c Pour toutes cartes incompl\u00e8tes, aucun point n&rsquo;est marqu\u00e9 et la carte est remplac\u00e9e par une carte de la couleur oppos\u00e9e \u00e0 celle ci (indiqu\u00e9e en bas \u00e0 gauche).<br>\ud83c\udfb4  Les cartes \u00ab\u00a0nouveau d\u00e9part\u00a0\u00bb , elles scorent de fa\u00e7on plus particuli\u00e8re si une carte est incompl\u00e8te , chaque joueur marque 1 point par jeton faveur de la couleur indiqu\u00e9e en bas \u00e0 droite de cette carte<br><br>Apr\u00e8s ce d\u00e9compte, les jetons offrande sont r\u00e9cup\u00e9r\u00e9s et une nouvelle carte Nouveau d\u00e9part est s\u00e9lectionn\u00e9e.<br><\/p>\n\n\n\n<p>Une fois les 4 saisons pass\u00e9es, un d\u00e9compte classique s&rsquo;op\u00e8re puis un d\u00e9compte sp\u00e9cifique li\u00e9 au grand arbre s&rsquo;applique en fonction de la majorit\u00e9 de la couleur des jetons Faveur des joueurs.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-b1f1e86866d406804c9fc0129df6244e\"><br><br>\u2728 Conclusion<\/h4>\n\n\n\n<p><br><br>\ud83c\udfa8 Clairement la premi\u00e8re impression de ce jeu est visuelle. Suzanne Demontrond (A qui l&rsquo;ont doit d\u00e9j\u00e0 le travail sur Boussanga) \u00e0 r\u00e9alis\u00e9 une \u0153uvre magnifique.  L&rsquo;identit\u00e9 d&rsquo;Inori r\u00e9v\u00e8le ainsi un talent prometteur.<\/p>\n\n\n\n<p>\ud83d\udee0\ufe0f Les m\u00e9caniques du jeu, sans \u00eatre enti\u00e8re innovantes, sont efficaces. Le petit twist du placement sur la zone du grand arbre et la gestion de remplacement des cartes conf\u00e8re \u00e0 ce jeu une certaine tenue tout au long de la partie.<\/p>\n\n\n\n<p>\ud83d\udcab La re jouabilit\u00e9 semble correcte vue le nombre de cartes voyage disponible.<br><br>\ud83c\udfac La th\u00e9matique est ici difficile \u00e0 juger tellement le jeu joue sur un cot\u00e9 abstrait et \u00e9th\u00e9r\u00e9 en grande partie aid\u00e9 par la qualit\u00e9 de la direction artistique mais oui pourquoi pas &#8230;on peut retrouver certaines sensations spirituelles \ud83d\ude05<br><br>Inori est donc un tr\u00e8s beau jeu \u00e0 la th\u00e9matique l\u00e9g\u00e8rement abstraite et aux m\u00e9caniques plut\u00f4t classiques mais teint\u00e9es de petites trouvailles pertinentes. <br>M\u00eame un amateur de th\u00e9matique forte que je suis, le ressortira de temps en temps pour partager le plaisir d&rsquo;avoir un jeu si beau.<br><\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569483_572853351860061_849545785807091356_n-1024x768.jpg\" alt=\"\" class=\"wp-image-59745\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569483_572853351860061_849545785807091356_n-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569483_572853351860061_849545785807091356_n-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569483_572853351860061_849545785807091356_n-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569483_572853351860061_849545785807091356_n-1536x1152.jpg 1536w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/462569483_572853351860061_849545785807091356_n.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Inori est un village construit sur un arbre sacr\u00e9. Votre mission est de g\u00e2ter les esprits qui cohabitent sur cet arbre afin obtenir le r\u00f4le supr\u00eame de gardien de ce lieu enchant\u00e9 ! Ce jeu de placement d&rsquo;offrandes se d\u00e9roule en 4 saisons, chaque joueur pla\u00e7ant successivement un&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":59298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-59296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-4502","auteurs-mathieu-aubert","auteurs-theo-riviere","editeurs-space-cowboys","illustrateurs-suzanne-demontrond","nombre_conseille-1355","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=59296"}],"version-history":[{"count":49,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59296\/revisions"}],"predecessor-version":[{"id":60111,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59296\/revisions\/60111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/59298"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=59296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=59296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=59296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}